{"id":1473775,"date":"2026-05-04T09:03:52","date_gmt":"2026-05-04T16:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/"},"modified":"2026-05-04T09:03:52","modified_gmt":"2026-05-04T16:03:52","slug":"hantavirus-causas-sintomas-tratamiento-roedores-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/","title":{"rendered":"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores"},"content":{"rendered":"<p>Se sospecha que el hantavirus, una enfermedad rara causada generalmente por la exposici\u00f3n a la orina o las heces de roedores infectados, es la causa de la muerte de tres personas a bordo de un crucero en el oc\u00e9ano Atl\u00e1ntico.<\/p>\n<p>Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), se ha confirmado un caso de hantavirus y se est\u00e1n investigando otros cinco casos sospechosos. El barco viajaba de Argentina a Cabo Verde, un archipi\u00e9lago frente a la costa de \u00c1frica Occidental.<\/p>\n<p>Al principio, el hantavirus puede manifestarse como una gripe, con s\u00edntomas como fatiga, fiebre, escalofr\u00edos y dolores musculares. Sin embargo, con el tiempo, a medida que el virus da\u00f1a el coraz\u00f3n, los pulmones o los ri\u00f1ones, los pacientes pueden sufrir dificultad respiratoria grave, insuficiencia org\u00e1nica e incluso la muerte.<\/p>\n<p>La OMS declar\u00f3 este lunes que no hay motivo de alarma y que el riesgo para la poblaci\u00f3n en general sigue siendo bajo. Sin embargo, los expertos est\u00e1n desconcertados sobre c\u00f3mo pudo haberse propagado la enfermedad en el crucero.<\/p>\n<p>Esto es lo que debes saber sobre el hantavirus.<\/p>\n<p>El hantavirus se refiere a una cepa de virus que se transmite por roedores a trav\u00e9s de sus fluidos corporales y excrementos.<\/p>\n<p>Los humanos suelen infectarse al inhalar part\u00edculas de excrementos secos de roedores. Esto ocurre normalmente cuando alguien intenta deshacerse de los excrementos barri\u00e9ndolos, lo que causa que las part\u00edculas se dispersen en el aire. El hantavirus m\u00e1s com\u00fan en Estados Unidos se transmite por el rat\u00f3n ciervo.<\/p>\n<p>Los humanos tambi\u00e9n pueden infectarse al tocar objetos contaminados y luego tocarse la boca o la nariz. El hantavirus tambi\u00e9n puede transmitirse a trav\u00e9s de mordeduras o ara\u00f1azos de roedores, aunque esto es poco frecuente.<\/p>\n<p>Solo se conoce un tipo de hantavirus, la cepa andina originaria de Sudam\u00e9rica, que se haya transmitido de persona a persona, y esto es poco com\u00fan.<\/p>\n<p>Los hantavirus son la causa de dos tipos de enfermedades graves.<\/p>\n<p>Los hantavirus que se encuentran en Europa y Asia pueden causar fiebre hemorr\u00e1gica con s\u00edndrome renal (FHSR), que afecta a los ri\u00f1ones. Lo que comienza con dolor de cabeza, dolor abdominal y n\u00e1useas puede derivar en hipotensi\u00f3n, hemorragia interna e insuficiencia renal aguda. Seg\u00fan los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC, por sus siglas en ingl\u00e9s), entre el 5 % y el 15 % de los casos son mortales, y los s\u00edntomas suelen tardar entre una y dos semanas en desarrollarse tras la exposici\u00f3n.<\/p>\n<p>Los hantavirus que se encuentran en Am\u00e9rica causan el s\u00edndrome pulmonar por hantavirus (SPH). Esta enfermedad, que afecta a los pulmones, inicialmente genera s\u00edntomas similares a los de la gripe. Con el tiempo, algunos pacientes pueden experimentar dificultad para respirar y opresi\u00f3n en el pecho, debido a la acumulaci\u00f3n de l\u00edquido en los pulmones. Tras la exposici\u00f3n, los s\u00edntomas pueden tardar entre una y ocho semanas en desarrollarse. Seg\u00fan los CDC, casi el 40 % de las personas que desarrollan s\u00edntomas respiratorios pueden fallecer a causa del SPH.<\/p>\n<p>Seg\u00fan los CDC, no existe un tratamiento espec\u00edfico para el hantavirus. Los pacientes pueden ser tratados con hidrataci\u00f3n, reposo y tratar los s\u00edntomas espec\u00edficos.<\/p>\n<p>Por eso, la prevenci\u00f3n es importante. Seg\u00fan los CDC, la mejor manera de protegerse del hantavirus es mantener a los roedores fuera de casa: sellando cualquier grieta o agujero, guardando bien los alimentos y depositando la basura en recipientes gruesos con tapas herm\u00e9ticas.<\/p>\n<p>Al limpiar excrementos de roedores, utiliza guantes, roc\u00eda los desechos con una soluci\u00f3n de lej\u00eda y espera cinco minutos antes de limpiar la zona con toallas de papel y desecharlas de forma segura.<\/p>\n<p>Seg\u00fan un estudio de 2024, se estima que cada a\u00f1o se producen entre 60.000 y 100.000 casos de fiebre hemorr\u00e1gica con s\u00edndrome renal (FHSR) en todo el mundo, de los cuales aproximadamente la mitad se registran en China.<\/p>\n<p>Seg\u00fan datos de los CDC, entre 1993 y 2023 se notificaron 890 casos de hantavirus en Estados Unidos, la mayor\u00eda de ellos en los estados del oeste.<\/p>\n<p>El inter\u00e9s por esta enfermedad poco conocida aument\u00f3 el a\u00f1o pasado, despu\u00e9s de que Betsy Arakawa, la esposa del actor ganador del Oscar Gene Hackman, falleciera a los 65 a\u00f1os a causa del s\u00edndrome pulmonar por hantavirus (SPH). Los registros de salud p\u00fablica locales obtenidos por CNN revelaron el hallazgo de roedores muertos y nidos de roedores en varias dependencias independientes de la propiedad de la pareja en Nuevo M\u00e9xico.<\/p>\n<p>Se cree que Arakawa falleci\u00f3 aproximadamente una semana antes que su marido, que se encontraba en una fase avanzada de la enfermedad de Alzheimer.<\/p>\n<p>A\u00fan no lo sabemos. La Dra. Charlotte Hammer, profesora adjunta y epidemi\u00f3loga de la Universidad de Cambridge, afirm\u00f3 que existen varios escenarios posibles.<\/p>\n<p>\u201cNo es de extra\u00f1ar que a veces los roedores se cuelen en un barco, lo cual podr\u00eda ser una posibilidad\u201d, dijo Hammer.<\/p>\n<p>Dado que el per\u00edodo de incubaci\u00f3n de la enfermedad es de una a ocho semanas, tambi\u00e9n es posible que algunas personas se hayan infectado cuando el barco atrac\u00f3 por \u00faltima vez en Argentina, a\u00f1adi\u00f3 Hammer. Otra posibilidad ser\u00eda la transmisi\u00f3n de persona a persona, la cual, seg\u00fan ella, ser\u00eda muy improbable a esta escala.<\/p>\n<p>Para averiguar c\u00f3mo se propag\u00f3 la enfermedad a bordo, el Dr. Scott Miscovich, m\u00e9dico de familia y presidente y CEO de Premier Medical Group, dijo que el barco necesita ser \u201ccultivado al m\u00e1ximo\u201d, en referencia al proceso de incubar virus para identificarlos.<\/p>\n<p>\u201cEs necesario tomar muestras de todas las gotitas, de todo el polvo de cada habitaci\u00f3n, de todas las cocinas, de todos los sistemas de ventilaci\u00f3n, y luego cultivarlas\u201d, dijo.<\/p>\n<p>La Organizaci\u00f3n Mundial de la Salud ha declarado que se est\u00e1n llevando a cabo investigaciones detalladas, incluida la secuenciaci\u00f3n del virus.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se sospecha que el hantavirus, una enfermedad rara causada generalmente por la exposici\u00f3n a la orina o las heces de roedores infectados, es la causa de la muerte de tres personas a bordo de un crucero en el oc\u00e9ano Atl\u00e1ntico. Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), se ha confirmado un caso de hantavirus [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473775","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores - Noticias\" \/>\n<meta property=\"og:description\" content=\"Se sospecha que el hantavirus, una enfermedad rara causada generalmente por la exposici\u00f3n a la orina o las heces de roedores infectados, es la causa de la muerte de tres personas a bordo de un crucero en el oc\u00e9ano Atl\u00e1ntico. Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), se ha confirmado un caso de hantavirus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-04T16:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores\",\"datePublished\":\"2026-05-04T16:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/\"},\"wordCount\":1058,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/\",\"name\":\"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-04T16:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores - Noticias","og_description":"Se sospecha que el hantavirus, una enfermedad rara causada generalmente por la exposici\u00f3n a la orina o las heces de roedores infectados, es la causa de la muerte de tres personas a bordo de un crucero en el oc\u00e9ano Atl\u00e1ntico. Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), se ha confirmado un caso de hantavirus [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-04T16:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores","datePublished":"2026-05-04T16:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/"},"wordCount":1058,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/","name":"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-04T16:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 es el hantavirus? Causas, s\u00edntomas y tratamiento de este virus transmitido por roedores","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/hantavirus-causas-sintomas-tratamiento-roedores-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-04T16:03:52Z","datePublished":"2026-05-04T16:03:52Z","dateModified":"2026-05-04T16:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 es el hantavirus? Causas, s\\u00edntomas y tratamiento de este virus transmitido por roedores\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/04\\\/hantavirus-causas-sintomas-tratamiento-roedores-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/04\\\/hantavirus-causas-sintomas-tratamiento-roedores-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-04T16:03:52Z\",\"datePublished\":\"2026-05-04T16:03:52Z\",\"dateModified\":\"2026-05-04T16:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461192,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/04\/14\/nidos-ratas-muertas-propiedad-gene-hackman-hantavirus-trax\/","url_meta":{"origin":1473775,"position":0},"title":"Encuentran nidos y ratas muertas en edificios auxiliares durante evaluaci\u00f3n de riesgo en la propiedad de Gene Hackman","author":"","date":"abril 14, 2025","format":false,"excerpt":"Los registros del Departamento de Salud P\u00fablica de Nuevo M\u00e9xico obtenidos por CNN revelaron hallazgos de ratas muertas y nidos de roedores en ocho edificios auxiliares en la propiedad del fallecido actor Gene Hackman y su esposa Betsy Arakawa.La evaluaci\u00f3n ambiental del lugar de la vivienda de la extensa propiedad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473798,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/crucero-hantavirus-oms-sospecha-transmision-personas-trax\/","url_meta":{"origin":1473775,"position":1},"title":"Brote de hantavirus en crucero: se sospecha que hubo transmisi\u00f3n de persona a persona, dice la OMS","author":"","date":"mayo 5, 2026","format":false,"excerpt":"Es posible que se haya producido cierta transmisi\u00f3n de persona a persona a bordo del crucero afectado por un brote de hantavirus que ha dejado tres muertos y varios enfermos, inform\u00f3 este martes la Organizaci\u00f3n Mundial de la Salud (OMS).\u201cSabemos que algunos de los casos mantuvieron un contacto muy estrecho\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473762,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/hantavirus-crucero-muertos-trax\/","url_meta":{"origin":1473775,"position":2},"title":"Brote de hantavirus en un crucero deja tres muertos y otros gravemente enfermos; zarp\u00f3 desde Argentina","author":"","date":"mayo 3, 2026","format":false,"excerpt":"Un presunto brote de hantavirus en un crucero en el oc\u00e9ano Atl\u00e1ntico mat\u00f3 a tres personas y enferm\u00f3 al menos a otras tres, inform\u00f3 el domingo la Organizaci\u00f3n Mundial de la Salud.En un comunicado a The Associated Press, la OMS dijo que estaba en marcha una investigaci\u00f3n, pero que al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459641,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/03\/07\/causas-muerte-gene-hackman-betsy-arakawa-hantavirus-trax\/","url_meta":{"origin":1473775,"position":3},"title":"Gene Hackman muri\u00f3 por causas naturales; su esposa, Betsy Arakawa, muri\u00f3 d\u00edas antes de hantavirus, dicen los investigadores","author":"","date":"marzo 7, 2025","format":false,"excerpt":"El actor ganador del premio Oscar, Gene Hackman, muri\u00f3 por causas naturales, dijo la m\u00e9dico forense jefe, la Dra. Heather Jarrell, este viernes en una conferencia de prensa.El actor de 95 a\u00f1os era hipertenso, ten\u00eda enfermedad cardiovascular ateroscler\u00f3tica, as\u00ed como enfermedad de Alzheimer, que Jarrell dijo que era \u201cun factor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473776,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/crucero-hantavirus-ushuaia-historia-epuyen-orix\/","url_meta":{"origin":1473775,"position":4},"title":"El crucero que enfrenta un brote mortal de hantavirus zarp\u00f3 de Argentina. El virus en ese pa\u00eds tiene un cap\u00edtulo traum\u00e1tico","author":"","date":"mayo 4, 2026","format":false,"excerpt":"El brote de hantavirus en un crucero ya dej\u00f3 tres muertos. El barco zarp\u00f3 desde Argentina, un pa\u00eds donde la enfermedad es end\u00e9mica, como en muchas zonas del mundo, pero es tambi\u00e9n donde circula uno de los genotipos asociados a la transmisi\u00f3n humana de la infecci\u00f3n del s\u00edndrome cardiopulmonar.Los hantavirus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473817,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/barco-hantavirus-canarias-epidemiologos-orix\/","url_meta":{"origin":1473775,"position":5},"title":"\u00bfLlegar\u00e1 a las Islas Canarias el crucero afectado por un brote de hantavirus? Epidemi\u00f3logos a\u00fan eval\u00faan la situaci\u00f3n","author":"","date":"mayo 5, 2026","format":false,"excerpt":"El destino de los cerca de los casi 150 pasajeros a bordo del MV Hondius, actualmente fondeado frente a las costas de Cabo Verde, sigue siendo incierto. El plan anunciado por la Organizaci\u00f3n Mundial de la Salud (OMS) este martes por la ma\u00f1ana era que la embarcaci\u00f3n se dirigiera a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473775"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473775\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}