{"id":1473793,"date":"2026-05-04T23:03:49","date_gmt":"2026-05-05T06:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/"},"modified":"2026-05-04T23:03:49","modified_gmt":"2026-05-05T06:03:49","slug":"legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/","title":{"rendered":"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual"},"content":{"rendered":"<p>Seg\u00fan la representante republicana Nancy Mace y documentos revisados \u200b\u200bpor CNN, los contribuyentes de EE.UU. han pagado m\u00e1s de US$ 300.000 en acuerdos confidenciales por acoso sexual en nombre de seis exmiembros de la C\u00e1mara de Representantes o sus oficinas.<\/p>\n<p>La Oficina de Derechos Laborales del Congreso se vio obligada a entregar los documentos del acuerdo al Congreso tras una citaci\u00f3n judicial de Mace, quien ha ayudado a liderar una iniciativa en el Capitolio para impulsar la transparencia y la rendici\u00f3n de cuentas tras las acusaciones de conducta sexual inapropiada que llevaron a dos <a href=\"https:\/\/www.cnn.com\/2026\/04\/24\/politics\/ethics-reforms-capitol-hill-misconduct\">renuncias de alto perfil<\/a>.<\/p>\n<p>Un an\u00e1lisis realizado por CNN de m\u00e1s de 1.000 p\u00e1ginas de expedientes, que incluyen notas de abogados, documentos de acuerdos y denuncias formales, ofrece una perspectiva de las acusaciones de que ciertos miembros se aprovecharon de sus posiciones de poder para maltratar a su personal.<\/p>\n<p>La Oficina de Derechos Laborales del Congreso interviene en una variedad de quejas contra los miembros, no exclusivamente por acoso sexual.<\/p>\n<p>Desde el 1 de enero de 1996 hasta el 12 de diciembre de 2018, la oficina aprob\u00f3 349 indemnizaciones o acuerdos extrajudiciales para resolver quejas contra oficinas del poder legislativo, seg\u00fan indic\u00f3 su asesor jur\u00eddico en una carta enviada al presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, James Comer, obtenida por CNN.<\/p>\n<p>Un total de 80 de esos casos fueron resueltos por una oficina de la C\u00e1mara o del Senado por diversos motivos. De este subconjunto, siete casos derivaron en pagos para abordar denuncias de acoso sexual.<\/p>\n<p>Los pagos a los que se hace referencia en la carta se realizaron con fondos p\u00fablicos provenientes de una cuenta del Tesoro que ya no est\u00e1 disponible para los legisladores.<\/p>\n<p>Veintitr\u00e9s expedientes de casos de acuerdos extrajudiciales en la jurisdicci\u00f3n de la Oficina de Derechos Laborales del Congreso fueron destruidos de conformidad con la pol\u00edtica de retenci\u00f3n de registros de dicha oficina.<\/p>\n<p>\u201cEsta \u2018Pol\u00edtica de Retenci\u00f3n de Registros de OCWR\u2019 se implement\u00f3 en 2013 para alinear a OCWR con las pr\u00e1cticas habituales de retenci\u00f3n de registros en todo el Gobierno\u201d, escribi\u00f3 el Asesor Jur\u00eddico General John N. Ohlweiler.<\/p>\n<p>En t\u00e9rminos generales, los acuerdos de conciliaci\u00f3n revisados \u200b\u200bpor CNN no implican que la oficina acusada admita haber cometido irregularidad alguna, sino que establecen que la oficina acepta el acuerdo \u201cpara evitar las molestias de un litigio prolongado y los gastos que dicho litigio supondr\u00eda para las partes y los contribuyentes\u201d, como se lee en uno de los acuerdos.<\/p>\n<p>Los acuerdos tambi\u00e9n detallan c\u00f3mo la oficina debe gestionar las cuestiones relacionadas con los t\u00e9rminos y condiciones de la rescisi\u00f3n del contrato laboral del demandante.<\/p>\n<p>Tras los cambios normativos implementados en 2018 a ra\u00edz del movimiento #MeToo, los miembros ya no pod\u00edan depender de los fondos p\u00fablicos para llegar a acuerdos extrajudiciales.<\/p>\n<p>La Comisi\u00f3n de \u00c9tica de la C\u00e1mara de Representantes anunci\u00f3 en un comunicado reciente que, desde la entrada en vigor de la nueva ley, \u201cla Comisi\u00f3n no ha recibido notificaci\u00f3n alguna de indemnizaciones o acuerdos relacionados con acusaciones de acoso sexual por parte de un miembro\u201d.<\/p>\n<p>El lunes, Mace mencion\u00f3 en una publicaci\u00f3n de X a seis exlegisladores o a las oficinas de legisladores involucrados en los acuerdos extrajudiciales que suman m\u00e1s de US$ 300.000.<\/p>\n<p> La mayor\u00eda de los miembros mencionados por la congresista renunciaron al Congreso tras enfrentar p\u00fablicamente acusaciones de conducta sexual inapropiada, entre ellos los exdiputados John Conyers, dem\u00f3crata de Michigan, y Blake Farenthold, republicano de Texas.<\/p>\n<p>En varios de estos casos, se inform\u00f3 p\u00fablicamente antes de sus renuncias que el miembro hab\u00eda utilizado fondos p\u00fablicos para acuerdos extrajudiciales.<\/p>\n<p>CNN ha intentado contactar con el excongresista o con un representante de los seis antiguos legisladores mencionados por Mace. Tres de los se\u00f1alados mencionados por la congresista, entre ellos Conyers y Farenthold, han fallecido.<\/p>\n<p>En 2017, la Comisi\u00f3n de \u00c9tica de la C\u00e1mara de Representantes inici\u00f3 una investigaci\u00f3n contra Conyers, quien en ese momento <a href=\"https:\/\/www.cnn.com\/2017\/11\/21\/politics\/michigan-rep-john-conyers-democrat-sexual-harassment-settlement\">neg\u00f3 haber cometido<\/a> irregularidad alguna, pero no impugn\u00f3 la existencia de un acuerdo o pago.<\/p>\n<p>Los documentos muestran que se realiz\u00f3 un desembolso por indemnizaci\u00f3n de m\u00e1s de US$ 27.000 y otro de US$ 50.000 en concepto de acuerdo extrajudicial en nombre de Conyers.<\/p>\n<p>Farenthold <a href=\"https:\/\/www.cnn.com\/2018\/04\/06\/politics\/blake-farenthold-resigns-congress\">renunci\u00f3<\/a> ese mismo a\u00f1o, en 2018, mientras tambi\u00e9n enfrentaba una investigaci\u00f3n \u00e9tica. Neg\u00f3 algunas de las acusaciones en su contra, pero se disculp\u00f3 por usar lenguaje inapropiado y por su papel en la creaci\u00f3n de un ambiente laboral hostil, y prometi\u00f3 reembolsar el dinero de los contribuyentes utilizado para el acuerdo.<\/p>\n<p>Los documentos muestran que se lleg\u00f3 a un acuerdo de US$ 84.000 en nombre de Farenthold.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan la representante republicana Nancy Mace y documentos revisados \u200b\u200bpor CNN, los contribuyentes de EE.UU. han pagado m\u00e1s de US$ 300.000 en acuerdos confidenciales por acoso sexual en nombre de seis exmiembros de la C\u00e1mara de Representantes o sus oficinas. La Oficina de Derechos Laborales del Congreso se vio obligada a entregar los documentos del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473793","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual - Noticias\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan la representante republicana Nancy Mace y documentos revisados \u200b\u200bpor CNN, los contribuyentes de EE.UU. han pagado m\u00e1s de US$ 300.000 en acuerdos confidenciales por acoso sexual en nombre de seis exmiembros de la C\u00e1mara de Representantes o sus oficinas. La Oficina de Derechos Laborales del Congreso se vio obligada a entregar los documentos del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T06:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual\",\"datePublished\":\"2026-05-05T06:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/\"},\"wordCount\":840,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/\",\"name\":\"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-05T06:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual - Noticias","og_description":"Seg\u00fan la representante republicana Nancy Mace y documentos revisados \u200b\u200bpor CNN, los contribuyentes de EE.UU. han pagado m\u00e1s de US$ 300.000 en acuerdos confidenciales por acoso sexual en nombre de seis exmiembros de la C\u00e1mara de Representantes o sus oficinas. La Oficina de Derechos Laborales del Congreso se vio obligada a entregar los documentos del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-05T06:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/"},"author":{"name":"","@id":""},"headline":"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual","datePublished":"2026-05-05T06:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/"},"wordCount":840,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/","name":"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-05T06:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Revelan que legisladores de EE.UU. pagaron con fondos p\u00fablicos m\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-05T06:03:49Z","datePublished":"2026-05-05T06:03:49Z","dateModified":"2026-05-05T06:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Revelan que legisladores de EE.UU. pagaron con fondos p\\u00fablicos m\\u00e1s de US$ 300.000 en pactos extrajudiciales por acoso sexual\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/04\\\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/04\\\/legisladores-ee-uu-fondos-publicos-pactos-acoso-sexual-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-05T06:03:49Z\",\"datePublished\":\"2026-05-05T06:03:49Z\",\"dateModified\":\"2026-05-05T06:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471256,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/02\/15\/departamento-justicia-lista-personas-archivos-epstein-trax\/","url_meta":{"origin":1473793,"position":0},"title":"El Departamento de Justicia env\u00eda al Congreso una lista con cientos de personas destacadas mencionadas en archivos de Epstein","author":"","date":"febrero 15, 2026","format":false,"excerpt":"El Departamento de Justicia envi\u00f3 el s\u00e1bado al Congreso una lista de \u201cpersonas pol\u00edticamente expuestas\u201d que aparecen en los millones de archivos publicados en relaci\u00f3n con sus investigaciones sobre el delincuente sexual condenado Jeffrey Epstein.La carta de seis p\u00e1ginas, de la que CNN obtuvo una copia, incluye los nombres de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471117,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/02\/11\/nombres-archivos-epstein-politicos-empresarios-famosos-hollywood-trax\/","url_meta":{"origin":1473793,"position":1},"title":"Pol\u00edticos, empresarios, figuras de Hollywood. Estos son los nombres que aparecen en los archivos de Epstein","author":"","date":"febrero 11, 2026","format":false,"excerpt":"Los archivos relacionados con el fallecido delincuente sexual convicto Jeffrey Epstein se han hecho p\u00fablicos a lo largo del \u00faltimo a\u00f1o en una serie de divulgaciones de documentos. M\u00e1s recientemente y de forma m\u00e1s amplia, el Departamento de Justicia de EE.UU. public\u00f3 millones de documentos (correos electr\u00f3nicos, mensajes de texto,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471843,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/03\/howard-lutnick-acepta-declarar-voluntariamente-epstein-trax\/","url_meta":{"origin":1473793,"position":2},"title":"El secretario de Comercio de Trump, Howard Lutnick, acepta declarar voluntariamente sobre su relaci\u00f3n con Jeffrey Epstein","author":"","date":"marzo 3, 2026","format":false,"excerpt":"El secretario de Comercio, Howard Lutnick, acept\u00f3 presentarse de manera voluntaria ante la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes para hablar sobre su relaci\u00f3n con Jeffrey Epstein, lo que genera un enfrentamiento entre los republicanos del Congreso y el Gobierno de Trump, que ha intentado minimizar los v\u00ednculos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470338,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/01\/21\/batalla-legal-blake-lively-justin-baldoni-taylor-swift-trax\/","url_meta":{"origin":1473793,"position":3},"title":"La batalla legal entre Blake Lively y Justin Baldoni tiene una nueva estrella: Taylor Swift","author":"","date":"enero 21, 2026","format":false,"excerpt":"La m\u00e1s reciente ronda del drama legal entre la actriz Blake Lively y su director de \u201cIt Ends with Us\u201d, Justin Baldoni, ofrece una inusual visi\u00f3n de la red de apoyo en la que Lively confi\u00f3 durante y despu\u00e9s de la producci\u00f3n de la pel\u00edcula, incluyendo a una de sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455915,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/11\/19\/republicana-presenta-resolucion-contra-banos-transgenero-capitolio-trax\/","url_meta":{"origin":1473793,"position":4},"title":"Una Republicana presenta resoluci\u00f3n contra ba\u00f1os transg\u00e9nero en el Capitolio luego de que primera mujer transg\u00e9nero fue elegida para el Congreso","author":"","date":"noviembre 19, 2024","format":false,"excerpt":"(CNN) -- Dos semanas despu\u00e9s de que se hiciera historia con la elecci\u00f3n de la primera persona transg\u00e9nero en el Congreso de Estados Unidos, una republicana de la C\u00e1mara de Representantes est\u00e1 presionando para prohibir el acceso de las mujeres transg\u00e9nero a los ba\u00f1os de mujeres del Capitolio.La representante de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451250,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/07\/18\/estados-unidos-acusa-ong-abuso-acoso-menores-migrantes-orix\/","url_meta":{"origin":1473793,"position":5},"title":"Acusa EE.UU. a ONG por abuso y acoso sexual contra menores migrantes","author":"","date":"julio 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Departamento de Justicia de Estados Unidos present\u00f3 una demanda contra la organizaci\u00f3n sin fines de lucro Southwest Key Programs, la mayor proveedora de refugio para ni\u00f1os no acompa\u00f1ados que llegan a la frontera sur del pa\u00eds y que recibe subsidios del gobierno federal. La acusa de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473793"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473793\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}