{"id":1473796,"date":"2026-05-05T01:03:49","date_gmt":"2026-05-05T08:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/"},"modified":"2026-05-05T01:03:49","modified_gmt":"2026-05-05T08:03:49","slug":"precios-petroleo-dispararon-primer-dia-proyecto-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/","title":{"rendered":"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan &#171;Proyecto Libertad&#187; de Trump para desbloquear el estrecho de Ormuz"},"content":{"rendered":"<p>El petr\u00f3leo alcanz\u00f3 su precio de cierre m\u00e1s alto del a\u00f1o el primer d\u00eda de la operaci\u00f3n del presidente Donald Trump para guiar a los barcos varados a trav\u00e9s del bloqueado estrecho de Ormuz, lo que subraya la intensa incertidumbre que a\u00fan aqueja el comercio mundial de energ\u00eda.<\/p>\n<p>Los futuros del crudo Brent, la referencia mundial del petr\u00f3leo, cayeron un 1,1 % hasta los US$ 113,4 por barril a la 1:58 a.m. (hora de Miami) del martes, tras haber subido un 5,8 % hasta los US$ 114,4 el lunes, el cierre m\u00e1s alto de 2026.<\/p>\n<p>El West Texas Intermediate (WTI), la referencia estadounidense, baj\u00f3 un 2,1 % hasta los US$ 104,3 por barril.<\/p>\n<p>El petr\u00f3leo se negocia mediante contratos de futuros, lo que implica un acuerdo para comprar o vender a un precio determinado en una fecha futura. El precio del WTI del martes refleja el petr\u00f3leo para entrega en junio, mientras que el Brent refleja el petr\u00f3leo para entrega en julio.<\/p>\n<p>Ser el mayor productor de petr\u00f3leo del mundo no ha eximido a Estados Unidos de una crisis energ\u00e9tica, que ha elevado el precio de la gasolina a US$ 4,46 por gal\u00f3n el lunes, desde un promedio de US$ 2,98 por gal\u00f3n antes de que comenzara la guerra, seg\u00fan la <a href=\"https:\/\/gasprices.aaa.com\/\">AAA<\/a>.<\/p>\n<p>Seg\u00fan Andy Lipow, presidente de la consultora Lipow Oil Associates, el precio de la gasolina en Estados Unidos podr\u00eda alcanzar los US$ 5 por gal\u00f3n si el estrecho de Ormuz permanece cerrado el pr\u00f3ximo mes.<\/p>\n<p>Este repunte casi igualar\u00eda el m\u00e1ximo hist\u00f3rico de US$ 5,02 por gal\u00f3n registrado en junio de 2022 tras la invasi\u00f3n rusa de Ucrania.<\/p>\n<p>Los recientes precios elevados se produjeron cuando Trump intent\u00f3 liberar el flujo de petroleros a trav\u00e9s del estrecho de Ormuz, que ha permanecido pr\u00e1cticamente cerrado por Ir\u00e1n desde que fue atacado por Estados Unidos e Israel, estrangulando alrededor del 20 % del suministro mundial de petr\u00f3leo antes de la guerra.<\/p>\n<p>La nueva iniciativa del presidente, denominada <a href=\"https:\/\/www.cnn.com\/2026\/05\/04\/middleeast\/project-freedom-hormuz-guide-ships-intl-hnk-ml?cid=external-feeds_iluminar_newsbreak\">\u201cProyecto Libertad\u201d,<\/a> comenz\u00f3 el lunes con el objetivo de \u201cguiar\u201d a los buques a trav\u00e9s del crucial canal de transporte de petr\u00f3leo y gas.<\/p>\n<p>Sin embargo, no se registr\u00f3 un aumento significativo en el tr\u00e1fico mar\u00edtimo: solo cuatro buques cruzaron el estrecho ayer, seg\u00fan S&#038;P Global Market Intelligence.<\/p>\n<p>Antes de la guerra, un promedio de m\u00e1s de 120 barcos al d\u00eda transitaban por esta vital v\u00eda fluvial.<\/p>\n<p>Varios buques mercantes y un <a href=\"https:\/\/www.cnn.com\/2026\/05\/04\/world\/live-news\/iran-war-hormuz-trump#cmorlqy9p00003b6r94ssz4yy\">importante puerto petrolero<\/a> en los Emiratos \u00c1rabes Unidos tambi\u00e9n fueron atacados el lunes, cuando Estados Unidos destruy\u00f3 algunas embarcaciones iran\u00edes, la mayor escalada desde que comenz\u00f3 el alto el fuego temporal hace cuatro semanas.<\/p>\n<p>El intercambio de disparos entre Estados Unidos e Ir\u00e1n puso a prueba el fr\u00e1gil alto el fuego entre ambos pa\u00edses, mientras Trump se negaba a decir si la tregua segu\u00eda vigente.<\/p>\n<p>La decisi\u00f3n de Estados Unidos e Israel de ir a la guerra con Ir\u00e1n ha desencadenado una crisis petrolera hist\u00f3rica, y pa\u00edses de todo el mundo, incluidos muchos aliados clave de Estados Unidos en Europa y Asia, se enfrentan ahora a precios del combustible disparados y costes crecientes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El petr\u00f3leo alcanz\u00f3 su precio de cierre m\u00e1s alto del a\u00f1o el primer d\u00eda de la operaci\u00f3n del presidente Donald Trump para guiar a los barcos varados a trav\u00e9s del bloqueado estrecho de Ormuz, lo que subraya la intensa incertidumbre que a\u00fan aqueja el comercio mundial de energ\u00eda. Los futuros del crudo Brent, la referencia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473796","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan &quot;Proyecto Libertad&quot; de Trump para desbloquear el estrecho de Ormuz - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan &quot;Proyecto Libertad&quot; de Trump para desbloquear el estrecho de Ormuz - Noticias\" \/>\n<meta property=\"og:description\" content=\"El petr\u00f3leo alcanz\u00f3 su precio de cierre m\u00e1s alto del a\u00f1o el primer d\u00eda de la operaci\u00f3n del presidente Donald Trump para guiar a los barcos varados a trav\u00e9s del bloqueado estrecho de Ormuz, lo que subraya la intensa incertidumbre que a\u00fan aqueja el comercio mundial de energ\u00eda. Los futuros del crudo Brent, la referencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T08:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan &#171;Proyecto Libertad&#187; de Trump para desbloquear el estrecho de Ormuz\",\"datePublished\":\"2026-05-05T08:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/\"},\"wordCount\":581,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/\",\"name\":\"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan \\\"Proyecto Libertad\\\" de Trump para desbloquear el estrecho de Ormuz - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-05T08:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan &#171;Proyecto Libertad&#187; de Trump para desbloquear el estrecho de Ormuz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan \"Proyecto Libertad\" de Trump para desbloquear el estrecho de Ormuz - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan \"Proyecto Libertad\" de Trump para desbloquear el estrecho de Ormuz - Noticias","og_description":"El petr\u00f3leo alcanz\u00f3 su precio de cierre m\u00e1s alto del a\u00f1o el primer d\u00eda de la operaci\u00f3n del presidente Donald Trump para guiar a los barcos varados a trav\u00e9s del bloqueado estrecho de Ormuz, lo que subraya la intensa incertidumbre que a\u00fan aqueja el comercio mundial de energ\u00eda. Los futuros del crudo Brent, la referencia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-05T08:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan &#171;Proyecto Libertad&#187; de Trump para desbloquear el estrecho de Ormuz","datePublished":"2026-05-05T08:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/"},"wordCount":581,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/","name":"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan \"Proyecto Libertad\" de Trump para desbloquear el estrecho de Ormuz - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-05T08:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan &#171;Proyecto Libertad&#187; de Trump para desbloquear el estrecho de Ormuz"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Precios del petr\u00f3leo se dispararon el primer d\u00eda del plan &#171;Proyecto Libertad&#187; de Trump para desbloquear el estrecho de Ormuz","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-05T08:03:49Z","datePublished":"2026-05-05T08:03:49Z","dateModified":"2026-05-05T08:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Precios del petr\\u00f3leo se dispararon el primer d\\u00eda del plan &#171;Proyecto Libertad&#187; de Trump para desbloquear el estrecho de Ormuz\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/05\\\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/05\\\/precios-petroleo-dispararon-primer-dia-proyecto-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-05T08:03:49Z\",\"datePublished\":\"2026-05-05T08:03:49Z\",\"dateModified\":\"2026-05-05T08:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472950,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/07\/precios-petroleo-caen-acciones-suben-alto-fuego-trump-trax\/","url_meta":{"origin":1473796,"position":0},"title":"Los precios del petr\u00f3leo caen y las acciones suben tras el anuncio de alto el fuego de Trump","author":"","date":"abril 7, 2026","format":false,"excerpt":"Los precios del petr\u00f3leo se desplomaron el martes despu\u00e9s de que el presidente Donald Trump acordara un alto el fuego de dos semanas con Ir\u00e1n, lo que aviv\u00f3 las esperanzas de que m\u00e1s petroleros pudieran transitar pronto por el estrat\u00e9gico estrecho de Ormuz.Sin embargo, los analistas advirtieron que a\u00fan quedan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472965,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/08\/gasolina-precio-sube-incertidumbre-guerra-iran-trax\/","url_meta":{"origin":1473796,"position":1},"title":"Los precios de la gasolina suben ligeramente mientras persiste la incertidumbre sobre la guerra en Ir\u00e1n","author":"","date":"abril 8, 2026","format":false,"excerpt":"El precio promedio de la gasolina regular subi\u00f3 2 centavos, hasta los US$ 4,16 por gal\u00f3n, seg\u00fan la \u00faltima lectura de la AAA del mi\u00e9rcoles, incluso con la ca\u00edda de los futuros del petr\u00f3leo tras el anuncio de un alto el fuego de dos semanas en la guerra en Ir\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473559,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/28\/precio-petroleo-usd-110-barril-guerra-iran-trax\/","url_meta":{"origin":1473796,"position":2},"title":"El precio del petr\u00f3leo supera los US$ 110 por barril ante las dudas sobre un acuerdo de paz en la guerra con Ir\u00e1n","author":"","date":"abril 28, 2026","format":false,"excerpt":"El precio del petr\u00f3leo super\u00f3 hoy los US$ 110 por barril por primera vez en tres semanas, ante la preocupaci\u00f3n de los operadores de que Estados Unidos e Ir\u00e1n no est\u00e9n m\u00e1s cerca de un acuerdo para poner fin a la guerra y reabrir por completo el vital estrecho de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472026,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/09\/por-que-precio-petroleo-100-dolares-barril-trax\/","url_meta":{"origin":1473796,"position":3},"title":"\u00bfPor qu\u00e9 se dispar\u00f3 el precio del petr\u00f3leo hasta los US$ 100 por barril?","author":"","date":"marzo 9, 2026","format":false,"excerpt":"Una interrupci\u00f3n hist\u00f3rica en la producci\u00f3n mundial de petr\u00f3leo hizo que los precios del crudo rompieran el lunes la barrera de los US$ 100 por primera vez en casi cuatro a\u00f1os.Sin que se vislumbre un final para la guerra con Ir\u00e1n, los futuros del petr\u00f3leo podr\u00edan tener considerablemente m\u00e1s margen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472002,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/08\/precio-petroleo-100-dolares-guerra-iran-trax\/","url_meta":{"origin":1473796,"position":4},"title":"Los precios del petr\u00f3leo se disparan por encima de US$ 100 por barril a medida que la guerra se intensifica en Ir\u00e1n","author":"","date":"marzo 8, 2026","format":false,"excerpt":"El precio del petr\u00f3leo se dispar\u00f3 por encima de US$ 100 por barril este domingo, la primera vez que cruza ese umbral desde la invasi\u00f3n rusa a Ucrania en 2022, y los inversionistas temen que la guerra en Ir\u00e1n signifique restricciones prolongadas en los flujos de petr\u00f3leo de Medio Oriente.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473092,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/13\/precios-petroleo-disparan-bloqueo-puertos-iranies-trax\/","url_meta":{"origin":1473796,"position":5},"title":"Los precios del petr\u00f3leo se disparan ante los planes de EE.UU. de bloquear los puertos iran\u00edes en el estrecho de Ormuz","author":"","date":"abril 13, 2026","format":false,"excerpt":"Los precios del petr\u00f3leo subieron este lunes, despu\u00e9s de que las fuerzas armadas de Estados Unidos dijera que implementar\u00eda un bloqueo mar\u00edtimo en el estrecho de Ormuz, una medida que podr\u00eda poner a prueba el actual alto el fuego y, al mismo tiempo, restringir a\u00fan m\u00e1s el suministro mundial de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473796"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473796\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}