{"id":1473811,"date":"2026-05-05T10:03:47","date_gmt":"2026-05-05T17:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/"},"modified":"2026-05-05T10:03:47","modified_gmt":"2026-05-05T17:03:47","slug":"veterano-fuerzas-especiales-profugo-disparo-esposa-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/","title":{"rendered":"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa"},"content":{"rendered":"<p>Investigadores est\u00e1n rastreando un terreno densamente boscoso en busca de un veterano armado de las fuerzas especiales sospechoso de intentar asesinar a su esposa, seg\u00fan las autoridades de Tennessee.<\/p>\n<p>Craig Berry se encuentra a la fuga desde las primeras horas del viernes, momento en que dispar\u00f3 a su esposa en Dover, en el extremo noroeste de Tennessee, cerca de la frontera con Kentucky, afirman las autoridades.<\/p>\n<p>\u201cEl sospechoso huy\u00f3 hacia el bosque, en las inmediaciones de la residencia, antes de que llegaran los agentes\u201d, declar\u00f3 la Oficina del Sheriff del condado de Stewart.<\/p>\n<p>Se ha emitido una orden de arresto contra Berry en la que se lo lo acusa de intento de homicidio, precis\u00f3 la oficina del sheriff. Las autoridades no han revelado el estado de salud actual de la esposa.<\/p>\n<p>Esta ardua operaci\u00f3n de b\u00fasqueda resulta especialmente compleja dadas las habilidades del sospechoso en entornos naturales.<\/p>\n<p>\u201cBerry es un veterano retirado de las fuerzas especiales y posee una amplia formaci\u00f3n en t\u00e1cticas de supervivencia\u201d, public\u00f3 el lunes la oficina del sheriff en Facebook.<\/p>\n<p>\u201cEs un excelente nadador y buceador, y se encuentra en buena condici\u00f3n f\u00edsica. Va armado con al menos una pistola y se cree que se llev\u00f3 munici\u00f3n adicional\u201d.<\/p>\n<p>Una c\u00e1mara de vigilancia instalada en el bosque capt\u00f3 una imagen que, seg\u00fan los investigadores, corresponde a Berry vistiendo ropa de camuflaje.<\/p>\n<p>\u201cNo descartamos la posibilidad de que haya recibido alg\u00fan tipo de ayuda externa tras el incidente\u201d, se\u00f1al\u00f3 la oficina del sheriff. \u201cNo disponemos de informaci\u00f3n que sugiera que ya no se encuentre en la zona\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Investigadores est\u00e1n rastreando un terreno densamente boscoso en busca de un veterano armado de las fuerzas especiales sospechoso de intentar asesinar a su esposa, seg\u00fan las autoridades de Tennessee. Craig Berry se encuentra a la fuga desde las primeras horas del viernes, momento en que dispar\u00f3 a su esposa en Dover, en el extremo noroeste [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473811","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa - Noticias\" \/>\n<meta property=\"og:description\" content=\"Investigadores est\u00e1n rastreando un terreno densamente boscoso en busca de un veterano armado de las fuerzas especiales sospechoso de intentar asesinar a su esposa, seg\u00fan las autoridades de Tennessee. Craig Berry se encuentra a la fuga desde las primeras horas del viernes, momento en que dispar\u00f3 a su esposa en Dover, en el extremo noroeste [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T17:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa\",\"datePublished\":\"2026-05-05T17:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/\"},\"wordCount\":306,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/\",\"name\":\"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-05T17:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa - Noticias","og_description":"Investigadores est\u00e1n rastreando un terreno densamente boscoso en busca de un veterano armado de las fuerzas especiales sospechoso de intentar asesinar a su esposa, seg\u00fan las autoridades de Tennessee. Craig Berry se encuentra a la fuga desde las primeras horas del viernes, momento en que dispar\u00f3 a su esposa en Dover, en el extremo noroeste [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-05T17:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/"},"author":{"name":"","@id":""},"headline":"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa","datePublished":"2026-05-05T17:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/"},"wordCount":306,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/","name":"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-05T17:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-05T17:03:47Z","datePublished":"2026-05-05T17:03:47Z","dateModified":"2026-05-05T17:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Buscan a veterano de las fuerzas especiales con amplio entrenamiento en supervivencia por disparar a su esposa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/05\\\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/05\\\/veterano-fuerzas-especiales-profugo-disparo-esposa-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-05T17:03:47Z\",\"datePublished\":\"2026-05-05T17:03:47Z\",\"dateModified\":\"2026-05-05T17:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455063,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/10\/13\/dijeron-que-eran-trabajadores-servicios-publicos-pero-cuando-salieron-esposa-atada-y-el-esposo-estaba-muerto-trax\/","url_meta":{"origin":1473811,"position":0},"title":"Dijeron que eran trabajadores de servicios p\u00fablicos, pero cuando salieron de la casa, la esposa estaba atada y el esposo estaba muerto","author":"","date":"octubre 13, 2024","format":false,"excerpt":"(CNN) -- Uno de los dos sospechosos acusados \u200b\u200bde hacerse pasar por trabajadores de servicios p\u00fablicos antes de matar a un hombre de Michigan y atar a su esposa fue detenido sin incidentes en Shreveport, Luisiana, este s\u00e1bado, dijeron las autoridades.El sospechoso, que no ha sido identificado, fue arrestado en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1405027,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2022\/06\/10\/tiroteo-en-maryland-identifican-a-victimas-el-autor-era-empleado-de-la-fabrica\/","url_meta":{"origin":1473811,"position":1},"title":"Tiroteo en Maryland: identifican a v\u00edctimas; el autor era empleado de la f\u00e1brica","author":"agomez","date":"junio 10, 2022","format":false,"excerpt":"El tirador es un hombre de 23 a\u00f1os, empleado de la f\u00e1brica de hormig\u00f3n ubicada en Smithsburg donde ocurrieron los hechos.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469602,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/12\/27\/tres-heridos-tiroteo-idaho-trax\/","url_meta":{"origin":1473811,"position":2},"title":"Tiroteo contra la Oficina del Sheriff en Idaho deja tres heridos; un hombre fue abatido, dicen autoridades","author":"agomez","date":"diciembre 27, 2025","format":false,"excerpt":"Un atacante armado con varias armas abri\u00f3 fuego en el vest\u00edbulo de la Oficina del Sheriff de Idaho y en la calle el viernes, hiriendo a tres personas antes de ser abatido en un enfrentamiento con la polic\u00eda, dijo el sheriff local.El presunto atacante dispar\u00f3 contra una camioneta afuera de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461384,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/04\/19\/tiroteo-sospechoso-universidad-estatal-florida-trax\/","url_meta":{"origin":1473811,"position":3},"title":"Autoridades dispararon a un sospechoso minutos despu\u00e9s de que llamadas al 911 reportaran un tiroteo en la FSU. Esto sabemos","author":"","date":"abril 19, 2025","format":false,"excerpt":"Cuando se produjeron m\u00faltiples disparos cerca de la uni\u00f3n estudiantil de la Universidad Estatal de Florida minutos antes del mediod\u00eda del jueves, los estudiantes huyeron del campus intentando ponerse a salvo mientras el sonido de las sirenas de emergencia se intensificaba.Apenas dos minutos despu\u00e9s de que las llamadas al 911\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450400,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/06\/16\/multiples-personas-heridas-tiroteo-parque-acuatico-michigan-trax\/","url_meta":{"origin":1473811,"position":4},"title":"Al menos nueve personas recibieron disparos, incluidos dos ni\u00f1os, en un centro recreativo de Michigan antes de que el sospechoso sea encontrado muerto, dice la Polic\u00eda","author":"","date":"junio 16, 2024","format":false,"excerpt":"(CNN) --\u00a0 \u00a0Un sospechoso del tiroteo que hiri\u00f3 al menos a nueve personas en un \u00e1rea recreativa en Rochester Hills, Michigan, este s\u00e1bado fue encontrado muerto en una casa cercana, dijo el sheriff del condado de Oakland, Michael Bouchard.El sospechoso, un hombre de 42 a\u00f1os cuyo nombre a\u00fan no ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466123,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/03\/nino-11-anos-houston-veterano-ejercito-trax\/","url_meta":{"origin":1473811,"position":5},"title":"Sospechoso del tiroteo mortal de un ni\u00f1o de 11 a\u00f1os por broma de &#171;tocar y correr&#187; es un veterano del Ej\u00e9rcito de EE.UU.","author":"","date":"septiembre 3, 2025","format":false,"excerpt":"Juli\u00e1n Guzm\u00e1n, de 11 a\u00f1os, y su primo estaban en una fiesta familiar el s\u00e1bado por la noche cuando decidieron salir solos.Lo que comenz\u00f3 como una diversi\u00f3n inocente pronto tuvo un desenlace devastador.Salieron a las calles de su vecindario en el este de Houston para jugar una broma cl\u00e1sica: tocar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473811"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473811\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}