{"id":1444324,"date":"2024-01-23T16:33:39","date_gmt":"2024-01-24T00:33:39","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444324"},"modified":"2024-01-23T16:33:39","modified_gmt":"2024-01-24T00:33:39","slug":"la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/","title":{"rendered":"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 El fiscal general de Venezuela, Tarek William Saab, anunci\u00f3 este lunes varias \u00f3rdenes de captura contra una periodista, oficiales retirados de las Fuerzas Armadas del pa\u00eds y defensores de derechos humanos quienes, seg\u00fan dijo en una rueda de prensa, estar\u00edan involucrados en un complot para matar al presidente Nicol\u00e1s Maduro y al gobernador del estado T\u00e1chira (fronterizo con Colombia), Freddy Bernal.<\/p>\n<p>Sin presentar pruebas, Saab mencion\u00f3 a la reportera Sebastiana Barr\u00e1ez, quien cubre temas militares y que actualmente escribe en el portal Infobae, a la abogada defensora de los derechos humanos Tamara Suj\u00fa, dos exoficiales de la Fuerza Armada Nacional Bolivariana y dos trabajadores de redes sociales.<\/p>\n<p>Barr\u00e1ez reaccion\u00f3 a trav\u00e9s de la red X asegurando que ha sido ligada a un acto que ella jam\u00e1s compartir\u00eda porque no cree en actos violentos y en su lugar cree en la vida y en la justicia de Dios.<\/p>\n<p>Infobae reaccion\u00f3 a la orden de aprehensi\u00f3n contra Barr\u00e1ez en respuesta a CNN asegurando que \u201cel r\u00e9gimen de Maduro est\u00e1 obsesionado con Infobae\u201d. Se\u00f1alan que han estado \u201ccensurados y bloqueados desde hace 3.400 d\u00edas, desde el 10 de octubre de 2014\u201d y que \u201ccontinuamente nombran y descalifican a sus periodistas por contar lo que ocurre en Venezuela\u201d. Al referir espec\u00edficamente el caso de Sebastiana Barr\u00e1ez precisaron que incluso hace un tiempo tuvieron que sacarla del pa\u00eds por considerar que \u201csu integridad corr\u00eda riesgo\u201d. La empresa a\u00f1adi\u00f3 que, a su juicio, Sebastiana es una excelente profesional, de su absoluta confianza y que seguir\u00e1 respald\u00e1ndola.<\/p>\n<p>CNN est\u00e1 buscando las reacciones de las otras personas solicitadas.<\/p>\n<p>Por su parte, Suj\u00fa dijo a CNN que es inocente y que no nombrar\u00e1 a un abogado defensor porque considera que \u201cVenezuela es una dictadura sin Estado de Derecho\u201d.<\/p>\n<p>La abogada agreg\u00f3 que esta acci\u00f3n es una represalia por las \u201cdecenas de casos de cr\u00edmenes de lesa humanidad\u201d que, como defensora de derechos humanos, ha llevado a la Corte Penal Internacional.<\/p>\n<p>En su cuenta de Twitter, Suj\u00fa afirm\u00f3 que el fiscal general, a quien llam\u00f3 \u201cfiscal de la dictadura\u201d, a su juicio \u201ccontin\u00faa criminalizando el trabajo de los abogados y defensores de DD.HH.\u201d. Destaca que sigue teniendo como mejores fuentes a familiares y a funcionarios, que, seg\u00fan escribi\u00f3, est\u00e1n \u201chartos de ver c\u00f3mo siguen cometi\u00e9ndose cr\u00edmenes de lesa humanidad\u201d.<\/p>\n<p>Saab hizo estos se\u00f1alamientos al presentar casos de \u201cconspiraciones contra el Estado venezolano\u201d que, dice, fueron identificados por los cuerpos de seguridad y el Ministerio P\u00fablico en el marco de una operaci\u00f3n denominada Brazalete Blanco, y que, seg\u00fan el m\u00e1ximo representante del Ministerio P\u00fablico venezolano, tendr\u00eda como objetivo el homicidio del presidente de Venezuela, Nicol\u00e1s Maduro, y del gobernador del estado T\u00e1chira, Freddy Bernal.<\/p>\n<p>Saab difundi\u00f3 videos de dos militares detenidos, uno de ellos, seg\u00fan se\u00f1ala Saab, ejerc\u00eda funciones como encargado de la seguridad de la Vi\u00f1eta, donde se ubica la actual residencia presidencial en Fuerte Tiuna, instalaci\u00f3n militar en la que se encuentra el Ministerio de la Defensa, ofreciendo detalles sobre los supuestos planes conspirativos.<\/p>\n<p>CNN no ha podido validar de forma independiente c\u00f3mo tuvieron lugar estos interrogatorios o si estos se realizaron en presencia de un abogado.<\/p>\n<p>Seg\u00fan Saab, las personas se\u00f1aladas ser\u00e1n investigadas por traici\u00f3n a la patria, homicidio intencional calificado en grado de tentativa en la persona del presidente de la Rep\u00fablica, homicidio intencional calificado en grado de tentativa en la persona del gobernador del estado T\u00e1chira, terrorismo y asociaci\u00f3n para delinquir.<\/p>\n<p>El Colegio Nacional de Periodistas asegur\u00f3 en X que el Gobierno \u201crepite el libreto para criminalizar el ejercicio period\u00edstico\u201d.<\/p>\n<p>Mientras, el Sindicato Nacional de Trabajadores de la Prensa tambi\u00e9n se pronunci\u00f3 en X para rechazar lo que calificaron como la \u201ccriminalizaci\u00f3n de la periodista Sebastiana Barr\u00e1ez\u201d. La organizaci\u00f3n agreg\u00f3 que el sometimiento a la persecuci\u00f3n judicial es una medida que busca generar censura y atentar contra la libertad e integridad de la periodista.<\/p>\n<p>Con frecuencia Maduro ha hecho referencia a planes conspirativos en su contra, la menci\u00f3n m\u00e1s reciente durante su discurso anual a la naci\u00f3n, en la cual asegur\u00f3 que en 2023 fueron desmantelados al menos tres complots.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 El fiscal general de Venezuela, Tarek William Saab, anunci\u00f3 este lunes varias \u00f3rdenes de captura contra una periodista, oficiales retirados de las Fuerzas Armadas del pa\u00eds y defensores de derechos humanos quienes, seg\u00fan dijo en una rueda de prensa, estar\u00edan involucrados en un complot para matar al presidente Nicol\u00e1s Maduro y al [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444324","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2013\u2013 El fiscal general de Venezuela, Tarek William Saab, anunci\u00f3 este lunes varias \u00f3rdenes de captura contra una periodista, oficiales retirados de las Fuerzas Armadas del pa\u00eds y defensores de derechos humanos quienes, seg\u00fan dijo en una rueda de prensa, estar\u00edan involucrados en un complot para matar al presidente Nicol\u00e1s Maduro y al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-24T00:33:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista\",\"datePublished\":\"2024-01-24T00:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/\"},\"wordCount\":770,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/\",\"name\":\"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-24T00:33:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/","og_locale":"es_ES","og_type":"article","og_title":"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista - Noticias","og_description":"(CNN Espa\u00f1ol) \u2013\u2013 El fiscal general de Venezuela, Tarek William Saab, anunci\u00f3 este lunes varias \u00f3rdenes de captura contra una periodista, oficiales retirados de las Fuerzas Armadas del pa\u00eds y defensores de derechos humanos quienes, seg\u00fan dijo en una rueda de prensa, estar\u00edan involucrados en un complot para matar al presidente Nicol\u00e1s Maduro y al [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/","og_site_name":"Noticias","article_published_time":"2024-01-24T00:33:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/"},"author":{"name":"","@id":""},"headline":"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista","datePublished":"2024-01-24T00:33:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/"},"wordCount":770,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/","name":"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-24T00:33:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Fiscal\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/23\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-24T00:33:39Z","datePublished":"2024-01-24T00:33:39Z","dateModified":"2024-01-24T00:33:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Fiscal\\u00eda de Venezuela asegura, sin presentar pruebas, que descubri\\u00f3 un complot para asesinar a Maduro y a un gobernador oficialista\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/23\\\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/23\\\/la-fiscalia-de-venezuela-asegura-sin-presentar-pruebas-que-descubrio-un-complot-para-asesinar-a-maduro-y-a-un-gobernador-oficialista\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-24T00:33:39Z\",\"datePublished\":\"2024-01-24T00:33:39Z\",\"dateModified\":\"2024-01-24T00:33:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471790,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/03\/02\/quien-es-tarek-william-saab-por-que-dejo-fiscal-delcy-orix\/","url_meta":{"origin":1444324,"position":0},"title":"\u00bfQu\u00e9 hay detr\u00e1s de la salida de Tarek William Saab y de los cambios en el Gabinete de Delcy Rodr\u00edguez?","author":"","date":"marzo 2, 2026","format":false,"excerpt":"Al presentar su renuncia como fiscal general de Venezuela, un cargo que ocup\u00f3 por casi 10 a\u00f1os, Tarek William Saab fue nombrado de inmediato como defensor del pueblo encargado. Ese cargo, seg\u00fan analistas consultados por CNN, representa un cambio significativo: aunque tiene menor visibilidad p\u00fablica que en su posici\u00f3n anterior,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445885,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/21\/fiscal-de-venezuela-acusa-a-la-activista-rocio-san-miguel-de-entregar-informacion-sensible-a-diplomaticos-extranjeros\/","url_meta":{"origin":1444324,"position":1},"title":"Fiscal de Venezuela acusa a la activista Roc\u00edo San Miguel de entregar informaci\u00f3n sensible a diplom\u00e1ticos extranjeros","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El fiscal general de Venezuela, Tarek William Saab, acus\u00f3 este lunes a Roc\u00edo San Miguel, activista detenida desde el pasado 8 de febrero por cargos de supuesta traici\u00f3n y conspiraci\u00f3n, de entregar informaci\u00f3n sensible a diplom\u00e1ticos de cuatro pa\u00edses extranjeros.En una rueda de prensa, Saab dijo, sin presentar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455057,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/10\/12\/maduro-presunto-complot-detenidos-eeuu-venezuela-trax\/","url_meta":{"origin":1444324,"position":2},"title":"AN\u00c1LISIS | La CIA, un infante de Marina y una recompensa de US$ 15 millones. Este presunto complot contra Maduro parece un guion de Hollywood, por una raz\u00f3n","author":"","date":"octubre 12, 2024","format":false,"excerpt":"(CNN) --\u00a0Era la historia inspiradora perfecta, justo a tiempo para Navidad.El 20 de diciembre del a\u00f1o pasado, Estados Unidos asegur\u00f3 la liberaci\u00f3n de 10 ciudadanos estadounidenses en Venezuela, seis de ellos detenidos injustamente, a cambio de un aliado cercano del presidente autoritario Nicol\u00e1s Maduro y un compromiso de Caracas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471649,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/25\/tarek-william-saab-alfredo-ruiz-angulo-renuncias-orix\/","url_meta":{"origin":1444324,"position":3},"title":"Tarek William Saab renuncia como fiscal de Venezuela y asume como defensor del Pueblo encargado","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Tarek William Saab y Alfredo Jos\u00e9 Ruiz Angulo renunciaron este mi\u00e9rcoles a sus cargos como fiscal general y defensor del Pueblo en Venezuela, respectivamente, inform\u00f3 el presidente de la Asamblea Nacional, Jorge Rodr\u00edguez.Durante la sesi\u00f3n del \u00f3rgano legislativo, Rodr\u00edguez ley\u00f3 ambas cartas de renuncia.En la suya, Ruiz Angulo dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456582,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","url_meta":{"origin":1444324,"position":4},"title":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"El Alto Comisionado para los Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU), Volker T\u00fcrk, dijo estar \u201cprofundamente preocupado\u201d por la situaci\u00f3n pol\u00edtica en Venezuela, a cuatro meses y medio de las controvertidas elecciones presidenciales del 28 de julio y a menos de un mes del comienzo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452761,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/09\/17\/venezuela-informe-onu-violaciones-derechos-humanos-orix\/","url_meta":{"origin":1444324,"position":5},"title":"La represi\u00f3n ordenada por Maduro tras las elecciones en Venezuela podr\u00eda constituir cr\u00edmenes contra la humanidad, seg\u00fan un informe de la ONU","author":"","date":"septiembre 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un nuevo informe de la Misi\u00f3n Internacional Independiente de Determinaci\u00f3n de los Hechos de la ONU sobre la Rep\u00fablica Bolivariana de Venezuela afirma que la represi\u00f3n ordenada por el Gobierno del presidente Nicol\u00e1s Maduro entre el 1 de septiembre de 2023 y el 31 de agosto de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1444324"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444324\/revisions"}],"predecessor-version":[{"id":1444339,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444324\/revisions\/1444339"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1444324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1444324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1444324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}