{"id":1444346,"date":"2024-01-24T03:33:41","date_gmt":"2024-01-24T11:33:41","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444346"},"modified":"2024-01-24T03:33:41","modified_gmt":"2024-01-24T11:33:41","slug":"retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/","title":{"rendered":"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 El inicio del juicio en Estados Unidos contra Juan Orlando Hern\u00e1ndez, expresidente de Honduras y acusado de conspiraci\u00f3n para traficar drogas y otros delitos, se pospuso para el pr\u00f3ximo 12 de febrero, dijo a CNN el abogado C\u00e9sar de Castro, asesor legal de Juan Carlos Bonilla Valladares, otro de los implicados en el caso.<\/p>\n<p>La decisi\u00f3n la tom\u00f3 el juez P. Kevin Castel en una audiencia realizada este martes en la Corte del Distrito Sur de Nueva York. Una de las razones por las que el juez dict\u00f3 el aplazamiento fue que otro de los coacusados, Mauricio Hern\u00e1ndez Pineda, present\u00f3 una moci\u00f3n para ser juzgado por separado, explic\u00f3 De Castro.<\/p>\n<p>El expresidente Juan Orlando Hern\u00e1ndez se declara inocente de cargos de narcotr\u00e1fico en EE.UU.<\/p>\n<p>Juan Orlando Hern\u00e1ndez, Juan Carlos Bonilla Valladares y Mauricio Hern\u00e1ndez Pineda est\u00e1n acusados de los mismos delitos dentro de este caso: conspiraci\u00f3n para importar coca\u00edna a EE.UU., conspiraci\u00f3n para poseer armas de fuego y dispositivos destructivos, y posesi\u00f3n de ese tipo de armamento.<\/p>\n<p>En la audiencia de este martes, tambi\u00e9n se autoriz\u00f3 que el expresidente Juan Orlando Hern\u00e1ndez tenga acceso a una computadora port\u00e1til sin internet para que pueda revisar documentos judiciales mientras se encuentra bajo arresto en un centro de detenci\u00f3n de Brooklyn, de acuerdo con una orden del juez.<\/p>\n<p>Adem\u00e1s, se inform\u00f3 que el exmandatario sum\u00f3 a otro abogado a su equipo legal encabezado por Raymond L. Col\u00f3n. El jurista que se integra al grupo es Renato Stabile.<\/p>\n<p>El expresidente de Honduras fue detenido en su pa\u00eds en febrero de 2022. Fue extraditado a EE.UU. en abril, donde un mes despu\u00e9s se declar\u00f3 inocente de los cargos que se le atribuyen.<\/p>\n<p>Bonilla Valladares y Hern\u00e1ndez Pineda tambi\u00e9n dicen ser inocentes de los delitos de los que se les acusa.<\/p>\n<p>Mar\u00eda Santana contribuy\u00f3 con este reporte.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 El inicio del juicio en Estados Unidos contra Juan Orlando Hern\u00e1ndez, expresidente de Honduras y acusado de conspiraci\u00f3n para traficar drogas y otros delitos, se pospuso para el pr\u00f3ximo 12 de febrero, dijo a CNN el abogado C\u00e9sar de Castro, asesor legal de Juan Carlos Bonilla Valladares, otro de los implicados en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444346","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2013\u2013 El inicio del juicio en Estados Unidos contra Juan Orlando Hern\u00e1ndez, expresidente de Honduras y acusado de conspiraci\u00f3n para traficar drogas y otros delitos, se pospuso para el pr\u00f3ximo 12 de febrero, dijo a CNN el abogado C\u00e9sar de Castro, asesor legal de Juan Carlos Bonilla Valladares, otro de los implicados en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-24T11:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero\",\"datePublished\":\"2024-01-24T11:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/\",\"name\":\"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-24T11:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/","og_locale":"es_ES","og_type":"article","og_title":"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero - Noticias","og_description":"(CNN Espa\u00f1ol) \u2013\u2013 El inicio del juicio en Estados Unidos contra Juan Orlando Hern\u00e1ndez, expresidente de Honduras y acusado de conspiraci\u00f3n para traficar drogas y otros delitos, se pospuso para el pr\u00f3ximo 12 de febrero, dijo a CNN el abogado C\u00e9sar de Castro, asesor legal de Juan Carlos Bonilla Valladares, otro de los implicados en [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/","og_site_name":"Noticias","article_published_time":"2024-01-24T11:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/"},"author":{"name":"","@id":""},"headline":"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero","datePublished":"2024-01-24T11:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/","name":"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-24T11:33:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-24T11:33:41Z","datePublished":"2024-01-24T11:33:41Z","dateModified":"2024-01-24T11:33:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Retrasan juicio contra el expresidente Juan Orlando Hern\\u00e1ndez en EE.UU. y comenzar\\u00e1 el 12 de febrero\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/24\\\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/24\\\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-24T11:33:41Z\",\"datePublished\":\"2024-01-24T11:33:41Z\",\"dateModified\":\"2024-01-24T11:33:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445849,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/21\/juicio-expresidente-honduras-juan-orlando-hernandez-primera-testigo-orix\/","url_meta":{"origin":1444346,"position":0},"title":"Comenz\u00f3 el juicio contra el expresidente de Honduras Juan Orlando Hern\u00e1ndez: los abogados definieron qui\u00e9n ser\u00e1 la primera testigo","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Mientras seleccionaban este martes al jurado del juicio contra Juan Orlando Hern\u00e1ndez, expresidente de Honduras, por cargos de tr\u00e1fico de drogas y uso de armas, el tribunal, la fiscal\u00eda y la defensa del exmandatario definieron qui\u00e9n ser\u00e1 el primer testigo que llevar\u00e1n al estrado. Se trata de una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450723,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/26\/juan-orlando-hernandez-expresidente-honduras-ningun-remordimiento-inocente-condenado-45-anios-ee-uu-trax\/","url_meta":{"origin":1444346,"position":1},"title":"Juan Orlando Hern\u00e1ndez, expresidente de Honduras, dijo que no tiene ning\u00fan remordimiento y reiter\u00f3 ser inocente antes de ser condenado a 45 a\u00f1os en EE.UU.","author":"","date":"junio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u201cEs mi \u00fanica oportunidad, porque lo m\u00e1s seguro es que voy a estar preso de por vida\u201d, dijo el expresidente de Honduras Juan Orlando Hern\u00e1ndez al dar un extenso mensaje este mi\u00e9rcoles, antes de que un juez estadounidense lo sentenciara a 45 a\u00f1os de c\u00e1rcel luego de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450711,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/26\/juan-orlando-hernandez-expresidente-honduras-aguarda-sentencia-narcotrafico-orix\/","url_meta":{"origin":1444346,"position":2},"title":"El expresidente de Honduras Juan Orlando Hern\u00e1ndez aguarda sentencia por narcotr\u00e1fico. As\u00ed fue el juicio y la acusaci\u00f3n en una corte de EE.UU.","author":"","date":"junio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los hondure\u00f1os esperan atentos la condena por narcotr\u00e1fico contra el expresidente Juan Orlando Hern\u00e1ndez en el Tribunal Federal del Distrito Sur de Manhattan este mi\u00e9rcoles, en un hecho pol\u00edtico sin precedentes en la historia del pa\u00eds.Se espera que este mi\u00e9rcoles se conozca cu\u00e1ntos a\u00f1os deber\u00e1 pasar tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445810,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/21\/abogado-juan-orlando-hernandez-expresidente-honduras-hermano-condenado-narcotrafico-orix\/","url_meta":{"origin":1444346,"position":3},"title":"Abogado de Juan Orlando Hern\u00e1ndez desestima en su alegato inicial la relaci\u00f3n del expresidente de Honduras con su hermano, ya condenado por narcotr\u00e1fico","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El abogado de Juan Orlando Hern\u00e1ndez, expresidente de Honduras, desestim\u00f3 este mi\u00e9rcoles la relaci\u00f3n del exmandatario con su hermano Tony, quien ya ha sido condenado por cargos de narcotr\u00e1fico en Estados Unidos, durante sus alegatos iniciales en el juicio que Hern\u00e1ndez enfrenta por cargos de tr\u00e1fico de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446460,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/04\/hijo-expresidente-lobo-detalles-sobornos-juan-orlando-hernandez-orix\/","url_meta":{"origin":1444346,"position":4},"title":"Hijo del expresidente Lobo da m\u00e1s detalles de los supuestos sobornos que dice haberle pagado a Juan Orlando Hern\u00e1ndez","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Fabio Lobo, hijo del expresidente de Honduras Porfirio Lobo, ampli\u00f3 este viernes detalles de los supuestos sobornos que dice haberle pagado a Juan Orlando Hern\u00e1ndez, quien sucedi\u00f3 a su padre en el gobierno del pa\u00eds centroamericano.Despu\u00e9s de su impactante aparici\u00f3n el jueves en el juicio que Hern\u00e1ndez enfrenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446059,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/27\/juan-orlando-hernandez-cachiros-lider-pago-hermana-orix\/","url_meta":{"origin":1444346,"position":5},"title":"Juicio a Juan Orlando Hern\u00e1ndez: un exl\u00edder del cartel Los Cachiros asegura que pag\u00f3 US$ 250.000 a la hermana del expresidente para la campa\u00f1a presidencial","author":"","date":"febrero 27, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Un exl\u00edder del cartel hondure\u00f1o Los Cachiros, Devis Leonel Rivera Maradiaga, dijo este martes que entreg\u00f3 US$ 250.000 para la campa\u00f1a presidencial de Juan Orlando Hern\u00e1ndez, en una nueva declaraci\u00f3n que apunta al entorno cercano del expresidente de Honduras en el juicio que se realiza en Nueva York\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1444346"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444346\/revisions"}],"predecessor-version":[{"id":1444363,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444346\/revisions\/1444363"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1444346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1444346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1444346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}