{"id":1444428,"date":"2024-01-25T19:33:36","date_gmt":"2024-01-26T03:33:36","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444428"},"modified":"2024-01-25T19:33:36","modified_gmt":"2024-01-26T03:33:36","slug":"guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/","title":{"rendered":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s"},"content":{"rendered":"<p>\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed<\/p>\n<p>Una fotograf\u00eda tomada desde el sur de Israel, en la frontera con Gaza, muestra humo ondeando sobre el territorio palestino durante bombardeo israel\u00ed el 25 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo militante Hamas. (Cr\u00e9dito: JACK GUEZ\/AFP v\u00eda Getty Images)<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Una fotograf\u00eda tomada desde el sur de Israel, en la frontera con Gaza, muestra humo ondeando sobre el territorio palestino durante bombardeo israel\u00ed el 25 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo militante Hamas. (Cr\u00e9dito: JACK [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444428","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s - Noticias\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Una fotograf\u00eda tomada desde el sur de Israel, en la frontera con Gaza, muestra humo ondeando sobre el territorio palestino durante bombardeo israel\u00ed el 25 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo militante Hamas. (Cr\u00e9dito: JACK [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T03:33:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s\",\"datePublished\":\"2024-01-26T03:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/\"},\"wordCount\":90,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/\",\"name\":\"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-26T03:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/","og_locale":"es_ES","og_type":"article","og_title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s - Noticias","og_description":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed Una fotograf\u00eda tomada desde el sur de Israel, en la frontera con Gaza, muestra humo ondeando sobre el territorio palestino durante bombardeo israel\u00ed el 25 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo militante Hamas. (Cr\u00e9dito: JACK [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/","og_site_name":"Noticias","article_published_time":"2024-01-26T03:33:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/"},"author":{"name":"","@id":""},"headline":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","datePublished":"2024-01-26T03:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/"},"wordCount":90,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/","name":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-26T03:33:36+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-26T03:33:36Z","datePublished":"2024-01-26T03:33:36Z","dateModified":"2024-01-26T03:33:36Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\\u00e1s\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/25\\\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/25\\\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-26T03:33:36Z\",\"datePublished\":\"2024-01-26T03:33:36Z\",\"dateModified\":\"2024-01-26T03:33:36Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444419,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-23\/","url_meta":{"origin":1444428,"position":0},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 25, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edUna fotograf\u00eda tomada desde el sur de Israel, en la frontera con Gaza, muestra humo ondeando sobre el territorio palestino durante bombardeo israel\u00ed el 25 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444430,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-25\/","url_meta":{"origin":1444428,"position":1},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 25, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edUna fotograf\u00eda tomada desde el sur de Israel, en la frontera con Gaza, muestra humo ondeando sobre el territorio palestino durante bombardeo israel\u00ed el 25 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444709,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/31\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-53\/","url_meta":{"origin":1444428,"position":2},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 31, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Una columna de humo estalla durante el bombardeo israel\u00ed en Khan Yunis desde Rafah, en el sur de la Franja de Gaza, el 30 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo militante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444684,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/31\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-52\/","url_meta":{"origin":1444428,"position":3},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 31, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Los combatientes levantan banderas de Iraq y de grupos paramilitares, incluidos al-Nujaba y Kataib Hezbollah, durante un funeral en Bagdad por cinco militantes asesinados un d\u00eda antes en un ataque estadounidense en el norte de Iraq, el 4 de diciembre de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449446,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/14\/ultima-hora-guerra-israel-hamas-gaza-en-vivo-orix-3\/","url_meta":{"origin":1444428,"position":4},"title":"\u00daltima hora de la guerra entre Israel y Hamas, en vivo: noticias, situaci\u00f3n en Gaza y m\u00e1s","author":"","date":"mayo 14, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las entradas m\u00e1s recientes haz clic aqu\u00edEl humo se eleva durante los ataques israel\u00edes en el este de Rafah, en el sur de Gaza, el 13 de mayo de 2024, en medio del conflicto en curso entre Israel y el grupo militante palestino Hamas. (Cr\u00e9dito: Stringer\/AFP\/Getty Images).The-CNN-Wire\u2122\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444315,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/23\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-12\/","url_meta":{"origin":1444428,"position":5},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 23, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edSoldados israel\u00edes cargan el at\u00fad de un colega asesinado en combate en Gaza, el 23 de enero de 2024. (Cr\u00e9dito: MENAHEM KAHANA\/AFP via Getty Images)The-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1444428"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444428\/revisions"}],"predecessor-version":[{"id":1444444,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444428\/revisions\/1444444"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1444428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1444428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1444428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}