{"id":1444431,"date":"2024-01-25T21:33:39","date_gmt":"2024-01-26T05:33:39","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444431"},"modified":"2024-01-25T21:33:39","modified_gmt":"2024-01-26T05:33:39","slug":"las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/","title":{"rendered":"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes"},"content":{"rendered":"<p>(CNN) &#8212; Las acciones de Tesla se desplomaron hasta un 11% despu\u00e9s de la apertura del mercado el jueves, eliminando US$ 73.000 millones del valor de mercado de la compa\u00f1\u00eda horas despu\u00e9s de que advirtiera sobre la desaceleraci\u00f3n del crecimiento en las ventas de autom\u00f3viles el\u00e9ctricos y una amenaza de la competencia china.<\/p>\n<p>En una presentaci\u00f3n de resultados el mi\u00e9rcoles, el fabricante de autom\u00f3viles m\u00e1s valioso del mundo dijo que el crecimiento de sus ventas este a\u00f1o &#171;puede ser notablemente menor&#187; que el anterior mientras contin\u00faa desarrollando el veh\u00edculo de &#171;pr\u00f3xima generaci\u00f3n&#187;, probablemente un modelo de menor precio.<\/p>\n<p>Si bien inform\u00f3 un aumento considerable del 38% en las entregas el a\u00f1o pasado en comparaci\u00f3n con 2022, Tesla apunt\u00f3 previamente a una tasa de crecimiento anual del 50% promediada durante varios a\u00f1os.<\/p>\n<p>Los resultados financieros de Tesla para el \u00faltimo trimestre tambi\u00e9n decepcionaron, con ganancias ajustadas por acci\u00f3n que cayeron un 40% respecto al a\u00f1o anterior, y los ingresos, que aumentaron un 3% hasta superar los US$ 25.000 millones, quedaron por debajo de las previsiones del mercado.<\/p>\n<p>Fue el segundo trimestre consecutivo en el que la compa\u00f1\u00eda no alcanz\u00f3 las ganancias previstas por los analistas, luego de una serie de resultados mejores de lo esperado que se remontan a principios de 2021.<\/p>\n<p>El precio de las acciones duplic\u00f3 durante el transcurso de 2023, pero esas ganancias se produjeron durante la primera mitad del a\u00f1o y las acciones de Tesla tuvieron un comienzo d\u00e9bil en 2024, cayendo un 16% antes del informe de ganancias del mi\u00e9rcoles. La acci\u00f3n se cotiza actualmente a su nivel m\u00e1s bajo desde abril del a\u00f1o pasado.<\/p>\n<p>Las p\u00e9rdidas intrad\u00eda del jueves fueron comparables a una ca\u00edda inusualmente grande en un d\u00eda del 11,4% a finales de diciembre de 2022. En ese momento, los inversores estaban preocupados por las perspectivas de las ventas y la rentabilidad de Tesla, as\u00ed como por la salud de la econom\u00eda estadounidense.<\/p>\n<p>Las ganancias del cuarto trimestre de Tesla tambi\u00e9n revelaron ganancias bajo presi\u00f3n. El margen operativo de la empresa se redujo casi a la mitad, hasta el 8,2%, respecto al mismo per\u00edodo de 2022, impulsado en parte por un incremento de los costos relacionados con la producci\u00f3n de la camioneta Cybertruck. El nuevo modelo entr\u00f3 en producci\u00f3n a finales de 2023.<\/p>\n<p>Dan Ives, analista de la firma de investigaci\u00f3n de mercado Wedbush, dijo que la convocatoria de resultados de Tesla proporcion\u00f3 a los inversores &#171;respuestas m\u00ednimas&#187; a los m\u00e1rgenes cada vez m\u00e1s reducidos de la empresa.<\/p>\n<p>&#171;Est\u00e1bamos completamente equivocados al esperar que Musk y su equipo dieran un paso al frente como adultos en la sala y dieran una visi\u00f3n estrat\u00e9gica y financiera de los continuos recortes de precios, la estructura de m\u00e1rgenes y la demanda fluctuante&#187;, escribi\u00f3 en una nota el jueves.<\/p>\n<p>Amenaza de China<\/p>\n<p>Tesla ha recortado precios durante m\u00e1s de un a\u00f1o en un esfuerzo por impulsar las ventas al tiempo que enfrenta una competencia cada vez m\u00e1s intensa de sus rivales en China.<\/p>\n<p>BYD de China venci\u00f3 a Tesla en los \u00faltimos tres meses del a\u00f1o pasado, vendiendo m\u00e1s autos que el fabricante de autom\u00f3viles de Elon Musk por primera vez.<\/p>\n<p>Musk dijo a los analistas en la entrega de resultados del mi\u00e9rcoles que los fabricantes de autom\u00f3viles chinos eran &#171;las compa\u00f1\u00edas automotrices m\u00e1s competitivas del mundo&#187; y &#171;tendr\u00e1n un \u00e9xito significativo fuera de China&#187;.<\/p>\n<p>AN\u00c1LISIS | M\u00e9xico podr\u00eda ayudar a BYD, un gigante de los autos en China, a abrirse paso en el mercado de EE.UU.<\/p>\n<p>&#171;Francamente, creo que si no se establecen barreras comerciales, pr\u00e1cticamente demoler\u00e1n a la mayor\u00eda de las dem\u00e1s empresas automovil\u00edsticas del mundo&#187;, afirm\u00f3.<\/p>\n<p>La creciente competencia de BYD y otros fabricantes de autom\u00f3viles chinos caus\u00f3 una investigaci\u00f3n antidumping por parte de funcionarios europeos, que podr\u00eda llevar a la imposici\u00f3n de aranceles m\u00e1s altos a las importaciones de autom\u00f3viles de China. El dumping se refiere a la pr\u00e1ctica de exportar bienes a un pa\u00eds a precios que no reflejan su costo.<\/p>\n<p>\u00bfInter\u00e9s en comprar?<\/p>\n<p>Si bien las ganancias de Tesla fueron &#171;decepcionantes y poco caracter\u00edsticas&#187;, Garrett Nelson, analista senior de acciones de CFRA Research, espera que el lanzamiento de su veh\u00edculo de menor costo en los pr\u00f3ximos a\u00f1os proporcione &#171;el catalizador que las acciones necesitan&#187;, escribi\u00f3 en una nota este mi\u00e9rcoles.<\/p>\n<p>Ben Barringer, analista tecnol\u00f3gico de Quilter Cheviot, tambi\u00e9n se muestra optimista. Considera que el entorno econ\u00f3mico m\u00e1s amplio empieza a inclinarse a favor de Tesla.<\/p>\n<p>\u201cLas tasas de inter\u00e9s comenzar\u00e1n a bajar. Esto ser\u00e1 realmente positivo para Tesla, as\u00ed como para el sector automotriz en general, ya que los consumidores tienden a comprar sus veh\u00edculos con financiamiento\u201d, escribi\u00f3 en una nota el jueves.<\/p>\n<p>Chris Isidore contribuy\u00f3 con el reportaje.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Las acciones de Tesla se desplomaron hasta un 11% despu\u00e9s de la apertura del mercado el jueves, eliminando US$ 73.000 millones del valor de mercado de la compa\u00f1\u00eda horas despu\u00e9s de que advirtiera sobre la desaceleraci\u00f3n del crecimiento en las ventas de autom\u00f3viles el\u00e9ctricos y una amenaza de la competencia china. En una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444431","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Las acciones de Tesla se desplomaron hasta un 11% despu\u00e9s de la apertura del mercado el jueves, eliminando US$ 73.000 millones del valor de mercado de la compa\u00f1\u00eda horas despu\u00e9s de que advirtiera sobre la desaceleraci\u00f3n del crecimiento en las ventas de autom\u00f3viles el\u00e9ctricos y una amenaza de la competencia china. En una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T05:33:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes\",\"datePublished\":\"2024-01-26T05:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/\"},\"wordCount\":879,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/\",\"name\":\"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-26T05:33:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/","og_locale":"es_ES","og_type":"article","og_title":"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes - Noticias","og_description":"(CNN) &#8212; Las acciones de Tesla se desplomaron hasta un 11% despu\u00e9s de la apertura del mercado el jueves, eliminando US$ 73.000 millones del valor de mercado de la compa\u00f1\u00eda horas despu\u00e9s de que advirtiera sobre la desaceleraci\u00f3n del crecimiento en las ventas de autom\u00f3viles el\u00e9ctricos y una amenaza de la competencia china. En una [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/","og_site_name":"Noticias","article_published_time":"2024-01-26T05:33:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/"},"author":{"name":"","@id":""},"headline":"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes","datePublished":"2024-01-26T05:33:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/"},"wordCount":879,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/","name":"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-26T05:33:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-26T05:33:39Z","datePublished":"2024-01-26T05:33:39Z","dateModified":"2024-01-26T05:33:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las acciones de Tesla se desploman y arrasan con un valor de mercado de US$ 73.000 millones, tras resultados decepcionantes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/25\\\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/25\\\/las-acciones-de-tesla-se-desploman-y-arrasan-con-un-valor-de-mercado-de-us-73-000-millones-tras-resultados-decepcionantes\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-26T05:33:39Z\",\"datePublished\":\"2024-01-26T05:33:39Z\",\"dateModified\":\"2024-01-26T05:33:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460746,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/02\/tesla-ventas-desploman-caida-trax\/","url_meta":{"origin":1444431,"position":0},"title":"Las ventas de Tesla se desploman: la empresa registra la mayor ca\u00edda de su historia","author":"","date":"abril 2, 2025","format":false,"excerpt":"Las ventas de Tesla se desplomaron un 13% en los tres primeros meses de este a\u00f1o, en medio de reacciones negativas contra el CEO Elon Musk y de la creciente competencia de veh\u00edculos el\u00e9ctricos de otros fabricantes.Tesla inform\u00f3 que entreg\u00f3 336.681 autos en el primer trimestre de 2025, en comparaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457957,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/28\/tesla-acciones-musk-trax\/","url_meta":{"origin":1444431,"position":1},"title":"Tesla acaba de tener su peor a\u00f1o en ventas, pero las acciones han tenido una gran racha","author":"","date":"enero 28, 2025","format":false,"excerpt":"Tesla probablemente reportar\u00e1 m\u00e1rgenes de ganancia m\u00e1s estrechos en sus resultados trimestrales y anuales este mi\u00e9rcoles, como resultado de su primera ca\u00edda en las ventas anuales en su historia en 2024 y una guerra de precios en el sector de veh\u00edculos el\u00e9ctricos debido a la creciente competencia. Pero los grandes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459205,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/02\/25\/elon-musk-perdio-52000-millones-hombre-mas-rico-trax\/","url_meta":{"origin":1444431,"position":2},"title":"Elon Musk perdi\u00f3 US$ 52.000 millones de patrimonio neto este a\u00f1o y sigue siendo la persona m\u00e1s rica del mundo","author":"","date":"febrero 25, 2025","format":false,"excerpt":"Elon Musk perdi\u00f3 US$ 52.000 millones en patrimonio neto desde que comenz\u00f3 el a\u00f1o, pero sigue siendo la persona m\u00e1s rica del mundo por un amplio margen, seg\u00fan el \u00cdndice de Multimillonarios de Bloomberg.Las acciones de Tesla de Musk cayeron un 8% antes del cierre del mercado este martes, despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447663,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/02\/ventas-tesla-caen-esperado-trax\/","url_meta":{"origin":1444431,"position":3},"title":"Las ventas de Tesla caen mucho m\u00e1s de lo esperado","author":"","date":"abril 2, 2024","format":false,"excerpt":"(CNN) -- Tesla registr\u00f3 su primera ca\u00edda anual en ventas desde la pandemia mientras enfrenta una mayor competencia de veh\u00edculos el\u00e9ctricos por parte de los fabricantes de autom\u00f3viles chinos y occidentales, lo que gener\u00f3 una disminuci\u00f3n en la demanda de la marca.La compa\u00f1\u00eda de autom\u00f3viles el\u00e9ctricos, cuyo CEO es Elon\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467064,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/10\/02\/ventas-tesla-record-riqueza-musk-trax\/","url_meta":{"origin":1444431,"position":4},"title":"Las ventas de Tesla alcanzaron un r\u00e9cord en el tercer trimestre y aumentaron la riqueza de Musk","author":"","date":"octubre 2, 2025","format":false,"excerpt":"Las ventas de Tesla se dispararon a un nivel r\u00e9cord en el tercer trimestre, ya que los compradores estadounidenses se apresuraron a adquirir sus autos antes de que expirara, el 30 de septiembre, un cr\u00e9dito fiscal federal de US$ 7.500.La compa\u00f1\u00eda vendi\u00f3 un r\u00e9cord de 497.099 veh\u00edculos en todo el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447827,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/07\/pasando-tesla-elon-musk-trax\/","url_meta":{"origin":1444431,"position":5},"title":"\u00bfQu\u00e9 ocurre con Tesla y el d\u00e9bil desempe\u00f1o en el \u00faltimo trimestre?","author":"","date":"abril 7, 2024","format":false,"excerpt":"(CNN) -- Tesla registr\u00f3 su primera ca\u00edda anual en las ventas desde la pandemia el trimestre pasado, un declive que fue peor de lo esperado. La compa\u00f1\u00eda culp\u00f3 a la d\u00e9bil econom\u00eda china, al incendio provocado en su f\u00e1brica alemana y a las limitaciones de suministro debido a la escalada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1444431"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444431\/revisions"}],"predecessor-version":[{"id":1444448,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444431\/revisions\/1444448"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1444431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1444431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1444431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}