{"id":1444445,"date":"2024-01-26T04:33:38","date_gmt":"2024-01-26T12:33:38","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444445"},"modified":"2024-01-26T04:33:38","modified_gmt":"2024-01-26T12:33:38","slug":"quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/","title":{"rendered":"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Alabama ejecut\u00f3 este jueves a Kenneth Smith,\u00a0condenado a muerte por un asesinato en 1988, con el m\u00e9todo de\u00a0hipoxia de nitr\u00f3geno.\u00a0Esta es la primera vez en Estados Unidos que una ejecuci\u00f3n se realiza con el procedimiento de gas nitr\u00f3geno.<\/p>\n<p>Ejecutan a Kenneth Smith en Alabama, el primero en morir por gas nitr\u00f3geno<\/p>\n<p>El recluso Kenneth Smith se convirti\u00f3 en la primera persona que fue ejecutada mediante el m\u00e9todo de hipoxia de nitr\u00f3geno, que ha sido objeto de cr\u00edticas debido a que Alabama ha ocultado detalles clave sobre c\u00f3mo funciona.<\/p>\n<p>Smith y sus abogados, junto con expertos de Estados Unidos y hasta de la ONU, cuestionaron si las posibles complicaciones del procedimiento con gas nitr\u00f3geno podr\u00edan provocar dolor excesivo o incluso tortura para el recluso, quien anteriormente hab\u00eda pedido su ejecuci\u00f3n con este m\u00e9todo en lugar de la inyecci\u00f3n letal.<\/p>\n<p>Condenan a pena de muerte al atacante de una sinagoga en Pittsburgh que cobr\u00f3 la vida de 11 personas en 2018<\/p>\n<p>Alabama es uno de los tres estados estadounidenses que aprobaron el uso de gas nitr\u00f3geno como pena de muerte.<\/p>\n<p>Los otros dos estados que han aprobado la pena de muerte con gas nitr\u00f3geno son Oklahoma y Mississippi, pero no la han empleado, por lo que Alabama es el primero en la historia.<\/p>\n<p>\u00bfQu\u00e9 es el gas nitr\u00f3geno y por qu\u00e9 plantea preocupaci\u00f3n su uso en ejecuciones?<\/p>\n<p>\u00bfQui\u00e9n es Kenneth Smith y por qu\u00e9 le aplicaron pena de muerte?<\/p>\n<p>Kenneth Eugene Smith fue condenado a pena de muerte por su participaci\u00f3n en el asesinato por encargo de Elizabeth Sennett en 1988 en Alabama. Seg\u00fan los registros judiciales, su marido, el ministro Charles Sennett, contrat\u00f3 a alguien que a su vez contrat\u00f3 a otras dos personas, entre ellas Smith, para que mataran a su esposa y lo hicieran pasar por un robo.<\/p>\n<p>Sennett, que seg\u00fan los tribunales ten\u00eda una amante y hab\u00eda suscrito una p\u00f3liza de seguros para su esposa, se suicid\u00f3 una semana despu\u00e9s del asesinato, cuando los investigadores se centraron en \u00e9l. Smith fue finalmente detenido despu\u00e9s de que los investigadores registraran su casa y encontraran la videograbadora de los Sennett.<\/p>\n<p>El caso de Smith fue juzgado por un jurado en dos ocasiones, seg\u00fan indic\u00f3 el fiscal general de Alabama, Steve Marshall. En su segundo juicio, que tuvo lugar en 1996, el jurado de Smith vot\u00f3 11 a 1 a favor de recomendar la cadena perpetua, pero un juez la anul\u00f3 e impuso la pena de muerte.<\/p>\n<p>Smith hab\u00eda expresado su deseo de ser ejecutado por hipoxia de nitr\u00f3geno antes de que Alabama intentara ejecutarlo en noviembre de 2022 con una inyecci\u00f3n letal. El estado cancel\u00f3 ese intento porque los funcionarios no pudieron colocar una v\u00eda intravenosa antes de que expirara la orden de ejecuci\u00f3n.<\/p>\n<p>Smith volvi\u00f3 a compartir su deseo de ser ejecutado con nitr\u00f3geno despu\u00e9s del intento con inyecci\u00f3n letal, y luego cambi\u00f3 de opini\u00f3n en agosto, cuando el estado accedi\u00f3 repentinamente a utilizar el m\u00e9todo de hipoxia de nitr\u00f3geno y public\u00f3 el protocolo ampliamente editado. Smith impugn\u00f3 entonces el protocolo, alegando que le expon\u00eda a un &#171;dolor sobrea\u00f1adido&#187;, pod\u00eda provocarle un derrame cerebral o dejarle en estado vegetativo si fallaba, seg\u00fan consta en los expedientes judiciales.<\/p>\n<p>La sentencia de un juez federal en enero de 2024 despej\u00f3 el camino para que Alabama siguiera adelante con la ejecuci\u00f3n con nitr\u00f3geno, al considerar que &#171;sencillamente no hab\u00eda pruebas suficientes para concluir&#187; que el protocolo causar\u00eda a Smith un &#171;dolor sobrea\u00f1adido&#187;. Y aunque el juez reconoci\u00f3 que el protocolo &#171;ampliamente editado&#187; manten\u00eda el &#171;conocido velo de secretismo sobre los procedimientos de la pena capital&#187; del Departamento de Instituciones Penitenciarias, tambi\u00e9n se\u00f1al\u00f3 que Alabama hab\u00eda proporcionado al equipo de Smith un protocolo sin editar. En los alegatos orales del mes pasado se revelaron m\u00e1s detalles, incluida la m\u00e1scara concreta que se utilizar\u00e1.<\/p>\n<p>Horas antes del procedimiento, Smith acudi\u00f3 al alto tribunal con una solicitud que buscaba suspender la ejecuci\u00f3n con el fin de que los jueces decidieran si deb\u00edan evaluar una impugnaci\u00f3n legal al fallo que autoriz\u00f3 al estado realizarla. Sin embargo, la corte rechaz\u00f3 la medida de \u00faltimo minuto.<\/p>\n<p>Con informaci\u00f3n de Dakin Andone, Jamiel Lynch, Ariane De Vogue y Emma Tucker, de CNN. Esta noticia fue publicada previamene el 24 de enero y actualizada el 25 de enero del 2024.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Alabama ejecut\u00f3 este jueves a Kenneth Smith,\u00a0condenado a muerte por un asesinato en 1988, con el m\u00e9todo de\u00a0hipoxia de nitr\u00f3geno.\u00a0Esta es la primera vez en Estados Unidos que una ejecuci\u00f3n se realiza con el procedimiento de gas nitr\u00f3geno. Ejecutan a Kenneth Smith en Alabama, el primero en morir por gas nitr\u00f3geno El [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444445","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Alabama ejecut\u00f3 este jueves a Kenneth Smith,\u00a0condenado a muerte por un asesinato en 1988, con el m\u00e9todo de\u00a0hipoxia de nitr\u00f3geno.\u00a0Esta es la primera vez en Estados Unidos que una ejecuci\u00f3n se realiza con el procedimiento de gas nitr\u00f3geno. Ejecutan a Kenneth Smith en Alabama, el primero en morir por gas nitr\u00f3geno El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T12:33:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos?\",\"datePublished\":\"2024-01-26T12:33:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/\"},\"wordCount\":796,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/\",\"name\":\"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-26T12:33:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Alabama ejecut\u00f3 este jueves a Kenneth Smith,\u00a0condenado a muerte por un asesinato en 1988, con el m\u00e9todo de\u00a0hipoxia de nitr\u00f3geno.\u00a0Esta es la primera vez en Estados Unidos que una ejecuci\u00f3n se realiza con el procedimiento de gas nitr\u00f3geno. Ejecutan a Kenneth Smith en Alabama, el primero en morir por gas nitr\u00f3geno El [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/","og_site_name":"Noticias","article_published_time":"2024-01-26T12:33:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos?","datePublished":"2024-01-26T12:33:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/"},"wordCount":796,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/","name":"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-26T12:33:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos?","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-26T12:33:38Z","datePublished":"2024-01-26T12:33:38Z","dateModified":"2024-01-26T12:33:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n fue Kenneth Smith y por qu\\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/26\\\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/26\\\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-26T12:33:38Z\",\"datePublished\":\"2024-01-26T12:33:38Z\",\"dateModified\":\"2024-01-26T12:33:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444443,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos\/","url_meta":{"origin":1444445,"position":0},"title":"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos?","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Alabama ejecut\u00f3 este jueves a Kenneth Smith,\u00a0condenado a muerte por un asesinato en 1988, con el m\u00e9todo de\u00a0hipoxia de nitr\u00f3geno.\u00a0Esta es la primera vez en Estados Unidos que una ejecuci\u00f3n se realiza con el procedimiento de gas nitr\u00f3geno.Ejecutan a Kenneth Smith en Alabama, el primero en morir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444479,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/quien-fue-kenneth-smith-y-por-que-le-aplicaron-la-pena-de-muerte-en-alabama-estados-unidos-3\/","url_meta":{"origin":1444445,"position":1},"title":"\u00bfQui\u00e9n fue Kenneth Smith y por qu\u00e9 le aplicaron la pena de muerte en Alabama, Estados Unidos?","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Alabama ejecut\u00f3 este jueves a Kenneth Smith,\u00a0condenado a muerte por un asesinato en 1988, con el m\u00e9todo de\u00a0hipoxia de nitr\u00f3geno.\u00a0Esta es la primera vez en Estados Unidos que una ejecuci\u00f3n se realiza con el procedimiento de gas nitr\u00f3geno.Ejecutan a Kenneth Smith en Alabama, el primero en morir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444417,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/quien-es-kenneth-smith-y-por-que-le-aplican-pena-de-muerte-en-alabama-estados-unidos\/","url_meta":{"origin":1444445,"position":2},"title":"\u00bfQui\u00e9n es Kenneth Smith y por qu\u00e9 le aplican pena de muerte en Alabama, Estados Unidos?","author":"","date":"enero 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Alabama planea aplicar esta semana la primera pena de muerte con gas nitr\u00f3geno en la historia de Estados Unidos.El recluso Kenneth Smith es la persona que ser\u00e1 ejecutada mediante el m\u00e9todo de hipoxia de nitr\u00f3geno, que ha sido objeto de cr\u00edticas debido a que Alabama ha ocultado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444481,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/tras-la-ejecucion-de-kenneth-smith-fiscal-general-dice-que-alabama-definitivamente-tendra-mas-ejecuciones-por-hipoxia-de-nitrogeno\/","url_meta":{"origin":1444445,"position":3},"title":"Tras la ejecuci\u00f3n de Kenneth Smith, fiscal general dice que Alabama &#171;definitivamente tendr\u00e1 m\u00e1s ejecuciones por hipoxia de nitr\u00f3geno&#187;","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN) -- El fiscal General de Alabama, Steve Marshall, defendi\u00f3 el m\u00e9todo de ejecuci\u00f3n utilizado para ejecutar a Kenneth Smith y dijo: \"Definitivamente tendremos m\u00e1s ejecuciones por hipoxia de nitr\u00f3geno en Alabama\".\"A partir de anoche, la hipoxia de nitr\u00f3geno como medio de ejecuci\u00f3n ya no es algo no probado, sino\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444384,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/24\/que-es-el-gas-nitrogeno-y-por-que-plantea-preocupacion-su-uso-en-ejecuciones\/","url_meta":{"origin":1444445,"position":4},"title":"\u00bfQu\u00e9 es el gas nitr\u00f3geno y por qu\u00e9 plantea preocupaci\u00f3n su uso en ejecuciones?","author":"","date":"enero 24, 2024","format":false,"excerpt":"(CNN) -- Esta semana est\u00e1 previsto que se lleve a cabo en Alabama la primera ejecuci\u00f3n conocida con gas nitr\u00f3geno. El condenado es Kenneth Smith, que recibi\u00f3 la pena de muerte por su papel en el asesinato por encargo de Elizabeth Sennett en 1988.Poco se sabe acerca de c\u00f3mo se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444449,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/pago-su-deuda-esta-noche-dice-hijo-de-la-victima-de-kenneth-smith-tras-la-ejecucion\/","url_meta":{"origin":1444445,"position":5},"title":"&#171;Pag\u00f3 su deuda esta noche&#187;, dice hijo de la v\u00edctima de Kenneth Smith tras la ejecuci\u00f3n","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN) -- \"Nada de lo que pas\u00f3 hoy aqu\u00ed va a traer de vuelta a mam\u00e1\", dijo el hijo de Elizabeth Sennett, v\u00edctima de Kenneth Eugene Smith, durante una rueda de prensa tras su ejecuci\u00f3n el jueves por la noche en Atmore, Alabama.\"No vamos a estar saltando y gritando, no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1444445"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444445\/revisions"}],"predecessor-version":[{"id":1444464,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444445\/revisions\/1444464"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1444445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1444445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1444445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}