{"id":1444467,"date":"2024-01-26T14:33:26","date_gmt":"2024-01-26T22:33:26","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444467"},"modified":"2024-01-26T14:33:26","modified_gmt":"2024-01-26T22:33:26","slug":"mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/","title":{"rendered":"&#171;Mami Nena&#187;, la abuelita gamer que es experta en disparar en &#171;Free Fire&#187;"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 \u00a0 \u2013Ah\u00ed hay uno\u2026 est\u00e1 yendo a la otra zona\u2026 \u00a1s\u00ed!\u2026 \u00a1chiuuuuu!<\/p>\n<p>En medio de disparos, clics y exclamaciones apresuradas, Mar\u00eda Elena Ar\u00e9valo, una due\u00f1a de casa de 81 a\u00f1os, analiza los movimientos de &#171;sus enemigos&#187; \u2014como les dice ella\u2014 a trav\u00e9s de la pantalla del computador.<\/p>\n<p>En su casa en la localidad de Llay Llay, a 90 kil\u00f3metros de Santiago de Chile, ella viste un delantal y prende un ventilador para capear la intensa ola de calor que azota al pa\u00eds austral mientras juega &#171;Free Fire&#187;, un popular videojuego de disparos en l\u00ednea donde millones de jugadores buscan sobrevivir en una isla imaginaria. All\u00ed, Mar\u00eda Elena tiene un personaje que viste un kimono, armas de fuego y un ave f\u00e9nix que la acompa\u00f1a como su compa\u00f1ero, a quien ella llama &#171;Benito&#187; en honor a su difunto esposo.<\/p>\n<p>&#171;Yo empec\u00e9 a jugar en 2018, por ah\u00ed. Se muri\u00f3 mi esposo, entonces yo qued\u00e9 sola. Estaba con mi nieto no m\u00e1s, que viv\u00eda aqu\u00ed. \u00c9l ten\u00eda todas estas cosas. Entonces dijo &#8216;\u00bfpor qu\u00e9 usted no aprende a jugar, para que no pase sentada aqu\u00ed? \u00bfpor qu\u00e9 no juega?'&#187;, cuenta Mar\u00eda Elena, m\u00e1s conocida como &#171;Mami Nena&#187; en internet.<\/p>\n<p>Tras la muerte de su esposo, con quien vivi\u00f3 por m\u00e1s de 50 a\u00f1os, &#171;Mami Nena&#187; relata que entr\u00f3 en una profunda depresi\u00f3n. Pero la insistencia de su nieto H\u00e9ctor Carrasco, un estudiante universitario de administraci\u00f3n de empresas de 20 a\u00f1os, la termin\u00f3 por convencer.<\/p>\n<p>C\u00f3mo la inteligencia artificial generativa podr\u00eda cambiar radicalmente los videojuegos<\/p>\n<p>&#171;No sab\u00eda ni mover el mouse yo, no sab\u00eda tocar una tecla, nada de esas cosas. Pero \u00e9l me ense\u00f1\u00f3, entonces como que yo la pena ya no la sent\u00eda&#187;, afirma la abuela.<\/p>\n<p>Con su nieto empezaron a jugar cada vez m\u00e1s, a grabar videos y contenido para redes sociales. Y para sorpresa de varios internautas, las habilidades de &#171;Mami Nena&#187; se comenzaron a notar. &#171;Eso es lo que yo le hall\u00e9 el gusto, porque yo jugaba con otra persona. Ah\u00ed yo me sent\u00eda mejor. Y no era nada una sola persona, eran varios los que jugaban en el juego. Hasta que le fui yo dando, y me gust\u00f3&#187;, cuenta &#171;Mami Nena&#187;.<\/p>\n<p>La popularidad de la &#171;abuela gamer&#187; comenz\u00f3 a crecer en Latinoam\u00e9rica y en el mundo entero. Su canal de Youtube, donde sube videos de ella jugando y comentando las partidas, ya supera los 640.000 suscriptores y en TikTok ya le siguen m\u00e1s de 380.000 personas. En 2022, la propia compa\u00f1\u00eda creadora del videojuego decidi\u00f3 invitarla a un evento en Ciudad de M\u00e9xico como rostro influyente de la marca &#171;Free Fire&#187;. Ella no lo pod\u00eda creer.<\/p>\n<p>Mar\u00eda Elena, m\u00e1s conocida como &#171;Mami Nena&#187;, en internet.<\/p>\n<p>&#171;No me imagin\u00e9 nunca yo, porque dije, \u00bfpor qu\u00e9 me invitan a M\u00e9xico a m\u00ed? Habiendo tantas otras personas. No puede ser. \u00a1Pero me invitaron! Lo pas\u00e9 bien, as\u00ed que estoy agradecida con M\u00e9xico. Me tuvieron paciencia, andaban conmigo del brazo para todas partes, porque era la mayor ah\u00ed, las \u2018influencers\u2019 eran muy muy j\u00f3venes, y yo era la mayor&#187;, cuenta &#171;Mami Nena&#187; entre risas.<\/p>\n<p>Pero los reconocimientos no terminaron ah\u00ed. En diciembre de 2023, la Universidad Cat\u00f3lica de Chile decidi\u00f3 nombrarla como una de los 100 l\u00edderes adultos mayores del pa\u00eds austral, y la invitaron a una ceremonia especial en Santiago. Mar\u00eda Elena insiste en que todo se lo debe a su nieto H\u00e9ctor: &#171;Es por mi nieto. Si no hubiera sido por \u00e9l, no s\u00e9. A lo mejor yo no estar\u00eda tambi\u00e9n. Porque yo me encerr\u00e9 en mi casa, pero con \u00e9l, yo sal\u00ed para fuera, comenc\u00e9 a jugar, empec\u00e9 a hacer otras cosas&#187;.<\/p>\n<p>Por su parte, H\u00e9ctor Carrasco cuenta que su abuela le ha ense\u00f1ado que &#171;cualquier persona, de cualquier edad, puede lograr todo lo que se proponga&#187;. &#171;Me ha ense\u00f1ado demasiadas cosas. Y cosas muy importantes&#187;, afirma el estudiante con una sonrisa mientras mira a su abuela de reojo.<\/p>\n<p>Mar\u00eda Elena dice que ahora juega mucho menos que antes debido a una esclerodermia, una enfermedad que provoca el endurecimiento de la piel de sus manos. Sin embargo, insiste en que no puede quedarse &#171;sin hacer nada&#187;, que para los adultos mayores es importante &#171;tener un pasatiempo&#187;.<\/p>\n<p>&#171;Tienen que hacer algo, aunque sea un juego, cualquier juego, pero que no se dejen estar. Hagan cualquier cosa, aprendan lo que quieran aprender, que tejan, que cosan, que hagan lo que puedan hacer. Como adultos mayores, hay muchas cosas que se pueden hacer todav\u00eda&#187;, recalca Mami Nena.<\/p>\n<p>Con la mente activa y siguiendo los ejercicios recomendados por su m\u00e9dico, esta &#171;abuela gamer&#187; afirma que seguir\u00e1 jugando hasta que su salud lo permita. Por su nieto, por sus fans, pero principalmente, por ella misma.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 \u00a0 \u2013Ah\u00ed hay uno\u2026 est\u00e1 yendo a la otra zona\u2026 \u00a1s\u00ed!\u2026 \u00a1chiuuuuu! En medio de disparos, clics y exclamaciones apresuradas, Mar\u00eda Elena Ar\u00e9valo, una due\u00f1a de casa de 81 a\u00f1os, analiza los movimientos de &#171;sus enemigos&#187; \u2014como les dice ella\u2014 a trav\u00e9s de la pantalla del computador. En su casa en la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444467","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Mami Nena&quot;, la abuelita gamer que es experta en disparar en &quot;Free Fire&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Mami Nena&quot;, la abuelita gamer que es experta en disparar en &quot;Free Fire&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0 \u00a0 \u2013Ah\u00ed hay uno\u2026 est\u00e1 yendo a la otra zona\u2026 \u00a1s\u00ed!\u2026 \u00a1chiuuuuu! En medio de disparos, clics y exclamaciones apresuradas, Mar\u00eda Elena Ar\u00e9valo, una due\u00f1a de casa de 81 a\u00f1os, analiza los movimientos de &#171;sus enemigos&#187; \u2014como les dice ella\u2014 a trav\u00e9s de la pantalla del computador. En su casa en la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T22:33:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Mami Nena&#187;, la abuelita gamer que es experta en disparar en &#171;Free Fire&#187;\",\"datePublished\":\"2024-01-26T22:33:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/\"},\"wordCount\":855,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/\",\"name\":\"\\\"Mami Nena\\\", la abuelita gamer que es experta en disparar en \\\"Free Fire\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-26T22:33:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Mami Nena&#187;, la abuelita gamer que es experta en disparar en &#171;Free Fire&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Mami Nena\", la abuelita gamer que es experta en disparar en \"Free Fire\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/","og_locale":"es_ES","og_type":"article","og_title":"\"Mami Nena\", la abuelita gamer que es experta en disparar en \"Free Fire\" - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0 \u00a0 \u2013Ah\u00ed hay uno\u2026 est\u00e1 yendo a la otra zona\u2026 \u00a1s\u00ed!\u2026 \u00a1chiuuuuu! En medio de disparos, clics y exclamaciones apresuradas, Mar\u00eda Elena Ar\u00e9valo, una due\u00f1a de casa de 81 a\u00f1os, analiza los movimientos de &#171;sus enemigos&#187; \u2014como les dice ella\u2014 a trav\u00e9s de la pantalla del computador. En su casa en la [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/","og_site_name":"Noticias","article_published_time":"2024-01-26T22:33:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/"},"author":{"name":"","@id":""},"headline":"&#171;Mami Nena&#187;, la abuelita gamer que es experta en disparar en &#171;Free Fire&#187;","datePublished":"2024-01-26T22:33:26+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/"},"wordCount":855,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/","name":"\"Mami Nena\", la abuelita gamer que es experta en disparar en \"Free Fire\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-26T22:33:26+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Mami Nena&#187;, la abuelita gamer que es experta en disparar en &#171;Free Fire&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Mami Nena&#187;, la abuelita gamer que es experta en disparar en &#171;Free Fire&#187;","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-26T22:33:26Z","datePublished":"2024-01-26T22:33:26Z","dateModified":"2024-01-26T22:33:26Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Mami Nena&#187;, la abuelita gamer que es experta en disparar en &#171;Free Fire&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/26\\\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/26\\\/mami-nena-la-abuelita-gamer-que-es-experta-en-disparar-en-free-fire\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-26T22:33:26Z\",\"datePublished\":\"2024-01-26T22:33:26Z\",\"dateModified\":\"2024-01-26T22:33:26Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473513,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/","url_meta":{"origin":1444467,"position":0},"title":"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen","author":"","date":"abril 26, 2026","format":false,"excerpt":"El presidente Donald Trump y la primera dama Melania Trump estaban sentados en el escenario del enorme sal\u00f3n de baile del Washington Hilton poco despu\u00e9s de las 8:30 p.m. (hora de Miami) del s\u00e1bado por la noche, interactuando de manera juguetona con el artista de la velada, el mentalista Oz\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473283,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/17\/madonna-lady-gaga-colaboracion-orix\/","url_meta":{"origin":1444467,"position":1},"title":"La rivalidad de Madonna y Lady Gaga podr\u00eda terminar con una in\u00e9dita colaboraci\u00f3n para &#171;El diablo viste a la moda 2&#187;","author":"","date":"abril 17, 2026","format":false,"excerpt":"Hablar de la historia del pop contempor\u00e1neo es imposible sin ellas: Madonna y Lady Gaga, dos artistas consagradas, separadas por generaciones pero que coinciden en ser referentes mundiales obligatorios en la historia de la m\u00fasica reciente. Ambas elevaron m\u00e1s all\u00e1 de lo imaginable los l\u00edmites del espect\u00e1culo, con un \u00e9xito\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470399,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/01\/22\/trump-hablo-jueves-maria-corina-machado-trax\/","url_meta":{"origin":1444467,"position":2},"title":"Trump dice que habl\u00f3 este jueves con la l\u00edder opositora venezolana Mar\u00eda Corina Machado","author":"","date":"enero 22, 2026","format":false,"excerpt":"El presidente Donald Trump dijo que habl\u00f3 hoy con la l\u00edder opositora venezolana Mar\u00eda Corina Machado, aunque continu\u00f3 expresando su apoyo a la presidenta encargada del pa\u00eds, quien asumi\u00f3 despu\u00e9s de que Estados Unidos capturara a Nicol\u00e1s Maduro.\u201cTambi\u00e9n habl\u00e9 con Mar\u00eda hoy, y saben, me cae muy bien\u201d, dijo Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473530,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/27\/melania-trump-experiencia-traumatica-publico-trax\/","url_meta":{"origin":1444467,"position":3},"title":"Melania Trump suele ser extremadamente reservada, pero tuvo que afrontar una &#171;experiencia traum\u00e1tica&#187; en el escenario p\u00fablico","author":"","date":"abril 27, 2026","format":false,"excerpt":"\u201cUn ruido desagradable\u201d.Seg\u00fan su marido, esa fue la primera reacci\u00f3n de la primera dama Melania Trump al o\u00edr disparos afuera del sal\u00f3n de baile donde ella y el presidente Donald Trump estaban sentados en el escenario para la Cena de Corresponsales de la Casa Blanca del s\u00e1bado.Se enderez\u00f3, con la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459892,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/13\/mujer-dejo-ee-uu-mudarse-espana-hijo-tragedia-familiar-trax\/","url_meta":{"origin":1444467,"position":4},"title":"&#171;Valencia nos ha ayudado a sanar&#187;: Esta mujer dej\u00f3 EE.UU. para mudarse a Espa\u00f1a con su hijo tras una tragedia familiar","author":"","date":"marzo 13, 2025","format":false,"excerpt":"Al vivir lo que ella describe como una existencia de \u201ccuento de hadas\u201d con su esposo y su hijo en Chicago, Mar\u00eda Robertson-Justiniano sinti\u00f3 que su futuro ya estaba planeado.Pero todo cambi\u00f3 en 2018, cuando su marido Alex muri\u00f3 inesperadamente.\u201cFue un shock total\u201d, le dice Mar\u00eda a CNN Travel, describiendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472004,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/03\/08\/mujer-arrestada-disparos-casa-rihanna-trax\/","url_meta":{"origin":1444467,"position":5},"title":"Detienen a una mujer tras realizar disparos en la casa de Rihanna","author":"","date":"marzo 8, 2026","format":false,"excerpt":"Una persona fue arrestada despu\u00e9s de que se disparara un arma contra la casa de Rihanna en Beverly Hills, California.El Departamento de Polic\u00eda de Los \u00c1ngeles confirm\u00f3 que ocurri\u00f3 un incidente de tiroteo a la 1:20 p.m. (hora del Pac\u00edfico) el domingo 8 de marzo. Indicaron que se efectuaron entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1444467"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444467\/revisions"}],"predecessor-version":[{"id":1444483,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444467\/revisions\/1444483"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1444467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1444467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1444467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}