{"id":1444504,"date":"2024-01-27T08:33:40","date_gmt":"2024-01-27T16:33:40","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444504"},"modified":"2024-01-27T08:33:40","modified_gmt":"2024-01-27T16:33:40","slug":"opinion-la-verdad-oculta-sobre-los-ovnis-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/","title":{"rendered":"OPINI\u00d3N | La verdad oculta sobre los ovnis"},"content":{"rendered":"<p>Nota del editor: Peter Bergen es analista de seguridad nacional de CNN, vicepresidente de New America, profesor de pr\u00e1cticas en la Universidad Estatal de Arizona y presentador del podcast de Audible &#171;In the Room with Peter Bergen&#187;, que tambi\u00e9n se puede escuchar en Apple y Spotify. Erik German es el productor principal de &#171;In the Room&#187;. Las opiniones expresadas en este comentario son suyas. Puedes leer m\u00e1s art\u00edculos de opini\u00f3n en cnne.com\/opinion.<\/p>\n<p>(CNN) &#8212; Un exfuncionario del Pent\u00e1gono \u2014impulsado, dice, por su deber con la verdad\u2014 hace p\u00fablica una acusaci\u00f3n explosiva. Frente a una multitud de c\u00e1maras de televisi\u00f3n y miembros del Congreso, este funcionario afirma que el gobierno de EE.UU. ha mantenido en secreto naves extraterrestres estrelladas durante d\u00e9cadas.<\/p>\n<p>Parece el argumento de una pel\u00edcula de Hollywood. Pero el a\u00f1o pasado, los estadounidenses lo vieron en las noticias. El exfuncionario del Pent\u00e1gono, David Grusch, hab\u00eda sido oficial de inteligencia de la Fuerza A\u00e9rea. Dijo a un comit\u00e9 del Congreso que se hab\u00eda enterado de un programa del Pent\u00e1gono de d\u00e9cadas de duraci\u00f3n centrado en la &#171;recuperaci\u00f3n de accidentes y la ingenier\u00eda inversa&#187; de ovnis de otros planetas. Grusch tambi\u00e9n dijo que los restos encontrados en los lugares donde se estrellaron las naves espaciales eran &#171;biol\u00f3gicos no humanos&#187;.<\/p>\n<p>David Grusch (Cr\u00e9dito: BRENDAN SMIALOWSKI\/AFP via Getty Images)<\/p>\n<p>As\u00ed es. Naves espaciales alien\u00edgenas estrelladas y extraterrestres muertos, ah\u00ed mismo en el Registro del Congreso. Si no fue la cosa m\u00e1s salvaje jam\u00e1s transmitida en C-SPAN, debe haber estado cerca. Alguien deber\u00eda investigar esto, \u00bfverdad?<\/p>\n<p>Resulta que alguien ya lo hab\u00eda hecho. En 2022, el Pent\u00e1gono contrat\u00f3 a un veterano cient\u00edfico y oficial de inteligencia llamado Sean Kirkpatrick para crear una nueva oficina encargada de investigar los avistamientos de ovnis por parte del ej\u00e9rcito estadounidense. Bautizada por el Departamento de Defensa de EE.UU. como la Oficina de Resoluci\u00f3n de Anomal\u00edas en Todos los Dominios, Kirkpatrick nos dijo que su equipo investig\u00f3 casos de ovnis y entrevist\u00f3 a miembros del servicio de EE.UU. que dijeron tener conocimiento de encuentros con ovnis.<\/p>\n<p>Kirkpatrick se jubil\u00f3 recientemente de su trabajo en el Pent\u00e1gono y habl\u00f3 con nosotros para el podcast de Audible &#171;In the Room&#187;.<\/p>\n<p>Kirkpatrick y su equipo investigaron todos los avistamientos de ovnis del gobierno estadounidense desde Roswell, en la d\u00e9cada de 1940, y plasmaron sus conclusiones en un informe que probablemente se har\u00e1 p\u00fablico este mes.<\/p>\n<p>En la entrevista m\u00e1s extensa que ha concedido a los medios de comunicaci\u00f3n, Kirkpatrick expuso de forma convincente que las historias que han circulado durante d\u00e9cadas sobre el supuesto encubrimiento por parte del gobierno de los ovnis relacionados con extraterrestres pueden haber sido alimentadas en gran medida por verdaderos creyentes dentro del gobierno de EE.UU. o con estrechos v\u00ednculos con \u00e9l.<\/p>\n<p>Un informe sin precedentes sobre los ovnis y otros momentos de 2023 que podr\u00edan compararse con la ciencia ficci\u00f3n<\/p>\n<p>Desde que se acu\u00f1\u00f3 por primera vez el t\u00e9rmino &#171;platillo volador&#187;, gran parte del pensamiento conspirativo sobre los ovnis ha sido generado por personas que han visto aviones estadounidenses altamente secretos y quieren respuestas. Y cuando el gobierno no da respuestas, la imaginaci\u00f3n del p\u00fablico toma el relevo.<\/p>\n<p>Pero de hecho, seg\u00fan Kirkpatrick, su investigaci\u00f3n descubri\u00f3 que la mayor\u00eda de los avistamientos de ovnis son de tecnolog\u00eda avanzada que el gobierno de EE.UU. necesita mantener en secreto, de aviones que naciones rivales est\u00e1n utilizando para espiar a EE.UU. o de drones y globos civiles benignos.<\/p>\n<p>&#171;Hay entre un 2 y un 5% de todos los informes de ovnis que son (&#8230;) lo que llamar\u00edamos verdaderamente an\u00f3malos&#187;, afirma Kirkpatrick. Y cree que lo m\u00e1s probable es que las explicaciones para ese peque\u00f1o porcentaje se encuentren aqu\u00ed mismo, en la Tierra.<\/p>\n<p>El incidente de Roswell<\/p>\n<p>As\u00ed es como Kirkpatrick y su equipo explican el incidente de Roswell, que desempe\u00f1a un papel destacado en la historia de los ovnis. Y es que, en 1947, un comunicado de prensa del ej\u00e9rcito estadounidense afirmaba que un platillo volador se hab\u00eda estrellado cerca del Campo A\u00e9reo del Ej\u00e9rcito de Roswell, en Nuevo M\u00e9xico.<\/p>\n<p>Un d\u00eda despu\u00e9s, el ej\u00e9rcito se retract\u00f3 y dijo que el objeto estrellado era un globo meteorol\u00f3gico. Los peri\u00f3dicos publicaron el titular inicial sobre el platillo, siguieron con el desmentido oficial y el inter\u00e9s por el caso se fue apagando. Hasta 1980, cuando un par de investigadores de ovnis publicaron un libro en el que afirmaban que se hab\u00edan recuperado cuerpos extraterrestres de los restos de Roswell y que el gobierno estadounidense hab\u00eda ocultado las pruebas.<\/p>\n<p>Kirkpatrick afirma que su oficina investig\u00f3 a fondo el incidente de Roswell y descubri\u00f3 que a finales de la d\u00e9cada de 1940 y principios de la de 1950 ocurr\u00edan muchas cosas cerca del aer\u00f3dromo de Roswell. Hab\u00eda un programa de espionaje llamado Proyecto Mogul, que lanzaba largas ristras de globos met\u00e1licos de formas extra\u00f1as. Estaban dise\u00f1ados para monitorear pruebas nucleares sovi\u00e9ticas y eran altamente secretos.<\/p>\n<p>Al mismo tiempo, el ej\u00e9rcito estadounidense realizaba pruebas con otros globos de gran altitud que transportaban maniqu\u00edes humanos equipados con sensores y metidos en bolsas del tama\u00f1o del cuerpo para protegerlos de los elementos. Adem\u00e1s, al menos un avi\u00f3n militar se estrell\u00f3 en las inmediaciones con 11 v\u00edctimas mortales.<\/p>\n<p>Haci\u00e9ndose eco de investigaciones gubernamentales anteriores, Kirkpatrick y su equipo llegaron a la conclusi\u00f3n de que los globos Mogul estrellados, las operaciones de recuperaci\u00f3n de los maniqu\u00edes de prueba derribados y los atisbos de las consecuencias carbonizadas de ese accidente a\u00e9reo real probablemente se combinaron en una \u00fanica narrativa falsa sobre una nave espacial extraterrestre estrellada.<\/p>\n<p>Kirkpatrick tambi\u00e9n expone argumentos convincentes de que algo similar est\u00e1 ocurriendo hoy en d\u00eda. Afirma que la nueva tecnolog\u00eda que est\u00e1 volando ahora podr\u00eda ayudar a explicar gran parte de la era moderna de avistamientos de ovnis desde principios de la d\u00e9cada del 2000. No se trata solo de tecnolog\u00eda secreta del gobierno. Muchos observadores se quedan perplejos cuando ven drones de \u00faltima generaci\u00f3n e incluso globos de aspecto extra\u00f1o.<\/p>\n<p>&#171;\u00bfQu\u00e9 es m\u00e1s probable?&#187; pregunt\u00f3 Kirkpatrick. &#171;\u00bfEl hecho de que haya una tecnolog\u00eda de punta que se est\u00e9 comercializando en Florida y de la que t\u00fa no sepas nada, o que tengamos extraterrestres?&#187;, dijo. &#171;Y me genera m\u00e1s perplejidad cuando les ense\u00f1as &#8216;aqu\u00ed est\u00e1 la empresa de Florida que construye exactamente lo que has descrito&#8217;. Y su respuesta es &#8216;bueno, no, no, no, tienen que ser extraterrestres, y lo est\u00e1s encubriendo'&#187;.<\/p>\n<p>No obstante, los ovnis siguen siendo una aut\u00e9ntica preocupaci\u00f3n para la seguridad nacional, principalmente porque constituyen un peligro para la aviaci\u00f3n. Como dijo Kirkpatrick, &#171;los pilotos militares que vuelan a m\u00e1s de Mach 1, si se topan con un globo con una cuerda, les arrancar\u00e1 un ala&#187;.<\/p>\n<p>Desde 2020, el Pent\u00e1gono ha normalizado, desestigmatizado y aumentado el volumen de informes sobre ovnis por parte de los militares estadounidenses. Kirkpatrick dice que esa es la raz\u00f3n por la que el globo esp\u00eda chino fue avistado en primer lugar el a\u00f1o pasado. El incidente demuestra que la pol\u00edtica del gobierno estadounidense de tomarse en serio los ovnis est\u00e1 funcionando.<\/p>\n<p>Los que verdaderamente creen en los ovnis<\/p>\n<p>As\u00ed que, frente a la evidencia real, \u00bfpor qu\u00e9 hay gente dentro y alrededor del gobierno que promueve la idea sin fundamento de invasores extraterrestres encubiertos por el gobierno de EE.UU.?<\/p>\n<p>&#171;Los verdaderos creyentes no est\u00e1n solo fuera del gobierno, muchos de ellos est\u00e1n dentro del gobierno&#187;, nos dijo Kirkpatrick, incluido el difunto senador estadounidense Harry Reid, el dem\u00f3crata de Nevada que fue l\u00edder de la mayor\u00eda del Senado. Otro actor clave fue Robert Bigelow, multimillonario de Nevada y propietario de una empresa llamada Bigelow Aerospace, amigo de Reid de larga data y con quien compart\u00eda un prolongado inter\u00e9s por los ovnis. Kirkpatrick dice: &#171;El senador Harry Reid era un verdadero creyente y pensaba que &#8216;eh, el gobierno est\u00e1 ocultando esto a la supervisi\u00f3n del Congreso'&#187;.<\/p>\n<p>En 2007, el senador Reid consigui\u00f3 financiaci\u00f3n para un programa de la Agencia de Inteligencia de Defensa estadounidense que pag\u00f3 US$ 22 millones a la empresa aeroespacial de su colega Bigelow, dinero que la empresa gast\u00f3 en investigaciones sobre fen\u00f3menos paranormales. Entre otras investigaciones, el equipo de Bigelow estudi\u00f3 los avistamientos de ovnis por parte de personal militar estadounidense y propuso crear laboratorios para estudiar los supuestos restos f\u00edsicos de naves extraterrestres. (En el programa &#171;60 Minutes&#187; de mayo de 2017, Bigelow dijo estar &#171;absolutamente convencido&#187; de que los extraterrestres existen y de que los ovnis han visitado la Tierra).<\/p>\n<p>Reid dijo a un reportero en Nevada en 2021 que, aunque se trataba de un programa secreto para investigar los ovnis, Bigelow no se benefici\u00f3 de &#171;alg\u00fan trato de favor (&#8230;), se sac\u00f3 a licitaci\u00f3n&#187;. Reid tambi\u00e9n dijo a The New York Times: &#171;No estoy avergonzado o apenado o arrepentido de haber puesto esto en marcha (&#8230;). Creo que es una de las cosas buenas que hice en mi servicio en el Congreso&#187;.<\/p>\n<p>Sin embargo, se\u00f1ala Kirkpatrick, &#171;nada de eso se manifest\u00f3 realmente en ninguna prueba&#187; de naves extraterrestres. Pero las historias sobre estos programas secretos se difundieron dentro del Pent\u00e1gono, se adornaron y recibieron el impulso ocasional de los miembros del servicio que hab\u00edan o\u00eddo rumores o vislumbrado tecnolog\u00eda o aeronaves aparentemente de ciencia ficci\u00f3n.<\/p>\n<p>Y Kirkpatrick dice que sus investigadores finalmente rastrearon estos movimientos hasta menos de una docena de personas.<\/p>\n<p>&#171;Todo se remonta al mismo n\u00facleo de personas&#187;, afirma Kirkpatrick. Esto es tan extra\u00f1o como ir\u00f3nico. Porque, durante d\u00e9cadas, los verdaderos creyentes en los ovnis nos han estado diciendo que existe una conspiraci\u00f3n del gobierno estadounidense para ocultar pruebas de la existencia de extraterrestres. Pero, si se cree a Kirkpatrick, la verdad m\u00e1s mundana es que estas historias est\u00e1n siendo alimentadas por un grupo de verdaderos creyentes en los ovnis dentro y fuera del gobierno.<\/p>\n<p>Lamentablemente, para todos los amantes de los ovnis, esa puede ser la mayor conclusi\u00f3n del informe de Kirkpatrick al Congreso, que se espera que se publique a finales de este mes. Mucha gente de fuera ha especulado durante mucho tiempo sobre si los programas del Pent\u00e1gono centrados en los extraterrestres no estaban dando resultados y quiz\u00e1s se estaban autoperpetuando de forma sospechosa.<\/p>\n<p>Pero ahora, personas de gran credibilidad dentro del Pent\u00e1gono -con autorizaciones de seguridad de muy alto nivel- dicen por fin que han examinado todas y cada una de las pruebas secretas sobre supuestos ovnis alien\u00edgenas. Y por lo que pueden decir, son enteramente humanas.<\/p>\n<p>Aunque Kirkpatrick concede que a aquellos que realmente creen que hay visitas extraterrestres aqu\u00ed en la Tierra, poco les convencer\u00e1 de lo contrario: &#171;No hay absolutamente nada que yo vaya a hacer, decir o presentar como prueba que vaya a hacer que los verdaderos creyentes se conviertan (&#8230;). Es una creencia religiosa que trasciende el pensamiento cr\u00edtico y el pensamiento racional&#187;.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota del editor: Peter Bergen es analista de seguridad nacional de CNN, vicepresidente de New America, profesor de pr\u00e1cticas en la Universidad Estatal de Arizona y presentador del podcast de Audible &#171;In the Room with Peter Bergen&#187;, que tambi\u00e9n se puede escuchar en Apple y Spotify. Erik German es el productor principal de &#171;In the [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444504","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OPINI\u00d3N | La verdad oculta sobre los ovnis - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPINI\u00d3N | La verdad oculta sobre los ovnis - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nota del editor: Peter Bergen es analista de seguridad nacional de CNN, vicepresidente de New America, profesor de pr\u00e1cticas en la Universidad Estatal de Arizona y presentador del podcast de Audible &#171;In the Room with Peter Bergen&#187;, que tambi\u00e9n se puede escuchar en Apple y Spotify. Erik German es el productor principal de &#171;In the [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-27T16:33:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"OPINI\u00d3N | La verdad oculta sobre los ovnis\",\"datePublished\":\"2024-01-27T16:33:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/\"},\"wordCount\":1936,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/\",\"name\":\"OPINI\u00d3N | La verdad oculta sobre los ovnis - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-27T16:33:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPINI\u00d3N | La verdad oculta sobre los ovnis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPINI\u00d3N | La verdad oculta sobre los ovnis - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/","og_locale":"es_ES","og_type":"article","og_title":"OPINI\u00d3N | La verdad oculta sobre los ovnis - Noticias","og_description":"Nota del editor: Peter Bergen es analista de seguridad nacional de CNN, vicepresidente de New America, profesor de pr\u00e1cticas en la Universidad Estatal de Arizona y presentador del podcast de Audible &#171;In the Room with Peter Bergen&#187;, que tambi\u00e9n se puede escuchar en Apple y Spotify. Erik German es el productor principal de &#171;In the [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/","og_site_name":"Noticias","article_published_time":"2024-01-27T16:33:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/"},"author":{"name":"","@id":""},"headline":"OPINI\u00d3N | La verdad oculta sobre los ovnis","datePublished":"2024-01-27T16:33:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/"},"wordCount":1936,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/","url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/","name":"OPINI\u00d3N | La verdad oculta sobre los ovnis - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-27T16:33:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"OPINI\u00d3N | La verdad oculta sobre los ovnis"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"OPINI\u00d3N | La verdad oculta sobre los ovnis","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-27T16:33:40Z","datePublished":"2024-01-27T16:33:40Z","dateModified":"2024-01-27T16:33:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"OPINI\\u00d3N | La verdad oculta sobre los ovnis\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/27\\\/opinion-la-verdad-oculta-sobre-los-ovnis-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/27\\\/opinion-la-verdad-oculta-sobre-los-ovnis-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-27T16:33:40Z\",\"datePublished\":\"2024-01-27T16:33:40Z\",\"dateModified\":\"2024-01-27T16:33:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444501,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/opinion-la-verdad-oculta-sobre-los-ovnis\/","url_meta":{"origin":1444504,"position":0},"title":"OPINI\u00d3N | La verdad oculta sobre los ovnis","author":"","date":"enero 27, 2024","format":false,"excerpt":"Nota del editor: Peter Bergen es analista de seguridad nacional de CNN, vicepresidente de New America, profesor de pr\u00e1cticas en la Universidad Estatal de Arizona y presentador del podcast de Audible \"In the Room with Peter Bergen\", que tambi\u00e9n se puede escuchar en Apple y Spotify. Erik German es el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445955,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/23\/opinion-quien-ganando-general-petraeus-trax\/","url_meta":{"origin":1444504,"position":1},"title":"OPINI\u00d3N | \u00bfQui\u00e9n va ganando? El general Petraeus opina sobre la guerra de Ucrania, dos a\u00f1os despu\u00e9s de su inicio","author":"","date":"febrero 23, 2024","format":false,"excerpt":"Nota del editor: Peter Bergen es analista de seguridad nacional de CNN, vicepresidente de New America y profesor en la Universidad Estatal de Arizona. y presentador del podcast de Audible \"In the Room\", tambi\u00e9n disponible en Apple y Spotify. Bergen es autor de \"The Cost of Chaos: The Trump Administration\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451263,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/19\/corte-internacional-de-justicia-onu-ocupacion-israeli-ribera-occidental-jerusalen-este-ilegal-trax\/","url_meta":{"origin":1444504,"position":2},"title":"Tribunal superior de la ONU dice que la ocupaci\u00f3n israel\u00ed de la Ribera Occidental y de Jerusal\u00e9n Este es ilegal","author":"","date":"julio 19, 2024","format":false,"excerpt":"(CNN) -- El m\u00e1ximo tribunal de las Naciones Unidas dijo este viernes en una opini\u00f3n consultiva que la ocupaci\u00f3n israel\u00ed de la Ribera Occidental y de Jerusal\u00e9n Este es ilegal, en una opini\u00f3n sin precedentes que pide a Israel que ponga fin a su ocupaci\u00f3n de d\u00e9cadas en los territorios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458858,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/02\/18\/el-escandalo-usdlibra-de-javier-milei-y-la-opinion-publica-es-una-crisis-de-alto-impacto\/","url_meta":{"origin":1444504,"position":3},"title":"El esc\u00e1ndalo $LIBRA de Javier Milei y la opini\u00f3n p\u00fablica: &#171;Es una crisis de alto impacto&#187;","author":"","date":"febrero 18, 2025","format":false,"excerpt":"Shila Vilker, analista pol\u00edtica, habl\u00f3 este martes en CNN Radio sobre las repercusiones del esc\u00e1ndalo $LIBRA y la entrevista que dio el presidente Javier Milei: \u201cEsto tiene y va a tener impacto en la opini\u00f3n p\u00fablica\u201d.\u201cMe gust\u00f3 para encuadrar el tema la palabra terremoto. Los terremotos suelen tener ondas expansivas.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443753,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/15\/opinion-iowa-es-el-faro-del-camino\/","url_meta":{"origin":1444504,"position":4},"title":"OPINI\u00d3N | Iowa es el faro del camino","author":"","date":"enero 15, 2024","format":false,"excerpt":"Nota del editor: Jorge D\u00e1vila Miguel es Licenciado en Periodismo desde 1973 y ha mantenido una carrera continuada en su profesi\u00f3n hasta la fecha. Ostenta posgrados en Ciencias de la Informaci\u00f3n Social y Medios de Comunicaci\u00f3n Sociales, as\u00ed como estudios superiores posuniversitarios en Relaciones Internacionales, Econom\u00eda Pol\u00edtica e Historia Latinoamericana.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446997,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/15\/opinion-problemas-monarquia-britanica-dano-orix\/","url_meta":{"origin":1444504,"position":5},"title":"OPINI\u00d3N | \u00bfPueden tantos problemas da\u00f1ar la monarqu\u00eda brit\u00e1nica?","author":"","date":"marzo 15, 2024","format":false,"excerpt":"Nota del editor: Mari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1444504"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444504\/revisions"}],"predecessor-version":[{"id":1444520,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444504\/revisions\/1444520"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1444504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1444504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1444504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}