{"id":1444513,"date":"2024-01-27T13:33:28","date_gmt":"2024-01-27T21:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444513"},"modified":"2024-01-27T13:33:28","modified_gmt":"2024-01-27T21:33:28","slug":"la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/","title":{"rendered":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU."},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2014 La vida de Griselda Blanco, conocida como \u201cLa Madrina&#187; de la droga, es contada en una miniserie de Netflix, desde este 25 de enero, con la actuaci\u00f3n protag\u00f3nica de la barranquillera Sof\u00eda Vergara.<\/p>\n<p>Su apodo no es en vano. El Departamento de Justicia de Estados Unidos se\u00f1ala que, para 1984, ella era la cabeza de una numerosa y violenta organizaci\u00f3n en Miami: &#171;Le encantaba el poder que le daba ser matriarca de una &#8216;familia&#8217; de la coca\u00edna, y model\u00f3 su organizaci\u00f3n a partir de la familia mafiosa retratada en la pel\u00edcula \u2018El Padrino\u2019&#187;. Su fijaci\u00f3n era tal, que incluso uno de sus cuatro hijos se llama Michael Corleone.<\/p>\n<p>Blanco se suma a la lista de figuras del narcotr\u00e1fico cuya historia se ha llevado a pel\u00edculas, series y libros, siendo en su mayor\u00eda hombres, entre los que destaca el nombre de Pablo Escobar, quien, seg\u00fan el libro &#171;La vida y la muerte de Griselda Blanco&#187;, de la periodista Martha Soto, habr\u00eda reconocido haber entrado al narcotr\u00e1fico para seguir su ejemplo.<\/p>\n<p>De la pobreza a formar un imperio del narcotr\u00e1fico<\/p>\n<p>Ana Griselda Blanco Restrepo naci\u00f3 en Cartagena, Colombia, el 15 de febrero de 1943. Existe otra versi\u00f3n que se\u00f1ala que naci\u00f3 en Santa Marta, lugar en el que fue bautizada.<\/p>\n<p>En 1955, se mud\u00f3 con su madre a Medell\u00edn, donde comenz\u00f3 una vida criminal en los barrios pobres. A los 12 a\u00f1os ya lideraba una banda de carteristas y habr\u00eda cometido su primer secuestro y asesinato, seg\u00fan dice el libro \u201cCocaine Cowgirl\u201d, una investigaci\u00f3n de la periodista Jennie Erin Smith. Su siguiente paso fue casarse con Carlos Trujillo, un falsificador de documentos relacionado con el tr\u00e1fico de personas, cuando apenas ten\u00eda 13 a\u00f1os, dice la investigaci\u00f3n. Se mud\u00f3 a Queens, en Nueva York, y tuvo a sus primeros tres hijos: Dixon, Uber y Osvaldo. A\u00f1os m\u00e1s tarde, Trujillo falleci\u00f3 supuestamente de cirrosis, pero en el libro &#171;Drugs in American Society: An Encyclopedia of History, Politics, Culture, and the Law&#187;, de Nancy E. Marion y Willard M. Oliver, la muerte se le atribuye a ella.<\/p>\n<p>Despu\u00e9s se cas\u00f3 con Alberto Bravo, un contrabandista que, seg\u00fan el libro \u201cCocaine Cowgirl\u201d, la habr\u00eda vinculado con el tr\u00e1fico de coca\u00edna. Smith refiere que Blanco comenz\u00f3 siendo &#171;una mula&#187;, es decir, que transportaba sustancias ilegalmente, aprovechando los pocos filtros de seguridad que hab\u00eda en ese entonces para las mujeres en los aeropuertos. &#171;De estas t\u00e1cticas entonces innovadoras surgi\u00f3 el concepto de c\u00e1rtel&#187;, se lee en la p\u00e1gina 56 de una compilaci\u00f3n del Instituto Nacional de Justicia del Departamento de Justicia de EE.UU.<\/p>\n<p>Tambi\u00e9n es conocida por haber trazado algunas de las rutas que luego usar\u00edan otros c\u00e1rteles famosos.<\/p>\n<p>RESE\u00d1A | Sof\u00eda Vergara se convierte en &#171;Griselda&#187; en una serie al estilo de &#171;Narcos&#187;<\/p>\n<p>Adem\u00e1s, Blanco habr\u00eda sido responsable de la muerte de su segundo esposo y seguido el negocio por su cuenta, seg\u00fan el portal especializado InSight Crime. Tras la muerte de Bravo, tuvo un tercer matrimonio, con Dar\u00edo Sep\u00falveda, con quien procre\u00f3 a su cuarto hijo, Michael Corleone. De acuerdo con el mismo documento del Departamento de Justicia, Griselda mand\u00f3 a matar a Sep\u00falveda por haberse llevado a Colombia a su hijo Michael contra su voluntad. Por ello, tambi\u00e9n era conocida como &#171;viuda negra&#187;.<\/p>\n<p>A finales de 1970, se instal\u00f3 en Miami, donde afianz\u00f3 su negocio de drogas y desat\u00f3 una ola de violencia en las calles. &#171;A Griselda le encantaban los asesinatos. Los cuerpos se alineaban en las calles de Miami como resultado de sus enemistades&#187;, detalla el informe en la p\u00e1gina 56, dedicada a la narcotraficante.<\/p>\n<p>Tambi\u00e9n revela que \u201cLa Madrina&#187; fue quien comenz\u00f3 \u2013con &#171;los pistoleros&#187;, su grupo de secuaces\u2013 pr\u00e1cticas de mutilaciones para demostrar que realmente hab\u00edan matado a las personas, convirti\u00e9ndose en una marca registrada del C\u00e1rtel de Medell\u00edn; y que la masacre de Dadeland, ocurrida en 1979 en un centro comercial de Miami, se remonta a la \u00e9poca de Griselda Blanco.<\/p>\n<p>Debido a la competencia en Miami, Blanco traslad\u00f3 su organizaci\u00f3n al estado de California donde, seg\u00fan dicho informe, vivi\u00f3 en la opulencia.<\/p>\n<p>Sof\u00eda Vergara genera carcajadas mientras habla de la reina de la coca\u00edna<\/p>\n<p>Griselda Blanco form\u00f3 un imperio del tr\u00e1fico ilegal de droga desde Colombia hacia Estados Unidos en las d\u00e9cadas de los 70 y los 80, lo que le vali\u00f3 otro de sus apodos: &#171;La reina de la coca\u00edna&#187;. El portal Celebrity Networth la sit\u00faa en el cuarto lugar de su ranking de los 50 criminales m\u00e1s ricos del mundo, incluso por encima del famoso g\u00e1ngster estadounidense Al Capone, que ocupa el noveno lugar. La fortuna de Griselda se calculaba en US$ 2.000 millones, seg\u00fan el libro &#171;La patrona de Pablo Escobar. Vida y muerte de Griselda Blanco. La viuda negra, la mujer que lo form\u00f3&#187;, del periodista Jos\u00e9 Guarnizo.<\/p>\n<p>De acuerdo con el archivo de The New York Times, los fiscales federales del caso, Michael Q. Carey y Peter Bloch, dijeron que la organizaci\u00f3n colombiana distribuy\u00f3 en EE.UU. m\u00e1s de 9 kilogramos de coca\u00edna por semana entre 1972 y 1974, con un valor en la calle de US$ 2,5 millones semanales.<\/p>\n<p>Encuentro con la justicia<\/p>\n<p>En abril de 1975, el Gobierno present\u00f3 ante el tribunal federal del Distrito Sur de Nueva York una acusaci\u00f3n contra Blanco y otras 37 personas. Estaban acusados de conspirar para fabricar, importar y distribuir coca\u00edna a ese pa\u00eds, de acuerdo con una compilaci\u00f3n de la Oficina de las Naciones Unidas contra la Droga y el Delito (Unodc).<\/p>\n<p>En mayo de ese a\u00f1o, el tribunal federal emiti\u00f3 una orden de arresto contra Griselda. La fiscal\u00eda se bas\u00f3 en gran medida en el testimonio de Carmen Cab\u00e1n, una extraficante que se convirti\u00f3 en testigo del Gobierno. Cab\u00e1n testific\u00f3 sobre las operaciones entre 1972 y 1975 de la red de importaci\u00f3n de coca\u00edna en la que habr\u00eda participado Blanco. Sin embargo, no fue hasta 1985 que la Administraci\u00f3n de Control de Droga de EE.UU.(DEA) pudo detener a Blanco en Irvine, California, se\u00f1ala la Unodc. Blanco dio un nombre falso a los agentes que la arrestaron y portaba documentos de identificaci\u00f3n falsos.<\/p>\n<p>El tribunal de Nueva York conden\u00f3 a \u201cLa Madrina\u201d a 15 a\u00f1os de prisi\u00f3n y le impuso una multa de US$ 25.000, pero tambi\u00e9n habr\u00eda sido sentenciada en Miami por conspiraci\u00f3n para distribuir coca\u00edna, seg\u00fan la p\u00e1gina 56 del reporte del Instituto Nacional de Justicia del Departamento de Justicia de EE.UU. De acuerdo con una biograf\u00eda de Griselda Blanco, de la Encyclopedia Britannica, en 1994, la colombiana fue acusada de ordenar tres asesinatos en el \u00e1rea de Miami, y cuatro a\u00f1os m\u00e1s tarde, se declar\u00f3 culpable a cambio de una sentencia reducida.<\/p>\n<p>Su parad\u00f3jica muerte<\/p>\n<p>Despu\u00e9s de cumplir su condena en una prisi\u00f3n de Estados Unidos, Blanco fue deportada a Colombia y regres\u00f3 a vivir a Medell\u00edn, en donde se cree que quiso mantenerse alejada del negocio del narcotr\u00e1fico. Sin embargo, el 3 de septiembre de 2012 muri\u00f3, a los 69 a\u00f1os, luego de que le dieran dos disparos desde una moto afuera de una carnicer\u00eda.<\/p>\n<p>Testigos del asesinato escucharon el t\u00edpico sonido de una motocicleta y dos disparos, seg\u00fan inform\u00f3 Diego Chavarr\u00eda, vocero de la Polic\u00eda de Medell\u00edn. Griselda Blanco fue asesinada a quemarropa, un crimen similar al que, seg\u00fan las autoridades, ella ordenaba ejecutar en los a\u00f1os 70 y 80.<\/p>\n<p>Esta historia fue publicada el 26 de enero y ha sido actualizada<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2014 La vida de Griselda Blanco, conocida como \u201cLa Madrina&#187; de la droga, es contada en una miniserie de Netflix, desde este 25 de enero, con la actuaci\u00f3n protag\u00f3nica de la barranquillera Sof\u00eda Vergara. Su apodo no es en vano. El Departamento de Justicia de Estados Unidos se\u00f1ala que, para 1984, ella era [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444513","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2014 La vida de Griselda Blanco, conocida como \u201cLa Madrina&#187; de la droga, es contada en una miniserie de Netflix, desde este 25 de enero, con la actuaci\u00f3n protag\u00f3nica de la barranquillera Sof\u00eda Vergara. Su apodo no es en vano. El Departamento de Justicia de Estados Unidos se\u00f1ala que, para 1984, ella era [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-27T21:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU.\",\"datePublished\":\"2024-01-27T21:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/\"},\"wordCount\":1344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/\",\"name\":\"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-27T21:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/","og_locale":"es_ES","og_type":"article","og_title":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU. - Noticias","og_description":"(CNN Espa\u00f1ol) \u2014 La vida de Griselda Blanco, conocida como \u201cLa Madrina&#187; de la droga, es contada en una miniserie de Netflix, desde este 25 de enero, con la actuaci\u00f3n protag\u00f3nica de la barranquillera Sof\u00eda Vergara. Su apodo no es en vano. El Departamento de Justicia de Estados Unidos se\u00f1ala que, para 1984, ella era [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/","og_site_name":"Noticias","article_published_time":"2024-01-27T21:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/"},"author":{"name":"","@id":""},"headline":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU.","datePublished":"2024-01-27T21:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/"},"wordCount":1344,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/","url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/","name":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-27T21:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU.","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-27T21:33:28Z","datePublished":"2024-01-27T21:33:28Z","dateModified":"2024-01-27T21:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La historia real de Griselda Blanco: vida y muerte de la \\u201creina de la coca\\u00edna\\u201d colombiana que lider\\u00f3 un c\\u00e1rtel en EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/27\\\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/27\\\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-3\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-27T21:33:28Z\",\"datePublished\":\"2024-01-27T21:33:28Z\",\"dateModified\":\"2024-01-27T21:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444525,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-4\/","url_meta":{"origin":1444513,"position":0},"title":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU.","author":"","date":"enero 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2014 La vida de Griselda Blanco, conocida como \u201cLa Madrina\" de la droga, es contada en una miniserie de Netflix, desde este 25 de enero, con la actuaci\u00f3n protag\u00f3nica de la barranquillera Sof\u00eda Vergara.Su apodo no es en vano. El Departamento de Justicia de Estados Unidos se\u00f1ala que,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444474,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu\/","url_meta":{"origin":1444513,"position":1},"title":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU.","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2014 La vida de Griselda Blanco, conocida como \u201cLa Madrina\" de la droga, es contada en una miniserie de Netflix, desde este 25 de enero, con la actuaci\u00f3n protag\u00f3nica de la barranquillera Sof\u00eda Vergara.Su apodo no es en vano. El Departamento de Justicia de Estados Unidos se\u00f1ala que,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444477,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/26\/la-historia-real-de-griselda-blanco-vida-y-muerte-de-la-reina-de-la-cocaina-colombiana-que-lidero-un-cartel-en-ee-uu-2\/","url_meta":{"origin":1444513,"position":2},"title":"La historia real de Griselda Blanco: vida y muerte de la \u201creina de la coca\u00edna\u201d colombiana que lider\u00f3 un c\u00e1rtel en EE.UU.","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2014 La vida de Griselda Blanco, conocida como \u201cLa Madrina\" de la droga, es contada en una miniserie de Netflix, desde este 25 de enero, con la actuaci\u00f3n protag\u00f3nica de la barranquillera Sof\u00eda Vergara.Su apodo no es en vano. El Departamento de Justicia de Estados Unidos se\u00f1ala que,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462659,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/05\/21\/quien-es-griselda-lopez-perez-exesposa-chapo-orix\/","url_meta":{"origin":1444513,"position":3},"title":"La madre de Ovidio Guzm\u00e1n en EE.UU.: \u00bfqui\u00e9n es Griselda L\u00f3pez P\u00e9rez, la exesposa del Chapo?","author":"","date":"mayo 21, 2025","format":false,"excerpt":"A principios de mayo, varios familiares de Ovidio Guzm\u00e1n L\u00f3pez, \u201cEl Rat\u00f3n\u201d, incluida su madre Griselda L\u00f3pez P\u00e9rez, cruzaron la frontera de M\u00e9xico a Estados Unidos por la garita de San Ysidro en el occidente de ambos pa\u00edses, le dijo una fuente del Gobierno de EE.UU.El secretario de Seguridad de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469026,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/12\/06\/ryan-wedding-fbi-mas-buscados-trax\/","url_meta":{"origin":1444513,"position":4},"title":"&#171;La versi\u00f3n moderna de Pablo Escobar&#187;: el snowboarder ol\u00edmpico que se convirti\u00f3 en uno de los fugitivos m\u00e1s buscados del FBI","author":"","date":"diciembre 6, 2025","format":false,"excerpt":"Cuando compet\u00eda para el equipo de Canad\u00e1, Ryan Wedding termin\u00f3 en el puesto 24 del mundo en la modalidad de eslalon gigante paralelo de snowboard en los Juegos Ol\u00edmpicos de Invierno de 2002.Ahora, m\u00e1s de dos d\u00e9cadas despu\u00e9s, forma parte de otro grupo selecto: los 10 fugitivos m\u00e1s buscados del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471597,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/24\/mexico-carteles-principales-donde-operan-orix\/","url_meta":{"origin":1444513,"position":5},"title":"Mapa: cu\u00e1les son los principales grupos criminales de M\u00e9xico y d\u00f3nde operan","author":"","date":"febrero 24, 2026","format":false,"excerpt":"M\u00e9xico lleva d\u00e9cadas en lucha contra los carteles, que a\u00f1o a a\u00f1o le presentaron desaf\u00edos cambiantes y crecientes.El regreso de Donald Trump a la presidencia de EE.UU., en 2025, le sum\u00f3 un reto m\u00e1s esa lucha del Gobierno mexicano: ir tras los capos que manejan los carteles.La misi\u00f3n nunca fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1444513"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444513\/revisions"}],"predecessor-version":[{"id":1444529,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444513\/revisions\/1444529"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1444513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1444513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1444513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}