{"id":1444527,"date":"2024-01-27T20:33:28","date_gmt":"2024-01-28T04:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444527"},"modified":"2024-01-27T20:33:28","modified_gmt":"2024-01-28T04:33:28","slug":"los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/","title":{"rendered":"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 &#171;La sociedad de la nieve&#187;, la cinta de Netflix nominada al Oscar como mejor pel\u00edcula extranjera, llev\u00f3 al cine de un modo hiperrealista los detalles de una de las historias de supervivencia m\u00e1s impactantes del \u00faltimo medio siglo.<\/p>\n<p>El clima hostil, la falta de comida, una serie de avalanchas y el desaf\u00edo emocional que signific\u00f3 pasar 72 d\u00edas en la cima de los Andes sabiendo que las autoridades hab\u00edan suspendido la b\u00fasqueda fueron solo algunas de las dificultades con las que debieron lidiar los miembros del equipo de rugby uruguayo que viajaba a Chile por una competencia deportiva.<\/p>\n<p>Una cuesti\u00f3n de salud es reflejada casi como un detalle por el director de la pel\u00edcula, el espa\u00f1ol Juan Antonio Bayona, y llam\u00f3 la atenci\u00f3n de la audiencia: los sobrevivientes orinaban de un color marr\u00f3n oscuro, casi negro.<\/p>\n<p>\u00bfQui\u00e9nes fueron y qu\u00e9 ha sido de los sobrevivientes de la tragedia de los Andes? As\u00ed es vivir despu\u00e9s de &#171;La sociedad de la nieve&#187;<\/p>\n<p>Aunque hay una escena que lo muestra y un momento en el que los sobrevivientes lo mencionan, no existe en la pel\u00edcula una explicaci\u00f3n de cu\u00e1l podr\u00eda ser el motivo detr\u00e1s de este fen\u00f3meno fisiol\u00f3gico.<\/p>\n<p>M\u00e1s all\u00e1 del episodio puntual, lo cierto es que el color de la orina es un indicador importante de varias cuestiones relativas a los niveles de hidrataci\u00f3n, la cantidad y calidad de la alimentaci\u00f3n, el estado de los \u00f3rganos e incluso la ingesta de algunos medicamentos.<\/p>\n<p>Captura de una escena de la pel\u00edcula &#171;La sociedad de la nieve&#187;, en la que se ve que los sobrevivientes de la tragedia de los Andes orinaban de un color casi negro.<\/p>\n<p>Expertos consultados por CNN en Espa\u00f1ol coincidieron en que la orina oscura puede estar vinculada a la deshidrataci\u00f3n, incluso pese a que los sobrevivientes inger\u00edan agua a trav\u00e9s de un sistema rudimentario para lograr el derretimiento de la nieve.<\/p>\n<p>&#171;Los ri\u00f1ones son un filtro de la sangre, nos ayudan a librarnos de toxinas y tambi\u00e9n del agua. Cuando no tienen agua, los ri\u00f1ones producen un color oscuro, no negro, pero muy oscuro. Por eso, si no bebes l\u00edquido, producir\u00e1s poca orina, espesa y de un color amarillo anaranjado intenso. Por el contrario, si bebes mucha agua, tu orina ser\u00e1 transparente&#187;, explic\u00f3 el doctor Elmer Huerta, profesor de Medicina en la Universidad George Washington y colaborador de CNN.<\/p>\n<p>Con todo, el especialista m\u00e9dico afirm\u00f3 que las pel\u00edculas tienen elementos de ficci\u00f3n y dramatizaci\u00f3n: &#171;Quiz\u00e1s ese color casi negro sea una exageraci\u00f3n. Es probable que sea oscura, s\u00ed, pero no tanto&#187;.<\/p>\n<p>El doctor Juan Cardenas Rosales, internista y l\u00edder m\u00e9dico de la pr\u00e1ctica internacional de Mayo Clinic en Jacksonville, Florida, incluye otros factores a la explicaci\u00f3n de la deshidrataci\u00f3n.<\/p>\n<p>&#171;Por supuesto, el agua es la que permite la coloraci\u00f3n amarillo claro. Pero no creo que la deshidrataci\u00f3n llegue a provocar ese color tan oscuro, deber\u00eda estar combinada con algo m\u00e1s&#187;.<\/p>\n<p>Al indagar, entonces, sobre otros motivos m\u00e1s all\u00e1 de la deshidrataci\u00f3n, ambos especialistas coinciden en un posible diagn\u00f3stico.<\/p>\n<p>&#171;Creo que hay una segunda explicaci\u00f3n que depende del fr\u00edo&#187;, dijo el doctor Huerta. &#171;El fr\u00edo intenso genera hipotermia, un fen\u00f3meno al que todos los sobrevivientes estuvieron sometidos. Hay varios estudios que indican que quienes sufren hipotermia severa sufren un proceso de destrucci\u00f3n de las c\u00e9lulas de sus m\u00fasculos. Se llama rabdomiolisis&#187;, detall\u00f3.<\/p>\n<p>En efecto, la hipotermia intensa provoca destrucci\u00f3n de c\u00e9lulas musculares, las cuales liberan a la sangre una sustancia llamada mioglobina, de acuerdo con un art\u00edculo publicado en la Biblioteca Nacional de Medicina de los Institutos Nacionales de Salud de Estados Unidos (NIH, por sus siglas en ingl\u00e9s). Cuando la mioglobina llega a la sangre genera en la orina un marr\u00f3n muy oscuro, seg\u00fan el doctor Huerta, en la enfermedad identificada como rabdomiolisis o &#171;rabdo&#187;.<\/p>\n<p>Muestras de orina de distintos colores. (Cr\u00e9dito: Anthony Devlin\/Getty Images)<\/p>\n<p>&#171;En el caso de los sobrevivientes de los Andes, el cuadro cl\u00ednico pod\u00eda incluir deshidrataci\u00f3n, m\u00e1s hipotermia, m\u00e1s &#8216;rabdo'&#187;, dijo el Dr. Huerta a CNN.<\/p>\n<p>El doctor C\u00e1rdenas Rosales tambi\u00e9n dice que la orina oscura podr\u00eda ser causada por el da\u00f1o a los ri\u00f1ones producto de la rabdomiolisis. Sin embargo, destaca otra causa, adem\u00e1s del fr\u00edo, para que se d\u00e9 esa condici\u00f3n.<\/p>\n<p>&#171;Hacer mucho ejercicio o, como en el caso de los sobrevivientes de los Andres, hacer esfuerzos excesivos, tambi\u00e9n puede derivar en rabdomiolisis. Consiste en la liberaci\u00f3n de una toxina producto de una ruptura del tejido muscular que a veces puede da\u00f1ar los ri\u00f1ones&#187;, indic\u00f3.<\/p>\n<p>En cualquiera de ambos casos, el &#171;rabdo&#187; es una forma de da\u00f1o muscular que hace que las fibras musculares mueran y se liberen al torrente sangu\u00edneo. Sin atenci\u00f3n m\u00e9dica inmediata, puede provocar un da\u00f1o renal duradero, de acuerdo con un art\u00edculo de CNN.<\/p>\n<p>Aunque se trata de la explicaci\u00f3n m\u00e1s contundente al respecto de los involucrados en la tragedia de los Andes, el Dr. C\u00e1rdenas Rosales insiste en que, en condiciones normales, ese color oscuro en la orina podr\u00eda ser causado por m\u00faltiples factores.<\/p>\n<p>&#171;Puede ser por alimentos como abas, aloe, o por antibi\u00f3ticos o algunos medicamentos como los que son usados para el estre\u00f1imiento y para las convulsiones. Tambi\u00e9n puede responder a condiciones cr\u00f3nicas, como infecciones urinarias. Y tambi\u00e9n podr\u00eda deberse a alg\u00fan sangrado en el sistema urinario&#187;, concluye.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 &#171;La sociedad de la nieve&#187;, la cinta de Netflix nominada al Oscar como mejor pel\u00edcula extranjera, llev\u00f3 al cine de un modo hiperrealista los detalles de una de las historias de supervivencia m\u00e1s impactantes del \u00faltimo medio siglo. El clima hostil, la falta de comida, una serie de avalanchas y el desaf\u00edo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444527","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0 &#171;La sociedad de la nieve&#187;, la cinta de Netflix nominada al Oscar como mejor pel\u00edcula extranjera, llev\u00f3 al cine de un modo hiperrealista los detalles de una de las historias de supervivencia m\u00e1s impactantes del \u00faltimo medio siglo. El clima hostil, la falta de comida, una serie de avalanchas y el desaf\u00edo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-28T04:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9?\",\"datePublished\":\"2024-01-28T04:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/\"},\"wordCount\":1004,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/\",\"name\":\"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-28T04:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/","og_locale":"es_ES","og_type":"article","og_title":"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0 &#171;La sociedad de la nieve&#187;, la cinta de Netflix nominada al Oscar como mejor pel\u00edcula extranjera, llev\u00f3 al cine de un modo hiperrealista los detalles de una de las historias de supervivencia m\u00e1s impactantes del \u00faltimo medio siglo. El clima hostil, la falta de comida, una serie de avalanchas y el desaf\u00edo [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/","og_site_name":"Noticias","article_published_time":"2024-01-28T04:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/"},"author":{"name":"","@id":""},"headline":"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9?","datePublished":"2024-01-28T04:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/"},"wordCount":1004,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/","name":"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-28T04:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9?","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-28T04:33:28Z","datePublished":"2024-01-28T04:33:28Z","dateModified":"2024-01-28T04:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \\u00bfPor qu\\u00e9?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/27\\\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/01\\\/27\\\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-28T04:33:28Z\",\"datePublished\":\"2024-01-28T04:33:28Z\",\"dateModified\":\"2024-01-28T04:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444518,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/27\/los-sobrevivientes-de-la-tragedia-de-los-andes-orinaban-casi-negro-por-que\/","url_meta":{"origin":1444527,"position":0},"title":"Los sobrevivientes de la tragedia de los Andes orinaban casi negro. \u00bfPor qu\u00e9?","author":"","date":"enero 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 \"La sociedad de la nieve\", la cinta de Netflix nominada al Oscar como mejor pel\u00edcula extranjera, llev\u00f3 al cine de un modo hiperrealista los detalles de una de las historias de supervivencia m\u00e1s impactantes del \u00faltimo medio siglo.El clima hostil, la falta de comida, una serie de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444858,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/03\/por-que-se-estrello-el-avion-de-la-sociedad-de-la-nieve-que-fallo\/","url_meta":{"origin":1444527,"position":1},"title":"\u00bfPor qu\u00e9 se estrell\u00f3 el avi\u00f3n de &#171;La sociedad de la nieve&#187;? \u00bfQu\u00e9 fall\u00f3?","author":"","date":"febrero 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \"La sociedad de la nieve\", la exitosa pel\u00edcula del director espa\u00f1ol Juan Antonio Bayona que aborda uno de los accidentes a\u00e9reos que m\u00e1s impactaron al mundo ocurrido en los Andes hace casi m\u00e1s de 50 a\u00f1os, hace un retrato humano y conmovedor de la tragedia.El relato de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443203,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/05\/tragedia-de-los-andes-la-historia-que-llevo-al-canibalismo-y-que-se-considera-un-milagro\/","url_meta":{"origin":1444527,"position":2},"title":"Tragedia de los Andes: la historia que llev\u00f3 al canibalismo y que se considera un \u201cmilagro\u201d","author":"","date":"enero 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Fue llamado el \u201cmilagro navide\u00f1o\u201d, una muestra de fe, esperanza, inteligencia, trabajo en equipo e instinto de supervivencia que conmovi\u00f3 al mundo entero. Se conoce como el \u201cmilagro de los Andes\u201d.La tr\u00e1gica y extraordinaria historia comenz\u00f3 el 12 de octubre de 1972. Un total de 45 personas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443605,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/12\/como-decidieron-los-sobrevivientes-de-la-tragedia-de-los-andes-alimentarse-de-los-muertos\/","url_meta":{"origin":1444527,"position":3},"title":"\u00bfC\u00f3mo decidieron los sobrevivientes de la tragedia de los Andes alimentarse de los muertos?","author":"","date":"enero 12, 2024","format":false,"excerpt":"Nota del editor: Esta nota incluye descripciones que pueden resultar perturbadoras(CNN Espa\u00f1ol) -- Estaban a 3.600 metros de altura, rodeados de un infierno de hielo y nieve, sin nada para llevarse a la boca, sin vegetales ni animales cerca, sin siquiera insectos o al menos alg\u00fan gusano que buscar. Racionando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444058,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/18\/la-sociedad-de-la-nieve-nominada-al-bafta-a-mejor-pelicula-de-habla-no-inglesa\/","url_meta":{"origin":1444527,"position":4},"title":"&#171;La sociedad de la nieve&#187;, nominada al BAFTA a mejor pel\u00edcula de habla no inglesa","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN) -- Ya se sab\u00eda que \"La sociedad de la nieve\" \u2014la pel\u00edcula que cuenta la historia de los sobrevivientes del accidente a\u00e9reo en la cordillera de los Andes en 1972\u2014 es una de las semifinalistas en la competencia al Oscar en la categor\u00eda de Mejor Pel\u00edcula Internacional. Sin embargo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444061,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/18\/la-sociedad-de-la-nieve-nominada-al-bafta-a-mejor-pelicula-de-habla-no-inglesa-2\/","url_meta":{"origin":1444527,"position":5},"title":"&#171;La sociedad de la nieve&#187;, nominada al BAFTA a mejor pel\u00edcula de habla no inglesa","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN) -- Ya se sab\u00eda que \"La sociedad de la nieve\" \u2014la pel\u00edcula que cuenta la historia de los sobrevivientes del accidente a\u00e9reo en la cordillera de los Andes en 1972\u2014 es una de las semifinalistas en la competencia al Oscar en la categor\u00eda de Mejor Pel\u00edcula Internacional. Sin embargo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1444527"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444527\/revisions"}],"predecessor-version":[{"id":1444543,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1444527\/revisions\/1444543"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1444527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1444527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1444527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}