{"id":1449441,"date":"2024-05-13T17:03:43","date_gmt":"2024-05-14T00:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/"},"modified":"2024-05-13T17:03:43","modified_gmt":"2024-05-14T00:03:43","slug":"conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/","title":{"rendered":"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen"},"content":{"rendered":"<p>(CNN) &#8212; Michael Cohen implic\u00f3 a su exjefe Donald Trump en el esquema de pago de dinero por silencio a Stormy Daniels pocos d\u00edas antes de las elecciones de 2016, diciendo que entreg\u00f3 US$ 130.000 bajo la direcci\u00f3n de Trump y se le prometi\u00f3 el reembolso.<\/p>\n<p>El testimonio de Cohen vincula las acusaciones de la Fiscal\u00eda de que Trump viol\u00f3 la ley al falsificar registros comerciales para devolver el dinero a Cohen y ocultar el pago de dinero por silencio que Cohen dijo que hizo bajo la direcci\u00f3n de Trump. Trump se ha declarado inocente y niega haber tenido una aventura con Daniels.<\/p>\n<p>Michael Cohen testifica en el hist\u00f3rico juicio penal contra Donald Trump: dijo que a veces ment\u00eda e intimidaba por el expresidente<\/p>\n<p>Cohen y Trump evitaron en su mayor\u00eda el contacto visual mientras testificaba este lunes. Cohen mir\u00f3 directamente a la fiscal Susan Hoffinger durante la mayor parte de su testimonio, ocasionalmente escaneando la sala o mirando en direcci\u00f3n al jurado. Trump pas\u00f3 largos tramos del interrogatorio de Cohen con los ojos cerrados u hojeando una pila de noticias.<\/p>\n<p>Es probable que los abogados de Trump tengan su oportunidad de interrogar a Cohen el martes. Se espera que el abogado de Trump, Todd Blanche, trate de destruir la credibilidad de Cohen ante el jurado durante el contrainterrogatorio, pint\u00e1ndolo como un perjuro convicto que ha cambiado su historia m\u00e1s de una vez.<\/p>\n<p>Estas son las conclusiones del d\u00eda 16 del juicio de Trump por el pago de dinero por silencio:<\/p>\n<p>Cohen vincula a Trump con el pago a Daniels<\/p>\n<p>A trav\u00e9s de aproximadamente cinco horas de testimonio el lunes, Cohen explic\u00f3 a los miembros del jurado c\u00f3mo trabaj\u00f3 con el exeditor de National Enquirer David Pecker en nombre de Trump durante la campa\u00f1a de 2016 para matar historias negativas; c\u00f3mo mantuvo a Trump informado de sus negociaciones de dinero por silencio con Keith Davidson, el abogado de Daniels y la exmodelo de Playboy Karen McDougal; y c\u00f3mo Trump aprob\u00f3 y estaba al tanto de c\u00f3mo Cohen ser\u00eda falsamente reembolsado en 2017 por el pago a Daniels como servicios legales.<\/p>\n<p>Cohen es el pegamento que une a los otros testigos que los jurados han escuchado hasta ahora, conectado a trav\u00e9s de mensajes de texto de correo electr\u00f3nico y llamadas telef\u00f3nicas a Pecker, Davidson, Dylan Howard, Hope Hicks y otros que supuestamente estuvieron involucrados con los pagos de dinero por silencio.<\/p>\n<p>Cohen describi\u00f3 sus conversaciones con Trump durante las negociaciones con Daniels, que los fiscales respaldaron utilizando los registros telef\u00f3nicos de Cohen para mostrar cuando los dos hab\u00edan hablado. Tambi\u00e9n relacion\u00f3 el pago con la campa\u00f1a de Trump.<\/p>\n<p>&#171;Ten\u00eda que hacer esto&#187;, dijo Cohen en el estrado. &#171;Iba a ser catastr\u00f3fico para la campa\u00f1a&#187;.<\/p>\n<p>Despu\u00e9s de que Cohen y Davidson acordaran un pago de liquidaci\u00f3n de US$ 130.000 el 11 de octubre de 2016, Cohen dijo que intent\u00f3 alargar el proceso hasta despu\u00e9s de las elecciones por indicaci\u00f3n de Trump, alegando que necesitar\u00eda 10 d\u00edas para reunir el dinero y se\u00f1alando que la oficina estaba cerrada por Yom Kippur.<\/p>\n<p>Hoffinger pregunt\u00f3 por qu\u00e9 Cohen hizo eso.<\/p>\n<p>&#171;Porque despu\u00e9s de las elecciones, no importar\u00eda&#187;, dijo Cohen.<\/p>\n<p>&#171;\u00bfSeg\u00fan qui\u00e9n?&#187;, pregunt\u00f3 Hoffinger.<\/p>\n<p>&#171;Seg\u00fan el se\u00f1or Trump&#187;, dijo Cohen.<\/p>\n<p>Daniels se hart\u00f3 de los retrasos, lo que llev\u00f3 a Davidson a cancelar brevemente el acuerdo de conciliaci\u00f3n, antes de que renovaran el trato a finales de octubre.<\/p>\n<p>El d\u00eda antes de que Cohen transfiriera el dinero, tuvo dos llamadas con Trump por la ma\u00f1ana en las que sostiene le dijo a Trump que iba a abrir la cuenta para la LLC que transferir\u00eda el dinero a Daniels.<\/p>\n<p>&#171;Quer\u00eda asegurarme de que una vez m\u00e1s aprobaba lo que estaba haciendo porque requiero su aprobaci\u00f3n en todo esto&#187;, dijo Cohen.<\/p>\n<p>Hoffinger pregunt\u00f3 si Cohen habr\u00eda ido al banco sin la aprobaci\u00f3n de Trump.<\/p>\n<p>&#171;No&#187;, dijo Cohen. &#171;Todo requer\u00eda el visto bueno del se\u00f1or Trump; encima, quer\u00eda recuperar el dinero&#187;.<\/p>\n<p>Cohen describi\u00f3 c\u00f3mo minti\u00f3 en sus extractos bancarios, mentiras que condujeron a cargos federales en su contra en 2018, al decir que Essential Consultants LLC estaba siendo utilizada para consultor\u00eda inmobiliaria.<\/p>\n<p>Cuando se le pregunt\u00f3 si su banco habr\u00eda abierto la cuenta si hubiera sido sincero, Cohen dijo: &#171;Creo que probablemente no lo habr\u00edan hecho&#187;.<\/p>\n<p>AN\u00c1LISIS | Michael Cohen, el ex &#171;mat\u00f3n&#187; de Trump, est\u00e1 listo para dar un testimonio que definir\u00e1 el juicio por sobornos<\/p>\n<p>Cohen vincula el reembolso del dinero por silencio tambi\u00e9n a Trump<\/p>\n<p>Trump est\u00e1 acusado de 34 cargos de falsificaci\u00f3n de registros comerciales: 11 facturas, 12 comprobantes y 11 cheques, registros que, seg\u00fan los fiscales, provienen de los reembolsos mensuales que Cohen recibi\u00f3 en 2017 por el pago de dinero por silencio que hizo a Daniels.<\/p>\n<p>El lunes, los miembros del jurado escucharon a trav\u00e9s de Cohen por primera vez pruebas que conectan directamente a Trump con esos pagos.<\/p>\n<p>Cohen describi\u00f3 c\u00f3mo se enfureci\u00f3 en diciembre de 2016 cuando su bono anual de Navidad se hab\u00eda reducido en dos tercios.<\/p>\n<p>Dijo que inmediatamente se dirigi\u00f3 al entonces director financiero de Trump, Allen Weisselberg, &#171;y en un lenguaje colorido le expres\u00e9 lo verdaderamente molesto y enfadado que estaba. Esto no tiene ning\u00fan sentido&#187;.<\/p>\n<p>&#171;Estaba incluso para m\u00ed mismo inusualmente enfadado&#187;, dijo Cohen. &#171;Utilic\u00e9 bastantes improperios&#187;.<\/p>\n<p>Despu\u00e9s de a\u00f1o nuevo, Cohen dijo que fue a ver a Weisselberg para que le devolviera el pago de US$ 130.000. Weisselberg confirm\u00f3, seg\u00fan Cohen.<\/p>\n<p>A continuaci\u00f3n, se mostr\u00f3 al jurado el extracto bancario de First Republic de Cohen, que mostraba el pago del acuerdo de US$ 130.000 y la letra de Weisselberg detallando c\u00f3mo Cohen deb\u00eda ser reembolsado por US$ 420.000.<\/p>\n<p>Cohen testific\u00f3 que vio a Weisselberg escribir en el documento, mientras dec\u00eda a los jurados que su dinero ser\u00eda &#171;bruto&#187; para tener en cuenta los impuestos, porque se le estaba pagando en cuotas mensuales como ingresos, en lugar de como un reembolso.<\/p>\n<p>Es importante destacar que Cohen dijo que despu\u00e9s de su reuni\u00f3n, \u00e9l y Weisselberg fueron a la oficina de Trump para hablar con \u00e9l al respecto. Cohen dijo que se le dio el t\u00edtulo de abogado personal del presidente alrededor del mismo tiempo, pero no iba a ser pagado por ese t\u00edtulo.<\/p>\n<p>Hoffinger le pregunt\u00f3 si se le estaba pagando por futuros servicios legales.<\/p>\n<p>&#171;Eso era lo que se pretend\u00eda&#187;, dijo Cohen.<\/p>\n<p>&#171;\u00bfQu\u00e9 era en realidad?&#187;, pregunt\u00f3 Hoffinger.<\/p>\n<p>&#171;El reembolso de mi dinero&#187;, dijo Cohen.<\/p>\n<p>AN\u00c1LISIS | Trump se enfrenta cara a cara con un testimonio que ha negado durante a\u00f1os<\/p>\n<p>Cohen describe haber protegido a Trump<\/p>\n<p>Cohen, que sol\u00eda decir que recibir\u00eda una bala por Trump en el mejor momento de su relaci\u00f3n, testific\u00f3 el lunes sobre todo lo que hizo para proteger a su exjefe.<\/p>\n<p>A medida que Cohen describi\u00f3 cada historia medi\u00e1tica que mat\u00f3 y cada acuerdo de confidencialidad que cerr\u00f3 antes de las elecciones de 2016, siempre fue en nombre de la protecci\u00f3n de Trump.<\/p>\n<p>Cuando se trat\u00f3 del acuerdo de conciliaci\u00f3n con Daniels, Cohen dijo que mantuvo el control de un documento que revelaba las identidades de &#171;David Dennison&#187; y &#171;Peggy Peterson&#187; para poder proteger a Trump.<\/p>\n<p>Y testific\u00f3 que us\u00f3 Essential Consultants LLC para facilitar el pago a Daniels &#171;para protegerlo y aislarlo de la transacci\u00f3n&#187;.<\/p>\n<p>Hoffinger pregunt\u00f3 a Cohen si a veces intimidaba a la gente y Cohen confirm\u00f3 lo dicho.<\/p>\n<p>&#171;Lo \u00fanico que estaba en mi mente era cumplir la tarea para hacerlo feliz&#187;, dijo Cohen sobre Trump.<\/p>\n<p>Cohen tambi\u00e9n declar\u00f3 que es &#171;justo&#187; decir que una vez fue el &#171;arreglador&#187; de Trump y dijo al jurado que a veces ment\u00eda por Trump, incluso a su propia esposa.<\/p>\n<p>Cohen dijo que opt\u00f3 por adelantar los US$ 130.000 a Daniels de su l\u00ednea de cr\u00e9dito hipotecario de su propiedad personal porque su esposa habr\u00eda notado la gran suma que faltaba de su cuenta bancaria personal conjunta.<\/p>\n<p>Cohen pint\u00f3 a Trump, a quien a menudo llamaba &#171;jefe&#187;, como un microgestor que insist\u00eda en que se le mantuviera informado de los acontecimientos de cualquier situaci\u00f3n, incluidos los casos m\u00e1s discretos como los acuerdos de confidencialidad con McDougal y Daniels.<\/p>\n<p>Cohen admiti\u00f3 que tambi\u00e9n manten\u00eda constantemente informado a Trump porque quer\u00eda que se le reconociera el m\u00e9rito de gestionar sus asuntos, ya fuera negociando facturas o suprimiendo historias negativas en los medios de comunicaci\u00f3n.<\/p>\n<p>Cohen dijo que siempre quer\u00eda que Trump supiera que las situaciones estaban siendo arregladas y quer\u00eda &#171;obtener cr\u00e9dito por cumplir la tarea&#187;.<\/p>\n<p>La impactante imagen de Michael Cohen del mundo de Trump, parecido a una mafia<\/p>\n<p>Sin fuegos artificiales en el enfrentamiento entre Trump y Cohen<\/p>\n<p>A diferencia de su t\u00edpico personaje p\u00fablico, el jurado vio a un Cohen moderado que dio respuestas lentas y deliberadas en el interrogatorio directo.<\/p>\n<p>Cohen rara vez mir\u00f3 a Trump sentado en la mesa de la defensa, dirigiendo sus ojos principalmente a la fiscal que le interrogaba.<\/p>\n<p>Y aparte de revisar algunos documentos y pasar algunas notas a sus abogados, Trump pas\u00f3 la mayor parte del d\u00eda con los ojos cerrados. El expresidente mir\u00f3 a Cohen un par de veces, pero nunca hubo un momento obvio de contacto visual.<\/p>\n<p>Cohen s\u00ed provoc\u00f3 algunos movimientos de cabeza de lo que parec\u00eda desaprobaci\u00f3n por parte de Trump, incluso cuando Cohen mencion\u00f3 a la esposa de Trump, Melania.<\/p>\n<p>Cohen afirm\u00f3 que Trump no estaba preocupado por los sentimientos de su esposa cuando la infame cinta &#171;Access Hollywood&#187; se hizo p\u00fablica antes de las elecciones, un testimonio contrario a lo que las exasesoras de Trump Hicks y Madeleine Westerhout dijeron al jurado.<\/p>\n<p>Testific\u00f3: &#171;&#8216;No te preocupes, dice: &#8216;\u00bfCu\u00e1nto tiempo crees que estar\u00e9 en el mercado? No mucho&#8217;. No estaba pensando en Melania. Todo se trataba de la campa\u00f1a&#187;.<\/p>\n<p>En un momento dado, parec\u00eda que Trump hab\u00eda escuchado suficiente de la historia de Cohen como empleado dedicado, sacudiendo la cabeza con una sonrisa de labios fruncidos cuando Cohen testific\u00f3 que utiliz\u00f3 una empresa fantasma para pagar a Daniels para proteger a Trump.<\/p>\n<p>Trump sacudi\u00f3 la cabeza con una sonrisa sarc\u00e1stica cuando Cohen admiti\u00f3 que estaba decepcionado por no haber sido considerado para secretario general cuando Trump asumi\u00f3 el cargo.<\/p>\n<p>Crece el s\u00e9quito de Trump para el testimonio de Cohen<\/p>\n<p>A lo largo de las cuatro semanas que lleva el juicio, Trump ha recurrido a tener partidarios en el tribunal, tanto en las calles fuera del tribunal de Manhattan como dentro de los confines de la sala del juez Juan Merchan, y se ha quejado de no tener m\u00e1s apoyo.<\/p>\n<p>La semana pasada, el hijo de Trump, Eric Trump; su principal asesora de campa\u00f1a, Susie Wiles; y el senador Rick Scott, de Florida, aparecieron en la tribuna detr\u00e1s del expresidente.<\/p>\n<p>El lunes, Trump cont\u00f3 con su mayor s\u00e9quito de legisladores del Partido Republicano hasta la fecha, incluidos los posibles aspirantes a la vicepresidencia.<\/p>\n<p>Los senadores J.D. Vance, de Ohio, y Tommy Tuberville, de Alabama, estuvieron en la tribuna, al igual que la representante por Nueva York, Nicole Malliotakis, de Staten Island, af\u00edn a Trump, y los fiscales generales de Alabama y Iowa se unieron a Trump en el testimonio de alto perfil de Cohen, sentados en la galer\u00eda detr\u00e1s del expresidente en la mesa del acusado. Eric Trump y la abogada Alina Habba tambi\u00e9n estuvieron all\u00ed para apoyar a Trump.<\/p>\n<p>Los pol\u00edticos republicanos estuvieron detr\u00e1s de Trump mientras daba su nueva conferencia antes de entrar en la sala del tribunal el lunes por la ma\u00f1ana. Y tras el primer receso de la ma\u00f1ana, salieron a dar su propia versi\u00f3n ante las c\u00e1maras para denunciar el procedimiento que acababan de presenciar.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Michael Cohen implic\u00f3 a su exjefe Donald Trump en el esquema de pago de dinero por silencio a Stormy Daniels pocos d\u00edas antes de las elecciones de 2016, diciendo que entreg\u00f3 US$ 130.000 bajo la direcci\u00f3n de Trump y se le prometi\u00f3 el reembolso. El testimonio de Cohen vincula las acusaciones de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449441","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Michael Cohen implic\u00f3 a su exjefe Donald Trump en el esquema de pago de dinero por silencio a Stormy Daniels pocos d\u00edas antes de las elecciones de 2016, diciendo que entreg\u00f3 US$ 130.000 bajo la direcci\u00f3n de Trump y se le prometi\u00f3 el reembolso. El testimonio de Cohen vincula las acusaciones de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-14T00:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen\",\"datePublished\":\"2024-05-14T00:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/\"},\"wordCount\":2055,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/\",\"name\":\"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-14T00:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen - Noticias","og_description":"(CNN) &#8212; Michael Cohen implic\u00f3 a su exjefe Donald Trump en el esquema de pago de dinero por silencio a Stormy Daniels pocos d\u00edas antes de las elecciones de 2016, diciendo que entreg\u00f3 US$ 130.000 bajo la direcci\u00f3n de Trump y se le prometi\u00f3 el reembolso. El testimonio de Cohen vincula las acusaciones de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-14T00:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/"},"author":{"name":"","@id":""},"headline":"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen","datePublished":"2024-05-14T00:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/"},"wordCount":2055,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/","name":"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-14T00:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Conclusiones del d\u00eda 16 del juicio penal contra Donald Trump: primer d\u00eda de testimonio de Michael Cohen","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/13\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-14T00:03:43Z","datePublished":"2024-05-14T00:03:43Z","dateModified":"2024-05-14T00:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Conclusiones del d\\u00eda 16 del juicio penal contra Donald Trump: primer d\\u00eda de testimonio de Michael Cohen\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/13\\\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/13\\\/conclusiones-dia-16-juicio-penal-donald-trump-testimonio-michael-cohen-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-14T00:03:43Z\",\"datePublished\":\"2024-05-14T00:03:43Z\",\"dateModified\":\"2024-05-14T00:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449393,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/10\/conclusiones-dia-15-juicio-penal-donald-trump-dinero-silencio-trax\/","url_meta":{"origin":1449441,"position":0},"title":"Conclusiones del d\u00eda 15 del juicio penal a Donald Trump por el pago de dinero por silencio","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN) --\u00a0Una de las asesoras m\u00e1s cercanas de Donald Trump en la Casa Blanca termin\u00f3 su testimonio este viernes en el juicio del expresidente por el dinero pago de dinero por silencio, despejando el camino para que el testigo clave de la fiscal\u00eda suba al estrado el lunes.Se espera que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449634,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/conclusiones-ultimo-dia-testimonios-juicio-penal-donald-trump-trax\/","url_meta":{"origin":1449441,"position":1},"title":"Conclusiones del \u00faltimo d\u00eda de testimonios en el juicio penal contra Donald Trump por pagos de silencio","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN) --\u00a0La defensa concluy\u00f3 este martes la presentaci\u00f3n de su caso en el juicio penal de Donald Trump por el pago de dinero por silencio, tras unos 90 minutos de testimonios y sin que el expresidente subiera al estrado.Los abogados de Trump llamaron a dos testigos: un asistente legal que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448801,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/02\/conclusiones-decimo-juicio-trump-pagos-dinero-silencio-trax\/","url_meta":{"origin":1449441,"position":2},"title":"Conclusiones del d\u00e9cimo d\u00eda del juicio a Trump por pagos de dinero por silencio","author":"","date":"mayo 2, 2024","format":false,"excerpt":"(CNN) -- Este jueves, los abogados de Donald Trump trataron de pintar a uno de los testigos en el coraz\u00f3n del acuerdo de dinero por silencio con Stormy Daniels como alguien con un largo historial de obtener dinero de celebridades mientras va \"hasta la raya sin cometer extorsi\u00f3n\".El abogado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449610,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/20\/conclusiones-dia-19-juicio-penal-donald-trump-trax\/","url_meta":{"origin":1449441,"position":3},"title":"Conclusiones del d\u00eda 19 del juicio penal a Donald Trump por el pago de dinero por silencio","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN) -- La fiscal\u00eda concluy\u00f3 su caso contra Donald J. Trump este lunes en el juicio del expresidente por el pago de dinero por silencio, que se dirige hacia una conclusi\u00f3n tan pronto como la pr\u00f3xima semana.El testimonio de Michael Cohen finalmente termin\u00f3 este lunes despu\u00e9s de cuatro d\u00edas, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449829,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/29\/conclusiones-alegatos-finales-juicio-donald-trump-pago-dinero-silencio-trax\/","url_meta":{"origin":1449441,"position":4},"title":"Conclusiones de los alegatos finales en el juicio de Donald Trump por pago de dinero por silencio","author":"","date":"mayo 29, 2024","format":false,"excerpt":"(CNN) -- Los fiscales dijeron a los miembros del jurado este martes que vieron una \"monta\u00f1a de pruebas\" para demostrar que Donald Trump falsific\u00f3 registros empresariales con el fin de encubrir una historia perjudicial sobre un supuesto amor\u00edo al final de las elecciones de 2016.Los abogados de Trump dijeron al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448438,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/23\/conclusiones-sexta-jornada-juicio-penal-donald-trump-trax\/","url_meta":{"origin":1449441,"position":5},"title":"Conclusiones de la sexta jornada del juicio penal a Donald Trump por el pago de dinero por silencio","author":"","date":"abril 23, 2024","format":false,"excerpt":"Nueva York (CNN) -- El juez Juan Merchan parec\u00eda dispuesto este martes a sancionar a Donald Trump por violar la orden de silencio en su caso penal relacionado con el pago de dinero por silencio, despu\u00e9s de interrogar a los abogados del expresidente sobre por qu\u00e9 las publicaciones de Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449441"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449441\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}