{"id":1449506,"date":"2024-05-15T23:03:45","date_gmt":"2024-05-16T06:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/"},"modified":"2024-05-15T23:03:45","modified_gmt":"2024-05-16T06:03:45","slug":"reina-camila-no-sumara-pieles-nuevas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/","title":{"rendered":"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa"},"content":{"rendered":"<p>(CNN) &#8212; El Palacio de Buckingham le escribi\u00f3 a un grupo que lucha por los derechos de los animales para confirmar que la reina Camila ya no comprar\u00e1 ropa que incluya pieles de animales.<\/p>\n<p>La carta enviada a People for the Ethical Treatment of Animals (PETA), a la que CNN tuvo acceso, dec\u00eda que: \u201cSu Majestad no adquirir\u00e1 ninguna prenda de piel nueva\u201d. Sin embargo, no est\u00e1 claro cu\u00e1l es la posici\u00f3n de la Reina con respecto a los art\u00edculos de piel en su guardarropa actual.<\/p>\n<p>La medida sigue una postura similar adoptada por su difunta suegra, la reina Isabel II, quien descart\u00f3 comprar nuevos productos de piel en 2019.<\/p>\n<p>La correspondencia del Palacio fue en respuesta a una carta enviada por PETA a la reina en abril. All\u00ed, Elisa Allen, vicepresidenta de programas y operaciones de la organizaci\u00f3n en el Reino Unido, detalla las pr\u00e1cticas crueles que, seg\u00fan dice, se emplean en la industria de pieles, as\u00ed como su impacto en el medio ambiente.<\/p>\n<p>Victoria Beckham proh\u00edbe las pieles de animales en su l\u00ednea de moda<\/p>\n<p>La fundadora de la organizaci\u00f3n ben\u00e9fica, Ingrid Newkirk, acogi\u00f3 con satisfacci\u00f3n la noticia. En una declaraci\u00f3n enviada a CNN, dijo: \u201cPETA brinda por la reina Camila con una copa del mejor clarete por ser una verdadera reina al apoyar al 95% de los brit\u00e1nicos que tambi\u00e9n se niegan a usar pieles de animales, como muestran las encuestas&#187;.<\/p>\n<p>La noticia de la decisi\u00f3n tomada por la reina Isabel II fue divulgada por su asistente principal, Angela Kelly. En su libro \u201cThe Other Side of the Coin: The Queen, the Dresser and the Wardrobe\u201d, Kelly escribi\u00f3: \u201cSi Su Majestad debe asistir a un compromiso en un clima particularmente fr\u00edo, a partir de 2019 se utilizar\u00e1n pieles sint\u00e9ticas para garantizar que ella se mantenga caliente\u201d.<\/p>\n<p>PETA alienta a los propietarios a donar art\u00edculos existentes a su \u201cprograma de amnist\u00eda de pieles\u201d, que los env\u00eda a \u201cpersonas sin hogar, refugiados y personas en \u00e1reas devastadas por la guerra para ayudarlos a mantenerse calientes en los meses de invierno\u201d. En su sitio web explica el motivo: &#171;No podemos recuperar a los animales que sufrieron por estos abrigos, pero podemos utilizar pieles viejas para ayudar a los humanos que las necesitan desesperadamente&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El Palacio de Buckingham le escribi\u00f3 a un grupo que lucha por los derechos de los animales para confirmar que la reina Camila ya no comprar\u00e1 ropa que incluya pieles de animales. La carta enviada a People for the Ethical Treatment of Animals (PETA), a la que CNN tuvo acceso, dec\u00eda que: \u201cSu [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449506","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El Palacio de Buckingham le escribi\u00f3 a un grupo que lucha por los derechos de los animales para confirmar que la reina Camila ya no comprar\u00e1 ropa que incluya pieles de animales. La carta enviada a People for the Ethical Treatment of Animals (PETA), a la que CNN tuvo acceso, dec\u00eda que: \u201cSu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-16T06:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa\",\"datePublished\":\"2024-05-16T06:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/\",\"name\":\"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-16T06:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa - Noticias","og_description":"(CNN) &#8212; El Palacio de Buckingham le escribi\u00f3 a un grupo que lucha por los derechos de los animales para confirmar que la reina Camila ya no comprar\u00e1 ropa que incluya pieles de animales. La carta enviada a People for the Ethical Treatment of Animals (PETA), a la que CNN tuvo acceso, dec\u00eda que: \u201cSu [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-16T06:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/"},"author":{"name":"","@id":""},"headline":"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa","datePublished":"2024-05-16T06:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/","name":"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-16T06:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La reina Camila no sumar\u00e1 pieles nuevas a su guardarropa","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/15\/reina-camila-no-sumara-pieles-nuevas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-16T06:03:45Z","datePublished":"2024-05-16T06:03:45Z","dateModified":"2024-05-16T06:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La reina Camila no sumar\\u00e1 pieles nuevas a su guardarropa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/15\\\/reina-camila-no-sumara-pieles-nuevas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/15\\\/reina-camila-no-sumara-pieles-nuevas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-16T06:03:45Z\",\"datePublished\":\"2024-05-16T06:03:45Z\",\"dateModified\":\"2024-05-16T06:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458377,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/02\/06\/rey-carlos-reina-camila-papa-francisco-trax\/","url_meta":{"origin":1449506,"position":0},"title":"El rey Carlos y la reina Camila visitar\u00e1n al papa Francisco","author":"","date":"febrero 6, 2025","format":false,"excerpt":"El rey Carlos y la reina Camila viajar\u00e1n a Italia y al Vaticano en abril para reunirse con el papa Francisco, mientras la Iglesia Cat\u00f3lica celebra un a\u00f1o jubilar especial, que tiene lugar cada cuarto de siglo.El monarca brit\u00e1nico se unir\u00e1 a las 32 millones de personas que se espera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446194,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/02\/interrumpen-desfile-victoria-beckha-semana-moda-paris-manifestantes-derechos-animales-trax\/","url_meta":{"origin":1449506,"position":1},"title":"Interrumpen desfile de Victoria Beckham en la Semana de la Moda de Par\u00eds por manifestantes por los derechos de los animales","author":"","date":"marzo 2, 2024","format":false,"excerpt":"(CNN) --\u00a0 El desfile de Victoria Beckham en la Semana de la Moda de Par\u00eds fue interrumpido por activistas por los derechos de los animales cuando se unieron a sus modelos en la pasarela para protestar por el uso de productos animales como el cuero por parte de su marca.Manifestantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446450,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/04\/interrumpen-desfile-victoria-beckha-semana-moda-paris-manifestantes-derechos-animales-trax-2\/","url_meta":{"origin":1449506,"position":2},"title":"Interrumpen desfile de Victoria Beckham en la Semana de la Moda de Par\u00eds por manifestantes por los derechos de los animales","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) --\u00a0 El desfile de Victoria Beckham en la Semana de la Moda de Par\u00eds fue interrumpido por activistas por los derechos de los animales cuando se unieron a sus modelos en la pasarela para protestar por el uso de productos animales como el cuero por parte de su marca.Manifestantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473203,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/15\/carlos-visita-eeuu-trump-congreso-trax\/","url_meta":{"origin":1449506,"position":3},"title":"Carlos III hablar\u00e1 ante una sesi\u00f3n conjunta del Congreso y se reunir\u00e1 con Trump durante su visita de Estado a EE.UU.","author":"","date":"abril 15, 2026","format":false,"excerpt":"El rey Carlos III del Reino Unido se dirigir\u00e1 a una sesi\u00f3n conjunta del Congreso y se reunir\u00e1 en privado con el presidente de Estados Unidos, Donald Trump, durante su visita de Estado a EE.UU. a finales de este mes, anunci\u00f3 este martes el Palacio de Buckingham.Entre el 27 y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463418,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/06\/10\/vestidos-princesa-diana-subasta-realeza-trax\/","url_meta":{"origin":1449506,"position":4},"title":"Vestidos de la princesa Diana protagonizan la subasta &#171;m\u00e1s grande&#187; de moda de la difunta integrante de la realeza","author":"","date":"junio 10, 2025","format":false,"excerpt":"El traje de esqu\u00ed de la princesa Diana, un bolso Dior que le regal\u00f3 la primera dama de Francia y el vestido floral que us\u00f3 para visitar a ni\u00f1os en un hospital se encuentran entre decenas de art\u00edculos del guardarropa de la difunta integrante de la realeza que ser\u00e1n subastados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448557,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/26\/rey-carlos-funciones-publicas-trax\/","url_meta":{"origin":1449506,"position":5},"title":"El rey Carlos III volver\u00e1 a sus funciones p\u00fablicas la pr\u00f3xima semana","author":"","date":"abril 26, 2024","format":false,"excerpt":"(CNN) -- El rey Carlos III del Reino Unido reanudar\u00e1 sus funciones p\u00fablicas la pr\u00f3xima semana tras \"un per\u00edodo de tratamiento y recuperaci\u00f3n\", anunci\u00f3 este viernes el Palacio de Buckingham, dos meses despu\u00e9s de revelar que el monarca estaba siendo tratado por c\u00e1ncer.Carlos, de 75 a\u00f1os acompa\u00f1ar\u00e1 a su esposa,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449506"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449506\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}