{"id":1449569,"date":"2024-05-17T19:03:50","date_gmt":"2024-05-18T02:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/"},"modified":"2024-05-17T19:03:50","modified_gmt":"2024-05-18T02:03:50","slug":"ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/","title":{"rendered":"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0La muerte de la candidata a alcaldesa Lucero L\u00f3pez Maza en el municipio de La Concordia, en Chiapas, en un ataque que dej\u00f3 otros cinco fallecidos, volvi\u00f3 a manchar de sangre la campa\u00f1a electoral en el estado mexicano, donde operan grupos criminales de tr\u00e1fico de drogas y de migrantes.<\/p>\n<p>La Fiscal\u00eda General de Chiapas inform\u00f3 que la Polic\u00eda Estatal confirm\u00f3 la muerte de tres mujeres, una de ellas menor de edad, y tres hombres, todos por impacto de proyectil de arma de fuego.<\/p>\n<p>El Instituto de Elecciones y Participaci\u00f3n Ciudadana confirm\u00f3 en un comunicado la muerte de la candidata L\u00f3pez Maza, del Partido Popular Chiapaneco, y rechaz\u00f3 los hechos violentos que &#171;generan temor e incertidumbre entre la ciudadan\u00eda&#187;.<\/p>\n<p>Por su parte, el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo que \u201cen esa regi\u00f3n \u00faltimamente ha habido varios enfrentamientos\u201d. Pero tambi\u00e9n critic\u00f3 la cobertura period\u00edstica: &#171;Se lucra bastante con los asesinatos y con el dolor humano, es temporada de zopilotes&#187;.<\/p>\n<p>Una campa\u00f1a marcada por la violencia<\/p>\n<p>M\u00e9xico se acerca a sus elecciones presidenciales, legislativas y estatales, previstas para el 2 de junio. Desde que se inici\u00f3 oficialmente el proceso electoral en septiembre, y hasta el 1 de mayo, un promedio de al menos dos personas al d\u00eda, vinculadas al \u00e1mbito pol\u00edtico-electoral de M\u00e9xico, sufren alg\u00fan tipo de violencia, seg\u00fan el m\u00e1s reciente informe de la consultora privada Integralia. Las cifras oficiales son inferiores.<\/p>\n<p>Violencia pol\u00edtica nubla el panorama electoral en M\u00e9xico<\/p>\n<p>La violencia ha ido en aumento en el estado sure\u00f1o, que comparte frontera con Guatemala, mientras los c\u00e1rteles luchan por el control de rutas lucrativas para los migrantes y el contrabando de drogas. El cartel de Sinaloa y el cartel de Jalisco Nueva Generaci\u00f3n han estado involucrados en una guerra territorial en el \u00e1rea, y cientos de personas se vieron obligadas a huir de sus hogares en enero.<\/p>\n<p>(Cr\u00e9dito: Instituto Electoral de la Ciudad de M\u00e9xico)<\/p>\n<p>Otros ataques en Chiapas<\/p>\n<p>Esta misma semana, 11 personas murieron en tiroteos masivos en el municipio vecino de Chicomuselo, dijo el fiscal del estado.<\/p>\n<p>Sin dar m\u00e1s detalles del hecho violento, la Fiscal\u00eda dijo en un comunicado que elementos de investigaci\u00f3n hicieron el levantamiento de los cuerpos acompa\u00f1ados de familiares de las v\u00edctimas para su identificaci\u00f3n. CNN contact\u00f3 a la subsecretar\u00eda de Gobierno de Chiapas para tener m\u00e1s informaci\u00f3n del hecho, sin que hasta el momento tenga m\u00e1s informaci\u00f3n reportable.<\/p>\n<p>En las elecciones generales de M\u00e9xico, una ola de asesinatos ha puesto a la propia democracia en el punto de mira<\/p>\n<p>En abril, la candidata presidencial del oficialismo, Claudia Sheinbaum, fue abordada por hombres encapuchados durante una gira de campa\u00f1a por Chiapas. Los individuos le pidieron a Sheinbaum que, de llegar al poder, no se olvide de los problemas de seguridad que sufre la zona serrana.<\/p>\n<p>Luego de que L\u00f3pez Obrador minimizara el hecho y dijera que el incidente podr\u00eda ser un montaje con propaganda de opositores, un grupo de encapuchados grab\u00f3 un mensaje en el que uno respondi\u00f3: \u201cEsto no es un montaje, esto es real, esto que est\u00e1n viendo ustedes, como encapuchados, es real\u201d. CNN no ha podido verificar que las personas en el video sean las mismas que las del episodio con Sheinbaum.<\/p>\n<p>Semanas antes, tambi\u00e9n en abril, dos eventos con civiles armados dejaron 10 personas muertas, un agente de la Guardia Nacional herido y 13 guatemaltecos detenidos, inform\u00f3 la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana de M\u00e9xico.<\/p>\n<p>Al respecto, el primer enfrentamiento entre civiles se report\u00f3 en el municipio de La Concordia, donde se hallaron cinco hombres muertos, seg\u00fan inform\u00f3 la instituci\u00f3n federal. Horas despu\u00e9s, report\u00f3 la Secretar\u00eda, agentes de la Guardia Nacional fueron agredidos por civiles armados, por lo que repelieron la agresi\u00f3n, en un episodio que dej\u00f3 otros cinco hombres muertos, un agente de la Guardia Nacional herido y la detenci\u00f3n de 13 ciudadanos guatemaltecos en posesi\u00f3n de armas largas, cargadores, chalecos t\u00e1cticos y dos veh\u00edculos.<\/p>\n<p>CNN report\u00f3 en enero que la violencia asola la zona de Chicomuselo, lo que ha provocado el desplazamiento de cientos de habitantes de comunidades pertenecientes a ese municipio debido a la presencia de grupos del crimen organizado en disputa del territorio.<\/p>\n<p>Este viernes, el Gobierno de M\u00e9xico public\u00f3 en X que Chiapas y Yucat\u00e1n son los estados con la tasa de homicidios m\u00e1s baja por cada 100.000 habitantes a nivel nacional.<\/p>\n<p>L\u00edderes mexicanos han prometido una r\u00e1pida persecuci\u00f3n y han puesto en marcha un esfuerzo para proteger a los candidatos en peligro con escoltas armados. Pero algunos analistas y responsables de los partidos advierten que la violencia ya ha enfriado algunas campa\u00f1as; decenas de candidatos de varios estados han renunciado a sus candidaturas temiendo por sus vidas.<\/p>\n<p>Con informaci\u00f3n de Gerardo Lemos, Ivonne Vald\u00e9s, Rey Rodr\u00edguez y David Shortell<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0La muerte de la candidata a alcaldesa Lucero L\u00f3pez Maza en el municipio de La Concordia, en Chiapas, en un ataque que dej\u00f3 otros cinco fallecidos, volvi\u00f3 a manchar de sangre la campa\u00f1a electoral en el estado mexicano, donde operan grupos criminales de tr\u00e1fico de drogas y de migrantes. La Fiscal\u00eda General de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449569","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0La muerte de la candidata a alcaldesa Lucero L\u00f3pez Maza en el municipio de La Concordia, en Chiapas, en un ataque que dej\u00f3 otros cinco fallecidos, volvi\u00f3 a manchar de sangre la campa\u00f1a electoral en el estado mexicano, donde operan grupos criminales de tr\u00e1fico de drogas y de migrantes. La Fiscal\u00eda General de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-18T02:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico\",\"datePublished\":\"2024-05-18T02:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/\"},\"wordCount\":887,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/\",\"name\":\"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-18T02:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0La muerte de la candidata a alcaldesa Lucero L\u00f3pez Maza en el municipio de La Concordia, en Chiapas, en un ataque que dej\u00f3 otros cinco fallecidos, volvi\u00f3 a manchar de sangre la campa\u00f1a electoral en el estado mexicano, donde operan grupos criminales de tr\u00e1fico de drogas y de migrantes. La Fiscal\u00eda General de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-18T02:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico","datePublished":"2024-05-18T02:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/"},"wordCount":887,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/","name":"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-18T02:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-18T02:03:50Z","datePublished":"2024-05-18T02:03:50Z","dateModified":"2024-05-18T02:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo escal\\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/17\\\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/17\\\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-18T02:03:50Z\",\"datePublished\":\"2024-05-18T02:03:50Z\",\"dateModified\":\"2024-05-18T02:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449541,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/17\/seis-muertos-hechos-violentos-la-concordia-chiapas-en-mexico\/","url_meta":{"origin":1449569,"position":0},"title":"Tiroteo durante un acto de campa\u00f1a en La Concordia, Chiapas: una candidata a alcaldesa entre los seis muertos","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La Fiscal\u00eda General de Chiapas inform\u00f3 este jueves a trav\u00e9s de un comunicado que se reportaron seis personas muertas y dos heridos por hechos violentos durante un acto pol\u00edtico en el municipio de La Concordia, Chiapas, en M\u00e9xico.Las autoridades informaron que la Polic\u00eda Estatal confirm\u00f3 la muerte de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448384,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/","url_meta":{"origin":1449569,"position":1},"title":"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo este lunes que el incidente que tuvo la candidata presidencial del oficialismo Claudia Sheinbaum durante su gira de campa\u00f1a por Chiapas el domingo, en donde fue abordada por hombres encapuchados en su paso por la sierra, podr\u00eda ser\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451417,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/25\/presidente-arevalo-atencion-mexicanos-guatemala-orix\/","url_meta":{"origin":1449569,"position":2},"title":"El presidente Ar\u00e9valo asegura que est\u00e1n atendiendo a mexicanos que buscaron refugio en Guatemala","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Las autoridades de Guatemala est\u00e1n atendiendo a los mexicanos que han cruzado la frontera con el estado mexicano de Chiapas\u00a0en busca de refugio, asegur\u00f3 este jueves el presidente del pa\u00eds, Bernardo Ar\u00e9valo.El Gobierno centroamericano no ha informado cu\u00e1ntas personas cruzaron la frontera y CNN intenta determinar cu\u00e1ntos son.Los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446041,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/","url_meta":{"origin":1449569,"position":3},"title":"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico","author":"","date":"febrero 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0En apenas una d\u00e9cada, el mapa electoral de M\u00e9xico ha pasado de la hegemon\u00eda del Partido Revolucionario Institucional (PRI) al dominio de Morena, el partido fundado por el actual presidente, Andr\u00e9s Manuel L\u00f3pez Obrador.En seis a\u00f1os, Morena logr\u00f3 posicionarse como la primera fuerza pol\u00edtica. Los datos hablan por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463061,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/05\/31\/instituto-electoral-denuncia-robo-boletas-chiapas-orix\/","url_meta":{"origin":1449569,"position":4},"title":"El Instituto electoral de M\u00e9xico denuncia el robo de m\u00e1s de 131.000 boletas en Chiapas","author":"","date":"mayo 31, 2025","format":false,"excerpt":"El Instituto Nacional Electoral de M\u00e9xico (INE) denunci\u00f3 este s\u00e1bado el robo de 25 paquetes electorales con m\u00e1s de 131.000 boletas en el estado de Chiapas, en el sur del pa\u00eds, inform\u00f3 la consejera presidenta del organismo, Guadalupe Taddei.La funcionaria dio a conocer el hecho durante una conferencia de prensa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455265,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/10\/20\/chiapas-investiga-muerte-parroco-perez-orix\/","url_meta":{"origin":1449569,"position":5},"title":"Fiscal\u00eda de Chiapas investiga la muerte del p\u00e1rroco Marcelo P\u00e9rez P\u00e9rez","author":"","date":"octubre 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La Fiscal\u00eda del estado mexicano de Chiapas investiga el homicidio del padre Marcelo P\u00e9rez P\u00e9rez, registrado en el barrio de Cuxtitali, en la ciudad de San Crist\u00f3bal de Las Casas, inform\u00f3 la instituci\u00f3n en un comunicado publicado este domingo en su perfil de Facebook.El sacerdote era p\u00e1rroco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449569"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449569\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}