{"id":1449584,"date":"2024-05-19T12:03:44","date_gmt":"2024-05-19T19:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/"},"modified":"2024-05-19T12:03:44","modified_gmt":"2024-05-19T19:03:44","slug":"quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/","title":{"rendered":"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Ebrahim Raisi, cl\u00e9rigo ultraconservador y exjefe judicial de Ir\u00e1n, fue electo presidente el 18 de junio de 2021 luego de que el Consejo de Guardianes vetara la participaci\u00f3n de los principales candidatos reformistas y centristas. \u00bfQui\u00e9n es exactamente Raisi?<\/p>\n<p>Pr\u00e1cticamente sin oposici\u00f3n, Raisi obtuvo casi 18 millones de votos &#8211;o cerca del 62% del total&#8211;, de acuerdo a la agencia estatal iran\u00ed IRNA y jur\u00f3 el 5 de agosto de 2021.\u00a0En tanto la participaci\u00f3n fue del 48%, muy por debajo del 72% de las \u00faltimas elecciones y una posible se\u00f1al del desencanto del electorado. Aunque las autoridades iran\u00edes sostuvieron en ese momento que esto se debi\u00f3 exclusivamente debido a la pandemia de covid-19 de ese entonces.<\/p>\n<p>Helic\u00f3ptero que transportaba al presidente de Ir\u00e1n Ebrahim Raisi &#171;experiment\u00f3 un incidente&#187;, dice agencia de noticias iran\u00ed<\/p>\n<p>Reemplaz\u00f3 de esta manera al moderado Hassan Rouhani, dos veces presidente de Ir\u00e1n.<\/p>\n<p>Raisi, exjefe judicial de Ir\u00e1n, centr\u00f3 su campa\u00f1a en una plataforma anti-corrupci\u00f3n, en un aparente intento de apaciguar las frustraciones de los votantes frente a una econom\u00eda en crisis (40% de inflaci\u00f3n, 11% de desempleo y ca\u00edda del 6% del PIB dos a\u00f1os consecutivos), atribuida a las sanciones de Estados Unidos para frenar el programa nuclear iran\u00ed.<\/p>\n<p>Ebrahim Raisi, presidente electo de Ir\u00e1n.<\/p>\n<p>A Raisi tambi\u00e9n se lo recuerda por su brutal historial en materia de derechos humanos y su rol en la represi\u00f3n de la oposici\u00f3n.<\/p>\n<p>Tanto el\u00a0Centro de Derechos Humanos de Ir\u00e1n (CHRI, por sus siglas en ingl\u00e9s)\u00a0como la organizaci\u00f3n\u00a0Human Rights Watch\u00a0y\u00a0Amnist\u00eda Internacional lo han acusado formar parte de un &#171;comit\u00e9 de la muerte&#187; que en 1988 habr\u00eda supervisado la ejecuci\u00f3n de miles de personas.<\/p>\n<p>Sus dos a\u00f1os como presidente del Tribunal Supremo de Ir\u00e1n estuvieron marcados por la intensificaci\u00f3n de la represi\u00f3n de la disidencia y los abusos de los derechos humanos, seg\u00fan la CHRI. Entre las muchas medidas de l\u00ednea dura de su mandato se encuentra la primera ejecuci\u00f3n en d\u00e9cadas de un hombre por consumo de alcohol.<\/p>\n<p>Raisi, un cl\u00e9rigo musulm\u00e1n que muchos consideran posible sucesor del actual l\u00edder supremo, Ali Khamenei, no ha respondido p\u00fablicamente a estas acusaciones.<\/p>\n<p>En los inicios de la Revoluci\u00f3n isl\u00e1mica<\/p>\n<p>Raisi naci\u00f3 en 1960 en Mashhad, unos 740 kil\u00f3metros al este de Teher\u00e1n, dentro de una familia clerical y recibi\u00f3 una formaci\u00f3n religiosa en la ciudad de Qom, uno de los sitios centrales del islam chiita.<\/p>\n<p>El l\u00edder supremo de Ir\u00e1n, ayatola Ali Khamenei. En el fondo, arriba, retrato de Ruhollah Khomeini, su antecesor.<\/p>\n<p>Raisi entr\u00f3 en contacto con las ideas de Ruhollah Khomeini, l\u00edder de la Revoluci\u00f3n isl\u00e1mica, tras su arribo a Qom en 1975, de acuerdo a su biograf\u00eda oficial. R\u00e1pidamente se hizo militante de la causa que promulgaba el control del clero sobre el estado, un concepto conocido como &#171;Vel\u0101yat-e faq\u012bh&#187;, o gobierno del jurista isl\u00e1mico.<\/p>\n<p>El \u00e9xito de la Revoluci\u00f3n en 1979 llev\u00f3 al monarca Mohammad Reza Shah Pahlavi al exilio y la instauraci\u00f3n de un gobierno bajo este sistema de rep\u00fablica isl\u00e1mica, con Khomeini como primer l\u00edder supremo.<\/p>\n<p>Raisi, miembro del orden religioso, se convirti\u00f3 tambi\u00e9n en fiscal en los inicios de este nuevo r\u00e9gimen y contribuy\u00f3 al apuntalamiento del gobierno frente a la oposici\u00f3n.<\/p>\n<p>En 1985 se convirti\u00f3 en vicefiscal general de Teher\u00e1n desde 1985, en medio de la brutal guerra con Iraq que dur\u00f3 entre 1980 y 1988<\/p>\n<p>En 1988, el a\u00f1o en que termin\u00f3 la guerra, habr\u00eda integrado el &#171;comit\u00e9 de la muerte&#187; y un a\u00f1o despu\u00e9s se convirti\u00f3 en fiscal de Teher\u00e1n, cargo que ocup\u00f3 hasta 1994.<\/p>\n<p>Una larga carrera hacia la presidencia de Ir\u00e1n<\/p>\n<p>Tras el ascenso de Ali Khamenei, actual l\u00edder supremo tras la muerte de Ruhollah Khomenei en 1989, Raisi continu\u00f3 avanzando en su carrera: dirigi\u00f3 la Organizaci\u00f3n General de Inspecci\u00f3n entre 1994 y 2004, se convirti\u00f3 en fiscal general de la Tribunal Clerical Especial (2012) y fue vicejefe de justicia entre 2004 y 2014, largo en el cual contribuy\u00f3 a la represi\u00f3n de las protestas de 2009 tras unas elecciones presidenciales empa\u00f1adas por denuncias de presunto fraude.<\/p>\n<p>Su perfil p\u00fablico comenz\u00f3 a crecer en 2016 cuando Raisi se convirti\u00f3 en custodio del santuario del imam Al\u012b al-Ri\u1e0d\u0101 en Mashhad, lo que signific\u00f3 estar al frente de activos valuados en miles de millones de d\u00f3lares y uno de los fondos de caridad m\u00e1s importantes de Ir\u00e1n.<\/p>\n<p>Raisi mantuvo este cargo hasta el 2019, cuando fue designado jefe judicial de la Rep\u00fablica Isl\u00e1mica de Ir\u00e1n, su ocupaci\u00f3n actual.<\/p>\n<p>Sus aspiraciones pol\u00edticas quedaron claras en 2017, cuando cobr\u00f3 notoriedad compitiendo en las elecciones presidenciales bajo su plataforma contra la corrupci\u00f3n. En esta \u00faltima ocasi\u00f3n fue derrotado por el moderado Hassan Rouhani, que logr\u00f3 la reelecci\u00f3n.<\/p>\n<p>Pero con los principales candidatos descalificados por el Consejo de Guardianes, y una participaci\u00f3n mucho m\u00e1s baja que en 2017, Raisi al parecer tuvo su revancha en 2021.<\/p>\n<p>Un gobierno marcado por tensiones con Occidente y la guerra en Gaza<\/p>\n<p>En junio de 2021, en su primera conferencia de prensa internacional desde que fue elegido presidente, Raisi afirm\u00f3 que no se reunir\u00eda con el presidente estadounidense Joe Biden, incluso si ambas partes accordaban los t\u00e9rminos para reactivar el acuerdo nuclear de 2015, en virtud del cual Ir\u00e1n se hab\u00eda comprometido a detener el enriquecimiento de uranio a cambio del levantamiento de las paralizantes sanciones estadounidenses.<\/p>\n<p>Respondiendo a una pregunta de CNN, Raisi acus\u00f3 en ese momento a Estados Unidos y a la Uni\u00f3n Europea de violar el acuerdo y pidi\u00f3 a Biden que levante todas las sanciones, antes de a\u00f1adir que el programa de misiles bal\u00edsticos de Ir\u00e1n &#171;no est\u00e1 sujeto a negociaci\u00f3n&#187;.<\/p>\n<p>Mientras que en noviembre de 2023, Raisi asisti\u00f3 a una cumbre en Arabia Saudita en la que l\u00edderes \u00e1rabes y musulmanes condenaron los &#171;cr\u00edmenes de guerra&#187; israel\u00edes en Gaza. En su intervenci\u00f3n en la cumbre, Raisi dijo que &#171;nos hemos reunido hoy aqu\u00ed para discutir el centro de atenci\u00f3n del mundo isl\u00e1mico, que es la causa palestina, donde hemos sido testigos de los peores cr\u00edmenes de la historia&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Ebrahim Raisi, cl\u00e9rigo ultraconservador y exjefe judicial de Ir\u00e1n, fue electo presidente el 18 de junio de 2021 luego de que el Consejo de Guardianes vetara la participaci\u00f3n de los principales candidatos reformistas y centristas. \u00bfQui\u00e9n es exactamente Raisi? Pr\u00e1cticamente sin oposici\u00f3n, Raisi obtuvo casi 18 millones de votos &#8211;o cerca del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449584","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Ebrahim Raisi, cl\u00e9rigo ultraconservador y exjefe judicial de Ir\u00e1n, fue electo presidente el 18 de junio de 2021 luego de que el Consejo de Guardianes vetara la participaci\u00f3n de los principales candidatos reformistas y centristas. \u00bfQui\u00e9n es exactamente Raisi? Pr\u00e1cticamente sin oposici\u00f3n, Raisi obtuvo casi 18 millones de votos &#8211;o cerca del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-19T19:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n\",\"datePublished\":\"2024-05-19T19:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/\"},\"wordCount\":1108,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/\",\"name\":\"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-19T19:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Ebrahim Raisi, cl\u00e9rigo ultraconservador y exjefe judicial de Ir\u00e1n, fue electo presidente el 18 de junio de 2021 luego de que el Consejo de Guardianes vetara la participaci\u00f3n de los principales candidatos reformistas y centristas. \u00bfQui\u00e9n es exactamente Raisi? Pr\u00e1cticamente sin oposici\u00f3n, Raisi obtuvo casi 18 millones de votos &#8211;o cerca del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-19T19:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/"},"author":{"name":"","@id":""},"headline":"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n","datePublished":"2024-05-19T19:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/"},"wordCount":1108,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/","name":"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-19T19:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-19T19:03:44Z","datePublished":"2024-05-19T19:03:44Z","dateModified":"2024-05-19T19:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Qui\\u00e9n es Ebrahim Raisi, el cl\\u00e9rigo conservador y juez controversial que se convirti\\u00f3 en presidente de Ir\\u00e1n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/19\\\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/19\\\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-19T19:03:44Z\",\"datePublished\":\"2024-05-19T19:03:44Z\",\"dateModified\":\"2024-05-19T19:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449616,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/iran-ceremonias-funebres-presidente-ebrahim-raisi-investigaciones-trax\/","url_meta":{"origin":1449584,"position":0},"title":"Ir\u00e1n inicia d\u00edas de ceremonias f\u00fanebres por el presidente Ebrahim Raisi mientras los investigadores establecen las causas del accidente en el que muri\u00f3","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN) -- Las ceremonias f\u00fanebres por el fallecido presidente de Ir\u00e1n Ebrahim Raisi comenzar\u00e1n este martes, tras su muerte en un accidente de helic\u00f3ptero, mientras las autoridades investigan las causas que causaron que la aeronave se estrellara contra la ladera de una remota monta\u00f1a en medio de la niebla el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449624,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/opinion-ghitis-presidente-iran-raisi-muerto-lucha-poder-trax\/","url_meta":{"origin":1449584,"position":1},"title":"OPINI\u00d3N | El presidente de Ir\u00e1n ha muerto. La lucha por el poder apenas comienza","author":"","date":"mayo 21, 2024","format":false,"excerpt":"Nota del editor: Frida Ghitis, exproductora y corresponsal de CNN, es columnista de asuntos mundiales. Es colaboradora semanal de opini\u00f3n de CNN, columnista del diario The Washington Post y columnista de World Politics Review. Las opiniones expresadas en este comentario le pertenecen \u00fanicamente a su autora. Ver m\u00e1s opiniones en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449590,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/19\/helicoptero-presidente-iran-raisi-en-vivo-orix\/","url_meta":{"origin":1449584,"position":2},"title":"Qu\u00e9 sabemos del accidente el helic\u00f3ptero del presidente de Ir\u00e1n, en vivo: noticias y desarrollos","author":"","date":"mayo 19, 2024","format":false,"excerpt":"\ud83d\udd04 Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientesEl helic\u00f3ptero que transportaba al presidente de Ir\u00e1n, Ebrahim Raisi, visto en el momento del despegue cerca de la frontera entre Ir\u00e1n y Azerbaiy\u00e1n el 19 de mayo. Esta fotograf\u00eda de terceros fue proporcionada por la Agencia de Noticias de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449599,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/20\/muerte-raisi-iran-medio-oriente-analisis-trax\/","url_meta":{"origin":1449584,"position":3},"title":"An\u00e1lisis: La muerte de Raisi llega en un momento complicado para Ir\u00e1n y el Medio Oriente","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN) -- La muerte del presidente Ebrahim Raisi y del ministro de Asuntos Exteriores de Ir\u00e1n en un accidente de helic\u00f3ptero en una remota ladera de una monta\u00f1a se produce en un momento especialmente tenso en Medio Oriente (y para Ir\u00e1n a nivel interno).La guerra de Israel contra Hamas y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449623,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/","url_meta":{"origin":1449584,"position":4},"title":"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN) -- Incluso antes de que el jefe del ej\u00e9rcito de Ir\u00e1n, Mohammad Bagheri, ordenara una investigaci\u00f3n sobre el accidente de helic\u00f3ptero que cost\u00f3 a la Rep\u00fablica Isl\u00e1mica la vida de dos de sus principales pol\u00edticos,\u00a0ya se estaba culpando a Estados Unidos.El cuerpo del presidente\u00a0Ebrahim Raisi\u00a0era sacado cuidadosamente del lugar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449593,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/20\/helicoptero-presidente-iran-raisi-en-vivo-orix-2\/","url_meta":{"origin":1449584,"position":5},"title":"Muerte del presidente de Ir\u00e1n en un accidente de helic\u00f3ptero, en vivo: noticias, reacciones y m\u00e1s","author":"","date":"mayo 20, 2024","format":false,"excerpt":"\ud83d\udd04 Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientesEn esta foto facilitada por la Agencia de Noticias de la Rep\u00fablica Isl\u00e1mica IRNA el 19 de mayo de 2024 se muestra el helic\u00f3ptero que transporta al presidente de Ir\u00e1n, Ebrahim Raisi, despegando en la frontera iran\u00ed con Azerbaiy\u00e1n tras la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449584"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449584\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}