{"id":1449662,"date":"2024-05-21T23:03:47","date_gmt":"2024-05-22T06:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/"},"modified":"2024-05-21T23:03:47","modified_gmt":"2024-05-22T06:03:47","slug":"stonehenge-acontecimiento-lunar-vinculo-luna-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/","title":{"rendered":"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna"},"content":{"rendered":"<p>(CNN) &#8212; Para quienes se han reunido a lo largo de los siglos en Stonehenge \u2014el imponente monumento prehist\u00f3rico que domina la llanura de Salisbury, en el suroeste de Inglaterra, desde hace unos 4.500 a\u00f1os\u2014, probablemente estaba claro c\u00f3mo el Sol pudo influir en su dise\u00f1o.<\/p>\n<p>El eje central del c\u00edrculo de piedras estaba, y sigue estando, alineado con la salida del sol en pleno verano y la puesta de sol en pleno invierno, y las piedras enmarcan de forma espectacular la salida y la puesta del sol cuando los d\u00edas son m\u00e1s largos y m\u00e1s cortos.<\/p>\n<p>\u00bfPero Stonehenge y otros posibles monumentos megal\u00edticos del mundo tambi\u00e9n se alinean con la Luna?<\/p>\n<p>La idea de que Stonehenge estaba vinculado de alg\u00fan modo a la Luna gan\u00f3 terreno en la d\u00e9cada de 1960. Sin embargo, el concepto no se hab\u00eda explorado de forma sistem\u00e1tica, afirma Clive Ruggles, profesor em\u00e9rito de arqueoastronom\u00eda en la facultad de arqueolog\u00eda e historia antigua de la Universidad de Leicester.<\/p>\n<p>Este verano, los arque\u00f3logos est\u00e1n utilizando un fen\u00f3meno lunar poco conocido que se produce cada 18,6 a\u00f1os para investigarlo como parte de su trabajo para entender por qu\u00e9 se construy\u00f3 Stonehenge.<\/p>\n<p>Parada lunar<\/p>\n<p>Al igual que el sol, la luna sale por el este y se pone por el oeste. Sin embargo, la salida y la puesta de la luna se desplazan de norte a sur y viceversa en el espacio de un mes. Los extremos norte y sur tambi\u00e9n cambian en un periodo de unos 18 a\u00f1os y medio. El estancamiento lunar es cuando la salida y la puesta de la luna m\u00e1s septentrional y meridional est\u00e1n m\u00e1s alejadas.<\/p>\n<p>&#171;La salida de la luna cambia cada d\u00eda y, si se hace un seguimiento durante un mes, se observa que hay un l\u00edmite norte y un l\u00edmite sur m\u00e1s all\u00e1 de los cuales la luna nunca sale (o se pone)&#187;, explica Fabio Silva, profesor titular de modelado arqueol\u00f3gico de la Universidad de Bournemouth, por correo electr\u00f3nico.<\/p>\n<p>&#171;Si observ\u00e1ramos estos l\u00edmites a lo largo de 19 a\u00f1os, nos dar\u00edamos cuenta de que cambian como un acorde\u00f3n: se expanden hasta un l\u00edmite m\u00e1ximo (el estancamiento lunar mayor) y luego empiezan a contraerse hasta un l\u00edmite m\u00ednimo (el estancamiento lunar menor)&#187;.<\/p>\n<p>Este par\u00f3n lunar mayor est\u00e1 previsto para enero de 2025, pero desde ahora hasta mediados de 2025, la Luna puede parecer, a un observador casual, inusualmente baja y alta en el cielo nocturno durante el mes lunar.<\/p>\n<p>Descubren un santuario de 4.000 a\u00f1os parecido a Stonehenge en Pa\u00edses Bajos<\/p>\n<p>Algunos creen que las piedras de la estaci\u00f3n de Stonehenge est\u00e1n alineadas con la parada lunar. (Cr\u00e9dito: English Heritage)<\/p>\n<p>&#171;Si est\u00e1s en uno de esos 19 a\u00f1os, entonces de vez en cuando, ver\u00e1s la luna saliendo o poni\u00e9ndose mucho m\u00e1s al norte o al sur de lo que lo hace la mayor\u00eda de las veces. En los a\u00f1os intermedios nunca la ver\u00e1s all\u00ed&#187;, explica Ruggles.<\/p>\n<p>A pesar del nombre del fen\u00f3meno, en realidad la Luna no est\u00e1 quieta durante este periodo.<\/p>\n<p>&#171;Lo que se detiene son estos l\u00edmites, y el momento en que esto ocurre es en enero del a\u00f1o que viene&#187;, a\u00f1adi\u00f3 Ruggles. &#171;Pero durante aproximadamente un a\u00f1o, si por casualidad ves la salida de la luna en el momento adecuado, la ver\u00e1s salir excepcionalmente baja (en el cielo)&#187;.<\/p>\n<p>Stonehenge est\u00e1 formado por dos tipos de piedra: piedras de sars\u00e9n m\u00e1s grandes y piedras azules m\u00e1s peque\u00f1as que forman dos c\u00edrculos conc\u00e9ntricos. Seg\u00fan Ruggles, las piedras de la estaci\u00f3n de Stonehenge, que forman un rect\u00e1ngulo alrededor del c\u00edrculo, se alinean aproximadamente con las posiciones extremas de la Luna durante la parada lunar.<\/p>\n<p>C\u00f3mo se consigui\u00f3 esta alineaci\u00f3n lunar, si fue por dise\u00f1o y su posible finalidad son temas de debate que el equipo quiere investigar.<\/p>\n<p>Stonehenge se construy\u00f3 hace unos 4.500 a\u00f1os (Fotograf\u00eda: Andre Pattenden\/English Heritage)<\/p>\n<p>Averiguar las conexiones celestes de Stonehenge<\/p>\n<p>Aunque no existen documentos escritos que arrojen luz sobre el significado y la importancia de Stonehenge, los arque\u00f3logos creen desde hace tiempo que sus alineaciones solares fueron intencionadas. Tales alineaciones se han identificado en muchos lugares del mundo y habr\u00edan sido relativamente f\u00e1ciles de identificar para los antiguos constructores, dado que el conocimiento del ciclo anual del sol y su conexi\u00f3n con las estaciones habr\u00eda sido esencial para la subsistencia.<\/p>\n<p>Sin embargo, es mucho m\u00e1s dif\u00edcil decir si Stonehenge tiene realmente una conexi\u00f3n con el par\u00f3n lunar.<\/p>\n<p>&#171;No creo que podamos afirmarlo definitivamente, pero para m\u00ed hay algunas pruebas que me hacen pensar que fue deliberado&#187;, afirma Ruggles.<\/p>\n<p>Una pista fue el hecho de que los arque\u00f3logos han encontrado restos humanos incinerados agrupados en el sureste, cerca de donde se producir\u00e1 la salida de la Luna m\u00e1s meridional.<\/p>\n<p>&#171;Creo que existe la posibilidad de que conocieran esa direcci\u00f3n de la luna y se convirtiera en una especie de direcci\u00f3n sagrada&#187;, afirma Ruggles.<\/p>\n<p>Desde abril, Ruggles y Silva, junto con colegas de la Universidad de Bournemouth, la Universidad de Oxford y English Heritage, la organizaci\u00f3n que gestiona el yacimiento, han estado documentando la salida y puesta de la luna en los momentos clave en los que la luna est\u00e1 alineada con las piedras de la estaci\u00f3n. Seg\u00fan Silva, se espera que la luna se alinee con el rect\u00e1ngulo de piedras de la estaci\u00f3n dos veces al mes desde febrero de 2024 hasta noviembre de 2025.<\/p>\n<p>&#171;Esto ocurrir\u00e1 en diferentes momentos del d\u00eda y de la noche a lo largo del a\u00f1o, y la luna estar\u00e1 en el lugar correcto en diferentes fases cada mes&#187;, explic\u00f3 Silva en un comunicado en abril.<\/p>\n<p>El equipo quiere comprender qu\u00e9 patrones de luz y sombra crea la luna en Stonehenge y si pudieron tener alg\u00fan significado para las personas que construyeron y utilizaron el monumento.<\/p>\n<p>El &#171;Stonehenge espa\u00f1ol&#187; emerge de una presa afectada por la sequ\u00eda<\/p>\n<p>Los investigadores est\u00e1n estudiando las alineaciones lunares en Chimney Rock (Colorado), donde aparece la luna llena el 26 de diciembre de 2023. (Cr\u00e9dito: Amanda Bosh\/Stephen Levine)<\/p>\n<p>Otros monumentos con posible v\u00ednculo lunar<\/p>\n<p>Stonehenge no es el \u00fanico monumento megal\u00edtico potencialmente vinculado al par\u00f3n lunar.<\/p>\n<p>En Estados Unidos, Erica Ellingson, profesora em\u00e9rita de astrof\u00edsica de la Universidad de Colorado en Boulder, investiga las alineaciones lunares en Chimney Rock, una cresta rocosa situada a unos 300 metros sobre el fondo de un valle en Colorado. El punto de referencia presenta dos grandes rocas en forma de pilar que enmarcan el horizonte.<\/p>\n<p>Entre los a\u00f1os 900 y 1150, los antepasados del pueblo construyeron edificios de varios pisos y espacios rituales en este lugar elevado de dif\u00edcil acceso, con su espectacular vista, dijo Ellington, y sigue siendo un lugar importante para los 26 grupos de nativos americanos que tienen v\u00ednculos tradicionales o culturales con la zona.<\/p>\n<p>&#171;La extraordinaria vista del cielo entre los pin\u00e1culos gemelos sugiere una conexi\u00f3n astron\u00f3mica, pero la brecha est\u00e1 ligeramente demasiado al norte para que el Sol brille nunca a trav\u00e9s de ella. La Luna, sin embargo, puede verse salir por all\u00ed cuando se encuentra cerca de su posici\u00f3n m\u00e1s septentrional, durante la principal estaci\u00f3n de parada lunar&#187;, explica por correo electr\u00f3nico.<\/p>\n<p>Otras pruebas de la observaci\u00f3n de la Luna proceden de la dataci\u00f3n por anillos de \u00e1rboles de las vigas de madera de los edificios antiguos cercanos, que indica que su construcci\u00f3n est\u00e1 relacionada con las fechas de las paradas lunares de hace casi 1.000 a\u00f1os, a\u00f1adi\u00f3.<\/p>\n<p>Las piedras de Calanais, situadas en la isla de Lewis (Escocia) y erigidas antes que Stonehenge, tambi\u00e9n podr\u00edan estar relacionadas con la parada lunar, seg\u00fan Ruggles.<\/p>\n<p>Bradley Schaefer, profesor em\u00e9rito del departamento de F\u00edsica y Astronom\u00eda de la Universidad Estatal de Luisiana, se mostr\u00f3 muy esc\u00e9ptico ante la posibilidad de que los antiguos conocieran la parada lunar y construyeran monumentos alineados con ella. Lo m\u00e1s probable, sugiri\u00f3, es que se tratara de una coincidencia.<\/p>\n<p>&#171;Cada sitio antiguo tiene docenas o cientos de posibles l\u00edneas de visi\u00f3n, y una o m\u00e1s siempre apuntan a alg\u00fan lugar cerca de una de las 8 direcciones del punto muerto&#187;, dijo por correo electr\u00f3nico.<\/p>\n<p>El estancamiento lunar es dif\u00edcil de reconocer para un observador casual de la Luna, a\u00f1adi\u00f3, y s\u00f3lo es realmente visible en los datos detallados de las observaciones de la salida y la puesta de la Luna.<\/p>\n<p>Aunque el cambio en la posici\u00f3n de la Luna es sutil y los registros hist\u00f3ricos que documentan el estancamiento lunar son escasos y dif\u00edciles de interpretar, Ellington dijo que cree que el v\u00ednculo es plausible porque muchos pueblos antiguos observaban el cielo muy de cerca.<\/p>\n<p>&#171;Un observador de la Luna habr\u00eda visto c\u00f3mo la Luna empezaba a salir o a ponerse fuera de estos l\u00edmites, alej\u00e1ndose cada vez m\u00e1s a medida que se acercaba la gran parada lunar&#187;, explic\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Para quienes se han reunido a lo largo de los siglos en Stonehenge \u2014el imponente monumento prehist\u00f3rico que domina la llanura de Salisbury, en el suroeste de Inglaterra, desde hace unos 4.500 a\u00f1os\u2014, probablemente estaba claro c\u00f3mo el Sol pudo influir en su dise\u00f1o. El eje central del c\u00edrculo de piedras estaba, y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449662","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Para quienes se han reunido a lo largo de los siglos en Stonehenge \u2014el imponente monumento prehist\u00f3rico que domina la llanura de Salisbury, en el suroeste de Inglaterra, desde hace unos 4.500 a\u00f1os\u2014, probablemente estaba claro c\u00f3mo el Sol pudo influir en su dise\u00f1o. El eje central del c\u00edrculo de piedras estaba, y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-22T06:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna\",\"datePublished\":\"2024-05-22T06:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/\"},\"wordCount\":1606,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/\",\"name\":\"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-22T06:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna - Noticias","og_description":"(CNN) &#8212; Para quienes se han reunido a lo largo de los siglos en Stonehenge \u2014el imponente monumento prehist\u00f3rico que domina la llanura de Salisbury, en el suroeste de Inglaterra, desde hace unos 4.500 a\u00f1os\u2014, probablemente estaba claro c\u00f3mo el Sol pudo influir en su dise\u00f1o. El eje central del c\u00edrculo de piedras estaba, y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-22T06:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/"},"author":{"name":"","@id":""},"headline":"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna","datePublished":"2024-05-22T06:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/"},"wordCount":1606,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/","name":"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-22T06:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un raro acontecimiento lunar podr\u00eda revelar el v\u00ednculo de Stonehenge con la Luna","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-22T06:03:47Z","datePublished":"2024-05-22T06:03:47Z","dateModified":"2024-05-22T06:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un raro acontecimiento lunar podr\\u00eda revelar el v\\u00ednculo de Stonehenge con la Luna\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/21\\\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/21\\\/stonehenge-acontecimiento-lunar-vinculo-luna-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-22T06:03:47Z\",\"datePublished\":\"2024-05-22T06:03:47Z\",\"dateModified\":\"2024-05-22T06:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456780,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/19\/por-que-reconstruyo-stonehenge-inglaterra-trax\/","url_meta":{"origin":1449662,"position":0},"title":"Los cient\u00edficos creen saber por qu\u00e9 se reconstruy\u00f3 Stonehenge hace miles de a\u00f1os","author":"","date":"diciembre 19, 2024","format":false,"excerpt":"Los cient\u00edficos hicieron un descubrimiento importante este a\u00f1o relacionado con Stonehenge, uno de los mayores misterios de la humanidad, y cada vez se conocen a\u00fan m\u00e1s revelaciones.En agosto, un equipo de investigadores comparti\u00f3 pruebas que suger\u00edan que la Piedra del Altar, un monolito ic\u00f3nico en el coraz\u00f3n de Stonehenge, fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452661,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/09\/13\/busqueda-origen-piedra-del-altar-stonehenge-trax\/","url_meta":{"origin":1449662,"position":1},"title":"Intensifican b\u00fasqueda del origen de la misteriosa Piedra del Altar de Stonehenge","author":"","date":"septiembre 13, 2024","format":false,"excerpt":"(CNN) -- Con la esperanza de resolver uno de los m\u00e1s grandes misterios sobre el ic\u00f3nico monolito, los ge\u00f3logos han trasladado la b\u00fasqueda de los or\u00edgenes del Altar de Piedra central de Stonehenge a Escocia despu\u00e9s de que una investigaci\u00f3n reciente redirigiera la b\u00fasqueda desde Gales.Pero en un giro sorprendente,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450513,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/19\/manifestantes-just-stop-oil-rocian-stonehenge-pintura-trax\/","url_meta":{"origin":1449662,"position":2},"title":"Manifestantes de Just Stop Oil roc\u00edan Stonehenge con pintura","author":"","date":"junio 19, 2024","format":false,"excerpt":"(CNN) -- Manifestantes ambientalistas rociaron con pintura naranja la estructura prehist\u00f3rica m\u00e1s famosa del Reino Unido, Stonehenge, un d\u00eda antes de que grandes multitudes se re\u00fanan all\u00ed para el solsticio de verano.Un video publicado en X por Just Stop Oil muestra a dos de los activistas del grupo rociando el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459334,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/02\/28\/como-ver-desfile-7-planetas-febrero-astronomos-trax\/","url_meta":{"origin":1449662,"position":3},"title":"C\u00f3mo ver el desfile de 7 planetas de febrero, seg\u00fan astr\u00f3nomos","author":"","date":"febrero 28, 2025","format":false,"excerpt":"Febrero termina con un regalo para los observadores del cielo: un desfile de siete planetas en el cielo nocturno, entre ellos Mercurio, Urano y Neptuno, junto a planetas t\u00edpicamente brillantes como Marte, Venus, J\u00fapiter y Saturno. Pero no ser\u00e1 f\u00e1cil observar a los siete, dicen astr\u00f3nomos.Mientras que los siete planetas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459918,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/14\/marzo-2025-luna-de-sangre-trax\/","url_meta":{"origin":1449662,"position":4},"title":"FOTOS | La &#171;luna de sangre&#187; de marzo ilumina el cielo","author":"","date":"marzo 14, 2025","format":false,"excerpt":"La Luna brill\u00f3 con un espectacular color rojo entre el jueves por la noche y el viernes por la ma\u00f1ana, al pasar a la sombra de la Tierra durante un eclipse lunar total.Un eclipse lunar se produce cuando la Tierra se encuentra entre el Sol y la Luna, y los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463398,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/06\/10\/luna-llena-junio-2025-luna-de-fresa-trax\/","url_meta":{"origin":1449662,"position":5},"title":"Luna llena de junio 2025: cu\u00e1ndo es, a qu\u00e9 hora y c\u00f3mo ver la luna de fresa","author":"","date":"junio 10, 2025","format":false,"excerpt":"La luna llena de junio, apodada luna de fresa, brillar\u00e1 intensamente el martes por la noche y el mi\u00e9rcoles por la ma\u00f1ana.La luna estar\u00e1 en su punto m\u00e1s lleno a las 3:44 a.m. ET del mi\u00e9rcoles, pero a\u00fan aparecer\u00e1 brillante y baja en el este despu\u00e9s del atardecer del martes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449662"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449662\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}