{"id":1449665,"date":"2024-05-22T01:03:42","date_gmt":"2024-05-22T08:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/"},"modified":"2024-05-22T01:03:42","modified_gmt":"2024-05-22T08:03:42","slug":"milei-sanchez-empresas-economia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/","title":{"rendered":"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Apenas unas horas despu\u00e9s de que estallara el conflicto diplom\u00e1tico entre Argentina y Espa\u00f1a, empresas espa\u00f1olas salieron a repudiar los dichos del presidente Javier Milei.\u00a0L\u00edderes de algunas de estas corporaciones acababan de reunirse con el mandatario argentino el d\u00eda anterior.<\/p>\n<p>El s\u00e1bado por la ma\u00f1ana, en el marco del viaje de Milei a Espa\u00f1a \u2015cuestionado por actores argentinos por no tener en agenda a priori ni ninguna reuni\u00f3n de inter\u00e9s nacional\u2015, el gobierno argentino difundi\u00f3 el listado de empresarios con quienes el mandatario se reunir\u00eda, justificando as\u00ed el viaje. \u201cLos m\u00e1s importantes de Espa\u00f1a. entre los que destacan representantes de BBVA, Santander, Iberia, Mapfre y Telef\u00f3nica y al presidente de la Confederaci\u00f3n Espa\u00f1ola de Organizaciones Empresariales (CEOE), Antonio Garamendi\u201d, comunicaron desde la oficina de prensa.<\/p>\n<p>Horas m\u00e1s tarde, las mismas compa\u00f1\u00edas salieron a desmarcarse de los dichos de Milei, interpretados en ese pa\u00eds como agravios.<\/p>\n<p>\u201cRechazamos profundamente las declaraciones fuera de tono, no en un mensaje diplom\u00e1tico, que es el que tiene que haber entre dos pa\u00edses amigos, contra el presidente del Gobierno y contra la mujer del presidente. No es el sitio ni el lugar, no es lo que se pide a dos pa\u00edses hermanos\u201d, dijo Garamendi. \u201c\u00daltimamente falta y falla la lealtad institucional. La democracia est\u00e1 porque est\u00e1n las instituciones, independientemente de que a alguien le guste o no le guste nuestro presidente de Gobierno, y en este caso, por supuesto no nos ha gustado para nada\u201d, sentenci\u00f3 en una entrevista con la Cadena SER.<\/p>\n<p>Otras corporaciones apoyaron la mirada del titular del CEOE y apuntaron contra lo ocurrido. Iberia difundi\u00f3 un comunicado en el que aclar\u00f3 que en el encuentro solo se habl\u00f3 de econom\u00eda y puso distancia a lo sucedido posteriormente. \u201cEn un acto pol\u00edtico que nada ten\u00eda que ver con el encuentro empresarial del s\u00e1bado, el presidente de Argentina hizo unas declaraciones que no atienden al lenguaje diplom\u00e1tico que debe usarse entre dos pa\u00edses amigos, con estrechas relaciones bilaterales\u201d, abund\u00f3.<\/p>\n<p>Espa\u00f1a es el tercer inversor m\u00e1s importante del pa\u00eds, seg\u00fan el \u00faltimo informe de Inversi\u00f3n Extranjera Directa (IED) del Banco Central de Argentina, y el m\u00e1s importante de Europa. Solo lo preceden Estados Unidos, en primer lugar, y Brasil, a continuaci\u00f3n.<\/p>\n<p>En el tercer trimestre de 2023, las inversiones espa\u00f1olas alcanzaron los US$ 746 millones, lo que implic\u00f3 un alza interanual de 18%. Este dato se refuerza con el reciente informe del Instituto Nacional de Estad\u00edstica y Censo (Indec) que ubica a la Uni\u00f3n Europea como el segundo principal socio comercial, una nueva tendencia, siendo un lugar que durante todo el a\u00f1o pasado ocup\u00f3 China.<\/p>\n<p>Federico Vaccarezza, investigador en relaciones comerciales internacionales, dice que Espa\u00f1a es el puente de Argentina con la Uni\u00f3n Europea. \u201cEsto que pas\u00f3 es muy grave porque la Uni\u00f3n Europea es nuestro segundo socio comercial m\u00e1s importante, y Espa\u00f1a ocupa un lugar fundamental en el bloque\u201d, explica a CNN.<\/p>\n<p>El experto plantea un escenario global bipolar con dos grandes grupos que dividen el mapa del comercio: los BRICS (una creciente alianza fundada en 2011 por Brasil, Rusia, India, China y Sud\u00e1frica) y el G7 (integrado por Estados Unidos, Canad\u00e1, Francia, Alemania, Italia, Jap\u00f3n y Reino Unido), y traza el recorrido de Milei en un claro posicionamiento con este \u00faltimo.<\/p>\n<p>\u201cEn el medio ten\u00e9s un mont\u00f3n de pa\u00edses que, como lo que buscan satisfacer es su inter\u00e9s nacional, a veces pueden apostar a un lado y otras al otro, tratando de hacer equilibrio\u201d, se\u00f1ala.<\/p>\n<p>Consultado por la prensa local, el presidente de Argentina dijo que las empresas que tienen inversiones en el pa\u00eds \u201cest\u00e1n determinadas por los v\u00ednculos entre individuos y van a permanecer en el pa\u00eds\u201d.<\/p>\n<p>Y, en contraposici\u00f3n a la postura de los empresarios espa\u00f1oles que refirieron un mal obrar diplom\u00e1tico, la canciller argentina, Diana Mondino, lo llev\u00f3 al plano de lo personal. \u201cLa relaci\u00f3n personal no debe afectar la relaci\u00f3n entre los pa\u00edses (&#8230;) Las inversiones se manejan de otra manera, son de largu\u00edsimo plazo\u201d, dijo.<\/p>\n<p>Vaccarezza concuerda con que no es probable que las empresas ya instaladas en Argentina se vayan por este contexto, pero marca un contrapunto.<\/p>\n<p>\u201cTodas las grandes empresas, todas las grandes multinacionales, son extensiones econ\u00f3micas de los intereses de grandes Estados. En algunos casos, hay corporaciones que tienden a tener un inter\u00e9s propio indistintamente de lo que diga tal o cual presidente, pero el embajador tiene la funci\u00f3n de representar los intereses de su pa\u00eds frente al otro y eso puede ser importante, por ejemplo, en un eventual cambio de condiciones\u201d, explic\u00f3.<\/p>\n<p>Carlos Cu\u00e9, periodista espa\u00f1ol del diario El Pa\u00eds que trabaja temas argentinos, dijo a la local Radio con vos que nunca vio antes que las empresas emitieran un comunicado en repudio de un pa\u00eds en el que tienen intereses.<\/p>\n<p>\u201cLas empresas nunca se meten en esos l\u00edos\u201d, se\u00f1al\u00f3 y plante\u00f3 que ve\u00eda dif\u00edcil que se generaran grandes acuerdos econ\u00f3micos o inversiones \u201ccon los gobiernos en estas condiciones\u201d.<\/p>\n<p>Vaccarezza plantea adem\u00e1s el tema de la competencia entre econom\u00edas.<\/p>\n<p>\u201cLo que hay que tener en cuenta es que Argentina, como pa\u00eds emergente, compite con muchos pa\u00edses que buscan atraer inversiones hacia la regi\u00f3n, y no hay nada que Argentina ofrezca que otros pa\u00edses ya no ofrezcan en condiciones m\u00e1s competitivas\u201d, advierte.<\/p>\n<p>El asunto recuerda a c\u00f3mo durante el primer debate de la Ley de Bases Milei tuiteaba agravios hacia diputados y gobernadores, mientras sus ministros intentaban negociar con ellos. Ahora se pelea con S\u00e1nchez, a la par que busca inversiones espa\u00f1olas.<\/p>\n<p>En su momento, la Ley de Bases no logr\u00f3 su tratamiento en el Congreso, pero ahora, tras acuerdos pol\u00edticos y una bajada de tono, logr\u00f3 aprobarse en la C\u00e1mara baja y con perspectivas a tratarse pr\u00f3ximamente en el Senado.<\/p>\n<p>En materia internacional, ya son varios los esc\u00e1ndalos que el mandatario acumula en apenas cinco meses de gobierno, \u00bfOptar\u00e1 Milei por encontrar otro tono a las relaciones diplom\u00e1ticas?<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Apenas unas horas despu\u00e9s de que estallara el conflicto diplom\u00e1tico entre Argentina y Espa\u00f1a, empresas espa\u00f1olas salieron a repudiar los dichos del presidente Javier Milei.\u00a0L\u00edderes de algunas de estas corporaciones acababan de reunirse con el mandatario argentino el d\u00eda anterior. El s\u00e1bado por la ma\u00f1ana, en el marco del viaje de Milei [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449665","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Apenas unas horas despu\u00e9s de que estallara el conflicto diplom\u00e1tico entre Argentina y Espa\u00f1a, empresas espa\u00f1olas salieron a repudiar los dichos del presidente Javier Milei.\u00a0L\u00edderes de algunas de estas corporaciones acababan de reunirse con el mandatario argentino el d\u00eda anterior. El s\u00e1bado por la ma\u00f1ana, en el marco del viaje de Milei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-22T08:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina?\",\"datePublished\":\"2024-05-22T08:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/\"},\"wordCount\":1095,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/\",\"name\":\"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-22T08:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Apenas unas horas despu\u00e9s de que estallara el conflicto diplom\u00e1tico entre Argentina y Espa\u00f1a, empresas espa\u00f1olas salieron a repudiar los dichos del presidente Javier Milei.\u00a0L\u00edderes de algunas de estas corporaciones acababan de reunirse con el mandatario argentino el d\u00eda anterior. El s\u00e1bado por la ma\u00f1ana, en el marco del viaje de Milei [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-22T08:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina?","datePublished":"2024-05-22T08:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/"},"wordCount":1095,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/","name":"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-22T08:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPuede el conflicto entre Milei y S\u00e1nchez implicar consecuencias econ\u00f3micas para Argentina?","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/22\/milei-sanchez-empresas-economia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-22T08:03:42Z","datePublished":"2024-05-22T08:03:42Z","dateModified":"2024-05-22T08:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPuede el conflicto entre Milei y S\\u00e1nchez implicar consecuencias econ\\u00f3micas para Argentina?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/22\\\/milei-sanchez-empresas-economia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/22\\\/milei-sanchez-empresas-economia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-22T08:03:42Z\",\"datePublished\":\"2024-05-22T08:03:42Z\",\"dateModified\":\"2024-05-22T08:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450576,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/21\/milei-viaje-espana-rezagos-crisis-diplomatica-madrid-pide-respeto-orix\/","url_meta":{"origin":1449665,"position":0},"title":"Milei vuelve a Espa\u00f1a a\u00fan con los rezagos de la crisis diplom\u00e1tica; las autoridades en Madrid le piden respeto a las instituciones","author":"","date":"junio 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un mes despu\u00e9s de generar una crisis diplom\u00e1tica con Espa\u00f1a, el presidente de Argentina Javier Milei vuelve a Madrid en una visita privada en la que no tiene pensado reunirse con representantes del Gobierno de Pedro S\u00e1nchez. Ante su inminente visita, funcionarios en Madrid han pedido a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450598,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/21\/analisis-milei-politica-espanola-gobierno-sanchez-cruce-de-ayuso-orix\/","url_meta":{"origin":1449665,"position":1},"title":"AN\u00c1LISIS | Milei irrumpe nuevamente en la pol\u00edtica espa\u00f1ola y el gobierno de S\u00e1nchez sale al cruce de Ayuso","author":"","date":"junio 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Este viernes, el presidente Javier Milei aterriz\u00f3 en Madrid para iniciar una nueva gira en Europa, continente al que viaja por quinta vez n\u00famero cinco en los casi 200 d\u00edas que lleva como mandatario de Argentina. Tras su paso por Espa\u00f1a, viajar\u00e1 a Alemania en donde tambi\u00e9n recibir\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449651,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/crisis-diplomatica-javier-milei-pedro-sanchez-argentina-espana-orix\/","url_meta":{"origin":1449665,"position":2},"title":"Las idas y vueltas de la crisis diplom\u00e1tica entre Javier Milei y Pedro S\u00e1nchez","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En su primer viaje a Espa\u00f1a como presidente de Argentina, Javier Milei no solo no concret\u00f3 una reuni\u00f3n bilateral con el presidente del Gobierno Pedro S\u00e1nchez, sino que acus\u00f3 de corrupci\u00f3n a su esposa en su propia casa.Durante el mitin internacional Viva 24,\u00a0una convenci\u00f3n que tuvo su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449709,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/23\/espana-embajadora-argentina-claves-escalada-sanchez-milei-analisis-orix\/","url_meta":{"origin":1449665,"position":3},"title":"AN\u00c1LISIS | \u00bfQu\u00e9 significa realmente que Espa\u00f1a retire a su embajadora de Argentina? Las claves de la escalada S\u00e1nchez-Milei","author":"","date":"mayo 23, 2024","format":false,"excerpt":"(CNN) -- Las tensiones diplom\u00e1ticas entre los gobiernos de Argentina y Espa\u00f1a, aunque no son nuevas, llegaron este martes a un nuevo nivel, con el anuncio del ministro de Asuntos Exteriores del pa\u00eds europeo, Jos\u00e9 Manuel Albares, de que retirar\u00e1n de forma definitiva a su embajadora en Buenos Aires, Mar\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449561,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/17\/analisis-milei-viaje-espana-orix\/","url_meta":{"origin":1449665,"position":4},"title":"AN\u00c1LISIS | \u00bfQu\u00e9 busca Milei con su viaje a Espa\u00f1a?","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Ni la acusaci\u00f3n del ministro de Transporte de Espa\u00f1a de \"ingerir sustancias\" en referencia al presidente de Argentina, Javier Milei, ni la contundente respuesta oficial de este respecto a los supuestos actos de corrupci\u00f3n que el gobierno del pa\u00eds europeo ha rechazado cambiaron los planes del mandatario en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449621,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/21\/no-pedir-disculpas-milei-pdro-sanchez-orix\/","url_meta":{"origin":1449665,"position":5},"title":"\u201cNo le voy a pedir disculpas\u201d, dice Javier Milei sobre su confrontaci\u00f3n con Pedro S\u00e1nchez","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Argentina, Javier Milei, dijo que no se disculpar\u00e1 con el presidente del Gobierno espa\u00f1ol, Pedro S\u00e1nchez, quien le pidi\u00f3 rectificar las declaraciones que dio en Espa\u00f1a durante un encuentro del partido de ultraderecha Vox y por las cuales el Ejecutivo de S\u00e1nchez llam\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449665"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449665\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}