{"id":1449673,"date":"2024-05-22T11:04:02","date_gmt":"2024-05-22T18:04:02","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/"},"modified":"2024-05-22T11:04:02","modified_gmt":"2024-05-22T18:04:02","slug":"cuanto-cobra-presidente-mexico-ministros-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/","title":{"rendered":"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En solo unos d\u00edas, M\u00e9xico decidir\u00e1 qui\u00e9n dirigir\u00e1 al pa\u00eds por los siguientes seis a\u00f1os. La persona que llegue a la presidencia no gobernar\u00e1 sola, estar\u00e1 acompa\u00f1ada de los secretarios que conformar\u00e1n su gabinete, quienes pondr\u00e1n en marcha el rumbo que les marque para la naci\u00f3n en materia econ\u00f3mica, social, de seguridad y m\u00e1s.<\/p>\n<p>\u00bfAlguna vez te has preguntado cu\u00e1nto ganan por gobernar el presidente y sus ministros?<\/p>\n<p>El salario aprobado para el presidente en 2024<\/p>\n<p>Para 2024, el Presupuesto de Egresos de la Federaci\u00f3n asign\u00f3 al presidente \u2015actualmente Andr\u00e9s Manuel L\u00f3pez Obrador\u2015 un ingreso mensual bruto (antes de la retenci\u00f3n de impuestos y deducciones personales) de unos US$ 11.150 (186.093 pesos mexicanos).<\/p>\n<p>De ese monto, el sueldo base es de unos US$ 3.050, mientras que poco m\u00e1s de US$ 8.000 son bajo el concepto de compensaci\u00f3n garantizada, que es un pago complementario al salario base, pero que no se toma en cuenta para calcular prestaciones o aportaciones de seguridad social.<\/p>\n<p>Expertas dicen que propuestas de principales candidatas presidenciales para combatir feminicidios en M\u00e9xico se quedan cortas<\/p>\n<p>El mandatario tambi\u00e9n tiene autorizados casi US$ 100 mensuales de prestaciones, incluidas la prima quinquenal por antig\u00fcedad, la ayuda de despensa y el seguro colectivo para el retiro.<\/p>\n<p>Ya descontando el impuesto sobre la renta (ISR) y las deducciones personales de seguridad social y seguros, el presidente puede recibir mensualmente unos US$ 7.750. Este es el tope autorizado por el Presupuesto \u2015aprobado por la C\u00e1mara de Diputados.<\/p>\n<p>En cuanto al ingreso anual neto (tras la retenci\u00f3n del ISR), el titular del Ejecutivo tiene aprobada una remuneraci\u00f3n de aproximadamente US$ 119.300. Este c\u00e1lculo incluye el salario, la compensaci\u00f3n y otras prestaciones como prima vacacional, aguinaldo, gratificaci\u00f3n, ahorro solidario y seguro de vida institucional.<\/p>\n<p>El sueldo reportado por AMLO<\/p>\n<p>El presidente L\u00f3pez Obrador tiene un salario mensual neto de unos US$ 7.680 (128.205 pesos), seg\u00fan la p\u00e1gina web N\u00f3mina Transparente de la Secretar\u00eda de la Funci\u00f3n P\u00fablica, con datos de la pasada quincena del 16 al 30 de abril.<\/p>\n<p>El sueldo aprobado para los secretarios en 2024<\/p>\n<p>El presupuesto aprobado establece que el sueldo mensual bruto de los secretarios de Estado es de m\u00e1ximo US$ 10.950 (182.726 pesos).<\/p>\n<p>Los ministros tienen aprobadas prestaciones, tanto en efectivo como en especie, por un m\u00e1ximo de unos US$ 2.595.<\/p>\n<p>Y cada secretario tiene autorizado un ingreso mensual neto que incluye salario y prestaciones ordinarias, sin importar si son peri\u00f3dicas o en fechas definidas, de unos US$ 9.715 como m\u00e1ximo.<\/p>\n<p>El sueldo reportado por el gabinete de AMLO<\/p>\n<p>Los secretarios que conforman el Gobierno de L\u00f3pez Obrador, con excepci\u00f3n de dos cuyos datos no est\u00e1n disponibles, ganan mensualmente por su cargo \u2015luego de descontados los impuestos\u2015 un estimado de US$ 7.600 (entre 126.597 y 126.994 pesos mexicanos), seg\u00fan la p\u00e1gina N\u00f3mina Transparente y la Plataforma Nacional de Transparencia, con datos de 2024.<\/p>\n<p>Aunque los salarios vigentes del secretario de Marina y del secretario de la Defensa Nacional no est\u00e1n disponibles en la p\u00e1gina de N\u00f3mina Transparente de la SFP, hay informaci\u00f3n sobre sus ingresos de 2023 en la Plataforma Nacional de Transparencia.<\/p>\n<p>El almirante Jos\u00e9 Rafael Ojeda Dur\u00e1n, secretario de Marina, report\u00f3 un sueldo mensual de unos US$ 7.640 durante el primer trimestre de 2023, \u00fanico per\u00edodo disponible para consultar su salario.<\/p>\n<p>El secretario de la Defensa Nacional, el general Luis Cresencio Sandoval, tuvo un salario mensual durante el primer semestre de aproximadamente US$ 7.180 y de unos US$ 7.720 en el segundo semestre de 2023.<\/p>\n<p>CNN contact\u00f3 a la Semar y la Sedena para conocer el salario actualizado de los ministros, sin obtener respuesta inmediata.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En solo unos d\u00edas, M\u00e9xico decidir\u00e1 qui\u00e9n dirigir\u00e1 al pa\u00eds por los siguientes seis a\u00f1os. La persona que llegue a la presidencia no gobernar\u00e1 sola, estar\u00e1 acompa\u00f1ada de los secretarios que conformar\u00e1n su gabinete, quienes pondr\u00e1n en marcha el rumbo que les marque para la naci\u00f3n en materia econ\u00f3mica, social, de seguridad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449673","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; En solo unos d\u00edas, M\u00e9xico decidir\u00e1 qui\u00e9n dirigir\u00e1 al pa\u00eds por los siguientes seis a\u00f1os. La persona que llegue a la presidencia no gobernar\u00e1 sola, estar\u00e1 acompa\u00f1ada de los secretarios que conformar\u00e1n su gabinete, quienes pondr\u00e1n en marcha el rumbo que les marque para la naci\u00f3n en materia econ\u00f3mica, social, de seguridad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-22T18:04:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros?\",\"datePublished\":\"2024-05-22T18:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/\"},\"wordCount\":653,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/\",\"name\":\"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-22T18:04:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; En solo unos d\u00edas, M\u00e9xico decidir\u00e1 qui\u00e9n dirigir\u00e1 al pa\u00eds por los siguientes seis a\u00f1os. La persona que llegue a la presidencia no gobernar\u00e1 sola, estar\u00e1 acompa\u00f1ada de los secretarios que conformar\u00e1n su gabinete, quienes pondr\u00e1n en marcha el rumbo que les marque para la naci\u00f3n en materia econ\u00f3mica, social, de seguridad [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-22T18:04:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros?","datePublished":"2024-05-22T18:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/"},"wordCount":653,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/","name":"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-22T18:04:02+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfCu\u00e1nto cobra el presidente de M\u00e9xico y cu\u00e1nto cobran los ministros?","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/22\/cuanto-cobra-presidente-mexico-ministros-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-22T18:04:02Z","datePublished":"2024-05-22T18:04:02Z","dateModified":"2024-05-22T18:04:02Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfCu\\u00e1nto cobra el presidente de M\\u00e9xico y cu\\u00e1nto cobran los ministros?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/22\\\/cuanto-cobra-presidente-mexico-ministros-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/22\\\/cuanto-cobra-presidente-mexico-ministros-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-22T18:04:02Z\",\"datePublished\":\"2024-05-22T18:04:02Z\",\"dateModified\":\"2024-05-22T18:04:02Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458267,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/02\/05\/renuncia-jorge-rojas-dapre-orix\/","url_meta":{"origin":1449673,"position":0},"title":"Renuncia director administrativo de la presidencia de Colombia tras el pol\u00e9mico Consejo de Ministros de Petro","author":"","date":"febrero 5, 2025","format":false,"excerpt":"El director del Departamento Administrativo de la Presidencia de la Rep\u00fablica (DAPRE), Jorge Rojas, present\u00f3 su renuncia irrevocable luego de la pol\u00e9mica durante un Consejo de Ministros del gobierno de Colombia en la Casa de Nari\u00f1o transmitido en vivo.En declaraciones a W Radio Colombia, Rojas, un funcionario de alto nivel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448768,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/02\/nuevo-ingreso-minimo-integral-en-venezuela-se-ubicara-en-us-130-el-gobierno-no-precisa-en-cuanto-quedara-el-salario-minimo-trax\/","url_meta":{"origin":1449673,"position":1},"title":"Nuevo \u201cingreso m\u00ednimo integral\u201d en\u00a0Venezuela\u00a0se ubicar\u00e1 en US$ 130; el Gobierno no precisa en cu\u00e1nto quedar\u00e1 el salario m\u00ednimo","author":"","date":"mayo 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Venezuela, Nicol\u00e1s Maduro, anunci\u00f3 este mi\u00e9rcoles 1 de mayo \u2014en el D\u00eda del Trabajador\u2014 un incremento del \u201cingreso m\u00ednimo integral\u201d que ser\u00e1 equivalente a US$ 130 mensuales pagaderos en bol\u00edvares, la moneda local.Maduro afirm\u00f3 en el anuncio que, con sanciones o sin sanciones en\u00a0Venezuela,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466059,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/09\/01\/sheinbaum-mexico-respetado-informe-gobierno-orix\/","url_meta":{"origin":1449673,"position":2},"title":"Sheinbaum dice en su primer informe de gobierno que M\u00e9xico &#171;vive un momento estelar&#187; frente a &#171;expectativas catastr\u00f3ficas&#187;","author":"","date":"septiembre 1, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, defendi\u00f3 su gesti\u00f3n tras los primeros 11 meses de gobierno y asegur\u00f3 que el pa\u00eds vive \u201cun momento estelar\u201d con crecimiento econ\u00f3mico y desarrollo social \u201cfrente a las expectativas catastr\u00f3ficas que hab\u00edan dado a conocer organismos financieros internacionales\u201d.La mandataria confirm\u00f3 que esta semana recibir\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461843,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/05\/01\/maximiliano-ferraro-hay-un-patron-de-conducta-en-el-presidente-milei-de-confundir-lo-publico-con-lo-privado\/","url_meta":{"origin":1449673,"position":3},"title":"Maximiliano Ferraro: &#171;Hay un patr\u00f3n de conducta en el presidente Milei de confundir lo p\u00fablico con lo privado&#187;","author":"","date":"mayo 1, 2025","format":false,"excerpt":"Maximiliano Ferraro, diputado nacional de la Coalici\u00f3n C\u00edvica por la ciudad de Buenos Aires, se refiri\u00f3 a la interpelaci\u00f3n al jefe de Gabinete y las elecciones porte\u00f1as.En CNN Primera Ma\u00f1ana afirm\u00f3 que \u201cla interpelaci\u00f3n a Guillermo Francos dejo sabor a nada. Est\u00e1 claro que las respuestas m\u00e1s constantes del jefe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450171,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/09\/cuanto-cobra-un-eurodiputado-orix\/","url_meta":{"origin":1449673,"position":4},"title":"\u00bfCu\u00e1nto cobra un eurodiputado? Los parlamentarios europeos ganan casi cinco veces m\u00e1s que un trabajador medio en Espa\u00f1a","author":"","date":"junio 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los eurodiputados cobran un salario mensual de 10.075,18 euros brutos (unos US$ 10.961,44), dietas y cuentan con un presupuesto de \u20ac 28.696 al mes (unos US$ 31.187) para contratar asistentes, de acuerdo con los datos del Parlamento Europeo.Sin embargo, una parte de este sueldo bruto est\u00e1 sujeto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459438,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/03\/secretario-comercio-trump-esquema-arancelario-mexico-canada-trax\/","url_meta":{"origin":1449673,"position":5},"title":"Trump podr\u00eda considerar un esquema arancelario diferente para M\u00e9xico y Canad\u00e1, dice secretario de Comercio a CNN","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Horas antes de la fecha l\u00edmite de las 12:01 a.m. ET para la entrada en vigor de los aranceles del 25% a las importaciones de M\u00e9xico y Canad\u00e1, as\u00ed como un arancel adicional del 10% a las importaciones chinas, el secretario de Comercio Howard Lutnick dijo este lunes que el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449673"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449673\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}