{"id":1449766,"date":"2024-05-25T23:03:50","date_gmt":"2024-05-26T06:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/"},"modified":"2024-05-25T23:03:50","modified_gmt":"2024-05-26T06:03:50","slug":"lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/","title":{"rendered":"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica"},"content":{"rendered":"<p>(CNN) &#8212; En sus primeros comentarios p\u00fablicos luego de un discurso controvertido en una reciente graduaci\u00f3n universitaria, el pateador de los Kansas City Chiefs, Harrison Butker, respondi\u00f3 este viernes a la reacci\u00f3n violenta que recibi\u00f3.<\/p>\n<p>\u201cSi no estaba claro que muchos odian los valores cat\u00f3licos eternos, ahora lo est\u00e1\u201d, dijo Butker durante un discurso en la gala \u2018Courage Under Fire\u2019 en Nashville este viernes por la noche.<\/p>\n<p>El discurso fue publicado en X por el medio de comunicaci\u00f3n de derecha The Daily Wire este viernes.<\/p>\n<p>Esta es la primera vez que el tres veces campe\u00f3n del Super Bowl habla p\u00fablicamente sobre su discurso en el Benedictine College del 11 de mayo, donde calific\u00f3 el Mes del Orgullo como un \u201cpecado mortal\u201d y dijo que los logros de una mujer en el hogar son m\u00e1s valiosos que cualquier logro acad\u00e9mico u objetivos profesionales, entre otras cosas.<\/p>\n<p>La gala de este viernes por la noche fue organizada por la Academia Regina Caeli, un grupo escolar cat\u00f3lico h\u00edbrido de campus y educaci\u00f3n en el hogar con varias ubicaciones en todo el pa\u00eds. La gala cont\u00f3 con varios otros oradores, incluida la personalidad de los medios de derecha y presentador del Daily Wire, Matt Walsh.<\/p>\n<p>&#171;En los \u00faltimos d\u00edas, mis creencias, o lo que la gente piensa que creo, han sido el centro de innumerables discusiones en todo el mundo&#187;, dijo Butker, que forma parte de la junta directiva de la escuela.<\/p>\n<p>La Academia Regina Caeli no respondi\u00f3 de inmediato a la solicitud de comentarios de CNN.<\/p>\n<p>\u201cAl principio, mucha gente expres\u00f3 un nivel de odio impactante. Pero a medida que pasaron los d\u00edas, incluso aquellos que no estaban de acuerdo con mis puntos de vista compartieron su apoyo a mi libertad de religi\u00f3n\u201d, dijo Butker este viernes.<\/p>\n<p>Butker reafirm\u00f3 su compromiso con su fe cat\u00f3lica diciendo: &#171;Nuestro amor por Jes\u00fas y, por lo tanto, nuestro deseo de hablar abiertamente nunca debe ser superado por el anhelo de nuestra naturaleza ca\u00edda de ser amado por el mundo&#187;.<\/p>\n<p>Durante su discurso, Butker se refiri\u00f3 a San Daniel, el profeta b\u00edblico que fue arrojado al foso de los leones por comprometerse a orar a Dios, a pesar de una ley que condenaba a muerte a sus fieles.<\/p>\n<p>\u201cNo puedo evitar temblar al pensar en el valor que muchos santos han demostrado en sus vidas\u201d, dijo Butker.<\/p>\n<p>Dios salv\u00f3 a Daniel debido a su compromiso con la fe, seg\u00fan el Antiguo Testamento.<\/p>\n<p>\u201c\u00bfSer\u00eda tan audaz si la repercusi\u00f3n fuera la que enfrent\u00f3 Daniel al ser dado de comer a los leones? En realidad, cualquier coraje que haya mostrado me llevar\u00e1 a alg\u00fan sufrimiento menor. Y eso har\u00e1 que a algunas personas tal vez nunca les guste, pero esa podr\u00eda ser la voluntad de Dios\u201d, dijo el pateador de los Chiefs.<\/p>\n<p>La NFL emiti\u00f3 un comunicado a principios de este mes diciendo que los comentarios de Butker no reflejan las opiniones de la liga.<\/p>\n<p>Su compa\u00f1ero estrella de los Chiefs, Travis Kelce, respondi\u00f3 recientemente al discurso de graduaci\u00f3n diciendo que no est\u00e1 de acuerdo con &#171;casi ninguna&#187; de las opiniones de Butker, pero lo valora como compa\u00f1ero de equipo, inform\u00f3 CNN anteriormente.<\/p>\n<p>\u201cLo aprecio como compa\u00f1ero de equipo. Creo que Pat [Mahomes] lo dijo mejor cuando es una gran persona y un gran compa\u00f1ero de equipo\u201d, dijo Kelce en el \u00faltimo episodio del podcast \u201cNew Heights\u201d que presenta con su hermano Jason.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; En sus primeros comentarios p\u00fablicos luego de un discurso controvertido en una reciente graduaci\u00f3n universitaria, el pateador de los Kansas City Chiefs, Harrison Butker, respondi\u00f3 este viernes a la reacci\u00f3n violenta que recibi\u00f3. \u201cSi no estaba claro que muchos odian los valores cat\u00f3licos eternos, ahora lo est\u00e1\u201d, dijo Butker durante un discurso en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449766","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; En sus primeros comentarios p\u00fablicos luego de un discurso controvertido en una reciente graduaci\u00f3n universitaria, el pateador de los Kansas City Chiefs, Harrison Butker, respondi\u00f3 este viernes a la reacci\u00f3n violenta que recibi\u00f3. \u201cSi no estaba claro que muchos odian los valores cat\u00f3licos eternos, ahora lo est\u00e1\u201d, dijo Butker durante un discurso en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-26T06:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica\",\"datePublished\":\"2024-05-26T06:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/\"},\"wordCount\":633,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/\",\"name\":\"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-26T06:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica - Noticias","og_description":"(CNN) &#8212; En sus primeros comentarios p\u00fablicos luego de un discurso controvertido en una reciente graduaci\u00f3n universitaria, el pateador de los Kansas City Chiefs, Harrison Butker, respondi\u00f3 este viernes a la reacci\u00f3n violenta que recibi\u00f3. \u201cSi no estaba claro que muchos odian los valores cat\u00f3licos eternos, ahora lo est\u00e1\u201d, dijo Butker durante un discurso en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-26T06:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/"},"author":{"name":"","@id":""},"headline":"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica","datePublished":"2024-05-26T06:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/"},"wordCount":633,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/","name":"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-26T06:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El pateador de los Kansas City Chiefs responde a los pol\u00e9micos comentarios de graduaci\u00f3n durante una gala de una escuela cat\u00f3lica","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/25\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-26T06:03:50Z","datePublished":"2024-05-26T06:03:50Z","dateModified":"2024-05-26T06:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El pateador de los Kansas City Chiefs responde a los pol\\u00e9micos comentarios de graduaci\\u00f3n durante una gala de una escuela cat\\u00f3lica\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/25\\\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/25\\\/lanzador-de-los-kansas-city-chiefs-responde-a-polemicos-comentarios-graduacion-durante-gala-escuela-catolica-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-26T06:03:50Z\",\"datePublished\":\"2024-05-26T06:03:50Z\",\"dateModified\":\"2024-05-26T06:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449528,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/16\/analisis-las-reacciones-al-discurso-de-graduacion-de-harrison-butker-jugador-de-la-nfl-alcanzan-un-nuevo-nivel\/","url_meta":{"origin":1449766,"position":0},"title":"AN\u00c1LISIS | Las reacciones al discurso de graduaci\u00f3n de Harrison Butker, jugador de la NFL, alcanzan un nuevo nivel","author":"","date":"mayo 16, 2024","format":false,"excerpt":"(CNN) -- La NFL se distanci\u00f3 de los pol\u00e9micos comentarios del pateador de los Kansas City Chiefs, Harrison Butker, durante un reciente discurso de graduaci\u00f3n. Adem\u00e1s de calificar el Mes del Orgullo de \"pecado mortal\" y lamentar las iniciativas en favor de la diversidad y la equidad, Butker desat\u00f3 una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445302,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/12\/los-kansas-city-chiefs-derrotan-a-los-san-francisco-49ers-en-tiempo-extra-en-el-super-bowl-lviii-y-se-convierten-en-los-primeros-campeones-consecutivos-de-la-nfl-en-19-anos\/","url_meta":{"origin":1449766,"position":1},"title":"Los Kansas City Chiefs derrotan a los San Francisco 49ers en tiempo extra en el Super Bowl LVIII y se convierten en los primeros campeones consecutivos de la NFL en 19 a\u00f1os","author":"","date":"febrero 12, 2024","format":false,"excerpt":"(CNN) --\u00a0 Los Kansas City Chiefs se convirtieron este domingo en el primer equipo en ganar Super Bowl consecutivos en 19 a\u00f1os, derrotando a los San Francisco 49ers 25-22 en tiempo extra en Las Vegas. Liderados por el mariscal de campo Patrick Mahomes, los Chiefs han ganado Super Bowl en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445305,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/12\/los-kansas-city-chiefs-derrotan-a-los-san-francisco-49ers-en-tiempo-extra-en-el-super-bowl-lviii-y-se-convierten-en-los-primeros-campeones-consecutivos-de-la-nfl-en-19-anos-2\/","url_meta":{"origin":1449766,"position":2},"title":"Los Kansas City Chiefs derrotan a los San Francisco 49ers en tiempo extra en el Super Bowl LVIII y se convierten en los primeros campeones consecutivos de la NFL en 19 a\u00f1os","author":"","date":"febrero 12, 2024","format":false,"excerpt":"(CNN) --\u00a0 Los Kansas City Chiefs se convirtieron este domingo en el primer equipo en ganar Super Bowl consecutivos en 19 a\u00f1os, derrotando a los San Francisco 49ers 25-22 en tiempo extra en Las Vegas. Liderados por el mariscal de campo Patrick Mahomes, los Chiefs han ganado Super Bowl en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468634,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/11\/23\/resultados-nfl-semana-12-futbol-americano-orix\/","url_meta":{"origin":1449766,"position":3},"title":"Semana 12 de la NFL: los Chiefs reviven; Ravens y Patriots siguen en racha ganadora","author":"","date":"noviembre 23, 2025","format":false,"excerpt":"La semana 12 de la NFL ya dej\u00f3 un par de sorpresas, siendo la m\u00e1s significativa la victoria de los Houston Texans ante los Buffalo Bills el jueves, y un gran partido entre los los Indianapolis Colts y los Kansas City Chiefs.Parec\u00eda que se terminaba la temporada de los Chiefs,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466181,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/09\/05\/latinos-nfl-jugadores-futbol-americano-orix\/","url_meta":{"origin":1449766,"position":4},"title":"Del legado latino al presente: la NFL 2025\/2026 marca un hito para sus jugadores hispanos","author":"","date":"septiembre 5, 2025","format":false,"excerpt":"La Liga Nacional de F\u00fatbol Americano Profesional, la NFL, arranc\u00f3 su temporada n\u00famero 106 este mes, que coincide adem\u00e1s con el mes de la Herencia Hispana. Han sido muchos los latinos que han contribuido a lo largo de los a\u00f1os al deporte m\u00e1s popular de Estados Unidos dejando su huella\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457910,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/27\/los-chiefs-y-eagles-reservan-sus-viajes-al-super-bowl-trax\/","url_meta":{"origin":1449766,"position":5},"title":"Los Chiefs y los Eagles reservan pasajes al super bowl","author":"","date":"enero 27, 2025","format":false,"excerpt":"El enfrentamiento del Super Bowl ya est\u00e1 oficialmente decidido: los Philadelphia Eagles y los Kansas City Chiefs se enfrentar\u00e1n una vez m\u00e1s por el premio m\u00e1s grande de la NFL en el Super Bowl LIX en dos semanas en Nueva Orleans.El gran juego est\u00e1 programado para comenzar a las 6:30\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449766"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449766\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}