{"id":1449767,"date":"2024-05-26T01:03:46","date_gmt":"2024-05-26T08:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/"},"modified":"2024-05-26T01:03:46","modified_gmt":"2024-05-26T08:03:46","slug":"no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/","title":{"rendered":"&#171;No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia&#187;, dice Boris Becker"},"content":{"rendered":"<p>(CNN) &#8212; Cuando Rafael Nadal deje Roland Garros como jugador por \u00faltima vez, uno de los mayores amores de todo el deporte llegar\u00e1 a su fin.<\/p>\n<p>Desde que hizo su debut ganador en el Abierto de Francia de 2005 cuando ten\u00eda 18 a\u00f1os y venci\u00f3 a Roger Federer en las semifinales en su cumplea\u00f1os n\u00famero 19, Nadal ha perdido s\u00f3lo tres veces en la arcilla parisina en los 19 a\u00f1os transcurridos.<\/p>\n<p>El r\u00e9cord de victorias y derrotas de Nadal en la capital francesa es de 112-3, una impresionante tasa de victorias del 97,4%, aunque tambi\u00e9n tuvo que retirarse antes de su partido de tercera ronda en 2016 debido a una lesi\u00f3n.<\/p>\n<p>El nombre del espa\u00f1ol se ha convertido en sin\u00f3nimo del Abierto de Francia; La estatua del &#8216;Rey de la Arcilla&#8217;, posada despu\u00e9s de golpear uno de esos famosos golpes de derecha, se encuentra en la entrada del lugar desde 2021.<\/p>\n<p>&#171;Lo ganas cinco veces, eso es mucho&#187;, dijo a CNN el gran tenista Boris Becker. \u201cLo ganas 10 veces, es imposible. Nadal lo ha ganado 14 veces. No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale ese\u201d.<\/p>\n<p>Becker se\u00f1ala a algunos de los grandes del tenis, incluido \u00e9l mismo, que no lograron ganar el Abierto de Francia para resaltar a\u00fan m\u00e1s lo absurdo del r\u00e9cord de Nadal en Par\u00eds.<\/p>\n<p>\u201c[Bjorn] Borg lo gan\u00f3 seis veces, lo que en ese momento era inaudito, pero [Pete] Sampras nunca lo gan\u00f3, [Stefan] Edberg nunca lo gan\u00f3, Becker nunca lo gan\u00f3. As\u00ed que no es ninguna verg\u00fcenza no ganar el Abierto de Francia\u201d, afirm\u00f3 el alem\u00e1n de 56 a\u00f1os.<\/p>\n<p>\u201cLo creas o no, me gust\u00f3 jugar en Par\u00eds. Tuve un gran apoyo, les gust\u00f3 mi estilo. S\u00e9 que nunca lo gan\u00e9, el \u00fanico major que no gan\u00e9. Llegu\u00e9 a las semifinales varias veces, pero lo hice lo mejor que pude con mi estilo\u201d, a\u00f1adi\u00f3 Becker, conocido por su servicio y volea.<\/p>\n<p>El juego de Nadal est\u00e1 casi hecho a medida para la arcilla. El fuerte efecto liftado en sus golpes de fondo significa que la pelota se agarra a la superficie y rebota alto hacia el oponente, algo que atorment\u00f3 el rev\u00e9s de Federer a lo largo de los a\u00f1os.<\/p>\n<p>Nadal gan\u00f3 el primer Grand Slam de su carrera en el Abierto de Francia de 2005. (Cr\u00e9dito: Christophe Ena\/AP)<\/p>\n<p>La velocidad y agilidad de Nadal no solo le permite alcanzar m\u00e1s bolas que muchos otros jugadores, lo que obliga a los oponentes a realizar m\u00e1s tiros para ganar un punto, sino que tambi\u00e9n lo coloca en posici\u00f3n antes y le permite deslizarse elegantemente a trav\u00e9s de la tierra roja en sus tiros.<\/p>\n<p>La arcilla suelta tambi\u00e9n absorbe algo de velocidad de la pelota, lo que hace que los tiros sean m\u00e1s lentos y los peloteos m\u00e1s largos, algo en lo que la excelente forma f\u00edsica de Nadal le dio una ventaja, pero que ahora probablemente lo perjudicar\u00e1 dadas las lesiones que ha tenido que afrontar.<\/p>\n<p>\u201cEl objetivo final en tierra batida, la mentalidad es cometer un error menos que el rival, lo cual es diferente a todas las dem\u00e1s superficies\u201d, explica Becker. \u201cAs\u00ed que si buscas m\u00e1s ganadores que tu oponente en tierra batida, al final vas a perder.<\/p>\n<p>\u201cLa arcilla es f\u00edsicamente muy exigente. Hay que tener una t\u00e9cnica de deslizamiento especial que sea diferente al resto de superficies.<\/p>\n<p>\u201cUn buen efecto liftado de derecha o de rev\u00e9s ayuda, pero hoy en d\u00eda los jugadores practican muchos drop shots, muchos saques de patada e incluso entran [a la red], por lo que la versatilidad tambi\u00e9n es muy importante en arcilla\u201d.<\/p>\n<p>Se habla mucho sobre el p\u00fablico del Abierto de Francia cada a\u00f1o, algunos buenos, otros malos, pero proporciona quiz\u00e1s la atm\u00f3sfera m\u00e1s bulliciosa de cualquier torneo de tenis del mundo.<\/p>\n<p>El hecho de que un p\u00fablico partidario decida apoyarte como jugador o animarte puede tener un impacto en el resultado de un partido, dice Becker.<\/p>\n<p>Nadal, no hace falta decirlo, es siempre el favorito del p\u00fablico del Abierto de Francia y disfrut\u00f3 de un apoyo vociferante en algunos de sus partidos m\u00e1s dif\u00edciles.<\/p>\n<p>El Abierto de Francia fue el \u00fanico Grand Slam que Becker no logr\u00f3 ganar. (Cr\u00e9dito: Getty images)<\/p>\n<p>\u201cJugaren Philippe Chatrier frente a un p\u00fablico parisino es algo \u00fanico y muy desafiante\u201d, dice Becker. \u201cLa cancha es probablemente la cancha de arcilla m\u00e1s grande del tenis, puedes sentirte intimidado muy r\u00e1pidamente.<\/p>\n<p>\u201cNo hay otra ciudad en el mundo que se parezca a la multitud parisina. Es muy, muy singular, es muy ruidoso. Si te apoyan, genial. Si no te apoyan, no tienes ninguna posibilidad.<\/p>\n<p>&#171;Por eso creo que la multitud casi importa m\u00e1s en Par\u00eds que en cualquier otro lugar del mundo&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Cuando Rafael Nadal deje Roland Garros como jugador por \u00faltima vez, uno de los mayores amores de todo el deporte llegar\u00e1 a su fin. Desde que hizo su debut ganador en el Abierto de Francia de 2005 cuando ten\u00eda 18 a\u00f1os y venci\u00f3 a Roger Federer en las semifinales en su cumplea\u00f1os n\u00famero [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449767","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia&quot;, dice Boris Becker - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia&quot;, dice Boris Becker - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Cuando Rafael Nadal deje Roland Garros como jugador por \u00faltima vez, uno de los mayores amores de todo el deporte llegar\u00e1 a su fin. Desde que hizo su debut ganador en el Abierto de Francia de 2005 cuando ten\u00eda 18 a\u00f1os y venci\u00f3 a Roger Federer en las semifinales en su cumplea\u00f1os n\u00famero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-26T08:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia&#187;, dice Boris Becker\",\"datePublished\":\"2024-05-26T08:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/\"},\"wordCount\":876,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/\",\"name\":\"\\\"No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia\\\", dice Boris Becker - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-26T08:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia&#187;, dice Boris Becker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia\", dice Boris Becker - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia\", dice Boris Becker - Noticias","og_description":"(CNN) &#8212; Cuando Rafael Nadal deje Roland Garros como jugador por \u00faltima vez, uno de los mayores amores de todo el deporte llegar\u00e1 a su fin. Desde que hizo su debut ganador en el Abierto de Francia de 2005 cuando ten\u00eda 18 a\u00f1os y venci\u00f3 a Roger Federer en las semifinales en su cumplea\u00f1os n\u00famero [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-26T08:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia&#187;, dice Boris Becker","datePublished":"2024-05-26T08:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/"},"wordCount":876,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/","name":"\"No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia\", dice Boris Becker - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-26T08:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia&#187;, dice Boris Becker"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;No conozco ning\u00fan otro r\u00e9cord en ning\u00fan otro deporte que iguale el \u00e9xito de Rafael Nadal en el Abierto de Francia&#187;, dice Boris Becker","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/26\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-26T08:03:46Z","datePublished":"2024-05-26T08:03:46Z","dateModified":"2024-05-26T08:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;No conozco ning\\u00fan otro r\\u00e9cord en ning\\u00fan otro deporte que iguale el \\u00e9xito de Rafael Nadal en el Abierto de Francia&#187;, dice Boris Becker\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/26\\\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/26\\\/no-conozco-ningun-otro-record-otro-deporte-iguale-exito-rafael-nadal-abierto-de-francia-dice-boris-becker-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-26T08:03:46Z\",\"datePublished\":\"2024-05-26T08:03:46Z\",\"dateModified\":\"2024-05-26T08:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448513,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/25\/rafael-nadal-limitaciones-lesiones-abierto-francia-trax\/","url_meta":{"origin":1449767,"position":0},"title":"Rafael Nadal todav\u00eda enfrenta &#171;limitaciones&#187; por lesiones y no est\u00e1 seguro de si competir\u00e1 en el Abierto de Francia","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- Rafael Nadal dijo que trata de disfrutar cada momento que pasa en una cancha de tenis al tiempo que lucha contra las lesiones.En declaraciones a los periodistas antes del Abierto de Madrid, Nadal, que s\u00f3lo ha jugado cinco partidos este a\u00f1o, puso en duda su participaci\u00f3n en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462795,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/05\/26\/rafael-nadal-despedida-ovacion-trax\/","url_meta":{"origin":1449767,"position":1},"title":"Rafael Nadal recibe un emotivo homenaje en su despedida en el Roland Garros","author":"","date":"mayo 26, 2025","format":false,"excerpt":"Pocos deportistas se han convertido en sin\u00f3nimo de un \u00fanico evento m\u00e1s que Rafael Nadal y el Abierto de Francia.El espa\u00f1ol gan\u00f3 un r\u00e9cord de 14 t\u00edtulos en el Grand Slam en arcilla durante su ilustre carrera y Roland Garros le dio a su legendario campe\u00f3n un \u00faltimo adi\u00f3s especial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455932,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/19\/rafael-nadal-pierde-posiblemente-ultimo-partido-profesional-carrera-trax\/","url_meta":{"origin":1449767,"position":2},"title":"Rafael Nadal se despide: perdi\u00f3 su \u00faltimo partido profesional y se retira como una leyenda","author":"","date":"noviembre 19, 2024","format":false,"excerpt":"(CNN) \u2014 En escenas emotivas en Espa\u00f1a, Rafael Nadal, en su \u00faltimo evento de tenis profesional, perdi\u00f3 este martes ante Botic van de Zandschulp, de Pa\u00edses Bajos, en los cuartos de final de la Copa Davis en M\u00e1laga.El p\u00fablico trat\u00f3 de animar al 22 veces campe\u00f3n de Grand Slam individual,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455020,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/10\/10\/grand-slam-10-tenistas-orix\/","url_meta":{"origin":1449767,"position":3},"title":"Estos son los 10 tenistas masculinos con m\u00e1s t\u00edtulos de Grand Slam","author":"","date":"octubre 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La leyenda del tenis Rafael Nadal anunci\u00f3 este jueves su retiro despu\u00e9s de la final de la Copa Davis en noviembre. El espa\u00f1ol de 38 a\u00f1os es considerado uno de los mejores tenistas de todos los tiempos, compitiendo con Novak Djokovic y Roger Federer, pero \u00bfqui\u00e9n es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450158,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/07\/final-del-abierto-de-francia-iga-swiatek-favorita-tercer-titulo-consecutivo-cuando-enfrente-jasmine-paolini-paris-trax\/","url_meta":{"origin":1449767,"position":4},"title":"Final del Abierto de Francia: Iga \u015awi\u0105tek es la gran favorita para ganar el tercer t\u00edtulo consecutivo cuando se enfrente a la italiana Jasmine Paolini en Par\u00eds","author":"","date":"junio 7, 2024","format":false,"excerpt":"(CNN) --La No. 1 del mundo, Iga \u015awi\u0105tek, tiene una oportunidad de oro para ganar su tercer t\u00edtulo consecutivo y cuarto en general del Abierto de Francia este s\u00e1bado cuando se enfrente a la italiana Jasmine Paolini en la final.Ninguna mujer ha ganado tres t\u00edtulos consecutivos en Roland Garros desde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442977,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/01\/rafael-nadal-regresa-tras-una-lesion-y-no-descarta-seguir-mas-alla-de-2024\/","url_meta":{"origin":1449767,"position":5},"title":"Rafael Nadal regresa tras una lesi\u00f3n y no descarta seguir m\u00e1s all\u00e1 de 2024","author":"","date":"enero 1, 2024","format":false,"excerpt":"(CNN) -- Rafael Nadal hizo su tan esperada reaparici\u00f3n tras una lesi\u00f3n este domingo, jugando en su primer partido desde enero cuando sali\u00f3 a la cancha con su compa\u00f1ero de dobles Marc L\u00f3pez en el Brisbane International, y no descart\u00f3 seguir jugando despu\u00e9s de la temporada 2024.Aunque la pareja espa\u00f1ola\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449767"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449767\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}