{"id":1449833,"date":"2024-05-29T13:03:38","date_gmt":"2024-05-29T20:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/"},"modified":"2024-05-29T13:03:38","modified_gmt":"2024-05-29T20:03:38","slug":"opinion-fenomeno-musical-hamilton-hispano-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/","title":{"rendered":"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical &#171;Hamilton&#187; lo cre\u00f3 un hispano"},"content":{"rendered":"<p>Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion<\/p>\n<p>(CNN Espa\u00f1ol) &#8212; \u201cHamilton\u201d es la historia del pasado de Estados Unidos contada por los Estados Unidos de ahora. \u201cUn musical teatral \u00fanico, que ha transformado el teatro y la forma en que pensamos sobre la historia\u201d, dijo el New York Times en su maravillosa rese\u00f1a de la obra. \u00a1Una nueva e inspiradora forma de contar la historia!<\/p>\n<p>Y con una m\u00fasica potente, que combina hip-hop, jazz, R&#038;B y Broadway, \u201cHamilton\u201d toma la historia de Alexander Hamilton -uno de los padres fundadores y uno de los autores principales de los Federalist Papers- para crear un momento revolucionario en el teatro: un musical con un profundo impacto en la cultura, la pol\u00edtica y la educaci\u00f3n. Y despu\u00e9s de su estreno en Broadway, hace 9 a\u00f1os, ha creado un nuevo inter\u00e9s en la historia de EE.UU. en los que fueron tiempos vitales para su consolidaci\u00f3n como naci\u00f3n. La he visto muchas veces y es palpable el entusiasmo de las audiencias de todas las edades.<\/p>\n<p>Con libreto, m\u00fasica y letra del genial puertorrique\u00f1o Lin-Manuel Miranda, un elenco multirracial, direcci\u00f3n de Thomas Kail, coreograf\u00eda de Andy Blankenbuehler y supervisi\u00f3n musical y orquestaciones de Alex Lacamoire, \u201cHamilton\u201d se basa en la aclamada biograf\u00eda hom\u00f3nima de Ron Chernow. Y es un extraordinario fen\u00f3meno internacional que lanz\u00f3 a Miranda al escenario de los grandes triunfadores.<\/p>\n<p>Miranda ha dicho en varias ocasiones lo que me dijo a m\u00ed hace cinco a\u00f1os: \u201cLa raz\u00f3n del triunfo de \u2018Hamilton\u2019 es porque no hay realmente distancia entre lo que pas\u00f3 hace m\u00e1s de 200 a\u00f1os y lo que es -y c\u00f3mo luce- Estados Unidos hoy. Y eso ayuda a crear una conexi\u00f3n mucho mejor que si solo hubiera 20 hombres blancos en el escenario\u201d.<\/p>\n<p>Lin-Manuel Miranda dijo que decidi\u00f3 escribir una obra de teatro dedicada a Hamilton por varias razones. En primer lugar, estaba fascinado por el personaje porque ve\u00eda en \u00e9l a un hombre cuya vida y legado ofrec\u00edan una narrativa rica y compleja que merec\u00eda ser explorada en profundidad.<\/p>\n<p>OPINI\u00d3N | \u00bfEl rencor tensa a\u00fan m\u00e1s las relaciones entre el pr\u00edncipe Harry y su familia?<\/p>\n<p>Adem\u00e1s, Miranda quer\u00eda crear una obra que fuera relevante para el p\u00fablico contempor\u00e1neo e identific\u00f3 en la historia de Hamilton temas universales como la inmigraci\u00f3n, la identidad, el liderazgo y el legado, que resonar\u00edan en la audiencia moderna.<\/p>\n<p>Por \u00faltimo, Miranda pens\u00f3 que \u201cHamilton\u201d era una oportunidad para innovar en el g\u00e9nero del teatro musical combinando elementos de hip-hop, rap y m\u00fasica contempor\u00e1nea con la narrativa tradicional del teatro musical y as\u00ed obtener algo fresco y emocionante.<\/p>\n<p>El musical -ganador de los premios Tony, Grammy, Olivier y Pulitzer- tiene producciones simult\u00e1neas en varios pa\u00edses \u00a1y es dif\u00edcil conseguir boletos! Rese\u00f1as excelentes de respetados peri\u00f3dicos y cr\u00edticos teatrales, igual que las recomendaciones a viva voz de quienes lo han visto y los vuelven a ver, han creado el m\u00edtico \u00e9xito de Hamilton.<\/p>\n<p>\u00a1Un \u00e9xito cada d\u00eda mayor, pues todos quieren ver \u201cHamilton\u201d y conocer qui\u00e9n era el famoso patriota estadounidense que cre\u00f3 tantas leyes y tuvo una vida y unos amores tan controversiales! Y lo pueden hacer en producciones simult\u00e1neas en Nueva York, varias ciudades de EE.UU., adem\u00e1s del Reino Unido, Irlanda, Australia, Singapur y otros pa\u00edses en Asia.<\/p>\n<p>Yo lo he visto cinco veces (tres en Nueva York y dos en Londres) y en cada producci\u00f3n descubro algo nuevo. Tanto mi hija como mi nieta de 12 a\u00f1os, que adoran la m\u00fasica y la historia de Estados Unidos y lo han visto varias veces, se saben de memoria cada canci\u00f3n. \u00a1Y es que la energ\u00eda de Hamilton es \u00fanica! Poderosa, vibrante, contagiosa y con un profundo sentimiento pol\u00edtico y social.<\/p>\n<p>Como dato curioso, en Nueva York puede visitarse la casa donde vivi\u00f3 Hamilton en la parte alta de Manhattan (muy interesante experiencia), igual que su tumba en el cementerio de la hist\u00f3rica iglesia de la Trinidad en la zona de Wall Street. Junto a \u00e9l descansa su esposa Eliza, cuya historia de amor es parte del dram\u00e1tico musical. Es un curioso lugar de descanso para este hombre, experto en n\u00fameros y finanzas, quien fuera el primer secretario del Tesoro del pa\u00eds en el gobierno de George Washington y cuya efigie adorna los billetes de US$ 10.<\/p>\n<p>Tr\u00e1gicamente, Alexander Hamilton muri\u00f3 el 12 de julio de 1804 -con solo 47 a\u00f1os- en un absurdo duelo con el oponente pol\u00edtico Aaron Burr.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion (CNN Espa\u00f1ol) &#8212; \u201cHamilton\u201d es la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449833","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical &quot;Hamilton&quot; lo cre\u00f3 un hispano - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical &quot;Hamilton&quot; lo cre\u00f3 un hispano - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion (CNN Espa\u00f1ol) &#8212; \u201cHamilton\u201d es la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-29T20:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical &#171;Hamilton&#187; lo cre\u00f3 un hispano\",\"datePublished\":\"2024-05-29T20:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/\"},\"wordCount\":879,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/\",\"name\":\"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical \\\"Hamilton\\\" lo cre\u00f3 un hispano - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-29T20:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical &#171;Hamilton&#187; lo cre\u00f3 un hispano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical \"Hamilton\" lo cre\u00f3 un hispano - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/","og_locale":"es_ES","og_type":"article","og_title":"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical \"Hamilton\" lo cre\u00f3 un hispano - Noticias","og_description":"Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion (CNN Espa\u00f1ol) &#8212; \u201cHamilton\u201d es la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-29T20:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/"},"author":{"name":"","@id":""},"headline":"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical &#171;Hamilton&#187; lo cre\u00f3 un hispano","datePublished":"2024-05-29T20:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/"},"wordCount":879,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/","name":"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical \"Hamilton\" lo cre\u00f3 un hispano - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-29T20:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical &#171;Hamilton&#187; lo cre\u00f3 un hispano"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical &#171;Hamilton&#187; lo cre\u00f3 un hispano","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-29T20:03:38Z","datePublished":"2024-05-29T20:03:38Z","dateModified":"2024-05-29T20:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"OPINI\\u00d3N | Una nueva forma de contar la historia: el fen\\u00f3meno musical &#171;Hamilton&#187; lo cre\\u00f3 un hispano\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/29\\\/opinion-fenomeno-musical-hamilton-hispano-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/29\\\/opinion-fenomeno-musical-hamilton-hispano-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-29T20:03:38Z\",\"datePublished\":\"2024-05-29T20:03:38Z\",\"dateModified\":\"2024-05-29T20:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465859,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/26\/cargamento-record-drogas-sobredosis-florida-trax\/","url_meta":{"origin":1449833,"position":0},"title":"Incautan cargamento r\u00e9cord de drogas, suficiente para &#171;causar sobredosis a toda la poblaci\u00f3n&#187; de Florida, dice funcionario","author":"","date":"agosto 26, 2025","format":false,"excerpt":"Un barco de la Guardia Costera estadounidense descarg\u00f3 este lunes un alijo r\u00e9cord de drogas ilegales que, si hubiera llegado a las calles, representar\u00eda alrededor de 23 millones de dosis letales de coca\u00edna, comunic\u00f3 esta agencia.El patrullero Hamilton descarg\u00f3 aproximadamente 27.800 kilos de coca\u00edna y 6.600 kilos de marihuana en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455102,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/10\/15\/lyle-erik-menendez-entrevista-director-alejandro-hartmann-orix\/","url_meta":{"origin":1449833,"position":1},"title":"&#171;Creo que Lyle y Erik ya han pagado por el crimen de sus padres&#187;, dice el director de &#171;Los\u00a0hermanos Men\u00e9ndez&#187;","author":"","date":"octubre 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Lyle y Erik Men\u00e9ndez volvieron a estar ante los ojos del mundo despu\u00e9s de que Netflix estrenara dos proyectos en 2024 sobre sus vidas. Los hermanos, que en 1989\u00a0 confesaron haber matado\u00a0a sus padres en el interior de su mansi\u00f3n de Beverly Hills, alegaron a\u00f1os de abusos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464652,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/18\/juez-bloqueo-decreto-trump-ciudadania-nacimiento-hacerlo-de-nuevo-trax\/","url_meta":{"origin":1449833,"position":2},"title":"Juez que bloque\u00f3 el decreto de Trump sobre la ciudadan\u00eda por nacimiento quiere hacerlo de nuevo","author":"","date":"julio 18, 2025","format":false,"excerpt":"Un juez federal que anteriormente bloque\u00f3 el esfuerzo del presidente de Estados Unidos, Donald Trump, para poner fin a la ciudadan\u00eda por derecho de nacimiento pas\u00f3 m\u00e1s de una hora debatiendo este viernes si su interdicto nacional podr\u00eda mantenerse despu\u00e9s de que la Corte Suprema limitara la capacidad de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461783,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/30\/fernando-pedrosa-el-primer-logro-de-trump-es-haber-transformado-de-forma-muy-trascendente-al-resto-del-mundo\/","url_meta":{"origin":1449833,"position":3},"title":"Fernando Pedrosa: &#171;El primer logro de Trump es haber transformado de forma muy trascendente al resto del mundo&#187;","author":"","date":"abril 30, 2025","format":false,"excerpt":"Fernando Pedrosa, analista pol\u00edtico internacional, historiador y polit\u00f3logo, se refiri\u00f3 a los primeros 100 d\u00edas del segundo mandato de Donald Trump.En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201cel mundo que recibi\u00f3 Donald Trump es muy violento. En estos d\u00edas se ha posicionado como una figura centralizadora y nada pasa sin que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448689,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/","url_meta":{"origin":1449833,"position":4},"title":"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico","author":"","date":"abril 30, 2024","format":false,"excerpt":"(CNN) -- Decenas de estudiantes de la Universidad de Columbia se han atrincherado dentro del Edificio Hamilton, el lugar de la ocupaci\u00f3n universitaria de 1968, seg\u00fan una publicaci\u00f3n en redes sociales de Estudiantes de Columbia por la Justicia en Palestina.La Universidad de Columbia ha estado en el epicentro de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446503,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/04\/opinion-viajes-historia-mari-rodriguez-orix\/","url_meta":{"origin":1449833,"position":5},"title":"OPINI\u00d3N | \u00bfPor qu\u00e9 viajamos? \u00bfPara encontrar una nueva realidad? \u00a1Yo busco caminar sobre la historia!","author":"","date":"marzo 4, 2024","format":false,"excerpt":"Nota del editor: Mari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449833"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449833\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}