{"id":1449883,"date":"2024-05-31T02:03:50","date_gmt":"2024-05-31T09:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/"},"modified":"2024-05-31T02:03:50","modified_gmt":"2024-05-31T09:03:50","slug":"que-pasara-trump-condenado-juicio-pago-por-silencio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/","title":{"rendered":"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio?"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Un jurado de Nueva York conden\u00f3 a Donald Trump por 34 delitos graves de falsificaci\u00f3n de registros empresariales, lo que puso fin a un juicio que dur\u00f3 semanas, pero dio paso a una nueva fase del hist\u00f3rico caso.<\/p>\n<p>Trump se encuentra ahora en la posici\u00f3n \u00fanica de ser el primer expresidente de Estados Unidos condenado por un delito grave, y se enfrenta a la posibilidad de una pena de prisi\u00f3n o libertad condicional por sus delitos derivados de una trama de pagos de dinero por silencio antes de las elecciones presidenciales de 2016.<\/p>\n<p>Tambi\u00e9n es probable que Trump &#8211;conocido por interponer largos recursos contra las sentencias judiciales en su contra&#8211; apele la condena, lo que podr\u00eda retrasar significativamente su sentencia, fijada actualmente para el 11 de julio.<\/p>\n<p>Condenan a Donald Trump por todos los cargos de falsificaci\u00f3n de registros comerciales en un caso de pago por silencio en Nueva York<\/p>\n<p>Esto es lo que hay que saber sobre el caso tras la condena de Trump.<\/p>\n<p>\u00bfCu\u00e1ndo se dictar\u00e1 sentencia contra Trump?<\/p>\n<p>El juez Juan Merchan fij\u00f3 la sentencia de Trump para el 11 de julio a las 10 de la ma\u00f1ana, hora del Este.<\/p>\n<p>Merchan podr\u00eda condenar a Trump a libertad condicional o a una pena de 1 a\u00f1o y medio a 4 a\u00f1os por cada cargo en una prisi\u00f3n estatal, con un m\u00e1ximo de 20 a\u00f1os.<\/p>\n<p>Por ahora, el expresidente permanecer\u00e1 fuera de prisi\u00f3n mientras espera su sentencia. Los fiscales no pidieron que Trump pagara fianza alguna.<\/p>\n<p>(Cr\u00e9dito: SETH WENIG\/POOL\/AFP via Getty Images)<\/p>\n<p>\u00bfPuede Trump apelar su condena?<\/p>\n<p>Trump ha recurrido sistem\u00e1ticamente las sentencias judiciales en su contra en un intento de retrasar el proceso o de llevar su caso ante un tribunal que pueda darle la raz\u00f3n. El caso de Nueva York no es diferente.<\/p>\n<p>Poco despu\u00e9s de que Trump fuera condenado, su abogado Todd Blanche pidi\u00f3 a Merchan la absoluci\u00f3n de los cargos no obstante el veredicto de culpabilidad. El juez rechaz\u00f3 la petici\u00f3n pro forma.<\/p>\n<p>En el transcurso del juicio, el equipo legal de Trump tom\u00f3 otras medidas para preservar su derecho a apelar un posible veredicto de culpabilidad, estudiando resoluciones del juez sobre testimonios y pruebas. Es casi seguro que presentar\u00e1n dicho recurso en las pr\u00f3ximas semanas.<\/p>\n<p>AN\u00c1LISIS | \u00bfPodr\u00eda Donald Trump ir a la c\u00e1rcel tras ser declarado culpable en el juicio penal?<\/p>\n<p>\u00bfPuede Trump ser elegido presidente?<\/p>\n<p>En pocas palabras, s\u00ed.<\/p>\n<p>El profesor de Derecho de la Universidad de California en Los \u00c1ngeles Richard L. Hasen -uno de los mayores expertos del pa\u00eds en derecho electoral- ha afirmado sistem\u00e1ticamente que no hay nada en la Constituci\u00f3n estadounidense que impida a un criminal convicto presentarse al cargo m\u00e1s alto de la naci\u00f3n.<\/p>\n<p>&#171;Legalmente, nada cambia con el estatus de Trump como aspirante&#187;, escribi\u00f3 Hasen en su Blog de Derecho Electoral el jueves.<\/p>\n<p>&#171;La Constituci\u00f3n splo contiene unos requisitos limitados para presentarse a las elecciones (tener al menos 35 a\u00f1os, ser ciudadano natural y llevar al menos 14 a\u00f1os residiendo en Estados Unidos)&#187;, continu\u00f3 Hasen.<\/p>\n<p>Adem\u00e1s, los estados no pueden descalificar a Trump para presentarse debido a sus esfuerzos por anular las elecciones de 2020 debido a la sentencia del Tribunal Supremo a principios de este a\u00f1o, dijo Hasen, &#171;y no pueden a\u00f1adir cualificaciones como eliminar a los delincuentes convictos de la papeleta&#187;.<\/p>\n<p>AN\u00c1LISIS | Trump es ahora un delincuente convicto. \u00bfPuede todav\u00eda postularse a la presidencia?<\/p>\n<p>\u00bfLe costar\u00e1 la condena a Trump su derecho al voto?<\/p>\n<p>Aunque Trump, como residente de Florida, est\u00e1 sujeto a las normas draconianas del estado que privan del derecho al voto a ciertas personas con condenas por delitos graves, en \u00faltima instancia puede beneficiarse de c\u00f3mo los legisladores de Nueva York en 2021 facilitaron a los delincuentes la recuperaci\u00f3n del derecho al voto.<\/p>\n<p>En lo que respecta al veredicto de culpabilidad que se acaba de dictar en Manhattan, el derecho de Trump a votar en Florida en las elecciones de noviembre depender\u00e1 de si es condenado a una pena de prisi\u00f3n y de si ha terminado de cumplir esa condena en el momento de las elecciones.<\/p>\n<p>Florida proh\u00edbe votar a los delincuentes hasta que hayan cumplido la totalidad de su condena &#8211;incluida la libertad supervisada&#8211; y hasta que hayan pagado las multas y tasas asociadas. Este \u00faltimo requisito fue objeto de litigio despu\u00e9s de que la legislatura de Florida, dirigida por el Partido Republicano, aprobara una ley que socavaba una enmienda constitucional estatal que permit\u00eda a las personas condenadas por delitos graves recuperar el derecho de voto.<\/p>\n<p>Las prohibiciones de voto de los delincuentes de Florida se aplican a las personas con condenas de otros estados. Sin embargo, si la condena de un residente de Florida es de otro estado, Florida se remite a las leyes de ese estado en cuanto a la forma en que el delincuente puede recuperar su derecho al voto.<\/p>\n<p>En Nueva York, gracias a una ley de 2021, las personas con condenas por delitos graves recuperan su derecho al voto una vez que terminan su periodo de encarcelamiento, incluso si todav\u00eda est\u00e1n sujetos a libertad condicional. Eso significa que a Trump solo se le negar\u00eda su derecho al voto en Florida si est\u00e1 cumpliendo una pena de prisi\u00f3n por la condena de Manhattan en el momento de las elecciones.<\/p>\n<p>(Cr\u00e9dito: Lane-Pool\/Getty Images)<\/p>\n<p>\u00bfQu\u00e9 significa esto para los dem\u00e1s casos penales de Trump?<\/p>\n<p>La condena de Trump significa poco para sus otros tres casos penales, que seguir\u00e1n adelante como estaban antes de que fuera declarado culpable en el caso de Nueva York.<\/p>\n<p>La causa penal federal de Trump por subversi\u00f3n electoral ha quedado en suspenso mientras el Tribunal Supremo de EE.UU. estudia sus alegaciones de inmunidad presidencial. El juez que supervisa su caso de documentos clasificados en Florida aplaz\u00f3 indefinidamente el juicio. Y el caso de interferencia electoral en Georgia est\u00e1 en un limbo legal mientras Trump y varios de sus coacusados intentan descalificar al fiscal del \u00e1rea de Atlanta que present\u00f3 los cargos.<\/p>\n<p>Tierney Sneed de CNN contribuy\u00f3 a esta publicaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Un jurado de Nueva York conden\u00f3 a Donald Trump por 34 delitos graves de falsificaci\u00f3n de registros empresariales, lo que puso fin a un juicio que dur\u00f3 semanas, pero dio paso a una nueva fase del hist\u00f3rico caso. Trump se encuentra ahora en la posici\u00f3n \u00fanica de ser el primer expresidente de Estados Unidos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449883","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Un jurado de Nueva York conden\u00f3 a Donald Trump por 34 delitos graves de falsificaci\u00f3n de registros empresariales, lo que puso fin a un juicio que dur\u00f3 semanas, pero dio paso a una nueva fase del hist\u00f3rico caso. Trump se encuentra ahora en la posici\u00f3n \u00fanica de ser el primer expresidente de Estados Unidos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-31T09:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio?\",\"datePublished\":\"2024-05-31T09:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/\"},\"wordCount\":1073,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/\",\"name\":\"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-31T09:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio? - Noticias","og_description":"(CNN) &#8212;\u00a0Un jurado de Nueva York conden\u00f3 a Donald Trump por 34 delitos graves de falsificaci\u00f3n de registros empresariales, lo que puso fin a un juicio que dur\u00f3 semanas, pero dio paso a una nueva fase del hist\u00f3rico caso. Trump se encuentra ahora en la posici\u00f3n \u00fanica de ser el primer expresidente de Estados Unidos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-31T09:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio?","datePublished":"2024-05-31T09:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/"},"wordCount":1073,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/","name":"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-31T09:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 pasar\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio?","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/05\/31\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-31T09:03:50Z","datePublished":"2024-05-31T09:03:50Z","dateModified":"2024-05-31T09:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 pasar\\u00e1 ahora que Trump fue condenado en el juicio de pago por silencio?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/31\\\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/05\\\/31\\\/que-pasara-trump-condenado-juicio-pago-por-silencio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-31T09:03:50Z\",\"datePublished\":\"2024-05-31T09:03:50Z\",\"dateModified\":\"2024-05-31T09:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449838,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/29\/podria-donald-trump-carcel-declarado-culpable-juicio-penal-trax\/","url_meta":{"origin":1449883,"position":0},"title":"AN\u00c1LISIS | \u00bfPodr\u00eda Donald Trump ir a la c\u00e1rcel si es declarado culpable en el juicio penal?","author":"","date":"mayo 29, 2024","format":false,"excerpt":"(CNN) --\u00a0El juicio penal de pago de dinero por silencio contra Donald Trump se acerca a su fin. El expresidente es acusado por la oficina del Fiscal de Distrito de Manhattan de 34 delitos penales estatales por falsificar registros comerciales, espec\u00edficamente relacionados con 11 facturas, 12 vales y 11 cheques.Los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457435,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/10\/conclusiones-audiencia-sentencia-de-donald-trump-trax\/","url_meta":{"origin":1449883,"position":1},"title":"Conclusiones de la audiencia de sentencia de Donald Trump","author":"","date":"enero 10, 2025","format":false,"excerpt":"Donald Trump fue sentenciado sin pena en el caso del pago de dinero por silencio en Nueva York el viernes despu\u00e9s de una audiencia simb\u00f3lica, hist\u00f3rica y sin precedentes, tras la primera condena por delito grave de un expresidente y pronto presidente en ejercicio.El juez Juan Merchan se dirigi\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449843,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/29\/conclusiones-deliberaciones-juicio-penal-donald-trump-trax\/","url_meta":{"origin":1449883,"position":2},"title":"Conclusiones del primer d\u00eda de deliberacionesn del jurado en el juicio penal contra Donald Trump","author":"","date":"mayo 29, 2024","format":false,"excerpt":"(CNN) -- El jurado en el juicio de Donald Trump por el pago de dinero por silencio en Nueva York termin\u00f3 su primer d\u00eda de deliberaciones el mi\u00e9rcoles sin llegar a un veredicto despu\u00e9s de m\u00e1s de cuatro horas y media de sesi\u00f3n.Los miembros del jurado volver\u00e1n el jueves a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449888,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/31\/condena-trump-momento-sombrio-volatil-historia-estados-unidos-trax\/","url_meta":{"origin":1449883,"position":3},"title":"AN\u00c1LISIS | La condena a Trump anuncia un momento sombr\u00edo y vol\u00e1til en la historia de Estados Unidos","author":"","date":"mayo 31, 2024","format":false,"excerpt":"(CNN) -- El primer acto de Donald Trump al convertirse en delincuente convicto fue lanzar un nuevo y furibundo ataque contra el Estado de derecho. Esto deja en evidencia la gravedad de la elecci\u00f3n que aguarda a los votantes estadounidenses.En cierto sentido, la condena de Trump por todos los cargos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448110,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/15\/analisis-primer-juicio-penal-trump-stormie-daniels-dinero-silencio-historico-trax\/","url_meta":{"origin":1449883,"position":4},"title":"AN\u00c1LISIS | El primer juicio penal a Trump es un momento hist\u00f3rico y solemne para EE.UU.","author":"","date":"abril 15, 2024","format":false,"excerpt":"(CNN) -- Estados Unidos cruzar\u00e1 un umbral hist\u00f3rico este lunes cuando por primera vez un expresidente vaya a juicio penal en un caso revestido de un significado fat\u00eddico porque Donald Trump podr\u00eda volver al Despacho Oval el pr\u00f3ximo a\u00f1o.Cuando el posible candidato del Partido Republicano entre en el tribunal para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456457,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/11\/fiscales-casos-trump-nueva-york-desestimados-trax\/","url_meta":{"origin":1449883,"position":5},"title":"El fiscal de Manhattan y el fiscal general del estado dicen que los casos de Trump en Nueva York no ser\u00e1n desestimados","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"El fiscal general de Nueva York y el fiscal del distrito de Manhattan dijeron este martes que no desestimar\u00e1n sus casos hist\u00f3ricos contra Donald Trump ahora que ha sido reelegido presidente.El fiscal de distrito de Manhattan, el dem\u00f3crata Alvin Bragg, argument\u00f3 en una presentaci\u00f3n hecha p\u00fablica el martes que la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449883"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449883\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}