{"id":1449931,"date":"2024-06-02T02:03:47","date_gmt":"2024-06-02T09:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/"},"modified":"2024-06-02T02:03:47","modified_gmt":"2024-06-02T09:03:47","slug":"incendio-forestal-california-obliga-resdientes-evacuar-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/","title":{"rendered":"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar"},"content":{"rendered":"<p>(CNN) &#8212; Un creciente incendio de pasto que comenz\u00f3 este s\u00e1bado por la tarde en el condado de San Joaqu\u00edn, California, ha consumido m\u00e1s de 4451 hecta\u00b4reas, lo que oblig\u00f3 a los residentes en su camino a evacuar el \u00e1rea, dicen las autoridades.<\/p>\n<p>El incendio Corral comenz\u00f3 en la ciudad de Tracy alrededor de las 2:30 p.m. y solo estaba contenido en un 13% hasta este s\u00e1bado por la noche, seg\u00fan el Departamento de Silvicultura y Protecci\u00f3n contra Incendios de California. La causa del incendio est\u00e1 bajo investigaci\u00f3n, seg\u00fan el departamento.<\/p>\n<p>Los funcionarios del \u00e1rea hab\u00edan advertido recientemente que las r\u00e1fagas de viento, las temperaturas m\u00e1s altas y el pasto seco podr\u00edan crear condiciones peligrosas propicias para el incendio.<\/p>\n<p>\u201cLas \u00e1reas al oeste del Acueducto de California, al sur de Corral Hollow Creek, al oeste hasta el condado de Alameda y al sur hasta el condado de Stanislaus deber\u00edan salir ahora\u201d, dijo el condado este s\u00e1bado.<\/p>\n<p>M\u00e1s temprano este s\u00e1bado por la noche, los funcionarios del condado de San Joaqu\u00edn ordenaron a los residentes de Tracy m\u00e1s cercanos al incendio Corral que huyeran y dijeron a otros cercanos que \u201cdeber\u00edan estar listos para irse\u201d. Se ha establecido un sitio de evacuaci\u00f3n temporal en el Centro Comunitario Larch Clover para los residentes afectados.<\/p>\n<p>Dos bomberos del condado de Alameda resultaron heridos mientras respond\u00edan al incendio, dijo a CNN el jefe del Batall\u00f3n de Bomberos de Cal, Josh Silveira, la madrugada del domingo. Ten\u00edan heridas leves a moderadas y fueron transportados a un hospital local para evaluaci\u00f3n y tratamiento, dijo Silveira.<\/p>\n<p>\u201cOrando por nuestros vecinos de Tracy y los socorristas\u201d, dijo el alcalde Kevin J. Lincoln , de la vecina ciudad de Stockton, en las redes sociales este s\u00e1bado por la noche.<\/p>\n<p>Una secci\u00f3n de la I-580 est\u00e1 cerrada en ambas direcciones debido al \u201cgran incendio de pasto, humo y visibilidad nula\u201d, seg\u00fan el Departamento de Transporte de California .<\/p>\n<p>El fuego podr\u00eda extenderse m\u00e1s y se espera que las r\u00e1fagas de viento contin\u00faen durante la noche en el \u00e1rea con velocidades de hasta 64 km\/h, seg\u00fan el Servicio Meteorol\u00f3gico Nacional en Sacramento. El calor sofocante durante la pr\u00f3xima semana podr\u00eda multiplicar las peligrosas condiciones de incendio.<\/p>\n<p>\u201cContin\u00faa una alerta de calor excesivo en todo el valle y las estribaciones adyacentes de martes a jueves, con m\u00e1ximas previstas para la tarde de 35 a 41\u00b0 C\u201d, dijo el servicio meteorol\u00f3gico.<\/p>\n<p>El Departamento de Silvicultura y Protecci\u00f3n contra Incendios de California suspendi\u00f3 recientemente toda quema residencial al aire libre de escombros de jardiner\u00eda, como ramas y hojas, en los condados de Alameda, Contra Costa, Santa Clara y el oeste de San Joaqu\u00edn y Stanislaus.<\/p>\n<p>El departamento dijo que la suspensi\u00f3n se debi\u00f3 al creciente peligro de incendio planteado por las condiciones c\u00e1lidas y secas en la regi\u00f3n. Tambi\u00e9n contribuyen el aumento de las temperaturas y los vientos que generan un gran volumen de hierba muerta. Los bomberos han respondido a m\u00e1s de 1.200 incendios forestales en todo el estado en lo que va del a\u00f1o, dijo el departamento este viernes.<\/p>\n<p>\u201cA medida que se intensifica el calor del verano, el compromiso y los esfuerzos inquebrantables de CAL FIRE Unidad Santa Clara se mantienen firmes para proteger a las comunidades de California de los incendios forestales. Si nos mantenemos alerta y seguimos las pautas de prevenci\u00f3n y seguridad contra incendios, podemos trabajar juntos para mitigar el riesgo y proteger a nuestras comunidades\u201d, dijo el jefe de la unidad de Santa Clara, Baraka Carter.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un creciente incendio de pasto que comenz\u00f3 este s\u00e1bado por la tarde en el condado de San Joaqu\u00edn, California, ha consumido m\u00e1s de 4451 hecta\u00b4reas, lo que oblig\u00f3 a los residentes en su camino a evacuar el \u00e1rea, dicen las autoridades. El incendio Corral comenz\u00f3 en la ciudad de Tracy alrededor de las [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449931","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un creciente incendio de pasto que comenz\u00f3 este s\u00e1bado por la tarde en el condado de San Joaqu\u00edn, California, ha consumido m\u00e1s de 4451 hecta\u00b4reas, lo que oblig\u00f3 a los residentes en su camino a evacuar el \u00e1rea, dicen las autoridades. El incendio Corral comenz\u00f3 en la ciudad de Tracy alrededor de las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-02T09:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar\",\"datePublished\":\"2024-06-02T09:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/\"},\"wordCount\":658,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/\",\"name\":\"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-02T09:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar - Noticias","og_description":"(CNN) &#8212; Un creciente incendio de pasto que comenz\u00f3 este s\u00e1bado por la tarde en el condado de San Joaqu\u00edn, California, ha consumido m\u00e1s de 4451 hecta\u00b4reas, lo que oblig\u00f3 a los residentes en su camino a evacuar el \u00e1rea, dicen las autoridades. El incendio Corral comenz\u00f3 en la ciudad de Tracy alrededor de las [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-02T09:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/"},"author":{"name":"","@id":""},"headline":"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar","datePublished":"2024-06-02T09:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/"},"wordCount":658,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/","name":"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-02T09:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un creciente creciente incendio forestal en California que abarca m\u00e1s de 4451 hect\u00e1reas est\u00e1 obligando a los residentes a evacuar","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/06\/02\/incendio-forestal-california-obliga-resdientes-evacuar-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-02T09:03:47Z","datePublished":"2024-06-02T09:03:47Z","dateModified":"2024-06-02T09:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un creciente creciente incendio forestal en California que abarca m\\u00e1s de 4451 hect\\u00e1reas est\\u00e1 obligando a los residentes a evacuar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/06\\\/02\\\/incendio-forestal-california-obliga-resdientes-evacuar-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/06\\\/02\\\/incendio-forestal-california-obliga-resdientes-evacuar-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-02T09:03:47Z\",\"datePublished\":\"2024-06-02T09:03:47Z\",\"dateModified\":\"2024-06-02T09:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450411,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/16\/incendio-los-angeles-consumido-4-500-hectareas-post-fire-trax\/","url_meta":{"origin":1449931,"position":0},"title":"Incendio en el condado de Los \u00c1ngeles ha consumido cerca de 4.500 hect\u00e1reas","author":"","date":"junio 16, 2024","format":false,"excerpt":"(CNN) -- Un incendio en el condado de Los \u00c1ngeles que oblig\u00f3 a evacuar a cientos de personas de un parque estatal ha quemado cerca de 4.500 hect\u00e1reas, dijeron las autoridades este domingo, a tan solo un d\u00eda despu\u00e9s de que iniciara.El Servicio Meteorol\u00f3gico Nacional de Los \u00c1ngeles advirti\u00f3 que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451470,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/28\/incendio-parque-california-mas-grande-que-el-de-phoenix-mientras-canada-incendio-esta-abrasando-parques-nacionales-mas-grandes-trax\/","url_meta":{"origin":1449931,"position":1},"title":"El incendio de un parque en California es ahora m\u00e1s grande que el de Phoenix, mientras que en Canad\u00e1 un incendio est\u00e1 abrasando uno de los parques nacionales m\u00e1s grandes","author":"","date":"julio 28, 2024","format":false,"excerpt":"(CNN) -- El mayor incendio forestal del a\u00f1o en California ha quemado un \u00e1rea m\u00e1s grande que la ciudad de Phoenix, ha destruido decenas de edificios y oblig\u00f3 a miles de residentes a huir de sus hogares mientras los incendios forestales causan estragos en el oeste de Estados Unidos. Mientras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449412,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/12\/miles-de-canadienses-obligados-evacuar-devastadores-incendios-forestales-ahora-humo-calidad-aire-sea-peligrosa-trax\/","url_meta":{"origin":1449931,"position":2},"title":"Miles de canadienses se han visto obligados a evacuar debido a los devastadores incendios forestales. Ahora el humo hace que la calidad del aire sea peligrosa","author":"","date":"mayo 12, 2024","format":false,"excerpt":"(CNN) -- Este s\u00e1bado se inst\u00f3 a miles de personas en todo Canad\u00e1 a evacuar los incendios forestales, y el humo que emanan de ellos podr\u00eda ser otro peligro que perdurar\u00e1 durante los pr\u00f3ximos dos d\u00edas, lo que resultar\u00eda en una mala calidad del aire y una visibilidad reducida.Aproximadamente 3.200\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457788,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/22\/evacuacion-sur-california-incendios-trax\/","url_meta":{"origin":1449931,"position":3},"title":"Miles bajo evacuaci\u00f3n en el sur de California mientras las autoridades advierten sobre la amenaza de incendios","author":"","date":"enero 22, 2025","format":false,"excerpt":"La amenaza de incendio sigue siendo cr\u00edtica en el sur de California, donde miles de residentes estaban bajo \u00f3rdenes de evacuaci\u00f3n este mi\u00e9rcoles mientras los equipos de bomberos combat\u00edan el incontrolable incendio Hughes cerca de Castaic, un suburbio ubicado en las colinas y monta\u00f1as del norte del condado de Los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457350,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/08\/incendios-california-donde-trax\/","url_meta":{"origin":1449931,"position":4},"title":"\u00bfQu\u00e9 est\u00e1 pasando con los incendios en California y d\u00f3nde est\u00e1n ocurriendo? Esto sabemos","author":"","date":"enero 8, 2025","format":false,"excerpt":"Cuatro incendios letales est\u00e1n destruyendo viviendas a medida que se propagan por el condado de Los \u00c1ngeles. El foco m\u00e1s grande, en Pacific Palisades, ha dejado a decenas de miles de personas bajo \u00f3rdenes de evacuaci\u00f3n. Un quinto foco pudo ser contenido.Mientras tanto, m\u00e1s de 1.400 bomberos est\u00e1n trabajando para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460324,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/24\/corea-sur-incendios-forestales-mortales-miles-personas-trax\/","url_meta":{"origin":1449931,"position":5},"title":"Corea del Sur combate incendios forestales mortales en el sureste mientras evac\u00faan a miles de personas","author":"","date":"marzo 24, 2025","format":false,"excerpt":"Corea del Sur est\u00e1 luchando por contener una serie de incendios forestales en el sureste del pa\u00eds despu\u00e9s de que m\u00e1s de dos docenas de focos que estallaron durante el fin de semana provocaron al menos cuatro muertos y obligaron a evacuar a miles de personas.Hasta el domingo por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1449931"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1449931\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1449931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1449931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1449931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}