{"id":1450039,"date":"2024-06-04T17:03:52","date_gmt":"2024-06-05T00:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/"},"modified":"2024-06-04T17:03:52","modified_gmt":"2024-06-05T00:03:52","slug":"spacex-lanzamiento-starship-junio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/","title":{"rendered":"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship"},"content":{"rendered":"<p>(CNN) &#8212; SpaceX recibi\u00f3 una licencia de lanzamiento que autoriza el cuarto vuelo de prueba de su enorme cohete lunar.<\/p>\n<p>Se espera que Starship, el veh\u00edculo de lanzamiento m\u00e1s potente jam\u00e1s construido, despegue el jueves, durante una ventana de lanzamiento de 120 minutos que se abre a las 8 a.m. ET. Una transmisi\u00f3n en vivo de la prueba de vuelo estar\u00e1 disponible en el sitio web de SpaceX unos 30 minutos antes del despegue.<\/p>\n<p>El veh\u00edculo incluye la nave espacial Starship en la parte superior y un cohete propulsor conocido como Super Heavy. Se lanzar\u00e1 desde las instalaciones privadas Starbase de la compa\u00f1\u00eda en Boca Chica, Texas.<\/p>\n<p>La Administraci\u00f3n Federal de Aviaci\u00f3n, que otorga licencias para el lanzamiento de cohetes comerciales, dio a SpaceX su aprobaci\u00f3n para la prueba de vuelo el martes y dijo que la compa\u00f1\u00eda \u201ccumpli\u00f3 con todos los requisitos de seguridad y otros requisitos de licencia para este vuelo de prueba\u201d.<\/p>\n<p>La nave Starship de SpaceX se ve en Starbase en Boca Chica, Texas, el 4 de junio antes de su cuarta prueba de vuelo. Cr\u00e9dito: Chandan Khanna\/AFP\/Getty Images<\/p>\n<p>SpaceX propuso tres escenarios relacionados con la entrada de Starship a la atm\u00f3sfera que no requerir\u00edan una investigaci\u00f3n si se pierde el veh\u00edculo, seg\u00fan la agencia. Esos posibles contratiempos incluyen una falla de un escudo t\u00e9rmico, cierta p\u00e9rdida de control del veh\u00edculo en pleno vuelo y la falla de un motor durante un aterrizaje.<\/p>\n<p>&#171;Si ocurre una anomal\u00eda diferente con el veh\u00edculo Starship, puede estar justificada una investigaci\u00f3n, as\u00ed como si ocurre una anomal\u00eda con el cohete propulsor Super Heavy&#187;, dijo la agencia en un comunicado.<\/p>\n<p>\u201cAdem\u00e1s, la FAA aprob\u00f3 el perfil de la misi\u00f3n que inclu\u00eda una entrada controlada y descontrolada del veh\u00edculo Starship. Si SpaceX decide ejecutar una entrada incontrolada, debe comunicar esa decisi\u00f3n a la FAA antes del lanzamiento\u201d, seg\u00fan el comunicado. &#171;Como tal, la p\u00e9rdida del veh\u00edculo Starship se considerar\u00eda un evento planificado y no ser\u00e1 necesaria una investigaci\u00f3n&#187;.<\/p>\n<p>Cada uno de los vuelos de prueba de Starship tiene diferentes objetivos que se basan en las lecciones aprendidas y los hitos alcanzados durante los vuelos anteriores.<\/p>\n<p>Esta vez, SpaceX se enfocar\u00e1 en \u201cdemostrar la capacidad de devolver y reutilizar Starship y Super Heavy. Los objetivos principales ser\u00e1n ejecutar un aterrizaje y un amerizaje suave en el Golfo de M\u00e9xico con el propulsor Super Heavy y lograr una entrada controlada de Starship\u201d, seg\u00fan un comunicado compartido por la compa\u00f1\u00eda.<\/p>\n<p>Si tiene \u00e9xito, se espera que Starship americe en el oc\u00e9ano \u00cdndico.<\/p>\n<p>SpaceX realiz\u00f3 m\u00faltiples actualizaciones de software y hardware en el Starship para incorporar las lecciones aprendidas del tercer vuelo.<\/p>\n<p>&#171;El cuarto vuelo de Starship tendr\u00e1 como objetivo acercarnos al futuro r\u00e1pidamente reutilizable que se vislumbra en el horizonte&#187;, seg\u00fan SpaceX. &#171;Continuamos desarrollando Starship, colocando hardware de vuelo en un entorno de vuelo para aprender lo m\u00e1s r\u00e1pido posible mientras construimos un sistema de transporte totalmente reutilizable dise\u00f1ado para transportar tripulaci\u00f3n y carga a la \u00f3rbita de la Tierra, la Luna, Marte y m\u00e1s all\u00e1&#187;.<\/p>\n<p>Tres vuelos de prueba<\/p>\n<p>Los dos primeros intentos de llevar Starship a velocidades orbitales en 2023 terminaron en explosiones, y la nave espacial y el propulsor estallaron antes de llegar a los lugares de aterrizaje previstos.<\/p>\n<p>Se sabe que SpaceX acepta grandes contratiempos en las primeras etapas del desarrollo de una nave espacial, y dice que estos fallos ayudan a la empresa a implementar r\u00e1pidamente cambios de dise\u00f1o que conduzcan a mejores resultados.<\/p>\n<p>SpaceX ha dicho que su enfoque para el desarrollo de cohetes est\u00e1 orientado a la velocidad. La empresa utiliza un m\u00e9todo de ingenier\u00eda llamado &#171;desarrollo r\u00e1pido en espiral&#187;. B\u00e1sicamente, este proceso se reduce al deseo de construir prototipos r\u00e1pidamente y volarlos voluntariamente para aprender c\u00f3mo construir uno mejor, m\u00e1s r\u00e1pido que si la empresa dependiera \u00fanicamente de pruebas y simulaciones en tierra.<\/p>\n<p>Mira el lanzamiento de la nave espacial Dragon de SpaceX 1:00<\/p>\n<p>Despu\u00e9s del explosivo primer y segundo vuelo de prueba de Starship, la compa\u00f1\u00eda inmediatamente trat\u00f3 de enmarcar estos contratiempos como \u00e9xitos.<\/p>\n<p>El tercer vuelo de prueba de casi una hora de duraci\u00f3n, realizado en marzo, logr\u00f3 varios hitos antes de romperse tras el reingreso, en lugar de amerizar en el oc\u00e9ano \u00cdndico.<\/p>\n<p>Mucho depende del \u00e9xito final de Starship. El director ejecutivo de SpaceX, Elon Musk, ha caracterizado repetidamente al cohete como fundamental para la misi\u00f3n fundacional de la compa\u00f1\u00eda: llevar humanos a Marte por primera vez.<\/p>\n<p>Fundamentalmente, la nave espacial Starship es tambi\u00e9n el veh\u00edculo que la NASA seleccion\u00f3 para llevar a la Luna a los astronautas lanzados desde Estados Unidos por primera vez en m\u00e1s de cinco d\u00e9cadas como parte de su programa Artemis. La agencia espacial est\u00e1 en una carrera con China, compitiendo por convertirse en la primera en desarrollar un puesto avanzado lunar permanente y sentar el precedente para los asentamientos en el espacio profundo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; SpaceX recibi\u00f3 una licencia de lanzamiento que autoriza el cuarto vuelo de prueba de su enorme cohete lunar. Se espera que Starship, el veh\u00edculo de lanzamiento m\u00e1s potente jam\u00e1s construido, despegue el jueves, durante una ventana de lanzamiento de 120 minutos que se abre a las 8 a.m. ET. Una transmisi\u00f3n en vivo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450039","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; SpaceX recibi\u00f3 una licencia de lanzamiento que autoriza el cuarto vuelo de prueba de su enorme cohete lunar. Se espera que Starship, el veh\u00edculo de lanzamiento m\u00e1s potente jam\u00e1s construido, despegue el jueves, durante una ventana de lanzamiento de 120 minutos que se abre a las 8 a.m. ET. Una transmisi\u00f3n en vivo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T00:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship\",\"datePublished\":\"2024-06-05T00:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/\"},\"wordCount\":897,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/\",\"name\":\"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-05T00:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship - Noticias","og_description":"(CNN) &#8212; SpaceX recibi\u00f3 una licencia de lanzamiento que autoriza el cuarto vuelo de prueba de su enorme cohete lunar. Se espera que Starship, el veh\u00edculo de lanzamiento m\u00e1s potente jam\u00e1s construido, despegue el jueves, durante una ventana de lanzamiento de 120 minutos que se abre a las 8 a.m. ET. Una transmisi\u00f3n en vivo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-05T00:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/"},"author":{"name":"","@id":""},"headline":"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship","datePublished":"2024-06-05T00:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/"},"wordCount":897,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/","name":"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-05T00:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/06\/04\/spacex-lanzamiento-starship-junio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-05T00:03:52Z","datePublished":"2024-06-05T00:03:52Z","dateModified":"2024-06-05T00:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"SpaceX recibe luz verde para el cuarto vuelo de prueba de Starship\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/06\\\/04\\\/spacex-lanzamiento-starship-junio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/06\\\/04\\\/spacex-lanzamiento-starship-junio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-05T00:03:52Z\",\"datePublished\":\"2024-06-05T00:03:52Z\",\"dateModified\":\"2024-06-05T00:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450059,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/05\/starship-spacex-lanzamiento-junio-cuando-como-ver-trax\/","url_meta":{"origin":1450039,"position":0},"title":"Cuarto lanzamiento del Starship de SpaceX: qu\u00e9 busca, cu\u00e1ndo es y c\u00f3mo ver en vivo","author":"","date":"junio 5, 2024","format":false,"excerpt":"(CNN) -- SpaceX recibi\u00f3 una licencia de lanzamiento que autoriza el cuarto vuelo de prueba del Starship, su enorme cohete lunar.\u00bfCu\u00e1ndo es y a qu\u00e9 hora?Se espera que Starship, el veh\u00edculo de lanzamiento m\u00e1s potente jam\u00e1s construido, despegue el jueves, durante una ventana de lanzamiento de 120 minutos que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446928,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/13\/spacex-lanzamiento-tercer-cohete-starship-trax\/","url_meta":{"origin":1450039,"position":1},"title":"SpaceX recibe luz verde para el tercer vuelo de prueba del enorme cohete Starship","author":"","date":"marzo 13, 2024","format":false,"excerpt":"(CNN) -- SpaceX est\u00e1 lista una vez m\u00e1s para volar su gigantesco cohete Starship, el veh\u00edculo de lanzamiento m\u00e1s poderoso jam\u00e1s construido, despu\u00e9s de que los reguladores federales aprobaron los planes de la compa\u00f1\u00eda para un tercer vuelo de prueba.El lanzamiento podr\u00eda tener lugar en cualquier momento durante una ventana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455061,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/10\/12\/spacex-vuelo-prueba-ambicioso-momento-starship-esto-es-lo-que-debes-saber-trax\/","url_meta":{"origin":1450039,"position":2},"title":"SpaceX est\u00e1 a punto de intentar su vuelo de prueba m\u00e1s ambicioso hasta el momento con Starship. Esto es lo que debes saber","author":"","date":"octubre 12, 2024","format":false,"excerpt":"(CNN) -- SpaceX se prepara para lanzar el \u00faltimo vuelo de prueba de Starship, el sistema de cohetes m\u00e1s poderoso jam\u00e1s construido, que alg\u00fan d\u00eda podr\u00eda usarse para transportar humanos a la Luna y Marte.Se espera que el despegue del cohete propulsor Super Heavy, coronado por la nave espacial Starship\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455936,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/19\/spacex-nuevo-espectacular-intento-atrapar-cohete-starship-pinzas-metalicas-trax\/","url_meta":{"origin":1450039,"position":3},"title":"SpaceX cancela intento de atrapar el cohete que impulsa a Starship","author":"","date":"noviembre 19, 2024","format":false,"excerpt":"(CNN) \u2014 El propulsor del cohete Super Heavy estaba programado para hacer otro aterrizaje impresionante, ya que fue atrapado en el aire por la torre de lanzamiento Mechazilla de SpaceX el mes pasado. Sin embargo, SpaceX opt\u00f3 por aterrizar el propulsor en el golfo de M\u00e9xico.La compa\u00f1\u00eda sorprendi\u00f3 al p\u00fablico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459460,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/03\/spacex-lanzamiento-cohete-starship-spacex-trax\/","url_meta":{"origin":1450039,"position":4},"title":"SpaceX cancel\u00f3 el lanzamiento de su octavo vuelo de prueba de la nave Starship","author":"","date":"marzo 3, 2025","format":false,"excerpt":"SpaceX cancel\u00f3 el octavo vuelo de prueba no tripulado de su gigantesco megacohete que impulsa la nave Starship.La misi\u00f3n se esperaba que despegara durante una ventana de lanzamiento de una hora que se abri\u00f3 a las 6:30 p.m., hora de Miami, desde las instalaciones Starbase de SpaceX en el sur\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465822,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/24\/spacex-cancela-intento-lanzamiento-starship-trax\/","url_meta":{"origin":1450039,"position":5},"title":"SpaceX cancel\u00f3 el intento de lanzamiento del megacohete Starship","author":"","date":"agosto 24, 2025","format":false,"excerpt":"SpaceX ten\u00eda como objetivo lanzar un d\u00e9cimo vuelo de prueba de una nave Starship y el propulsor Super Heavy alrededor de las 7:30 p.m. (hora de Miami) el domingo.Sin embargo, la compa\u00f1\u00eda pospuso el intento de lanzamiento debido a \u201cun problema con los sistemas terrestres\u201d, lo que indica que hubo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1450039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1450039"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1450039\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1450039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1450039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1450039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}