{"id":1450215,"date":"2024-06-11T03:03:42","date_gmt":"2024-06-11T10:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/"},"modified":"2024-06-11T03:03:42","modified_gmt":"2024-06-11T10:03:42","slug":"ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/","title":{"rendered":"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s"},"content":{"rendered":"<p>\ud83d\udd04 Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientes<\/p>\n<p>Palestinos inspeccionan los da\u00f1os y escombros un d\u00eda despu\u00e9s de una operaci\u00f3n de las fuerzas especiales israel\u00edes en el campo de Nuseirat, en el centro de Gaza, el 9 de junio de 2024. (Cr\u00e9dito: Eyad Baba\/AFP\/Getty Images)<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd04 Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientes Palestinos inspeccionan los da\u00f1os y escombros un d\u00eda despu\u00e9s de una operaci\u00f3n de las fuerzas especiales israel\u00edes en el campo de Nuseirat, en el centro de Gaza, el 9 de junio de 2024. (Cr\u00e9dito: Eyad Baba\/AFP\/Getty Images) The-CNN-Wire&trade; &amp; &copy; 2024 Cable News Network, Inc., [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1450215","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s - Noticias\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udd04 Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientes Palestinos inspeccionan los da\u00f1os y escombros un d\u00eda despu\u00e9s de una operaci\u00f3n de las fuerzas especiales israel\u00edes en el campo de Nuseirat, en el centro de Gaza, el 9 de junio de 2024. (Cr\u00e9dito: Eyad Baba\/AFP\/Getty Images) The-CNN-Wire&trade; &amp; &copy; 2024 Cable News Network, Inc., [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-11T10:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s\",\"datePublished\":\"2024-06-11T10:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/\"},\"wordCount\":89,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/\",\"name\":\"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-11T10:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s - Noticias","og_description":"\ud83d\udd04 Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientes Palestinos inspeccionan los da\u00f1os y escombros un d\u00eda despu\u00e9s de una operaci\u00f3n de las fuerzas especiales israel\u00edes en el campo de Nuseirat, en el centro de Gaza, el 9 de junio de 2024. (Cr\u00e9dito: Eyad Baba\/AFP\/Getty Images) The-CNN-Wire&trade; &amp; &copy; 2024 Cable News Network, Inc., [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/","og_site_name":"Noticias","article_published_time":"2024-06-11T10:03:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/"},"author":{"name":"","@id":""},"headline":"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s","datePublished":"2024-06-11T10:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/"},"wordCount":89,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/","url":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/","name":"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-11T10:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\u00e1s","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/06\/11\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-11T10:03:42Z","datePublished":"2024-06-11T10:03:42Z","dateModified":"2024-06-11T10:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00daltima hora de la guerra entre Israel y Hamas en Gaza, en vivo: rescate de rehenes, noticias y m\\u00e1s\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/06\\\/11\\\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/06\\\/11\\\/ultima-hora-de-la-guerra-entre-israel-y-hamas-en-gaza-en-vivo-rescate-de-rehenes-y-mas-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-11T10:03:42Z\",\"datePublished\":\"2024-06-11T10:03:42Z\",\"dateModified\":\"2024-06-11T10:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1444709,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/31\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-53\/","url_meta":{"origin":1450215,"position":0},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 31, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Una columna de humo estalla durante el bombardeo israel\u00ed en Khan Yunis desde Rafah, en el sur de la Franja de Gaza, el 30 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo militante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444419,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-23\/","url_meta":{"origin":1450215,"position":1},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 25, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edUna fotograf\u00eda tomada desde el sur de Israel, en la frontera con Gaza, muestra humo ondeando sobre el territorio palestino durante bombardeo israel\u00ed el 25 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444428,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-24\/","url_meta":{"origin":1450215,"position":2},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 25, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edUna fotograf\u00eda tomada desde el sur de Israel, en la frontera con Gaza, muestra humo ondeando sobre el territorio palestino durante bombardeo israel\u00ed el 25 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444430,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/25\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-25\/","url_meta":{"origin":1450215,"position":3},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"enero 25, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edUna fotograf\u00eda tomada desde el sur de Israel, en la frontera con Gaza, muestra humo ondeando sobre el territorio palestino durante bombardeo israel\u00ed el 25 de enero de 2024, en medio de las batallas en curso entre Israel y el grupo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444776,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/01\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-64\/","url_meta":{"origin":1450215,"position":4},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"febrero 1, 2024","format":false,"excerpt":"Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Las personas que huyeron de los combates en Gaza se reunieron en una calle abarrotada en Rafah, en la parte sur del territorio palestino, el 1 de febrero de 2024. Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty ImagesAl fondo se muestra una excavadora militar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444779,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/02\/guerra-entre-israel-y-hamas-en-vivo-noticias-combates-en-gaza-muertos-y-mas-65\/","url_meta":{"origin":1450215,"position":5},"title":"Guerra entre Israel y Hamas en vivo: noticias, combates en Gaza, muertos y m\u00e1s","author":"","date":"febrero 2, 2024","format":false,"excerpt":"Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00ed.Las personas que huyeron de los combates en Gaza se reunieron en una calle abarrotada en Rafah, en la parte sur del territorio palestino, el 1 de febrero de 2024. Cr\u00e9dito: MAHMUD HAMS\/AFP v\u00eda Getty ImagesAl fondo se muestra una excavadora militar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1450215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1450215"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1450215\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1450215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1450215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1450215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}