{"id":1451073,"date":"2024-07-12T11:03:51","date_gmt":"2024-07-12T18:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/"},"modified":"2024-07-12T11:03:51","modified_gmt":"2024-07-12T18:03:51","slug":"todos-atletas-mexico-juegos-olimpicos-paris-2024-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/","title":{"rendered":"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La delegaci\u00f3n mexicana que asistir\u00e1 a los Juegos Ol\u00edmpicos de Par\u00eds 2024 ya est\u00e1 lista para la justa que se llevar\u00e1 a cabo en la ciudad francesa del 24 de julio al 11 de agosto.<\/p>\n<p>Hasta el s\u00e1bado 6 de julio, de acuerdo con datos que el Comit\u00e9 Ol\u00edmpico Mexicano (COM) brind\u00f3 a CNN, M\u00e9xico tiene a 109 deportistas clasificados a Par\u00eds 2024, de los cuales 46 son hombres y 63 son mujeres.<\/p>\n<p>Esta cifra a\u00fan est\u00e1 muy lejos de la de Tokio 2020 (realizados en 2021 por la pandemia de covid-19), cuando M\u00e9xico llev\u00f3 a 162 deportistas, y tambi\u00e9n se queda atr\u00e1s de la de R\u00edo 2016, cuando el pa\u00eds tuvo 125 deportistas representando la bandera mexicana.<\/p>\n<p>As\u00ed qued\u00f3 el medallero de los Juegos ol\u00edmpicos de Tokio 2020<\/p>\n<p>La nataci\u00f3n art\u00edstica y los clavados son los deportes que m\u00e1s suman a la cuenta de 109 atletas mexicanos en Par\u00eds, con nueve deportistas cada uno.<\/p>\n<p>Precisamente en clavados es donde M\u00e9xico se ha mostrado m\u00e1s fuerte en Juegos Ol\u00edmpicos: es el deporte que m\u00e1s medallas le ha dado al pa\u00eds, con 15 de las 73 preseas que ha acumulado en su historia.<\/p>\n<p>Gabriela Ag\u00fandez y Alejandra Orozco participar\u00e1n en Par\u00eds 2024 en las pruebas de plataforma de 10 m sincronizado e individual. En Tokio 2020 (la foto es de esa justa ol\u00edmpica), las clavadistas ganaron el bronce en plataforma 10 m sincronizado. (Cr\u00e9dito: OLI SCARFF\/AFP v\u00eda Getty Images)<\/p>\n<p>Deportistas de M\u00e9xico en los Juegos Ol\u00edmpicos de Par\u00eds 2024<\/p>\n<p>Aqu\u00ed te desglosamos a los atletas mexicanos que disputar\u00e1n la justa ol\u00edmpica de verano, seg\u00fan su deporte y prueba en las que competir\u00e1n.<\/p>\n<p>Aguas abiertas<\/p>\n<p>Prueba: 10 km<\/p>\n<p>Martha Roc\u00edo Sandoval Ayala<br \/>\nPaulo Strehlke Delgado<\/p>\n<p>Atletismo<\/p>\n<p>Prueba: Marat\u00f3n<\/p>\n<p>Citlali Cristian Moscote<br \/>\nMargarita Hern\u00e1ndez Flores<\/p>\n<p>Prueba: 20 km marcha<\/p>\n<p>Jos\u00e9 Luis Doctor Morales<br \/>\nAlegna Aryday Gonz\u00e1lez Mu\u00f1oz (individual y relevo mixto de marcha)<br \/>\nEver Jair Palma Olivares (relevo mixto de marcha)<br \/>\nNoel Al\u00ed Chama Almaz\u00e1n<br \/>\nIlse Ariadna Guerrero Rodarte<br \/>\nAlejandra Ortega Sol\u00eds<br \/>\nRicardo Ortiz Rivera<\/p>\n<p>Prueba: 5.000 m<\/p>\n<p>Laura Esther Galv\u00e1n Rodr\u00edguez<br \/>\nAlma Delia Cort\u00e9s Garc\u00eda<\/p>\n<p>Prueba: 400 m<\/p>\n<p>Paola Mor\u00e1n Errej\u00f3n<\/p>\n<p>La mexicana Paola Moran reacciona despu\u00e9s de competir en las series de 400 metros femeninos en el Campeonato Mundial de Atletismo 2019 de la IAAF en el Estadio Internacional Khalifa, en Doha, el 30 de septiembre de 2019. (Cr\u00e9dito: JEWEL SAMAD\/AFP v\u00eda Getty Images)<\/p>\n<p>Prueba: 200 m<\/p>\n<p>Cecilia Tamayo Garza (tambi\u00e9n en 100 m)<\/p>\n<p>Prueba: Lanzamiento de martillo<\/p>\n<p>Diego Alan del Real Galindo<\/p>\n<p>Prueba: Lanzamiento de bala<\/p>\n<p>Uziel Aar\u00f3n Mu\u00f1oz Galarza<\/p>\n<p>Prueba: Salto de altura<\/p>\n<p>Erick Josu\u00e9 Portillo Rodr\u00edguez<br \/>\nEdgar Alejandro Rivera Morales<\/p>\n<p>Prueba: 800 m<\/p>\n<p>Jes\u00fas Tonatiu L\u00f3pez \u00c1lvarez<\/p>\n<p>B\u00e1dminton<\/p>\n<p>Prueba: individual<\/p>\n<p>Luis Ram\u00f3n Garrido Esquivel<\/p>\n<p>Boxeo<\/p>\n<p>Prueba: 50 kg<\/p>\n<p>F\u00e1tima Patricia Herrera \u00c1lvarez<\/p>\n<p>Prueba: 63,5 kg<\/p>\n<p>Miguel \u00c1ngel Mart\u00ednez Ram\u00edrez<\/p>\n<p>Prueba: 71 kg<\/p>\n<p>Marco Alonso Verde \u00c1lvarez<\/p>\n<p>Prueba: 75 kg<\/p>\n<p>Citlalli Vanessa Ortiz<\/p>\n<p>Canotaje slalom<\/p>\n<p>Pruebas: Kayak y kayak cross<\/p>\n<p>Sof\u00eda Reinoso D\u00edaz Barriga<\/p>\n<p>Canotaje velocidad<\/p>\n<p>Pruebas: K1 500 m y K2 500 m<\/p>\n<p>Beatriz de Lourdes Briones Fragoza<br \/>\nKarina Guadalupe Alan\u00eds Morales<\/p>\n<p>Ciclismo monta\u00f1a<\/p>\n<p>Prueba: Cross country<\/p>\n<p>Adair Zabdiel Guti\u00e9rrez Prieto<br \/>\nErika Monserrath Rodr\u00edguez Suarez<\/p>\n<p>Ciclismo pista<\/p>\n<p>Prueba: Velocidad por equipos<\/p>\n<p>Luz Daniela Gaxiola Gonz\u00e1lez (tambi\u00e9n las pruebas de velocidad individual y keirin)<br \/>\nJessica Salazar Valles<br \/>\nYuli Paola Verdugo Osuna (tambi\u00e9n las pruebas de velocidad individual y keirin)<\/p>\n<p>Prueba: \u00d3mnium<\/p>\n<p>Victoria Velasco Fuentes<br \/>\nRicardo Pe\u00f1a Salas<\/p>\n<p>Ciclismo ruta<\/p>\n<p>Prueba: Ruta<\/p>\n<p>Marcela Elizabeth Prieto Casta\u00f1eda<\/p>\n<p>Clavados<\/p>\n<p>Prueba: Plataforma 10 m<\/p>\n<p>Gabriela Belem Ag\u00fandez Garc\u00eda (individual y sincronizado)<br \/>\nAlejandro Orozco Loza (individual y sincronizado)<br \/>\nRandal Willars Valdez (individual y sincronizado)<br \/>\nKevin Berl\u00edn Reyes (individual y sincronizado)<\/p>\n<p>Gabriela Ag\u00fandez y Ajenadra Orozco (medallistas de bronce en plataforma 10 m sincronizado en Tokio 2020) ganaron el oro en los Juegos Panamericanos Santiago 2023 y son dos de las mejores deportistas mexicanas que estar\u00e1n en Par\u00eds 2024. (Cr\u00e9dito: RAUL ARBOLEDA\/AFP v\u00eda Getty Images)<\/p>\n<p>Prueba: Trampol\u00edn 3 m<\/p>\n<p>Osmar Olvera Ibarra (individual y sincronizado)<br \/>\nJuan Manuel Celaya Hern\u00e1ndez (sincronizado)<br \/>\nAranza V\u00e1zquez Montano (individual)<br \/>\nAlejandra Estudillo Torres (individual)<br \/>\nKevin Alexander Mu\u00f1oz Heredia (individual)<\/p>\n<p>Ecuestre<\/p>\n<p>Prueba: Salto (individual y equipo)<\/p>\n<p>Carlos Hank Guerreiro<br \/>\nJos\u00e9 Antonio Chedraui Egu\u00eda<br \/>\nEugenio Garza P\u00e9rez<br \/>\nAndr\u00e9s Azc\u00e1rraga Rivera Torres<\/p>\n<p>Esgrima<\/p>\n<p>Prueba: Sable individual<\/p>\n<p>Gibr\u00e1n Zea Armenta<\/p>\n<p>Gimnasia art\u00edstica<\/p>\n<p>Prueba: All around<\/p>\n<p>Natalia Isabel Escalera C\u00e1rdenas<br \/>\nAlexa Citlali Moreno Medina<br \/>\nAhtziri Viridiana Sandoval P\u00e9rez<\/p>\n<p>La mexicana Alexa Moreno compite en la final de salto femenino durante el 52\u00ba Campeonato Mundial de Gimnasia Art\u00edstica de la FIG, en Amberes, al norte de B\u00e9lgica, el 7 de octubre de 2023. (Cr\u00e9dito: LIONEL BONAVENTURE\/AFP v\u00eda Getty Images)<\/p>\n<p>Gimnasia r\u00edtmica<\/p>\n<p>Prueba: All around por grupos<\/p>\n<p>Dalia de Jes\u00fas Alcocer Pi\u00f1a<br \/>\nAna Sof\u00eda Flores Valdez<br \/>\nJulia Irene Guti\u00e9rrez Pereyra<br \/>\nKimberly Salazar L\u00f3pez<br \/>\nAdirem Tejeda Amaro<\/p>\n<p>Golf<\/p>\n<p>Prueba: individual masculino y femenino<\/p>\n<p>Carlos Ortiz Becerra<br \/>\nAbraham Ancer Sagastegui<br \/>\nMar\u00eda Gabriela L\u00f3pez Butr\u00f3n<br \/>\nMar\u00eda Jos\u00e9 Fassi \u00c1lvarez<\/p>\n<p>Halterofilia<\/p>\n<p>Prueba: 59 kg<\/p>\n<p>Janeth G\u00f3mez Valdivia<\/p>\n<p>Judo<\/p>\n<p>Prueba: 52 kg<\/p>\n<p>Paulina Lizbeth Mart\u00ednez Claro<\/p>\n<p>Prueba: 63 kg<\/p>\n<p>Prisca Guadalupe Awiti Alcaraz<\/p>\n<p>Lucha<\/p>\n<p>Prueba: Libre 57 kg<\/p>\n<p>Rom\u00e1n Guillermo Bravo-Young<\/p>\n<p>Prueba: Libre 65 kg<\/p>\n<p>Austin Klee G\u00f3mez<\/p>\n<p>Nataci\u00f3n<\/p>\n<p>Prueba: 50 m libres<\/p>\n<p>Gabriel Casta\u00f1o Garc\u00eda<\/p>\n<p>Prueba: 100 m libres<\/p>\n<p>Jorge Andr\u00e9s Iga C\u00e9sar (tambi\u00e9n 200m libres)<\/p>\n<p>Prueba: 100 m dorso<\/p>\n<p>Celia del Rocio Pulido Ortiz<\/p>\n<p>Prueba: 100 m pecho<\/p>\n<p>Miguel Alejandro de Lara Ojeda (tambi\u00e9n 200 m pecho)<\/p>\n<p>Nataci\u00f3n art\u00edstica<\/p>\n<p>Prueba: Equipo<\/p>\n<p>Nuria Lid\u00f3n Diosdado Garc\u00eda (tambi\u00e9n dueto)<br \/>\nJoana Betzab\u00e9 Jim\u00e9nez Garc\u00eda (tambi\u00e9n dueto)<br \/>\nRegina Alf\u00e9rez Licea<br \/>\nMar\u00eda Fernanda Arellano Germes<br \/>\nLuisa Samantha Jailib Rodr\u00edguez Rubio<br \/>\nJessica Sobrino Mizrahi<br \/>\nPamela N\u00fczeth Toscano Mill\u00e1n<br \/>\nItzamary Gonz\u00e1lez Cu\u00e9llar<br \/>\nGlenda Esthefania Inzunza Cabrera<\/p>\n<p>Nuria Garc\u00eda Diosdado y Joana Jim\u00e9nez Garc\u00eda compiten en la Final de Dueto Libre Femenino en la Superfinal de la Copa del Mundo de Nataci\u00f3n Art\u00edstica Budapest 2024, d\u00eda 2, el 6 de julio de 2024 en Budapest, Hungr\u00eda. (Cr\u00e9dito: David Balogh\/Getty Images)<\/p>\n<p>Pentatl\u00f3n moderno<\/p>\n<p>Prueba: individual masculino y femenino<\/p>\n<p>Duilio Jared Carrillo Gonz\u00e1lez<br \/>\nEmiliano Hern\u00e1ndez Uscanga<br \/>\nMariana Arceo Guti\u00e9rrez<br \/>\nCarmen Mayan Oliver Lara<\/p>\n<p>Remo<\/p>\n<p>Prueba: Lightweight Double Sculls (LM2X)<\/p>\n<p>Miguel \u00c1ngel Carballo Nieto<br \/>\nAlexis Bladimir L\u00f3pez Garc\u00eda<\/p>\n<p>Prueba: Single Sculls (W1X)<\/p>\n<p>Kenia Vanessa Lechuga Alan\u00eds<\/p>\n<p>Surf<\/p>\n<p>Prueba: Shortboard<\/p>\n<p>Alan George Cleland Qui\u00f1ones<\/p>\n<p>Taekwondo<\/p>\n<p>Prueba: +80 kg<\/p>\n<p>Carlos Adri\u00e1n Sansores Acevedo<\/p>\n<p>El mexicano Carlos Sansores Acevedo (a la izquierda) compite contra el canadiense Marc-andre Bergeron en las semifinales de Taekwondo Kyorugi +80 kg masculino, en el Parque Deportivo Estadio Nacional, durante el tercer d\u00eda de los Juegos Panamericanos Santiago 2023, el 23 de octubre de 2023, en Santiago, Chile. (Cr\u00e9dito: Ezra Shaw\/Getty Images)<\/p>\n<p>Prueba: 49 kg<\/p>\n<p>Daniela Paola Souza Naranjo<\/p>\n<p>Tenis de mesa<\/p>\n<p>Prueba: individual masculino y femenino<\/p>\n<p>Marcos Madrid Mantilla<br \/>\nArantxa Estefan\u00eda Coss\u00edo Aceves<\/p>\n<p>Tiro con arco<\/p>\n<p>Prueba: Recurvo<\/p>\n<p>Alejandra Valencia Trujillo (individual, equipo y mixto)<br \/>\n\u00c1ngela Ruiz Rosales (individual y equipo)<br \/>\nAna Paula V\u00e1zquez Flores (individual y equipo)<br \/>\nMat\u00edas Dami\u00e1n Grande Kalonchiz (individual, equipo y mixto)<br \/>\nCarlos Javier Rojas L\u00f3pez (individual y equipo)<br \/>\nBruno Mart\u00ednez Wing (individual y equipo)<\/p>\n<p>En esta imagen proporcionada por la Federaci\u00f3n Mundial de Tiro con Arco, la mexicana Alejandra Valencia durante la final de recurvo femenino de la Copa Mundial de Tiro con Arco Hyundai 2023, el 10 de septiembre de 2023, en Hermosillo, M\u00e9xico. (Cr\u00e9dito: Dean Alberga\/Handout\/Federaci\u00f3n Mundial de Tiro con Arco v\u00eda Getty Images)<\/p>\n<p>Tiro deportivo<\/p>\n<p>Prueba: Rifle aire 10 m<\/p>\n<p>Edson Ismael Ramirez Ramos (individual y mixto)<br \/>\nGoretti Alejandra Zumaya Flores (individual y mixto)<br \/>\nCarlos Quezada M\u00e1rquez (individual en esa prueba y tambi\u00e9n individual en la prueba 50 m rifle 3P)<\/p>\n<p>Prueba: Skeet individual<\/p>\n<p>Gabriela Guadalupe Rodr\u00edguez Garza<\/p>\n<p>Prueba: Pistola aire 10 m<\/p>\n<p>Alejandra Zavala V\u00e1zquez (individual en esa prueba y tambi\u00e9n individual en la prueba pistola deportiva 25 m)<\/p>\n<p>Triatl\u00f3n<\/p>\n<p>Pruebas: Individual y mixto<\/p>\n<p>Lizeth Rueda Santos<br \/>\nRosa Mar\u00eda Tapia Vidal<br \/>\nAram Michell Pe\u00f1aflor Moysen<br \/>\nCrisanto Grajales Valencia<\/p>\n<p>El mexicano Crisanto Grajales compite en el triatl\u00f3n masculino en Playa El Sol, en el d\u00eda 13 de los Juegos Panamericanos Santiago 2023, el 2 de noviembre de 2023 en Vi\u00f1a del Mar, Chile. (Cr\u00e9dito: Ezra Shaw\/Getty Images)<\/p>\n<p>Vela<\/p>\n<p>Prueba: Windsurfing IQFOIL<\/p>\n<p>Mariana Aguilar Ch\u00e1vez Pe\u00f3n<\/p>\n<p>Prueba: Dinghy ILCA 6<\/p>\n<p>Elena Oetling Ram\u00edrez<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La delegaci\u00f3n mexicana que asistir\u00e1 a los Juegos Ol\u00edmpicos de Par\u00eds 2024 ya est\u00e1 lista para la justa que se llevar\u00e1 a cabo en la ciudad francesa del 24 de julio al 11 de agosto. Hasta el s\u00e1bado 6 de julio, de acuerdo con datos que el Comit\u00e9 Ol\u00edmpico Mexicano (COM) brind\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451073","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La delegaci\u00f3n mexicana que asistir\u00e1 a los Juegos Ol\u00edmpicos de Par\u00eds 2024 ya est\u00e1 lista para la justa que se llevar\u00e1 a cabo en la ciudad francesa del 24 de julio al 11 de agosto. Hasta el s\u00e1bado 6 de julio, de acuerdo con datos que el Comit\u00e9 Ol\u00edmpico Mexicano (COM) brind\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T18:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024\",\"datePublished\":\"2024-07-12T18:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/\"},\"wordCount\":1480,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/\",\"name\":\"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-12T18:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024 - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La delegaci\u00f3n mexicana que asistir\u00e1 a los Juegos Ol\u00edmpicos de Par\u00eds 2024 ya est\u00e1 lista para la justa que se llevar\u00e1 a cabo en la ciudad francesa del 24 de julio al 11 de agosto. Hasta el s\u00e1bado 6 de julio, de acuerdo con datos que el Comit\u00e9 Ol\u00edmpico Mexicano (COM) brind\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-12T18:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/"},"author":{"name":"","@id":""},"headline":"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024","datePublished":"2024-07-12T18:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/"},"wordCount":1480,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/","name":"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-12T18:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Estos son todos los atletas de M\u00e9xico que competir\u00e1n en los Juegos Ol\u00edmpicos de Par\u00eds 2024","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/07\/12\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-12T18:03:51Z","datePublished":"2024-07-12T18:03:51Z","dateModified":"2024-07-12T18:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Estos son todos los atletas de M\\u00e9xico que competir\\u00e1n en los Juegos Ol\\u00edmpicos de Par\\u00eds 2024\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/07\\\/12\\\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/07\\\/12\\\/todos-atletas-mexico-juegos-olimpicos-paris-2024-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-12T18:03:51Z\",\"datePublished\":\"2024-07-12T18:03:51Z\",\"dateModified\":\"2024-07-12T18:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451380,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/24\/quienes-son-tamara-echegoyen-marcus-cooper-abanderados-espana-juegos-olimpicos-paris-2024-orix\/","url_meta":{"origin":1451073,"position":0},"title":"\u00bfQui\u00e9nes son Marcus Cooper y T\u00e1mara Echegoyen, abanderados de Espa\u00f1a en los Juegos Ol\u00edmpicos de Par\u00eds 2024?","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Espa\u00f1a ya est\u00e1 lista para el inicio de los Juegos Ol\u00edmpicos de Par\u00eds 2024, donde intentar\u00e1 superar su desempe\u00f1o de la justa ol\u00edmpica de Tokio 2020, en la que el pa\u00eds ib\u00e9rico qued\u00f3 en el lugar 22 del medallero con 3 preseas de oro, 8 de plata\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451413,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/25\/quienes-son-abanderados-mexico-juegos-olimpicos-paris-2024-orix\/","url_meta":{"origin":1451073,"position":1},"title":"\u00bfQui\u00e9nes son Alejandra Orozco y Emiliano Hern\u00e1ndez, abanderados de M\u00e9xico en los Juegos Ol\u00edmpicos de Par\u00eds 2024?","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Alejandra Orozco y Emiliano Hern\u00e1ndez ser\u00e1n los abanderados de la delegaci\u00f3n mexicana en la ceremonia de apertura de los Juegos Ol\u00edmpicos de Par\u00eds 2024 el 26 de julio. Esta es la segunda ocasi\u00f3n que algunos pa\u00edses, incluido M\u00e9xico, tienen dos abanderados. El Comit\u00e9 Ol\u00edmpico Internacional (COI) implement\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451443,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/26\/cuantas-medallas-mexico-juegos-olimpicos-paris-2024-orix\/","url_meta":{"origin":1451073,"position":2},"title":"\u00bfCu\u00e1ntas medallas lleva M\u00e9xico en los Juegos Ol\u00edmpicos de Par\u00eds 2024?","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0M\u00e9xico gan\u00f3 un total de 4 medallas de bronce en los Juegos Ol\u00edmpicos de Tokio 2020. \u00bfSuperar\u00e1n esta cifr\u00e1 en Par\u00eds? Consulta aqu\u00ed el medallero de M\u00e9xico en los Juegos Ol\u00edmpicos de Par\u00eds 2024 en vivo para ver las medallas que logra el pa\u00eds.Cu\u00e1ntas medallas ha ganado M\u00e9xico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451452,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/26\/cuando-compiten-atletas-colombia-juegos-olimpicos-paris-2024-calendario-horarios-orix\/","url_meta":{"origin":1451073,"position":3},"title":"\u00bfCu\u00e1ndo compiten los atletas de Colombia en los Juegos Ol\u00edmpicos de Par\u00eds 2024? Calendario y horarios","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Colombia participa en los Juegos Ol\u00edmpicos de Par\u00eds 2024 con 89 atletas en 16 disciplinas, incluidas f\u00fatbol, atletismo, nataci\u00f3n, lucha, gimnasia, entre otras.El pa\u00eds sudamericano llega con un total de 34 medallas acumuladas en su historia: 5 de oro, 13 de plata y 16 de bronce.Calendario de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451337,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/22\/lebron-james-abanderado-masculino-ee-uu-juegos-olimpicos-paris-2024-trax\/","url_meta":{"origin":1451073,"position":4},"title":"LeBron James ser\u00e1 el abanderado masculino de EE.UU. en los Juegos Ol\u00edmpicos de Par\u00eds 2024","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN) -- La leyenda de la NBA LeBron James fue elegido como el abanderado masculino del Equipo de Estados Unidos (Team USA) para la ceremonia de apertura de los Juegos Ol\u00edmpicos de Par\u00eds, anunci\u00f3 este lunes el Comit\u00e9 Ol\u00edmpico y Paral\u00edmpico de EE.UU.La ceremonia inaugural se celebrar\u00e1 a orillas del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451427,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/25\/por-que-rusia-no-participa-juegos-olimpicos-paris-2024-trax\/","url_meta":{"origin":1451073,"position":5},"title":"\u00bfPor qu\u00e9 Rusia no participa en los Juegos Ol\u00edmpicos de Par\u00eds 2024?","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN) -- El Comit\u00e9 Ol\u00edmpico Internacional (COI) decidi\u00f3 en octumbre de 2023 suspender la participaci\u00f3n en los Juegos Ol\u00edmpicos de Par\u00eds que est\u00e1n a punto de comenzar al Comit\u00e9 Ol\u00edmpico Ruso, lo que implic\u00f3 la p\u00e9rdida de financiamiento y el hecho de que el COI se reserva el derecho de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1451073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1451073"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1451073\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1451073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1451073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1451073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}