{"id":1451100,"date":"2024-07-14T08:03:50","date_gmt":"2024-07-14T15:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/"},"modified":"2024-07-14T08:03:50","modified_gmt":"2024-07-14T15:03:50","slug":"scaloni-argentina-como-le-ha-ido-seleccionador-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/","title":{"rendered":"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Desde que asumi\u00f3 la direcci\u00f3n t\u00e9cnica de la selecci\u00f3n de Argentina, Lionel Scaloni ha demostrado que su visi\u00f3n del f\u00fatbol aplicada con los envidiables talentos de los jugadores albicelestes, m\u00e1s la mezcla de juventud y experiencia, son una combinaci\u00f3n peligrosa para cualquier rival.<\/p>\n<p>Tras el doloroso fracaso de Argentina en el Mundial de Rusia 2018 de Jorge Sampaoli y a pesar de su nula experiencia en la direcci\u00f3n de clubes, el paso de Lionel Scaloni por las categor\u00edas juveniles de la selecci\u00f3n argentina (fue campe\u00f3n del torneo Sub-20 de la Alcudia) fue suficiente para que la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) se decidiera por \u00e9l para reestructurar la imagen del f\u00fatbol argentino. Una apuesta que inicialmente no fue bien recibida en todos los sectores y que gener\u00f3 desconfianza entre algunos.<\/p>\n<p>Qui\u00e9nes son los jugadores de la selecci\u00f3n de Argentina que han sido sensaci\u00f3n en la Copa Am\u00e9rica 2024<\/p>\n<p>Casi seis a\u00f1os despu\u00e9s de iniciar su per\u00edodo como entrenador de la selecci\u00f3n argentina, Scaloni ha disipado las dudas y la desconfianza a base de triunfos, entre los que destaca la Copa del Mundo obtenida en Qatar en 2022.<\/p>\n<p>Los alegr\u00edas de la &#8216;Scaloneta&#8217;<\/p>\n<p>Un a\u00f1o despu\u00e9s de su debut obtuvo el tercer puesto en la Copa Am\u00e9rica 2019. As\u00ed fue apagando las cr\u00edticas que trajo su nombramiento. El proceso hasta entonces lo llevar\u00eda a la AFA a ratificarlo en el cargo de cara a las Eliminatorias Sudamericanas para Qatar 2022.<\/p>\n<p>Fue segundo en esas eliminatorias sudamericanas, invicto en la clasificaci\u00f3n, y en noviembre, antes del Mundial, llev\u00f3 a 36 el n\u00famero de partidos sin perder. Por supuesto, esa racha se cort\u00f3 con la incre\u00edble derrota 2-1 ante Arabia Saudita en el debut en Qatar 2022.<\/p>\n<p>Antes del Mundial de Qatar, el cuadro de Scaloni consigui\u00f3 el primer gran trofeo de su era: ganarle a Brasil en el Maracan\u00e1 para quedarse con la Copa Am\u00e9rica 2020, jugada en 2021, y as\u00ed romper una racha de 28 a\u00f1os sin t\u00edtulos internacionales.<\/p>\n<p>Adem\u00e1s, esta Copa Am\u00e9rica fue el primer t\u00edtulo en la selecci\u00f3n mayor para Lionel Messi, uno que los argentinos no olvidar\u00e1n, y fue el impulso para ir por la gloria en Qatar 2022, que se convirti\u00f3 en el segundo trofeo mayor para Scaloni y Messi, el mayor sue\u00f1o cumplido a nivel de selecci\u00f3n.<\/p>\n<p>Tambi\u00e9n vale destacar la Finalissima a mediados de 2022, la victoria ante Italia en el partido de los campeones de Europa y Sudam\u00e9rica.<\/p>\n<p>Los n\u00fameros de Scaloni<\/p>\n<p>Ya pasaron casi seis a\u00f1os desde el debut de Scaloni como entrenador de la albiceleste el 8 de septiembre de 2018 frente a Guatemala. Aqu\u00ed te presentamos su balance como director t\u00e9cnico de la selecci\u00f3n de Argentina, seg\u00fan datos del sitio Tranfermarket.<\/p>\n<p>Partidos jugados: 74<\/p>\n<p>Victorias: 56<\/p>\n<p>Derrotas: 6<\/p>\n<p>Empates: 12<\/p>\n<p>Lionel Scaloni, seleccionador de Argentina, celebra con el trofeo de campe\u00f3n del Mundial de Qatar 2022 tras la victoria en la final entre Argentina y Francia en el Estadio Lusail el 18 de diciembre de 2022 en la ciudad de Lusail, Qatar. (Cr\u00e9dito: Julian Finney\/Getty Images)<\/p>\n<p>Con informaci\u00f3n de Sebasti\u00e1n Jim\u00e9nez<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Desde que asumi\u00f3 la direcci\u00f3n t\u00e9cnica de la selecci\u00f3n de Argentina, Lionel Scaloni ha demostrado que su visi\u00f3n del f\u00fatbol aplicada con los envidiables talentos de los jugadores albicelestes, m\u00e1s la mezcla de juventud y experiencia, son una combinaci\u00f3n peligrosa para cualquier rival. Tras el doloroso fracaso de Argentina en el Mundial [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451100","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Desde que asumi\u00f3 la direcci\u00f3n t\u00e9cnica de la selecci\u00f3n de Argentina, Lionel Scaloni ha demostrado que su visi\u00f3n del f\u00fatbol aplicada con los envidiables talentos de los jugadores albicelestes, m\u00e1s la mezcla de juventud y experiencia, son una combinaci\u00f3n peligrosa para cualquier rival. Tras el doloroso fracaso de Argentina en el Mundial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-14T15:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado?\",\"datePublished\":\"2024-07-14T15:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/\"},\"wordCount\":581,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/\",\"name\":\"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-14T15:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Desde que asumi\u00f3 la direcci\u00f3n t\u00e9cnica de la selecci\u00f3n de Argentina, Lionel Scaloni ha demostrado que su visi\u00f3n del f\u00fatbol aplicada con los envidiables talentos de los jugadores albicelestes, m\u00e1s la mezcla de juventud y experiencia, son una combinaci\u00f3n peligrosa para cualquier rival. Tras el doloroso fracaso de Argentina en el Mundial [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-14T15:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado?","datePublished":"2024-07-14T15:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/"},"wordCount":581,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/","name":"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-14T15:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado?","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-14T15:03:50Z","datePublished":"2024-07-14T15:03:50Z","dateModified":"2024-07-14T15:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfC\\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \\u00bfQu\\u00e9 ha ganado y qu\\u00e9 ha logrado?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/07\\\/14\\\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/07\\\/14\\\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-14T15:03:50Z\",\"datePublished\":\"2024-07-14T15:03:50Z\",\"dateModified\":\"2024-07-14T15:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447232,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/22\/argentina-el-salvador-como-ver-orix\/","url_meta":{"origin":1451100,"position":0},"title":"Argentina se mide ante El Salvador con la mira puesta en la Copa Am\u00e9rica","author":"","date":"marzo 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los campeones del mundo comienzan a calentar motores en la tierra de la pr\u00f3xima Copa Am\u00e9rica que se disputar\u00e1 en junio y julio pr\u00f3ximos. La selecci\u00f3n argentina enfrentar\u00e1 este viernes a las 8pm de Miami su primer amistoso del a\u00f1o ante El Salvador, en la ciudad de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449895,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/","url_meta":{"origin":1451100,"position":1},"title":"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica","author":"","date":"mayo 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El capit\u00e1n de la selecci\u00f3n argentina de f\u00fatbol, Lionel Messi, est\u00e1 en la recta final de su participaci\u00f3n en la primera parte del a\u00f1o con el Inter Miami, antes de sumarse al combinado nacional para disputar la Copa Am\u00e9rica en Estados Unidos. Despu\u00e9s de ausentarse en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450131,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/07\/argentina-copa-america-convocados-messi-lesionados-formacion-orix\/","url_meta":{"origin":1451100,"position":2},"title":"As\u00ed es la selecci\u00f3n de Argentina para la Copa Am\u00e9rica: el campe\u00f3n pone proa para defender su corona continental","author":"","date":"junio 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Previo a la consagraci\u00f3n mundial en Qatar en 2022, la selecci\u00f3n argentina ciment\u00f3 su sue\u00f1o mundialista con un primer gran t\u00edtulo, que fue la Copa Am\u00e9rica, de Brasil 2021. Defender esa corona, del certamen m\u00e1s prestigioso del f\u00fatbol continental, es lo que estar\u00e1 en juego para la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443392,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/01\/08\/messi-y-scaloni-la-reunion-pendiente-que-no-se-dio-en-argentina-y-se-espera-en-miami\/","url_meta":{"origin":1451100,"position":3},"title":"Messi y Scaloni, la reuni\u00f3n pendiente que no se dio en Argentina y se espera en Miami","author":"","date":"enero 8, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El encuentro entre Lionel Scaloni, el entrenador de la selecci\u00f3n de Argentina, y\u00a0su\u00a0capit\u00e1n, Lionel Messi, que se esperaba se\u00a0llevara\u00a0a cabo mientras los dos se encontraban en el pa\u00eds austral, finalmente no se dio.Despu\u00e9s de las declaraciones del DT campe\u00f3n del mundo en Brasil donde puso en duda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450353,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/14\/guatemala-seleccion-argentina-copa-america-2024-orix\/","url_meta":{"origin":1451100,"position":4},"title":"Guatemala, la \u00faltima prueba de Scaloni para definir la lista de la selecci\u00f3n argentina para la Copa Am\u00e9rica 2024","author":"","date":"junio 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Argentina juega su \u00faltimo partido amistoso previo a la defensa del t\u00edtulo de la Copa Am\u00e9rica cuya edici\u00f3n 2024 ser\u00e1 en Estados Unidos desde el 20 de junio al 14 de julio. Los dirigidos por Lionel Scaloni enfrentan a Guatemala este viernes en el FedExField en Maryland\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451108,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/14\/argentina-megacampeon-copa-america-scaloneta-analisis-orix\/","url_meta":{"origin":1451100,"position":5},"title":"Argentina, megacampe\u00f3n: la Scaloneta, un equipo que solo sabe ganar","author":"","date":"julio 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Argentina sabe de finales peleadas, ag\u00f3nicas. Tanto en el triunfo como en la derrota, pero la Argentina de Lionel Scaloni solo sabe ganar. Y esta vez triunf\u00f3 haciendo valer su dominio en el f\u00fatbol en la \u00faltima d\u00e9cada, cerrando \u2014quiz\u00e1\u2014 una era hist\u00f3rica con jugadores legendarios y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1451100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1451100"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1451100\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1451100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1451100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1451100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}