{"id":1451139,"date":"2024-07-15T17:03:49","date_gmt":"2024-07-16T00:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/"},"modified":"2024-07-15T17:03:49","modified_gmt":"2024-07-16T00:03:49","slug":"fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/","title":{"rendered":"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Durante el per\u00edodo Cret\u00e1cico, un g\u00e9nero de tiburones navegaba por el mar con hileras de dientes inusuales. Estos dientes, en su mayor\u00eda grandes y redondeados, no ten\u00edan como funci\u00f3n cortar a sus presas, sino triturar criaturas con caparaz\u00f3n.<\/p>\n<p>Sin embargo, desde su descubrimiento en el siglo XVIII, los cient\u00edficos han tenido que especular sobre el aspecto del resto de este antiguo depredador.<\/p>\n<p>Ahora, unos restos hallados en unas canteras de piedra caliza del noreste de M\u00e9xico dan por fin a los investigadores una idea m\u00e1s clara del aspecto del tibur\u00f3n, incluido un f\u00f3sil que muestra casi todos los elementos del esqueleto y un contorno del cuerpo de tejido blando del esp\u00e9cimen. Seg\u00fan un estudio publicado en abril en la revista acad\u00e9mica Proceedings of the Royal Society B: Biological Sciences, el hallazgo tambi\u00e9n revela en qu\u00e9 lugar del \u00e1rbol evolutivo de los tiburones se situaba el g\u00e9nero, conocido como Ptychodus, y otros rasgos hasta ahora desconocidos de este &#171;viejo enigma&#187;.<\/p>\n<p>C\u00f3mo tiburones tigre equipados con c\u00e1maras revelaron el mayor ecosistema de praderas marinas del mundo<\/p>\n<p>&#171;El hallazgo de los restos \u00f3seos en M\u00e9xico no s\u00f3lo nos permite unir estos dientes que llevan mucho tiempo buscando un esqueleto, sino que tambi\u00e9n nos permite, como cient\u00edficos, revisar nuestras hip\u00f3tesis anteriores sobre su biolog\u00eda y relaciones y ver en qu\u00e9 acertamos y en qu\u00e9 nos equivocamos&#187;, afirma en un correo electr\u00f3nico el Dr. Eduardo Villalobos Segura, coautor del estudio y profesor adjunto del departamento de Paleontolog\u00eda de la Universidad de Viena, Austria.<\/p>\n<p>Los expertos afirman que el descubrimiento tambi\u00e9n aporta informaci\u00f3n sobre la historia evolutiva de los tiburones que habitan nuestros oc\u00e9anos en la actualidad.<\/p>\n<p>Los tiburones son millones de a\u00f1os m\u00e1s antiguos que los dinosaurios, y otros cinco datos sorprendentes<\/p>\n<p>Antiguo pariente del gran tibur\u00f3n blanco<\/p>\n<p>La mayor\u00eda de las especies de Ptychodus vivieron hace entre 100 y 80 millones de a\u00f1os, a finales del Cret\u00e1cico. Los yacimientos en los que se descubrieron los f\u00f3siles en Nuevo Le\u00f3n, M\u00e9xico, cerca del municipio de Vallecillo, datan de hace aproximadamente entre 93,9 y 91,85 millones de a\u00f1os, explic\u00f3 Villalobos Segura.<\/p>\n<p>Como los esqueletos de los tiburones est\u00e1n hechos de cart\u00edlago, no se fosilizan bien, por lo que los arque\u00f3logos s\u00f3lo suelen encontrar dientes y pocos restos \u00f3seos. Pero las evidencias sugieren que los f\u00f3siles de Nuevo Le\u00f3n terminaron en condiciones mayormente estacionarias que habr\u00edan permitido una zona con deficiencia de ox\u00edgeno, lo que result\u00f3 en la preservaci\u00f3n de los esqueletos blandos, dijo Villalobos Segura.<\/p>\n<p>En el estudio, los investigadores analizaron seis f\u00f3siles hallados en el yacimiento, incluido el esp\u00e9cimen completo. Otros tres f\u00f3siles estaban casi completos y dos incompletos. Con estos restos, los autores del estudio determinaron que Ptychodus pertenec\u00eda al orden de los tiburones conocido como Lamniformes, o tiburones caballa, el mismo grupo al que pertenecen el extinto Otodus megalodon y el moderno gran tibur\u00f3n blanco. Lamniformes tambi\u00e9n incluye las especies modernas de tiburones megaboca, tibur\u00f3n arenero, tibur\u00f3n duende y tibur\u00f3n peregrino, entre otros.<\/p>\n<p>&#171;Los tiburones actuales representan s\u00f3lo una m\u00ednima parte de la asombrosa biodiversidad que se produjo a lo largo de toda su historia evolutiva (que abarca casi 400 millones de a\u00f1os)&#8230; estudiar los tiburones f\u00f3siles es crucial para comprender plenamente los fen\u00f3menos evolutivos relacionados con los grupos actuales&#187;, afirma en un correo electr\u00f3nico el Dr. Manuel Amadori, coautor del estudio e investigador postdoctoral del departamento de paleontolog\u00eda de la Universidad de Viena, Austria.<\/p>\n<p>Una orca solitaria mat\u00f3 a un tibur\u00f3n blanco en menos de dos minutos. Los cient\u00edficos dicen que podr\u00eda indicar un cambio ecol\u00f3gico<\/p>\n<p>La existencia de tiburones caballa con dientes trituradores era desconocida hasta ahora, dijo Amadori. &#171;Todav\u00eda queda mucho por descubrir, pero podemos decir que estamos ante otro importante paso adelante en la comprensi\u00f3n de la compleja historia evolutiva de los tiburones caballa&#187;, a\u00f1adi\u00f3.<\/p>\n<p>La silueta del cuerpo, que revela la forma del tibur\u00f3n y la ubicaci\u00f3n de sus aletas, tambi\u00e9n aporta pruebas de que este pez prehist\u00f3rico no era un simple habitante del fondo marino, como se cre\u00eda hasta ahora, sino un depredador de nado r\u00e1pido que podr\u00eda haber cazado y comido tortugas marinas y grandes ammonites en lugar de alimentarse \u00fanicamente de moluscos que se encontraban en el fondo del oc\u00e9ano, seg\u00fan los autores del estudio. Aunque la dieta exacta del tibur\u00f3n sigue siendo desconocida, los investigadores sugieren que esta hip\u00f3tesis revisada sobre lo que com\u00eda podr\u00eda ser una pista sobre la causa de la extinci\u00f3n de Ptychodus, ya que pone al tibur\u00f3n en competencia con otros depredadores marinos del Cret\u00e1cico Superior con dietas similares.<\/p>\n<p>&#171;Sin un esp\u00e9cimen completo (pruebas fehacientes), lo que se sab\u00eda sobre Ptychodus m\u00e1s all\u00e1 de los dientes eran en gran medida conjeturas cient\u00edficas&#187;, dijo Michael Everhart, conservador adjunto de Paleontolog\u00eda en el Museo Sternberg de Historia Natural en Hays, Kansas, y experto en f\u00f3siles marinos del Cret\u00e1cico Superior, en un correo electr\u00f3nico. No particip\u00f3 en el estudio.<\/p>\n<p>&#171;Los nuevos espec\u00edmenes responden a preguntas que se remontan a m\u00e1s de 180 a\u00f1os, a la d\u00e9cada de 1830, cuando Louis Agassiz (uno de los primeros cient\u00edficos y paleont\u00f3logos de renombre) acu\u00f1\u00f3 por primera vez el nombre Ptychodus&#187;, que significa diente rugoso o arrugado, a\u00f1adi\u00f3 Everhart.<\/p>\n<p>Los grandes tiburones blancos pueden haber acabado con el tibur\u00f3n m\u00e1s grande que haya existido<\/p>\n<p>Tiburones masivos trituradores de conchas<\/p>\n<p>Los hallazgos tambi\u00e9n sugieren que la especie m\u00e1s grande de Ptychodus puede haber sido ligeramente m\u00e1s peque\u00f1a de lo que se pensaba, alcanzando una longitud m\u00e1xima de 9,7 metros (casi 32 pies). Las estimaciones anteriores de una especie conocida como Ptychodus mortoni la situaban en 11,2 metros (casi 37 pies), pero el tama\u00f1o revisado sigue siendo mayor que el de los modernos tiburones depredadores, se\u00f1alan los autores en el estudio. Los tiburones blancos actuales alcanzan hasta 6 metros de longitud.<\/p>\n<p>Hay especies modernas que trituran caparazones, la mayor de las cuales es el tibur\u00f3n cebra, que alcanza una longitud m\u00e1xima de poco m\u00e1s de 3,5 metros (12 pies), ni de cerca tan gigantesco como el Ptychodus.<\/p>\n<p>&#171;Los dientes trituradores, junto con su tama\u00f1o gigantesco, hacen del Ptychodus un tibur\u00f3n \u00fanico&#187;, afirma Amadori. &#171;(En el registro f\u00f3sil) algunos dientes son macizos, poligonales y casi planos, mientras que otros tienen extra\u00f1as protuberancias redondeadas o c\u00faspides puntiagudas en la superficie superior. Todos ellos se un\u00edan para formar enormes placas dentales, que este depredador del pasado podr\u00eda haber utilizado para aplastar casi cualquier cosa que encontrara&#187;.<\/p>\n<p>Un nuevo f\u00f3sil que revela la vista lateral completa de Ptychodus med\u00eda casi 1,5 metros de longitud, lo que sugiere que se trataba de un tibur\u00f3n mucho m\u00e1s peque\u00f1o. Esto podr\u00eda deberse a que los restos pertenec\u00edan a un tibur\u00f3n m\u00e1s joven, o a que el g\u00e9nero Ptychodus inclu\u00eda varias especies de diferentes tama\u00f1os, dijo Villalobos Segura.<\/p>\n<p>Seg\u00fan la base de datos sin fines de lucro Mindat.org, actualmente se conocen 22 especies de Ptychodus. La mayor\u00eda de las especies e individuos de Ptychodus eran probablemente m\u00e1s peque\u00f1os que el esp\u00e9cimen m\u00e1s grande de Ptychodus mortoni descubierto, pero tambi\u00e9n podr\u00eda existir la posibilidad de que se encontraran especies m\u00e1s grandes, dijo Everhart.<\/p>\n<p>A menudo, los investigadores pueden diferenciar las distintas especies de Ptychodus por los distintos rasgos de los dientes, pero los autores del estudio no pudieron identificar a qu\u00e9 especie de Ptychodus pertenec\u00edan los seis f\u00f3siles estudiados debido a que los dientes estaban demasiado desgastados, explic\u00f3 Villalobos Segura.<\/p>\n<p>Un acercamiento a los dientes del esp\u00e9cimen completo de Nuevo Le\u00f3n. Cr\u00e9dito: Cortes\u00eda del Dr. J\u00fcrgen Kriwet<\/p>\n<p>Los investigadores dijeron que esperan que futuras investigaciones revelen m\u00e1s sobre el antiguo tibur\u00f3n, incluyendo su dieta y su papel en las cadenas alimenticias y ecosistemas marinos del pasado.<\/p>\n<p>&#171;(El estudio de abril) es una revisi\u00f3n exhaustiva de algunos f\u00f3siles notablemente completos del inusual tibur\u00f3n del Cret\u00e1cico, Ptychodus&#187;, dijo el Dr. Bretton Kent, profesor principal em\u00e9rito del departamento de Entomolog\u00eda de la Universidad de Maryland, que ha estudiado y dado conferencias sobre la diversificaci\u00f3n de los elasmobranquios (tiburones y rayas). No particip\u00f3 en el estudio.<\/p>\n<p>&#171;Nuestro mundo actual puede funcionar como un par de viseras que limitan el alcance de los posibles estilos de vida que podemos imaginar para los animales extintos. Los tiburones durofagos modernos (que consumen organismos de caparaz\u00f3n duro) son demersales, se alimentan en el fondo o cerca de \u00e9l. Y sus cuerpos suelen ser peque\u00f1os y no especialmente aerodin\u00e1micos. As\u00ed que un durofago gigantesco, aerodin\u00e1mico y de alta velocidad que era mucho m\u00e1s grande que un tibur\u00f3n blanco moderno es bastante notable&#187;, a\u00f1adi\u00f3 Kent, en un correo electr\u00f3nico.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Durante el per\u00edodo Cret\u00e1cico, un g\u00e9nero de tiburones navegaba por el mar con hileras de dientes inusuales. Estos dientes, en su mayor\u00eda grandes y redondeados, no ten\u00edan como funci\u00f3n cortar a sus presas, sino triturar criaturas con caparaz\u00f3n. Sin embargo, desde su descubrimiento en el siglo XVIII, los cient\u00edficos han tenido que especular sobre [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451139","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Durante el per\u00edodo Cret\u00e1cico, un g\u00e9nero de tiburones navegaba por el mar con hileras de dientes inusuales. Estos dientes, en su mayor\u00eda grandes y redondeados, no ten\u00edan como funci\u00f3n cortar a sus presas, sino triturar criaturas con caparaz\u00f3n. Sin embargo, desde su descubrimiento en el siglo XVIII, los cient\u00edficos han tenido que especular sobre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-16T00:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos\",\"datePublished\":\"2024-07-16T00:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/\"},\"wordCount\":1590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/\",\"name\":\"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-16T00:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos - Noticias","og_description":"(CNN) &#8212;\u00a0Durante el per\u00edodo Cret\u00e1cico, un g\u00e9nero de tiburones navegaba por el mar con hileras de dientes inusuales. Estos dientes, en su mayor\u00eda grandes y redondeados, no ten\u00edan como funci\u00f3n cortar a sus presas, sino triturar criaturas con caparaz\u00f3n. Sin embargo, desde su descubrimiento en el siglo XVIII, los cient\u00edficos han tenido que especular sobre [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-16T00:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/"},"author":{"name":"","@id":""},"headline":"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos","datePublished":"2024-07-16T00:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/"},"wordCount":1590,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/","name":"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-16T00:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-16T00:03:49Z","datePublished":"2024-07-16T00:03:49Z","dateModified":"2024-07-16T00:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El f\\u00f3sil de un antiguo tibur\\u00f3n de la era de los dinosaurios resuelve un misterio de siglos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/07\\\/15\\\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/07\\\/15\\\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-16T00:03:49Z\",\"datePublished\":\"2024-07-16T00:03:49Z\",\"dateModified\":\"2024-07-16T00:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462881,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/05\/27\/comia-megalodon-satisfacer-100-000-calorias-estudio-trax\/","url_meta":{"origin":1451139,"position":0},"title":"Esto es lo que realmente com\u00eda el megalod\u00f3n para satisfacer su requerimiento diario de 100.000 calor\u00edas, seg\u00fan nuevo estudio","author":"","date":"mayo 27, 2025","format":false,"excerpt":"Lo que los cient\u00edficos pensaban sobre los voraces h\u00e1bitos alimenticios del colosal megalod\u00f3n podr\u00eda ser objeto de revisi\u00f3n.Seg\u00fan un nuevo estudio, el depredador prehist\u00f3rico que se extingui\u00f3 hace unos 3,6 millones de a\u00f1os no cazaba solo grandes mam\u00edferos marinos como las ballenas, tal como pensaban los investigadores. Si no que,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456767,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/19\/depredador-dientes-de-sable-hallado-espana-trax\/","url_meta":{"origin":1451139,"position":1},"title":"El antiguo depredador dientes de sable hallado en Espa\u00f1a es el m\u00e1s antiguo de su especie","author":"","date":"diciembre 19, 2024","format":false,"excerpt":"Antes de que los dinosaurios caminaran sobre la Tierra y decenas de millones de a\u00f1os antes de que aparecieran los primeros mam\u00edferos, los parientes lejanos de los mam\u00edferos con colmillos largos y aserrados eran los carn\u00edvoros dominantes en la tierra. Los primeros animales de este linaje, llamados gorgon\u00f3psidos, han estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458304,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/02\/05\/descubren-antartida-fosil-ave-moderna-antigua-trax\/","url_meta":{"origin":1451139,"position":2},"title":"Descubren en la Ant\u00e1rtida el f\u00f3sil del ave moderna m\u00e1s antigua conocida","author":"","date":"febrero 5, 2025","format":false,"excerpt":"Un f\u00f3sil de cr\u00e1neo casi completo encontrado en la Ant\u00e1rtida revel\u00f3 el ave moderna m\u00e1s antigua conocida: una criatura del tama\u00f1o de un pato real emparentada con las aves acu\u00e1ticas que hoy viven cerca de lagos y oc\u00e9anos, seg\u00fan ha descubierto un nuevo estudio.El f\u00f3sil de 68 millones de a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445762,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/21\/el-fosil-famoso-en-realidad-es-solo-pintura-rocas-y-un-par-de-huesos-dicen-los-investigadores\/","url_meta":{"origin":1451139,"position":3},"title":"El f\u00f3sil famoso en realidad es solo pintura, rocas y un par de huesos, dicen los investigadores","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Seg\u00fan una nueva investigaci\u00f3n, un f\u00f3sil de 280 millones de a\u00f1os que se cree que es un esp\u00e9cimen bien conservado de un reptil antiguo es en gran medida una falsificaci\u00f3n.El f\u00f3sil, descubierto inicialmente en los Alpes italianos en 1931, tiene el nombre cient\u00edfico de Tridentinosaurus antiquus. Los cient\u00edficos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445843,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/21\/fosil-solo-pintura-rocas-y-par-de-huesos-dicen-los-investigadores-trax\/","url_meta":{"origin":1451139,"position":4},"title":"El f\u00f3sil famoso en realidad es solo pintura, rocas y un par de huesos, dicen los investigadores","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Seg\u00fan una nueva investigaci\u00f3n, un f\u00f3sil de 280 millones de a\u00f1os que se cree que es un esp\u00e9cimen bien conservado de un reptil antiguo es en gran medida una falsificaci\u00f3n.El f\u00f3sil, descubierto inicialmente en los Alpes italianos en 1931, tiene el nombre cient\u00edfico de Tridentinosaurus antiquus. Los cient\u00edficos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469590,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/12\/26\/misterio-evolucion-humana-2025-trax\/","url_meta":{"origin":1451139,"position":5},"title":"El mayor misterio de la evoluci\u00f3n humana empieza a despejarse: un avance en 2025 fue clave","author":"","date":"diciembre 26, 2025","format":false,"excerpt":"El mayor misterio de la evoluci\u00f3n humana, que surgi\u00f3 hace 15 a\u00f1os a partir de un hueso del me\u00f1ique de unos 60.000 a\u00f1os de antig\u00fcedad, finalmente comenz\u00f3 a desvelarse en 2025.El an\u00e1lisis del ADN extra\u00eddo del f\u00f3sil conmocion\u00f3 a la comunidad cient\u00edfica en 2010, cuando revel\u00f3 la existencia de una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1451139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1451139"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1451139\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1451139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1451139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1451139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}