{"id":1451164,"date":"2024-07-16T12:03:43","date_gmt":"2024-07-16T19:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/"},"modified":"2024-07-16T12:03:43","modified_gmt":"2024-07-16T19:03:43","slug":"accidente-autobus-peru-ayacucho-muertos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/","title":{"rendered":"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa"},"content":{"rendered":"<p>(CNN) &#8212; Al menos 23 personas murieron en Per\u00fa despu\u00e9s de que un autob\u00fas cayera m\u00e1s de 200 metros a un barranco el martes mientras viajaba desde Lima a la ciudad de Ayacucho, dijeron las autoridades.<\/p>\n<p>Las autoridades realizan operaciones de b\u00fasqueda y rescate, dijo el Ministerio del Interior del pa\u00eds en X, agregando que 13 personas resultaron heridas.<\/p>\n<p>El accidente ocurri\u00f3 alrededor de las 5 a.m. hora local en el sector de Ccarhuaccpampa, ubicado en el distrito de Paras, provincia de Cangallo, regi\u00f3n Ayacucho, a unos 10 minutos de Rumichaca, en el l\u00edmite con Huancavelica en la v\u00eda nacional Los Libertadores. Se desconoce la causa, dijeron las autoridades.<\/p>\n<p>Cr\u00e9dito: Agencia Andina<\/p>\n<p>Todos los heridos est\u00e1n siendo tratados en hospitales cercanos.<\/p>\n<p>Las carreteras monta\u00f1osas de Per\u00fa han sufrido varios accidentes mortales en los \u00faltimos a\u00f1os.<\/p>\n<p>En abril de 2021, se produjo un accidente de autob\u00fas en el departamento peruano de \u00c1ncash, a unos 724 kil\u00f3metros de Lima, que dej\u00f3 20 muertos y 14 heridos.<\/p>\n<p>En febrero de 2022, otras 20 personas murieron y 33 resultaron heridas luego de que un autob\u00fas descarrilara y cayera a un barranco de 100 metros en la provincia de Pataz, en el norte de Per\u00fa.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Al menos 23 personas murieron en Per\u00fa despu\u00e9s de que un autob\u00fas cayera m\u00e1s de 200 metros a un barranco el martes mientras viajaba desde Lima a la ciudad de Ayacucho, dijeron las autoridades. Las autoridades realizan operaciones de b\u00fasqueda y rescate, dijo el Ministerio del Interior del pa\u00eds en X, agregando que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451164","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Al menos 23 personas murieron en Per\u00fa despu\u00e9s de que un autob\u00fas cayera m\u00e1s de 200 metros a un barranco el martes mientras viajaba desde Lima a la ciudad de Ayacucho, dijeron las autoridades. Las autoridades realizan operaciones de b\u00fasqueda y rescate, dijo el Ministerio del Interior del pa\u00eds en X, agregando que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-16T19:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa\",\"datePublished\":\"2024-07-16T19:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/\"},\"wordCount\":239,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/\",\"name\":\"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-16T19:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa - Noticias","og_description":"(CNN) &#8212; Al menos 23 personas murieron en Per\u00fa despu\u00e9s de que un autob\u00fas cayera m\u00e1s de 200 metros a un barranco el martes mientras viajaba desde Lima a la ciudad de Ayacucho, dijeron las autoridades. Las autoridades realizan operaciones de b\u00fasqueda y rescate, dijo el Ministerio del Interior del pa\u00eds en X, agregando que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-16T19:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/"},"author":{"name":"","@id":""},"headline":"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa","datePublished":"2024-07-16T19:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/"},"wordCount":239,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/","name":"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-16T19:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos 23 muertos luego de que un autob\u00fas cayera a un barranco de m\u00e1s de 200 metros en Per\u00fa","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/07\/16\/accidente-autobus-peru-ayacucho-muertos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-16T19:03:43Z","datePublished":"2024-07-16T19:03:43Z","dateModified":"2024-07-16T19:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos 23 muertos luego de que un autob\\u00fas cayera a un barranco de m\\u00e1s de 200 metros en Per\\u00fa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/07\\\/16\\\/accidente-autobus-peru-ayacucho-muertos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/07\\\/16\\\/accidente-autobus-peru-ayacucho-muertos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-16T19:03:43Z\",\"datePublished\":\"2024-07-16T19:03:43Z\",\"dateModified\":\"2024-07-16T19:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458782,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/02\/15\/autobus-barranco-el-salvador-heridos-orix\/","url_meta":{"origin":1451164,"position":0},"title":"Cae un autob\u00fas a un barranco en El Salvador y hay al menos 28 heridos, ocho de gravedad","author":"","date":"febrero 15, 2025","format":false,"excerpt":"Al menos 28 personas resultaron heridas despu\u00e9s de que un autob\u00fas cayera este s\u00e1bado en un barranco en el kil\u00f3metro 76 de la Carretera Panamericana, a la altura de San Vicente, en El Salvador, inform\u00f3 mediante una publicaci\u00f3n en X la Direcci\u00f3n General de Protecci\u00f3n Civil del pa\u00eds centroamericano.No se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468261,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/11\/12\/peru-caida-autobus-decenas-muertos-orix\/","url_meta":{"origin":1451164,"position":1},"title":"M\u00e1s de 30 muertos y decenas de heridos por la ca\u00edda de un autob\u00fas al vac\u00edo en Per\u00fa","author":"","date":"noviembre 12, 2025","format":false,"excerpt":"M\u00e1s de 30 personas murieron tras la ca\u00edda de un autob\u00fas a un abismo en Per\u00fa. El incidente ocurri\u00f3 en Arequipa, en la provincia de Caman\u00e1. Walter Oporto, gerente regional de Salud de Arequipa, dijo al medio RPP que adem\u00e1s hay m\u00e1s de una decena de personas heridas que est\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457205,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/04\/accidente-autobus-suroeste-colombia-efe\/","url_meta":{"origin":1451164,"position":2},"title":"Al menos 12 muertos y 30 heridos en el accidente de un autob\u00fas en el suroeste de Colombia","author":"","date":"enero 4, 2025","format":false,"excerpt":"Al menos 12 personas murieron y otras 30 resultaron heridas este viernes luego de que un autob\u00fas que transportaba turistas se fue a un abismo en un sector de la V\u00eda Panamericana, la principal carretera del suroeste de Colombia, inform\u00f3 la Polic\u00eda.El automotor, con 42 personas a bordo, se accident\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464235,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/04\/personas-muertas-y-heridas-caida-autobus-rio-mexico-orix\/","url_meta":{"origin":1451164,"position":3},"title":"Al menos 9 personas muertas y 15 heridas por ca\u00edda de un autob\u00fas a un r\u00edo en M\u00e9xico","author":"","date":"julio 4, 2025","format":false,"excerpt":"Al menos nueve personas murieron y 15 m\u00e1s resultaron heridas despu\u00e9s de que un autob\u00fas, procedente de Cuernavaca y con destino a Tlapa de Comonfort, en el estado mexicano de Guerrero, cay\u00f3 este jueves al cauce de un r\u00edo, informaron las autoridades municipales a trav\u00e9s de su cuenta de Facebook.\u201cNos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472221,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/03\/15\/muere-el-candidato-presidencial-de-peru-napoleon-becerra-en-un-accidente-de-transito-informan-medios-estatales\/","url_meta":{"origin":1451164,"position":4},"title":"Muere el candidato presidencial de Per\u00fa Napole\u00f3n Becerra en un accidente de tr\u00e1nsito, informan medios estatales","author":"","date":"marzo 15, 2026","format":false,"excerpt":"El candidato presidencial de Per\u00fa Napole\u00f3n Becerra, quien era uno de los 36 aspirantes a la jefatura de Estado en los comicios generales de abril, falleci\u00f3 en un accidente de tr\u00e1nsito cuando se dirig\u00eda a cumplir una actividad proselitista en el sur del pa\u00eds, informaron este domingo medios estatales peruanos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461327,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/17\/cuatro-personas-murieron-una-herida-teleferico-barranco-italia-trax\/","url_meta":{"origin":1451164,"position":5},"title":"Cuatro personas murieron y una result\u00f3 herida al caer un telef\u00e9rico por un barranco en Italia","author":"","date":"abril 17, 2025","format":false,"excerpt":"Cuatro personas murieron y una result\u00f3 gravemente herida cuando un telef\u00e9rico se precipit\u00f3 a un barranco en Italia este jueves, informaron las autoridades locales.El accidente ocurri\u00f3 despu\u00e9s de que un cable del telef\u00e9rico de Monte Faito, cerca de Sorrento, se rompiera debido al mal tiempo, seg\u00fan Vincenzo De Luca, presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1451164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1451164"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1451164\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1451164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1451164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1451164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}