{"id":1456146,"date":"2024-11-28T17:03:51","date_gmt":"2024-11-29T01:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/"},"modified":"2024-11-28T17:03:51","modified_gmt":"2024-11-29T01:03:51","slug":"argentina-garrahan-hospital-pediatrico-oirx","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/","title":{"rendered":"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Guadalupe Butarac ten\u00eda 12 a\u00f1os la primera vez que lleg\u00f3 al hospital de pediatr\u00eda Garrahan. Desde que naci\u00f3, su mam\u00e1 sab\u00eda que las posibilidades de que su hija necesitara un trasplante en alg\u00fan momento eran altas. Los m\u00e9dicos se lo hab\u00edan diagnosticado desde el principio: ten\u00eda fibrosis qu\u00edstica, condici\u00f3n que afecta principalmente la parte digestiva y respiratoria del cuerpo. Los pulmones de Guadalupe no pod\u00edan funcionar sin asistencia externa.<br \/>\nMadre e hija son de Mendoza, provincia del occidente de Argentina, y viven solas. Desde que ten\u00eda uso de raz\u00f3n, la vida de Butarac estuvo marcada por su enfermedad. Primero por los tratamientos, despu\u00e9s porque no pod\u00eda vivir sin estar conectada a una m\u00e1quina. En esa \u00e9poca no iba al colegio: su enfermedad no se lo permit\u00eda.<\/p>\n<p>A medida que iba creciendo se hizo m\u00e1s evidente: necesitaba un trasplante pulmonar para poder seguir adelante. Seg\u00fan relata a CNN Erica P\u00eda, su mam\u00e1, en el Hospital Humberto Notti de Mendoza, donde la trataban, les explicaron que el \u00fanico lugar del pa\u00eds que hac\u00eda ese tipo de procedimientos en ni\u00f1os y adolescentes era el Hospital Garrahan. Por eso, en 2019, se trasladaron a Buenos Aires para conseguir la cirug\u00eda que pod\u00eda salvar su vida.<\/p>\n<p>La espera dur\u00f3 m\u00e1s de un a\u00f1o. En plena pandemia con su mam\u00e1 durmiendo en una habitaci\u00f3n que el hospital ofrece a familiares de pacientes que viven en otras provincias, recibieron la buena noticia: hab\u00eda llegado el momento del trasplante.<\/p>\n<p>Desde entonces la vida de Butarac dio un vuelco: su madre cuenta que por primera vez pudo vivir sin depender de conexiones a m\u00e1quinas, ir al colegio sin interrupciones, hacer amigos, pensar en un futuro. Hoy tiene 18 a\u00f1os y sue\u00f1a con estudiar Marketing en la Universidad.<\/p>\n<p>\u201cA m\u00ed el Hospital Garrahan me cambi\u00f3 la vida. Porque yo estaba padeciendo la enfermedad con mi hija, donde el tiempo se ven\u00eda agotando muy r\u00e1pido, el deterioro de ella era incre\u00edble, y cre\u00edamos que no \u00edbamos a avanzar para ning\u00fan lado. Y el haber llegado al hospital, todo el equipo m\u00e9dico es fabuloso, los profesionales son excelentes. Realmente para nosotros fue un volver a vivir porque mi hija estaba conectada todo el tiempo, no ten\u00eda vida social, no sal\u00eda de la casa, se la pasaba acostada. Era tanto el desgaste f\u00edsico que ten\u00eda para poder respirar, y a partir del trasplante mejor\u00f3 todo, su estado de \u00e1nimo, volvi\u00f3 a la escuela\u201d, relata P\u00eda.<\/p>\n<p>El Hospital Garrahan es el centro m\u00e9dico de alta complejidad pedi\u00e1trico m\u00e1s importante de Argentina y un referente en Am\u00e9rica Latina. La instituci\u00f3n describe que no solamente realiza el 50% de los trasplantes a menores y adolescentes del pa\u00eds, sino que atiende a cerca del 40% de los pacientes con c\u00e1ncer pedi\u00e1trico, y resuelve el 70% de las cardiopat\u00edas cong\u00e9nitas complejas que requieren intervenci\u00f3n en los primeros tres meses de vida. Y tambi\u00e9n es una de las principales instituciones que trata enfermedades cr\u00f3nicas complejas en Argentina. En 2023, el hospital atendi\u00f3 unos 36.000 pacientes con enfermedades complejas, 700.000 pacientes con consultas ambulatorias, 27.000 internaciones, realizaron alrededor de 10.000 cirug\u00edas y unos 120 trasplantes.<\/p>\n<p>En Argentina existe una red de medicina gratuita a cargo de los gobiernos provinciales y nacionales, dependiendo la especialidad de los hospitales financiada por el Estado, adem\u00e1s de la medicina privada.<\/p>\n<p>El trasplante pulmonar en menores es uno de los tantos procedimientos que solo realiza esta instituci\u00f3n y es una peque\u00f1a parte de los tratamientos que se podr\u00edan ver afectados con los recortes que viene sufriendo el hospital desde que comenz\u00f3 la gesti\u00f3n del presidente Javier Milei.<\/p>\n<p>Desde agosto de este a\u00f1o, los profesionales vienen denunciando la p\u00e9rdida del poder adquisitivo en los salarios, y en lo que va de 2024 ya llevan acumulados nueve paros. Cuando se compara la inflaci\u00f3n interanual de octubre con los aumentos que recibi\u00f3 el personal del hospital en ese per\u00edodo, la p\u00e9rdida del ingreso real alcanza el 104%, seg\u00fan el c\u00e1lculo de los propios trabajadores.<\/p>\n<p>El doctor Claudio Casta\u00f1os es jefe del Servicio de Neumonolog\u00eda del Hospital Garrahan de pediatr\u00eda; y es el especialista que lider\u00f3 el procedimiento que le devolvi\u00f3 el aire a Guadalupe. Distintos profesionales del Garrahan acuerdan que lo que cuenta es algo que se repite en las distintas especialidades del hospital desde que el salario de los m\u00e9dicos comenz\u00f3 a deteriorarse.<\/p>\n<p>\u201cAhora estamos medio parados con el programa de trasplante, porque justamente se nos fueron dos de los cirujanos. Eran cuatro cirujanos que hac\u00edan trasplante y dos se fueron. Uno se jubil\u00f3 y la otra se fue a vivir a Espa\u00f1a\u201d. Para esos procedimientos se requiere un equipo completo.<\/p>\n<p>Es decir, si un ni\u00f1o necesitara un trasplante pulmonar hoy en Argentina, habr\u00eda que revisar si un cirujano de adultos acepta realizar el procedimiento en el que no es especialista, por ejemplo, centros especializados en trasplantes para adultos y adolescentes como Fundaci\u00f3n Favaloro. \u201cNo s\u00e9 si lo aceptar\u00edan en alguno de los lugares de adultos, pero en principio no habr\u00eda lugar para trasplantarlo en Argentina\u201d, alerta Casta\u00f1os.<\/p>\n<p>2021: Radi\u00f3logas del hospital Garrahan en Buenos Aires denuncian haber estado expuestas a radiaci\u00f3n de manera insegura y haber perdido embarazos<\/p>\n<p>El Garrahan no es solamente un hospital: es tambi\u00e9n un centro educativo. En sus salas se formaron algunos de los profesionales m\u00e1s destacados de sus especialidades. Casta\u00f1os cuenta que un cirujano con el entrenamiento que hace falta en su \u00e1rea lleva unos 10 a\u00f1os de formaci\u00f3n, sin contar los siete que dura la carrera universitaria. Si un especialista se va al sector privado o emigra, el hospital tarda 10 a\u00f1os m\u00e1s en formar a alguien con conocimientos y experiencia similar.<\/p>\n<p>En los traslados sucesivos para observaci\u00f3n y controles, P\u00eda comparti\u00f3 con otros padres de la Casa Garrahan, un hogar que el hospital cede de manera gratuita a los familiares de los pacientes que no tienen d\u00f3nde quedarse en Buenos Aires, para que puedan acompa\u00f1ar a los pacientes durante sus tratamientos. Este es otro de los motivos por los que el desfinanciamiento de la instituci\u00f3n preocupa. Hasta junio la partida presupuestaria del hospital se manten\u00eda igual a las de 2023. Con ese presupuesto prorrogado se cubrieron gastos hasta junio, momento en el que el gobierno design\u00f3 un refuerzo de 90.000 millones de pesos (alrededor de US$ 80.000 al cambio paralelo) que, seg\u00fan los trabajadores, se utilizan para gastos de mantenimiento, pero no para la recomposici\u00f3n salarial.<\/p>\n<p>Adem\u00e1s, el hospital provee de medicamentos a quienes lo necesitan en sus tratamientos ambulatorios. Los profesionales del Garrahan est\u00e1n preocupados por lo que pueda suceder con este servicio si la inversi\u00f3n estatal no mejora.<\/p>\n<p>CNN se puso en contacto con el Ministerio de Salud para pedir su reacci\u00f3n respecto a las denuncias de los trabajadores, pero a\u00fan no ha obtenido respuesta.<\/p>\n<p>Tambi\u00e9n se contact\u00f3 con el equipo de comunicaci\u00f3n del hospital para confirmar los datos de renuncias de profesionales. Por ahora, explican, los n\u00fameros de 2024 son similares a los de a\u00f1os anteriores y los profesionales \u201csiempre se reemplazan\u201d.<\/p>\n<p>\u201cNo hay plata\u201d<\/p>\n<p>En octubre de este a\u00f1o, poco despu\u00e9s de asumir su cargo, el ministro de Salud, Mario Lugones, solicit\u00f3 la renuncia de los cuatro miembros del consejo de administraci\u00f3n del hospital y los reemplaz\u00f3 por otros tres. \u00bfCu\u00e1l fue el motivo? La administraci\u00f3n decidi\u00f3 otorgar al personal un bono extraordinario de 500.000 pesos (unos US$ 450 al cambio paralelo) proveniente de los recursos extrapresupuestarios que, por ejemplo, el hospital le factura a las obras sociales o prepagas (entidades que comercializan diversos planes de salud para brindar atenci\u00f3n m\u00e9dica). Estos fondos representan 20% del presupuesto total del hospital.<\/p>\n<p>Al ser un organismo aut\u00e1rquico, el Garrahan tiene la potestad de administrar estos ingresos sin intervenci\u00f3n del Gobierno. Sin embargo, entre los motivos que menciona el Ministerio de Salud para apartar a los miembros del consejo incluye que \u201cla decisi\u00f3n hab\u00eda sido inconsulta, sin previa evaluaci\u00f3n con la cartera sanitaria y no cumpl\u00eda con la premisa del Gobierno Nacional de d\u00e9ficit cero\u201d.<\/p>\n<p>El bono ofrecido por el consejo fue un paliativo moment\u00e1neo, ya que sin una actualizaci\u00f3n salarial y presupuestaria que acompa\u00f1e a la inflaci\u00f3n la atenci\u00f3n en el Garrahan corre peligro.<\/p>\n<p>\u201cUna m\u00e9dica emergent\u00f3loga con 20 a\u00f1os de antig\u00fcedad est\u00e1 ganando 1.450.000 pesos (unos US$ 1.300 al tipo de cambio paralelo) con carga horaria de 42 horas semanales. Una enfermera est\u00e1 ganando 890.000 pesos de bolsillo (unos US$ 800 en el mercado paralelo) y esto no alcanza\u201d, cuenta Norma Lezama, licenciada en Nutrici\u00f3n y secretaria general de la Asociaci\u00f3n de Profesionales y T\u00e9cnicos del Hospital Garrahan.<\/p>\n<p>Y agrega: \u201cUna guardia en el (hospital) privado se est\u00e1 pagando 300.000 (unos US$ 270 en el mercado de cambio paralelo) y en el hospital, 150.000 (unos US$ 130). O sea, exactamente la mitad. Y son guardias arduas, con muchos pacientes que acuden al hospital muchas veces despu\u00e9s de no haber obtenido una atenci\u00f3n en otros centros\u201d.<\/p>\n<p>\u201cSi no existiera el Hospital Garrahan volver\u00edamos 40 a\u00f1os atr\u00e1s, cuando escuch\u00e1bamos que se hac\u00edan campa\u00f1as para juntar dinero para solventar el traslado de un ni\u00f1o que requer\u00eda un trasplante hep\u00e1tico o un tratamiento oncol\u00f3gico y ten\u00eda que viajar fuera del pa\u00eds porque en nuestro pa\u00eds no exist\u00eda la posibilidad de tener el acceso a esas pr\u00e1cticas de alta complejidad\u201d, compara Lezama.<\/p>\n<p>El 10 de diciembre se cumple un a\u00f1o de mandato de Javier Milei. Los trabajadores ya anunciaron que ese d\u00eda har\u00e1n su d\u00e9cimo paro del a\u00f1o.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Guadalupe Butarac ten\u00eda 12 a\u00f1os la primera vez que lleg\u00f3 al hospital de pediatr\u00eda Garrahan. Desde que naci\u00f3, su mam\u00e1 sab\u00eda que las posibilidades de que su hija necesitara un trasplante en alg\u00fan momento eran altas. Los m\u00e9dicos se lo hab\u00edan diagnosticado desde el principio: ten\u00eda fibrosis qu\u00edstica, condici\u00f3n que afecta principalmente [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456146","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Guadalupe Butarac ten\u00eda 12 a\u00f1os la primera vez que lleg\u00f3 al hospital de pediatr\u00eda Garrahan. Desde que naci\u00f3, su mam\u00e1 sab\u00eda que las posibilidades de que su hija necesitara un trasplante en alg\u00fan momento eran altas. Los m\u00e9dicos se lo hab\u00edan diagnosticado desde el principio: ten\u00eda fibrosis qu\u00edstica, condici\u00f3n que afecta principalmente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-29T01:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores\",\"datePublished\":\"2024-11-29T01:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/\"},\"wordCount\":1715,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/\",\"name\":\"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-11-29T01:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/","og_locale":"es_ES","og_type":"article","og_title":"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Guadalupe Butarac ten\u00eda 12 a\u00f1os la primera vez que lleg\u00f3 al hospital de pediatr\u00eda Garrahan. Desde que naci\u00f3, su mam\u00e1 sab\u00eda que las posibilidades de que su hija necesitara un trasplante en alg\u00fan momento eran altas. Los m\u00e9dicos se lo hab\u00edan diagnosticado desde el principio: ten\u00eda fibrosis qu\u00edstica, condici\u00f3n que afecta principalmente [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/","og_site_name":"Noticias","article_published_time":"2024-11-29T01:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/"},"author":{"name":"","@id":""},"headline":"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores","datePublished":"2024-11-29T01:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/"},"wordCount":1715,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/","url":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/","name":"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-11-29T01:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El hospital pedi\u00e1trico m\u00e1s importante de Argentina peligra por las pol\u00edticas de Milei, denuncian los trabajadores","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/11\/28\/argentina-garrahan-hospital-pediatrico-oirx\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-11-29T01:03:51Z","datePublished":"2024-11-29T01:03:51Z","dateModified":"2024-11-29T01:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El hospital pedi\\u00e1trico m\\u00e1s importante de Argentina peligra por las pol\\u00edticas de Milei, denuncian los trabajadores\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/11\\\/28\\\/argentina-garrahan-hospital-pediatrico-oirx\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/11\\\/28\\\/argentina-garrahan-hospital-pediatrico-oirx\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-11-29T01:03:51Z\",\"datePublished\":\"2024-11-29T01:03:51Z\",\"dateModified\":\"2024-11-29T01:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460839,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/04\/kala-bidner-y-guadalupe-martinez-uria-musica-familia-y-el-camino-en-la-industria\/","url_meta":{"origin":1456146,"position":0},"title":"Kala Bidner y Guadalupe Mart\u00ednez Ur\u00eda: m\u00fasica, familia y el camino en la industria","author":"","date":"abril 4, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Guadalupe Mart\u00ednez Ur\u00eda y Kala Bidner dialogaron este viernes en Los Primeros de la Tarde con P\u00eda Shaw y Nacho Juliano sobre la carrera de cantante de Kala y el acompa\u00f1amiento que tiene de su madre.\u201cMi mam\u00e1 siempre me dijo que haga mi propio camino\u201d, expres\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464680,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/19\/texas-muertes-mystic-hija-recuerdos-trax\/","url_meta":{"origin":1456146,"position":1},"title":"Tres muertes en cinco meses: los recuerdos de su hija ayudan a una madre a sobrellevar la tragedia en Texas","author":"","date":"julio 19, 2025","format":false,"excerpt":"La \u00faltima vez que Lindsey McLeod McCrory vio con vida a su hija Blakely, la peque\u00f1a se dirig\u00eda al campamento con un collar sencillo pero profundo, uno que posteriormente la conectar\u00eda con su madre tras su fallecimiento.Era un collar de cuentas verdes y blancas del Campamento Mystic, un homenaje al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464374,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/09\/rio-guadalupe-refugio-dolor-futuro-incierto-inundaciones-trax\/","url_meta":{"origin":1456146,"position":2},"title":"El r\u00edo Guadalupe pas\u00f3 de ser un refugio de aventura y alegr\u00eda a un gran dolor con un futuro incierto tras las inundaciones","author":"","date":"julio 9, 2025","format":false,"excerpt":"Ron Duke valoraba el r\u00edo Guadalupe m\u00e1s que cualquier otra cosa.A sus 80 a\u00f1os, le encantaba remar en kayak por el cristalino cauce que recorre unos 400 kil\u00f3metros desde los manantiales de Texas Hill Country hasta la bah\u00eda de San Antonio, en el golfo. Su taller de carpinter\u00eda estaba cerca,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445943,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/02\/22\/muere-hydeia-broadbent-trax\/","url_meta":{"origin":1456146,"position":3},"title":"Muere a los 39 a\u00f1os Hydeia Broadbent, activista contra el VIH\/sida desde su ni\u00f1ez","author":"","date":"febrero 22, 2024","format":false,"excerpt":"(CNN) -- Hydeia Broadbent, conocida por generar consciencia sobre el VIH\/sida desde que era una ni\u00f1a, falleci\u00f3, seg\u00fan anunci\u00f3 su padre en Facebook. Ten\u00eda 39 a\u00f1os.\"Con gran tristeza debo informarles a todos que nuestra querida amiga, mentora e hija Hydeia falleci\u00f3 hoy tras vivir con VIH desde su nacimiento. A\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464753,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/22\/argentino-artese-autodeportarse-alligator-alcatraz-orix\/","url_meta":{"origin":1456146,"position":4},"title":"Es argentino y planeaba autodeportarse de EE.UU. con su familia. Lo detuvieron y lo enviaron a &#171;Alligator Alcatraz&#187;","author":"","date":"julio 22, 2025","format":false,"excerpt":"El proyecto para salir de Estados Unidos, tras una d\u00e9cada construyendo una vida en la Florida, era un hecho. Ten\u00eda nombre, logo y canal de YouTube: Argentinomades. Ser\u00eda un diario de viaje audiovisual donde esta pareja argentina y su hija, nacida en Espa\u00f1a, registrar\u00eda la que pensaron como una aventura,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466629,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/09\/19\/pareja-mexicana-detenida-ice-hijos-orix\/","url_meta":{"origin":1456146,"position":5},"title":"Una pareja mexicana fue detenida por ICE y su hija de 19 a\u00f1os se enfrent\u00f3 a los agentes migratorios","author":"","date":"septiembre 19, 2025","format":false,"excerpt":"Constantina Ram\u00edrez y Mois\u00e9s Enciso, una pareja de mexicanos que viven en Cicero, Illinois desde hace 15 a\u00f1os, fueron detenidos el domingo por agentes del Servicio de Control de Inmigraci\u00f3n y Aduanas de Estados Unidos (ICE, en ingl\u00e9s) en el d\u00eda de cumplea\u00f1os del menor de sus cuatro hijos, un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456146"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456146\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}