{"id":1456154,"date":"2024-11-29T02:03:39","date_gmt":"2024-11-29T10:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/"},"modified":"2024-11-29T02:03:39","modified_gmt":"2024-11-29T10:03:39","slug":"laos-envenenamientos-metanol-vodka-tigre-whisky-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/","title":{"rendered":"Australia advierte de que no se debe beber vodka y whisky &#171;Tiger&#187; en Laos tras la muerte de turistas"},"content":{"rendered":"<p>(CNN) &#8212; Australia advirti\u00f3 a los viajeros que no beban bebidas espirituosas elaboradas por un destilador de Laos, tras la muerte de seis turistas extranjeros por presunta intoxicaci\u00f3n con metanol en el pa\u00eds del Sudeste Asi\u00e1tico.<\/p>\n<p>El aviso actualizado publicado este viernes citaba &#171;serias preocupaciones de seguridad&#187; sobre el vodka y el whisky de la marca Tiger de Laos, a ra\u00edz de una intoxicaci\u00f3n masiva ocurrida a principios de mes en la ciudad norte\u00f1a de Vang Vieng, popular destino de mochileros.<\/p>\n<p>&#171;Las autoridades laosianas emitieron una orden que proh\u00edbe la venta y el consumo de vodka y whisky Tiger debido a su preocupaci\u00f3n por el riesgo que estos productos suponen para la salud.<\/p>\n<p>Laos detiene a empleados de hostal por intoxicaciones con metanol tras la muerte de seis turistas<\/p>\n<p>&#171;Est\u00e9 alerta ante los riesgos potenciales, especialmente con las bebidas espirituosas, incluidos los c\u00f3cteles&#187;.<\/p>\n<p>Los medios de comunicaci\u00f3n estatales en lengua inglesa no informaron de la aparente prohibici\u00f3n de las bebidas espirituosas de la marca Tiger en Laos. Las advertencias sobre las consecuencias potencialmente mortales del consumo de alcohol contaminado tras las intoxicaciones han llegado de gobiernos extranjeros a sus propios ciudadanos, no de las autoridades de Laos.<\/p>\n<p>Laos, un opaco Estado comunista, controla f\u00e9rreamente sus medios de comunicaci\u00f3n y guard\u00f3 silencio sobre las muertes durante m\u00e1s de una semana antes de emitir su primera declaraci\u00f3n. M\u00e1s de dos semanas despu\u00e9s, los detalles sobre la muerte de los turistas y la forma en que enfermaron \u2013incluido el alcance de las intoxicaciones\u2013 siguen siendo escasos, lo que frustra a las familias y a los viajeros que intentan reconstruir lo ocurrido en Vang Vieng.<\/p>\n<p>El gerente de un hostal en Vang Vieng muestra una botella del vodka Tiger en Vang Vieng, Laos, el 19 de noviembre de 2024. (Cr\u00e9dito: Anupam Nath\/AP)<\/p>\n<p>Las australianas Bianca Jones y Holly Bowles, ambas de 19 a\u00f1os; las danesas Anne-Sofie Orkild Coyman, de 20, y Frela Vennervald Sorensen, de 21; el estadounidense James Louis Hutson, de 57; y la abogada brit\u00e1nica Simone White, de 28, murieron presuntamente intoxicadas con metanol tras beber alcohol en Vang Vieng.<\/p>\n<p>A principios de esta semana, las autoridades locales detuvieron a ocho empleados vietnamitas de un albergue para mochileros en el que se hab\u00edan alojado al menos cinco de las v\u00edctimas, seg\u00fan el diario estatal Laotian Times.<\/p>\n<p>Parte de la investigaci\u00f3n se centr\u00f3 en los informes de que a los turistas se les ofrecieron chupitos de alcohol gratis en el Nana Backpacker Hostel.<\/p>\n<p>Mueren seis turistas en Laos por presuntas intoxicaciones con metanol, en medio de advertencias por alcohol adulterado<\/p>\n<p>El gerente y el propietario del albergue, tambi\u00e9n vietnamitas, fueron detenidos previamente para ser interrogados por la Polic\u00eda, seg\u00fan Associated Press. El gerente hab\u00eda declarado anteriormente que las dos mujeres australianas se unieron a m\u00e1s de 100 hu\u00e9spedes para tomar chupitos gratis en el albergue antes de salir por la noche, pero neg\u00f3 que otros hu\u00e9spedes hubieran informado de ning\u00fan problema, inform\u00f3 AP.<\/p>\n<p>Ante la escasa informaci\u00f3n facilitada por las autoridades laosianas, algunos viajeros de Vang Vieng y amigos de los fallecidos se han puesto manos a la obra para investigar. Uno de ellos, que pidi\u00f3 que no se revelara su nombre, dijo a CNN que hab\u00edan realizado una encuesta independiente entre viajeros que tambi\u00e9n enfermaron o fueron hospitalizados tras sospechar que se hab\u00edan intoxicado con metanol.<\/p>\n<p>Muchos de los encuestados describieron haber enfermado despu\u00e9s de beber en varios bares o albergues de la ciudad.<\/p>\n<p>Bianca Jones, izquierda, y Holly Bowles, estaban de mochilera en Laos cuando se enfermaron despu\u00e9s de una noche de fiesta. (Cr\u00e9dito: Facebook).<\/p>\n<p>CNN no puede verificar de forma independiente estos informes o los resultados de la encuesta.<\/p>\n<p>Laos Tiger Vodka y Tiger Whisky son una marca de bebidas espirituosas de producci\u00f3n local baratas de comprar y a menudo utilizadas en bebidas mezcladas y c\u00f3cteles. La marca no parece tener un sitio web p\u00fablico y la etiqueta del vodka dice que est\u00e1 &#171;destilado, mezclado y embotellado en Laos&#187;.<\/p>\n<p>El metanol es una sustancia qu\u00edmica alcoh\u00f3lica utilizada habitualmente en disolventes industriales, productos de limpieza y combustibles, aunque puede a\u00f1adirse a las bebidas alcoh\u00f3licas de forma inadvertida a trav\u00e9s de los m\u00e9todos tradicionales de elaboraci\u00f3n o deliberadamente para aumentar el volumen de las bebidas alcoh\u00f3licas, normalmente con \u00e1nimo de lucro.<\/p>\n<p>Se reportan varios muertos en intoxicaci\u00f3n masiva por metanol en Laos<\/p>\n<p>Solo peque\u00f1as cantidades de metanol pueden causar ceguera, n\u00e1useas y v\u00f3mitos, mientras que beber tan solo 30 mililitros (1 onza) puede ser letal.<\/p>\n<p>Si no se trata, las tasas de letalidad oscilan entre el 20% y el 40%, dependiendo de la concentraci\u00f3n del metanol y de la cantidad ingerida, seg\u00fan la organizaci\u00f3n ben\u00e9fica M\u00e9dicos Sin Fronteras, que hace un seguimiento de los casos de intoxicaci\u00f3n por metanol en todo el mundo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Australia advirti\u00f3 a los viajeros que no beban bebidas espirituosas elaboradas por un destilador de Laos, tras la muerte de seis turistas extranjeros por presunta intoxicaci\u00f3n con metanol en el pa\u00eds del Sudeste Asi\u00e1tico. El aviso actualizado publicado este viernes citaba &#171;serias preocupaciones de seguridad&#187; sobre el vodka y el whisky de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456154","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Australia advierte de que no se debe beber vodka y whisky &quot;Tiger&quot; en Laos tras la muerte de turistas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Australia advierte de que no se debe beber vodka y whisky &quot;Tiger&quot; en Laos tras la muerte de turistas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Australia advirti\u00f3 a los viajeros que no beban bebidas espirituosas elaboradas por un destilador de Laos, tras la muerte de seis turistas extranjeros por presunta intoxicaci\u00f3n con metanol en el pa\u00eds del Sudeste Asi\u00e1tico. El aviso actualizado publicado este viernes citaba &#171;serias preocupaciones de seguridad&#187; sobre el vodka y el whisky de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-29T10:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Australia advierte de que no se debe beber vodka y whisky &#171;Tiger&#187; en Laos tras la muerte de turistas\",\"datePublished\":\"2024-11-29T10:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/\"},\"wordCount\":875,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/\",\"name\":\"Australia advierte de que no se debe beber vodka y whisky \\\"Tiger\\\" en Laos tras la muerte de turistas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-11-29T10:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Australia advierte de que no se debe beber vodka y whisky &#171;Tiger&#187; en Laos tras la muerte de turistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Australia advierte de que no se debe beber vodka y whisky \"Tiger\" en Laos tras la muerte de turistas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Australia advierte de que no se debe beber vodka y whisky \"Tiger\" en Laos tras la muerte de turistas - Noticias","og_description":"(CNN) &#8212; Australia advirti\u00f3 a los viajeros que no beban bebidas espirituosas elaboradas por un destilador de Laos, tras la muerte de seis turistas extranjeros por presunta intoxicaci\u00f3n con metanol en el pa\u00eds del Sudeste Asi\u00e1tico. El aviso actualizado publicado este viernes citaba &#171;serias preocupaciones de seguridad&#187; sobre el vodka y el whisky de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/","og_site_name":"Noticias","article_published_time":"2024-11-29T10:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/"},"author":{"name":"","@id":""},"headline":"Australia advierte de que no se debe beber vodka y whisky &#171;Tiger&#187; en Laos tras la muerte de turistas","datePublished":"2024-11-29T10:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/"},"wordCount":875,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/","url":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/","name":"Australia advierte de que no se debe beber vodka y whisky \"Tiger\" en Laos tras la muerte de turistas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-11-29T10:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Australia advierte de que no se debe beber vodka y whisky &#171;Tiger&#187; en Laos tras la muerte de turistas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Australia advierte de que no se debe beber vodka y whisky &#171;Tiger&#187; en Laos tras la muerte de turistas","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/11\/29\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-11-29T10:03:39Z","datePublished":"2024-11-29T10:03:39Z","dateModified":"2024-11-29T10:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Australia advierte de que no se debe beber vodka y whisky &#171;Tiger&#187; en Laos tras la muerte de turistas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/11\\\/29\\\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/11\\\/29\\\/laos-envenenamientos-metanol-vodka-tigre-whisky-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-11-29T10:03:39Z\",\"datePublished\":\"2024-11-29T10:03:39Z\",\"dateModified\":\"2024-11-29T10:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456113,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/27\/laos-detiene-empleados-hostal-intoxicaciones-metanol-trax\/","url_meta":{"origin":1456154,"position":0},"title":"Laos detiene a empleados de hostal por intoxicaciones con metanol tras la muerte de seis turistas","author":"","date":"noviembre 27, 2024","format":false,"excerpt":"(CNN) -- Ocho empleados de un hostal para mochileros en Laos fueron detenidos por las autoridades locales mientras investigan las muertes de seis turistas extranjeros por sospecha de intoxicaci\u00f3n con metanol, seg\u00fan medios estatales del pa\u00eds del sudeste asi\u00e1tico.Las muertes de dos adolescentes australianas, una mujer brit\u00e1nica, un hombre estadounidense\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472380,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/03\/20\/bali-resaca-intoxicacion-metanol-trax\/","url_meta":{"origin":1456154,"position":1},"title":"Ella pens\u00f3 que ten\u00eda resaca tras su \u00faltima noche en Bali. Al d\u00eda siguiente no pod\u00eda ver","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Ashley King estaba en su mejor momento. Era 2011 y esta canadiense de 18 a\u00f1os estaba de a\u00f1o sab\u00e1tico. Acababa de pasar un mes en Bali, de camino a una excursi\u00f3n por Nueva Zelandia. Se lo estaba pasando tan bien que incluso hab\u00eda pensado en aplazar sus estudios universitarios un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467313,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/10\/12\/crisis-intoxicacion-metanol-brasil-trax\/","url_meta":{"origin":1456154,"position":2},"title":"&#171;A mi hermano lo mat\u00f3 la avaricia&#187;: dentro de la mortal crisis por las bebidas adulteradas con metanol en Brasil","author":"","date":"octubre 12, 2025","format":false,"excerpt":"Cuando Marcelo Lombardi, de 45 a\u00f1os, se quej\u00f3 de sentirse somnoliento un viernes, su familia no le dio mucha importancia.Lombardi sol\u00eda trabajar largas jornadas en la inmobiliaria familiar que lleva 17 a\u00f1os en Sao Paulo, Brasil, junto a dos de sus hermanas mayores. Abogado reconocido, era una figura apreciada en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456639,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/15\/siete-huespedes-hospitalizados-tras-beber-cocteles-resort-5-estrellas-fiji-trax\/","url_meta":{"origin":1456154,"position":3},"title":"Siete hu\u00e9spedes fueron hospitalizados tras beber c\u00f3cteles en un resort de 5 estrellas de Fiji","author":"","date":"diciembre 15, 2024","format":false,"excerpt":"Siete turistas fueron tratados por presunto envenenamiento tras beber c\u00f3cteles en un bar de un exclusivo resort de Fiji, que ahora investiga la polic\u00eda.Cuatro australianos de entre 18 y 56 a\u00f1os, junto con otras tres personas que se cree que son extranjeros, fueron trasladados al hospital despu\u00e9s de que les\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458383,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/02\/07\/cocaina-no-es-peor-que-whisky-petro-colombia-trax\/","url_meta":{"origin":1456154,"position":4},"title":"La coca\u00edna &#171;no es m\u00e1s mala que el whisky&#187;, dice Petro","author":"","date":"febrero 7, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, afirm\u00f3 que \u201cla coca\u00edna no es m\u00e1s mala que el whisky\u201d, al tiempo que suger\u00eda que el multimillonario comercio il\u00edcito de esta droga podr\u00eda \u201cdesmantelarse f\u00e1cilmente\u201d si se legalizara en todo el mundo.Colombia es el primer productor y exportador mundial de coca\u00edna, principalmente a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460437,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/26\/brett-gardner-muerte-hijo-yankees-costa-rica-trax\/","url_meta":{"origin":1456154,"position":5},"title":"Investigan por presunta intoxicaci\u00f3n la muerte del hijo de exestrella de los Yankees durante unas vacaciones en Costa Rica","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Se descart\u00f3 la asfixia como causa de muerte de Miller Gardner, el hijo de 14 a\u00f1os del exjardinero de los Yankees de Nueva York, Brett Gardner, seg\u00fan informaron a CNN el martes funcionarios costarricenses.Gardner y su esposa Jessica anunciaron el domingo que su hijo Miller hab\u00eda fallecido tras una enfermedad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456154"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456154\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}