{"id":1456205,"date":"2024-12-02T16:03:53","date_gmt":"2024-12-03T00:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/"},"modified":"2024-12-02T16:03:53","modified_gmt":"2024-12-03T00:03:53","slug":"ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/","title":{"rendered":"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego"},"content":{"rendered":"<p>(CNN) &#8212; Por primera vez desde que se implement\u00f3 un alto el fuego la semana pasada, Hezbollah dispar\u00f3 dos proyectiles hacia territorio ocupado por Israel, respondiendo a repetidos ataques israel\u00edes desde el acuerdo.<\/p>\n<p>Israel ha ejecutado ataques diarios en el L\u00edbano desde el jueves, el d\u00eda despu\u00e9s de que entr\u00f3 en vigor el alto el fuego. Una persona muri\u00f3 en un ataque en el sur de L\u00edbano, seg\u00fan el Ministerio de Salud liban\u00e9s.<\/p>\n<p>El alto el fuego entre Israel y Hezbollah en cuatro mapas y gr\u00e1ficos<\/p>\n<p>Hezbollah hab\u00eda disparado dos proyectiles, que aterrizaron en una zona abierta este lunes, seg\u00fan las Fuerzas de Defensa de Israel (FDI), que dijeron que nadie result\u00f3 herido. El Ej\u00e9rcito no especific\u00f3 el tipo de proyectil que se dispar\u00f3.<\/p>\n<p>Horas m\u00e1s tarde, el Ej\u00e9rcito de Israel dijo que comenz\u00f3 a atacar &#171;objetivos terroristas&#187; en L\u00edbano despu\u00e9s de que el primer ministro Benjamin Netanyahu prometiera retaliar en una declaraci\u00f3n, calificando el ataque de Hezbollah como &#171;una grave violaci\u00f3n del alto el fuego&#187;.<\/p>\n<p>Las FDI dijeron m\u00e1s temprano este lunes que sus propios ataques transfronterizos, a pesar del alto el fuego, fueron \u201cen respuesta a varios actos de Hezbollah en L\u00edbano que representaban una amenaza para los civiles israel\u00edes, en violaci\u00f3n de los entendimientos entre Israel y L\u00edbano&#187;. Dijo que atac\u00f3 veh\u00edculos militares en un sitio de fabricaci\u00f3n de misiles de Hezbollah en el Valle de la Bekaa y t\u00faneles cerca de la frontera siria en el norte de L\u00edbano.<\/p>\n<p>Los medios estatales libaneses informaron la tarde de este lunes que ataques a\u00e9reos israel\u00edes apuntaron a \u00e1reas en el distrito de Al-Tuffah en el sur, incluyendo el Monte Safi, el pueblo de Mlikh y las afueras del pueblo de Louaize. Los ataques a\u00e9reos tambi\u00e9n impactaron \u00e1reas en la Gobernaci\u00f3n de Nabatiyeh.<\/p>\n<p>Los medios estatales tambi\u00e9n informaron que drones israel\u00edes volaban bajo sobre Beirut y sus suburbios del sur, conocidos como Dahiyeh. Equipos de CNN en el terreno informaron haber escuchado un dron volando bajo sobre Beirut.<\/p>\n<p>Las FDI dijeron que atacaron a &#171;terroristas de Hezbollah, docenas de lanzadores e infraestructura terrorista en todo L\u00edbano&#187;. En el sur de L\u00edbano, el Ej\u00e9rcito dijo que atac\u00f3 el lanzador de Hezbollah que dispar\u00f3 dos proyectiles hacia el Monte Dov m\u00e1s temprano en el d\u00eda.<\/p>\n<p>&#171;Los lanzamientos de Hezbollah esta noche constituyen una violaci\u00f3n del acuerdo de alto el fuego entre Israel y L\u00edbano. El Estado de Israel exige que las partes relevantes en L\u00edbano cumplan con sus responsabilidades y eviten la actividad hostil de Hezbollah desde territorio liban\u00e9s&#187;, dijeron las FDI, y agregaron que Israel sigue comprometido a cumplir con las condiciones del acuerdo de alto el fuego.<\/p>\n<p>Tanto los gobiernos de Estados Unidos como de Francia advirtieron a Israel que creen que las FDI han violado los t\u00e9rminos del alto el fuego, seg\u00fan la afiliada de CNN Kan y el medio de comunicaci\u00f3n israel\u00ed Ynet.<\/p>\n<p>Una fuente con la fuerza de paz de las Naciones Unidas en L\u00edbano, UNIFIL, dice que Israel ha incumplido su acuerdo de alto el fuego con L\u00edbano \u201caproximadamente 100\u201d veces desde que la tregua entr\u00f3 en vigor la semana pasada. CNN solicit\u00f3 comentarios a las FDI.<\/p>\n<p>Israel ha violado el acuerdo de alto el fuego en L\u00edbano unas 100 veces, seg\u00fan fuente de paz de la ONU<\/p>\n<p>El ministro de Relaciones Exteriores de Israel, Gideon Sa\u2019ar, le dijo a su hom\u00f3logo franc\u00e9s en una llamada telef\u00f3nica que su pa\u00eds, de hecho, est\u00e1 haciendo cumplir el alto el fuego, que estipula la retirada de Hezbollah del \u00e1rea fronteriza entre Israel y L\u00edbano, en lugar de violarlo, dijo Sa\u2019ar en X este lunes.<\/p>\n<p>\u201cLa presencia de operativos de Hezbollah al sur del (r\u00edo) Litani (en L\u00edbano) es una violaci\u00f3n fundamental del acuerdo y deben moverse hacia el norte\u201d, dijo Sa\u2019ar, y agreg\u00f3 que Israel est\u00e1 \u201ccomprometido con la implementaci\u00f3n exitosa de los entendimientos del alto el fuego&#187;.<\/p>\n<p>Hezbollah, en un comunicado, dijo que apunt\u00f3 a posiciones militares israel\u00edes \u201ca la luz de las repetidas violaciones iniciadas por el enemigo israel\u00ed del acuerdo de alto el fuego&#187;. Hezbollah acus\u00f3 a Israel de romper el alto el fuego al \u201cdisparar contra civiles y realizar ataques a\u00e9reos en diferentes partes de L\u00edbano, resultando en el martirio de ciudadanos y heridas a otros, adem\u00e1s de la continua violaci\u00f3n del espacio a\u00e9reo liban\u00e9s por aviones hostiles israel\u00edes que llegan a la capital, Beirut&#187;.<\/p>\n<p>Las FDI dijeron que los dos proyectiles de Hezbollah fueron disparados hacia las Granjas de Shebaa, conocidas en Israel como Har Dov (Monte Dov), que seg\u00fan el derecho internacional se considera territorio sirio ocupado. Israel se apoder\u00f3 de las Granjas de Shebaa, junto con los Altos del Gol\u00e1n, de Siria despu\u00e9s de ser atacado en 1967. Estados Unidos reconoci\u00f3 la soberan\u00eda de Israel sobre los Altos del Gol\u00e1n en 2019.<\/p>\n<p>Un comienzo inestable<\/p>\n<p>Ambas partes, desde las primeras horas del alto el fuego de la semana pasada, se han acusado mutuamente de violaciones, y las crecientes tensiones corren el riesgo de poner en peligro el acuerdo por completo.<\/p>\n<p>Un alto funcionario israel\u00ed dijo el viernes que las fuerzas tienen la intenci\u00f3n de actuar de manera agresiva y unilateral contra cualquier violaci\u00f3n del alto el fuego por parte de Hezbollah.<\/p>\n<p>La acci\u00f3n militar unilateral israel\u00ed para hacer cumplir el alto el fuego no fue consagrada en el acuerdo entre Israel y L\u00edbano, pero Estados Unidos proporcion\u00f3 a Israel una carta separada que ofrec\u00eda garant\u00edas sobre el derecho de Israel a actuar bajo ciertos escenarios, dijeron funcionarios israel\u00edes a CNN previamente.<\/p>\n<p>El portavoz del Departamento de Estado de EE.UU., Matthew Miller, dijo este lunes que el alto el fuego no se ha roto. &#171;En t\u00e9rminos generales&#187;, el alto el fuego &#171;ha sido exitoso&#187;, dijo.<\/p>\n<p>&#171;Obviamente, cuando tienes cualquier alto el fuego, puedes ver violaciones del mismo&#187;, reconoci\u00f3 Miller. Se\u00f1al\u00f3 que Estados Unidos y Francia establecieron un mecanismo &#171;para examinar todos estos informes de violaciones del alto el fuego y tratarlos a trav\u00e9s de los canales que los mecanismos establecieron, y eso es lo que haremos en los pr\u00f3ximos d\u00edas&#187;.<\/p>\n<p>El funcionario del Departamento de Estado no quiso decir si Estados Unidos determin\u00f3 que alguna de las presuntas violaciones eran violaciones, al decir que el trabajo estaba en curso. Tampoco quiso comentar sobre los informes de que el enviado estadounidense Amos Hochstein hab\u00eda planteado violaciones en una carta al gobierno israel\u00ed.<\/p>\n<p>Disminuyen las esperanzas de alto el fuego en Gaza pese a los renovados esfuerzos de EE.UU. tras la tregua del L\u00edbano<\/p>\n<p>El acuerdo de alto el fuego estipula un cese de hostilidades de 60 d\u00edas, que los negociadores han descrito como la base de una tregua duradera. Durante ese tiempo, se espera que los combatientes de Hezbollah se retiren unos 40 kil\u00f3metros de la frontera entre Israel y L\u00edbano, mientras que las fuerzas terrestres israel\u00edes se retiran del territorio liban\u00e9s.<\/p>\n<p>La Resoluci\u00f3n 1701 del Consejo de Seguridad de la ONU, que puso fin a la \u00faltima guerra total entre los dos pa\u00edses en 2006, ha sido la base del acuerdo y las negociaciones se han centrado principalmente en la aplicaci\u00f3n del tratado.<\/p>\n<p>Seg\u00fan el acuerdo, L\u00edbano implementar\u00eda una supervisi\u00f3n m\u00e1s rigurosa de los movimientos de Hezbollah al sur del r\u00edo Litani del pa\u00eds, para evitar que los militantes se reagrupen all\u00ed.<\/p>\n<p>Los soldados de mantenimiento de la paz de las Naciones Unidas, el ej\u00e9rcito liban\u00e9s y un comit\u00e9 multinacional ser\u00e1n los encargados de supervisar los movimientos del grupo respaldado por Ir\u00e1n.<\/p>\n<p>Jennifer Hansler de CNN contribuy\u00f3 a este reporte<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Por primera vez desde que se implement\u00f3 un alto el fuego la semana pasada, Hezbollah dispar\u00f3 dos proyectiles hacia territorio ocupado por Israel, respondiendo a repetidos ataques israel\u00edes desde el acuerdo. Israel ha ejecutado ataques diarios en el L\u00edbano desde el jueves, el d\u00eda despu\u00e9s de que entr\u00f3 en vigor el alto el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456205","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Por primera vez desde que se implement\u00f3 un alto el fuego la semana pasada, Hezbollah dispar\u00f3 dos proyectiles hacia territorio ocupado por Israel, respondiendo a repetidos ataques israel\u00edes desde el acuerdo. Israel ha ejecutado ataques diarios en el L\u00edbano desde el jueves, el d\u00eda despu\u00e9s de que entr\u00f3 en vigor el alto el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-03T00:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego\",\"datePublished\":\"2024-12-03T00:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/\"},\"wordCount\":1377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/\",\"name\":\"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-03T00:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego - Noticias","og_description":"(CNN) &#8212; Por primera vez desde que se implement\u00f3 un alto el fuego la semana pasada, Hezbollah dispar\u00f3 dos proyectiles hacia territorio ocupado por Israel, respondiendo a repetidos ataques israel\u00edes desde el acuerdo. Israel ha ejecutado ataques diarios en el L\u00edbano desde el jueves, el d\u00eda despu\u00e9s de que entr\u00f3 en vigor el alto el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-03T00:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/"},"author":{"name":"","@id":""},"headline":"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego","datePublished":"2024-12-03T00:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/"},"wordCount":1377,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/","name":"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-03T00:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Despu\u00e9s de d\u00edas de ataques israel\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/02\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-03T00:03:53Z","datePublished":"2024-12-03T00:03:53Z","dateModified":"2024-12-03T00:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Despu\\u00e9s de d\\u00edas de ataques israel\\u00edes, Hezbollah responde y se acusan mutuamente de violaciones del alto el fuego\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/02\\\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/02\\\/ataques-israelies-hezbollah-acusan-violaciones-alto-el-fuego-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-03T00:03:53Z\",\"datePublished\":\"2024-12-03T00:03:53Z\",\"dateModified\":\"2024-12-03T00:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456222,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/03\/israel-amenaza-atacar-estado-libano-alto-fuego-hezbollah-trax\/","url_meta":{"origin":1456205,"position":0},"title":"Israel amenaza con atacar al Estado liban\u00e9s si fracasa alto el fuego con Hezbollah","author":"","date":"diciembre 3, 2024","format":false,"excerpt":"(CNN) -- El d\u00eda despu\u00e9s de que Hezbollah e Israel intercambiaran disparos por primera vez desde que se implement\u00f3 un alto el fuego la semana pasada, el ministro de Defensa de Israel present\u00f3 un ultim\u00e1tum al L\u00edbano, advirtiendo que si el acuerdo fracasa, Israel atacar\u00eda al estado liban\u00e9s, no solo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452163,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/08\/26\/israel-lanza-ataques-preventivos-libano-mientras-hezbollah-cientos-cohetes-trax\/","url_meta":{"origin":1456205,"position":1},"title":"Israel lanza ataques preventivos en L\u00edbano mientras Hezbollah responde con cientos de cohetes","author":"","date":"agosto 26, 2024","format":false,"excerpt":"(CNN) -- El Ej\u00e9rcito israel\u00ed dijo que unos 100 de sus aviones de combate \u201catacaron y destruyeron miles de ca\u00f1ones lanzacohetes de Hezbollah \u201d en decenas de sitios de lanzamiento desde el L\u00edbano este domingo.Israel dijo que lanz\u00f3 lo que llam\u00f3 ataques preventivos contra \u201cobjetivos terroristas en el L\u00edbano\u201d despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460269,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/22\/israel-ataca-hezbollah-libano-trax\/","url_meta":{"origin":1456205,"position":2},"title":"Israel ataca a Hezbollah en el sur del L\u00edbano en el mayor aumento de tensiones desde el alto el fuego","author":"","date":"marzo 22, 2025","format":false,"excerpt":"La Fuerza A\u00e9rea Israel\u00ed dice que atac\u00f3 objetivos de Hezbollah en el sur del L\u00edbano en respuesta a fuego de cohetes transfronterizo en el brote de tensiones m\u00e1s significativo desde que un alto el fuego introdujo una tensa calma a la regi\u00f3n.Informes de testigos desde el sur del L\u00edbano describieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456143,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/28\/israel-y-libano-acusaciones-violaciones-alto-el-fuego-trax\/","url_meta":{"origin":1456205,"position":3},"title":"Intercambian acusaciones de violaciones del alto el fuego en el L\u00edbano; esto es lo que se sabe sobre la fr\u00e1gil tregua","author":"","date":"noviembre 28, 2024","format":false,"excerpt":"(CNN) -- El acuerdo de alto el fuego entre Israel y Hezbollah en el L\u00edbano parece mantenerse en gran medida, a pesar de las acusaciones de violaciones desde ambos lados de la frontera.El presidente de Estados Unidos, Joe Biden, dijo que el acuerdo que entr\u00f3 en vigor la madrugada del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458063,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/31\/israel-ataca-libano-despues-del-alto-el-fuego-trax\/","url_meta":{"origin":1456205,"position":4},"title":"Las fuerzas de Israel atacan profundamente en el L\u00edbano, d\u00edas despu\u00e9s de la pr\u00f3rroga del cese del fuego","author":"","date":"enero 31, 2025","format":false,"excerpt":"Las Fuerzas de Defensa de Israel (FDI) afirman haber atacado varios objetivos de Hezbollah en el valle liban\u00e9s de la Bekaa, en el interior del pa\u00eds, pocos d\u00edas despu\u00e9s de prorrogar el alto el fuego con L\u00edbano.Las fuerzas afirman que los objetivos \u201cincluyen un emplazamiento terrorista de Hezbollah que contiene\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460678,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/01\/ataque-israeli-mata-beirut-fragil-alto-fuego-hezbollah-trax\/","url_meta":{"origin":1456205,"position":5},"title":"Ataque israel\u00ed deja tres muertos en Beirut, poniendo a prueba el fr\u00e1gil alto el fuego con Hezbollah","author":"","date":"abril 1, 2025","format":false,"excerpt":"Israel lanz\u00f3 un ataque sobre Beirut por segunda vez en d\u00edas, poniendo a prueba a\u00fan m\u00e1s el precario alto el fuego con Hezbollah alcanzado hace cuatro meses.El Ministerio de Salud del L\u00edbano dijo que tres personas murieron, incluida una mujer, y siete resultaron heridas en el ataque ocurrido la madrugada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456205"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456205\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}