{"id":1456232,"date":"2024-12-03T17:03:42","date_gmt":"2024-12-04T01:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/"},"modified":"2024-12-03T17:03:42","modified_gmt":"2024-12-04T01:03:42","slug":"polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/","title":{"rendered":"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 Una encendida pol\u00e9mica se ha desatado en Per\u00fa en torno a la dise\u00f1adora peruana Anis Samanez tras las declaraciones que realiz\u00f3 el jueves 28 de noviembre en Or\u00edgenes 2024, un evento celebrado en Lima con el fin de promover la innovaci\u00f3n y el dise\u00f1o en la industria de la moda.<\/p>\n<p>En el encuentro, la modista le cont\u00f3 al p\u00fablico asistente que estuvo en contacto con integrantes de la naci\u00f3n shipibo-konibo, uno de los grupos \u00e9tnicos m\u00e1s representativos y numerosos de la Amazonia peruana, para trabajar en una colaboraci\u00f3n con la comunidad.<\/p>\n<p>Apropiaci\u00f3n cultural: qu\u00e9 es y por qu\u00e9 es tan controversial<\/p>\n<p>En un video que recoge las declaraciones de Samanez y que se ha vuelto viral, la dise\u00f1adora hace el recuento de la propuesta que le hizo a los shipibo-konibo. \u201cQue ustedes (la comunidad) me ense\u00f1en un poco m\u00e1s de su cultura y yo les puedo ense\u00f1ar a cambio mi experiencia en el dise\u00f1o, de frente me dijeron &#8216;no&#8217;, me quer\u00edan cobrar, ni les cuento cu\u00e1nto me quer\u00edan cobrar\u2026\u201d, se\u00f1ala, para luego agregar: \u201cYo tambi\u00e9n soy peruana, que yo haya nacido en la costa no significa que sea menos peruana que ellos\u201d.<\/p>\n<p>Poco despu\u00e9s, dentro de la presentaci\u00f3n de Samanez en Or\u00edgenes, intervino Jos\u00e9 Forteza, editor de la revista Vogue en M\u00e9xico, quien argument\u00f3 que \u201cpatrimonio de la humanidad significa lo que es de todos\u201d.<\/p>\n<p>El arte ken\u00e9 es reconocido por el Gobierno peruano como una expresi\u00f3n representativa de la naci\u00f3n shipibo-konibo y est\u00e1 compuesto de una serie de conceptos y patrones de dise\u00f1o espec\u00edficos, lo que lo convierte en un arte muy apreciado debido a su complejidad y belleza.<\/p>\n<p>Las declaraciones de Samanez se viralizaron y convirtieron a la dise\u00f1adora en blanco de duras cr\u00edticas, al punto de que restringi\u00f3 la interacci\u00f3n con los usuarios de sus redes sociales, muchos de los cuales la acusaban de un supuesto intento de apropiaci\u00f3n cultural y le reprochaban su negativa a remunerar debidamente a los artesanos de la comunidad.<\/p>\n<p>En respuesta a las expresiones de Samanez y Forteza en Or\u00edgenes 2024, la reconocida artista y l\u00edder shipibo-konibo Olinda Silvano, en declaraciones a radio Exitosa, critic\u00f3 los comentarios de la dise\u00f1adora. Se\u00f1al\u00f3 que \u201cno se est\u00e1 valorando nuestro trabajo. Tenemos que hacer respetar nuestro arte amaz\u00f3nico, nuestro ken\u00e9\u201d.<\/p>\n<p>Tambi\u00e9n dijo que este arte es una fuente de ingresos para las familias shipibo-konibo. \u201cNosotros hacemos con nuestra propia mano, lo bordamos, hacemos el ken\u00e9 con fibras naturales\u201d. Una manta bordada, puntualiz\u00f3, puede ser confeccionada en entre tres y ocho meses, apuntando que no se valora el trabajo de los artesanos. CNN ha intentado ponerse en contacto con la artista y se encuentra a la espera de respuesta.<\/p>\n<p>AN\u00c1LISIS | Supremacismo blanco, pero con un bronceado<\/p>\n<p>Al respecto, el Ministerio de Cultura de Per\u00fa difundi\u00f3 un comunicado en el que rechaza las expresiones de Samanez y Forteza en Or\u00edgenes 2024, por considerar que van \u201ccontra el valor cultural e identitario de los conocimientos tradicionales\u201d de los shipibo-konibo.<\/p>\n<p>Adem\u00e1s, resalta el valor del arte ken\u00e9 como \u201cuna de las principales manifestaciones culturales de la identidad, cosmovisi\u00f3n y est\u00e9tica\u201d de la comunidad, reconocido como patrimonio cultural de la Naci\u00f3n en 2008.<\/p>\n<p>Este lunes, Samanez public\u00f3 un comunicado en su cuenta de Instagram donde se disculp\u00f3 por sus declaraciones. \u201cReconozco que me expres\u00e9 con ligereza acerca de manifestaciones que forman parte de nuestra construcci\u00f3n cultural y que son esenciales para nuestra identidad como pa\u00eds\u201d, afirma en la publicaci\u00f3n. Finalmente, tras subrayar el \u201cerror\u201d de sus palabras y asegurar que de su parte \u201cen ning\u00fan momento hubo mala intenci\u00f3n ni tampoco la voluntad de faltar el respeto hacia las tradiciones y comunidades\u201d, Samanez concluye que \u201cel video circulado lamentablemente no se muestra completo. Yo estaba contando mi primera aproximaci\u00f3n a la comunidad a\u00f1os atr\u00e1s, cuando desconoc\u00eda el medio. Luego de lo cual he construido una relaci\u00f3n de mucho aprendizaje y respeto con valiosas artesanas peruanas\u201d.<\/p>\n<p>Por su parte, Forteza, de Vogue, tambi\u00e9n en un comunicado en sus redes sociales, se sum\u00f3 a las disculpas expresadas por Samanez, y se\u00f1al\u00f3 que nunca tuvo intenci\u00f3n de \u201cirrespetar\u201d a nadie y que no tuvo la intenci\u00f3n de minimizar la experiencia y riqueza cultural de los pueblos originarios y las comunidades artesanas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 Una encendida pol\u00e9mica se ha desatado en Per\u00fa en torno a la dise\u00f1adora peruana Anis Samanez tras las declaraciones que realiz\u00f3 el jueves 28 de noviembre en Or\u00edgenes 2024, un evento celebrado en Lima con el fin de promover la innovaci\u00f3n y el dise\u00f1o en la industria de la moda. En el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456232","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2013\u2013 Una encendida pol\u00e9mica se ha desatado en Per\u00fa en torno a la dise\u00f1adora peruana Anis Samanez tras las declaraciones que realiz\u00f3 el jueves 28 de noviembre en Or\u00edgenes 2024, un evento celebrado en Lima con el fin de promover la innovaci\u00f3n y el dise\u00f1o en la industria de la moda. En el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-04T01:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda\",\"datePublished\":\"2024-12-04T01:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/\"},\"wordCount\":785,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/\",\"name\":\"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-04T01:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda - Noticias","og_description":"(CNN Espa\u00f1ol) \u2013\u2013 Una encendida pol\u00e9mica se ha desatado en Per\u00fa en torno a la dise\u00f1adora peruana Anis Samanez tras las declaraciones que realiz\u00f3 el jueves 28 de noviembre en Or\u00edgenes 2024, un evento celebrado en Lima con el fin de promover la innovaci\u00f3n y el dise\u00f1o en la industria de la moda. En el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-04T01:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/"},"author":{"name":"","@id":""},"headline":"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda","datePublished":"2024-12-04T01:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/"},"wordCount":785,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/","name":"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-04T01:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Pol\u00e9mica en Per\u00fa por acusaciones de apropiaci\u00f3n cultural a dise\u00f1adora de moda","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/03\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-04T01:03:42Z","datePublished":"2024-12-04T01:03:42Z","dateModified":"2024-12-04T01:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Pol\\u00e9mica en Per\\u00fa por acusaciones de apropiaci\\u00f3n cultural a dise\\u00f1adora de moda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/03\\\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/03\\\/polemica-peru-acusaciones-apropiacion-cultural-disenadora-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-04T01:03:42Z\",\"datePublished\":\"2024-12-04T01:03:42Z\",\"dateModified\":\"2024-12-04T01:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448446,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/23\/condenan-disenadora-colombiana-nancy-gonzalez-prision-envio-pieles-orix\/","url_meta":{"origin":1456232,"position":0},"title":"Condenan a la dise\u00f1adora colombiana Nancy Gonz\u00e1lez a 18 meses de prisi\u00f3n por el env\u00edo ilegal de pieles de animales a EE.UU.","author":"","date":"abril 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La dise\u00f1adora Nancy Gonz\u00e1lez de Barberi fue sentenciada este lunes a 18 meses de prisi\u00f3n en Estados Unidos tras declararse culpable en noviembre del a\u00f1o pasado de importar ilegalmente desde Colombia art\u00edculos elaborados en cuero y pieles de especies protegidas, inform\u00f3 el Departamento de Justicia en su p\u00e1gina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465239,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/07\/santa-rosa-peru-colombia-explainer-orix\/","url_meta":{"origin":1456232,"position":1},"title":"Santa Rosa: c\u00f3mo esta peque\u00f1a isla amaz\u00f3nica qued\u00f3 en medio de una controversia diplom\u00e1tica entre Per\u00fa y Colombia","author":"","date":"agosto 7, 2025","format":false,"excerpt":"La peque\u00f1a isla de Santa Rosa, en la Amazon\u00eda, est\u00e1 en el centro de una creciente controversia diplom\u00e1tica entre Per\u00fa y Colombia. Ubicada en el r\u00edo Amazonas, en la zona de la triple frontera con Brasil, la soberan\u00eda de Santa Rosa ha sido recientemente cuestionada por el presidente de Colombia,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470818,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/02\/03\/peru-nuevo-embajador-eeuu-china-orix\/","url_meta":{"origin":1456232,"position":2},"title":"China desplaz\u00f3 a EE.UU. como primer socio comercial de Per\u00fa. El nuevo embajador de Washington busca revertir esa tendencia","author":"","date":"febrero 3, 2026","format":false,"excerpt":"Bernie Navarro, un empresario estrechamente ligado a Per\u00fa, es el nuevo embajador de Estados Unidos en el pa\u00eds sudamericano y este martes present\u00f3 sus credenciales al presidente Jos\u00e9 Jer\u00ed en el Palacio de Gobierno, seg\u00fan inform\u00f3 el propio diplom\u00e1tico en X.Navarro est\u00e1 casado con una peruana y a\u00f1os atr\u00e1s celebr\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460049,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/18\/peru-dina-boluarte-pena-muerte-orix\/","url_meta":{"origin":1456232,"position":3},"title":"Dina Boluarte dice que est\u00e1 pensando &#171;seriamente en la pena de muerte&#187; tras homicidio de cantante de cumbia en Per\u00fa","author":"","date":"marzo 18, 2025","format":false,"excerpt":"La presidenta de Per\u00fa, Dina Boluarte, volvi\u00f3 a hablar este lunes sobre la posibilidad de instaurar la pena de muerte en Per\u00fa para enfrentar la grave situaci\u00f3n de inseguridad que vive el pa\u00eds.Las declaraciones de Boluarte se producen luego de que mataran a tiros a Paul Hambert Flores Garc\u00eda, cantante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457989,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/29\/diseno-nigeriana-moda-cuatridimensional-trax\/","url_meta":{"origin":1456232,"position":4},"title":"Dise\u00f1adora nigeriana causa sensaci\u00f3n con su moda &#171;cuatridimensional&#187;","author":"","date":"enero 29, 2025","format":false,"excerpt":"Es la hermana del legendario futbolista nigeriano Sunday Oliseh, pero ahora Tessy Oliseh-Amaize se est\u00e1 convirtiendo en una celebridad por derecho propio, haci\u00e9ndose un nombre en el mundo de la moda estadounidense.Como fundadora de la marca de moda Tesslo, y antigua estudiante de ciencias, produce una versi\u00f3n distintivamente moderna de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456173,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/29\/congreso-peru-amplia-vigencia-polemica-licencia-mineria-orix\/","url_meta":{"origin":1456232,"position":5},"title":"El Congreso de Per\u00fa ampl\u00eda seis meses la vigencia de pol\u00e9mica licencia de miner\u00eda a peque\u00f1a escala","author":"","date":"noviembre 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Pleno del Congreso de Per\u00fa aprob\u00f3 este viernes una extensi\u00f3n de seis meses para el Registro Integral para la Formalizaci\u00f3n de la peque\u00f1a miner\u00eda y miner\u00eda artesanal (Reinfo), que permite a productores dedicarse a esta actividad a peque\u00f1a escala sin que se considere un delito.La medida,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456232"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456232\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}