{"id":1456233,"date":"2024-12-03T17:03:42","date_gmt":"2024-12-04T01:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/"},"modified":"2024-12-03T17:03:42","modified_gmt":"2024-12-04T01:03:42","slug":"elon-musk-decenas-miles-millones-dolares-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/","title":{"rendered":"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco"},"content":{"rendered":"<p>Nueva York (CNN) &#8212;\u00a0Elon Musk no va a recibir los US$ 101.000 millones que tanto deseaba. Pero sigue estando entre las personas m\u00e1s ricas del planeta y a punto de enriquecerse mucho m\u00e1s en los pr\u00f3ximos a\u00f1os.<\/p>\n<p>La jueza del Tribunal de Equidad de Delaware, Kathaleen McCormick, volvi\u00f3 a desestimar un paquete salarial de 2018 de Tesla que le daba opciones para comprar 304 millones de acciones de la empresa al m\u00f3dico precio de US$ 23,34 por acci\u00f3n, una peque\u00f1a fracci\u00f3n del precio de cotizaci\u00f3n de Tesla de m\u00e1s de US$ 350 por acci\u00f3n el martes.<\/p>\n<p>Escribi\u00f3 que, aunque el 84% de los accionistas distintos de Musk y su hermano Kimbal hab\u00edan vuelto a aprobar el paquete de opciones desde su decisi\u00f3n inicial de desestimarlo en enero, un paquete salarial que dar\u00eda tanta riqueza al CEO de la empresa no era justo para los accionistas y su decisi\u00f3n anterior de rechazarlo sigue en vigor.<\/p>\n<p>El descomunal paquete salarial de Elon Musk en Tesla, valorado en miles de millones de d\u00f3lares, fue bloqueado de nuevo por una jueza<\/p>\n<p>Musk, en respuesta, acus\u00f3 a McCormick de ser &#171;una activista radical de extrema izquierda disfrazada de jueza&#187;.<\/p>\n<p>Pero no hace falta crear una p\u00e1gina de GoFundMe para Musk. Sigue siendo una de las personas m\u00e1s ricas del planeta, si no la m\u00e1s rica, incluso con la p\u00e9rdida de un paquete salarial de 12 cifras. Hay muchas formas en las que Musk puede acumular mucha m\u00e1s riqueza en los pr\u00f3ximos meses y a\u00f1os, incluso si no consigue impugnar la decisi\u00f3n judicial.<\/p>\n<p>Obtener un paquete salarial menor<\/p>\n<p>Musk podr\u00eda simplemente enriquecerse un poco menos.<\/p>\n<p>Con el paquete desechado, Musk esencialmente no ha cobrado desde que la \u00faltima de las opciones sobre acciones que se le concedieron en un paquete salarial de 2012 se deveng\u00f3 en 2018. Musk no recibe ning\u00fan salario en efectivo u otros bonos, solo opciones sobre acciones, como compensaci\u00f3n. Pero el aumento del valor de esas acciones y opciones ha catapultado el patrimonio neto de Musk de unos US$ 20.000 millones en 2018 a m\u00e1s de una docena de veces esa cantidad, incluso sin el paquete de 2018.<\/p>\n<p>Musk y Ramaswamy, estudian c\u00f3mo reducir el gasto del gobierno en la futura administraci\u00f3n Trump<\/p>\n<p>Los abogados de Tesla hab\u00edan argumentado que no era correcto que no se le pagara nada en absoluto debido a que el paquete de opciones hab\u00eda sido anulado por la jueza. Y dijeron que era importante para el futuro de la empresa que se motivara a Musk a permanecer centrado en la empresa con todos sus otros intereses dado que tambi\u00e9n es el CEO o principal accionista de la empresa de cohetes SpaceX, la plataforma de redes sociales X, la empresa de inteligencia artificial xAI, as\u00ed como la empresa de neurotecnolog\u00eda Neuralink, y la empresa de excavaci\u00f3n y construcci\u00f3n de t\u00faneles The Boring Company.<\/p>\n<p>Si a eso le sumamos su nuevo papel como asesor cercano del presidente electo Donald Trump y codirector de un esfuerzo para recortar el despilfarro del gobierno federal, est\u00e1 claro que tiene mucho que hacer adem\u00e1s de prestar atenci\u00f3n a una empresa que no le est\u00e1 pagando nada.<\/p>\n<p>Elon Musk habla con el presidente electo de EE.UU. Donald Trump e invitados durante el lanzamiento del sexto vuelo de prueba del cohete SpaceX Starship el 19 de noviembre de 2024. Cr\u00e9dito: Brandon Bell\/Getty Images<\/p>\n<p>Tambi\u00e9n publica prol\u00edficamente sus pensamientos en X, a menudo m\u00e1s de 100 veces al d\u00eda, y afirma estar entre los mejores jugadores de un videojuego a nivel mundial.<\/p>\n<p>Pero McCormick escribi\u00f3 en su decisi\u00f3n del lunes que no se opone a que Musk reciba alg\u00fan tipo de compensaci\u00f3n, solo que no una tan masiva como los 304 millones de opciones sobre acciones.<\/p>\n<p>&#171;El tribunal no consider\u00f3 que la junta no deber\u00eda haber pagado nada a Musk. Sin duda, hab\u00eda una serie de cantidades saludables que la junta podr\u00eda haber decidido pagar a Musk&#187;, escribi\u00f3.<\/p>\n<p>Elon Musk es m\u00e1s rico que nunca. Ahora su fortuna es de casi US$ 350.000 millones<\/p>\n<p>Obtener un nuevo paquete salarial<\/p>\n<p>En lugar de conformarse con algo menos, Musk podr\u00eda negociar un paquete salarial completamente nuevo a partir de este a\u00f1o.<\/p>\n<p>Incluso antes de las decisiones en contra de su paquete salarial de 2018, Musk hab\u00eda estado hablando de su deseo de un nuevo paquete salarial que le diera a\u00fan m\u00e1s control sobre Tesla. Los 411 millones de acciones de Tesla que posee actualmente le dan el control de alrededor del 13% de la empresa.<\/p>\n<p>Con los 304 millones de acciones adicionales, controlar\u00eda algo m\u00e1s del 20%.<\/p>\n<p>Pero ni siquiera eso ser\u00eda suficiente para Musk. En enero, justo antes de la decisi\u00f3n de McCormick que invalidaba el paquete salarial, escribi\u00f3 que no querr\u00eda hacer crecer Tesla para convertirla en l\u00edder en inteligencia artificial y rob\u00f3tica, \u00e1reas en las que prometi\u00f3 crecimiento, sin un plan de compensaci\u00f3n que le diera la propiedad de alrededor del 25% de la empresa.<\/p>\n<p>\u00bfQu\u00e9 porcentaje de la riqueza de Musk proviene de impuestos y ayuda del Gobierno?<\/p>\n<p>Eso ser\u00eda aproximadamente el doble de la participaci\u00f3n de aproximadamente el 13% que posee actualmente, sin esas opciones de 2018.<\/p>\n<p>&#171;Me siento inc\u00f3modo haciendo crecer Tesla para que sea un l\u00edder en IA y rob\u00f3tica sin tener ~25% de control de voto. Suficiente para ser influyente, pero no tanto como para que no pueda ser derrocado&#187;, tuite\u00f3 Musk en enero. &#171;A menos que ese sea el caso, preferir\u00eda construir productos fuera de Tesla&#187;.<\/p>\n<p>La gente pasa por delante de una tienda de Tesla en el Meatpacking District de Manhattan, el viernes 22 de noviembre de 2024, en Nueva York. Cr\u00e9dito: Julia Demaree Nikhinson\/AP<\/p>\n<p>Podr\u00eda parecer que un nuevo paquete salarial se encontrar\u00eda con los mismos problemas con los tribunales de Delaware. Pero a principios de este a\u00f1o los accionistas de Tesla aprobaron cambiar el estado de constituci\u00f3n de Tesla de Delaware a Texas. As\u00ed que los tribunales de Delaware no tendr\u00edan autoridad sobre cualquier futuro paquete salarial.<\/p>\n<p>Enriquecerse con otras empresas<\/p>\n<p>Los 411 millones de acciones que ya posee directamente ten\u00edan un valor de US$ 147.000 millones al cierre del lunes, lo que ayuda tanto a Bloomberg como a Forbes a situar su patrimonio neto por encima de los US$ 330.000 millones.<\/p>\n<p>Aunque esto incluye cierta valoraci\u00f3n por las opciones ahora rechazadas, es al menos el segundo hombre m\u00e1s rico sin las opciones, solo por detr\u00e1s del fundador de Amazon, Jeff Bezos, y quiz\u00e1 ligeramente por delante de Bezos, dependiendo de la estimaci\u00f3n que se utilice.<\/p>\n<p>Gran parte del resto de su riqueza procede de sus participaciones en SpaceX, que es la empresa privada m\u00e1s valiosa. Bloomberg estima que posee el 42% de SpaceX, lo que a\u00f1ade US$ 88.000 millones a su patrimonio neto. Bloomberg tambi\u00e9n inform\u00f3 el lunes de que SpaceX est\u00e1 planeando poner a la venta acciones que ahora est\u00e1n en manos de inversores privados, a un precio que aumentar\u00eda el valor de la empresa a US$ 350.000 millones. Eso elevar\u00eda el valor de su participaci\u00f3n a US$ 147.000 millones.<\/p>\n<p>Sus otras empresas tienen valoraciones relativamente modestas, pero siguen siendo sustanciales. Forbes calcula que xAI vale US$ 50.000 millones y que \u00e9l posee el 54% de sus acciones, es decir, US$ 27.000 millones de su capital privado. Pero la inteligencia artificial ha sido un sector importante para los inversores en el \u00faltimo a\u00f1o, y tambi\u00e9n podr\u00eda ver incrementada su valoraci\u00f3n en el futuro.<\/p>\n<p>Elon Musk muestra &#171;Cortex&#187;, el coraz\u00f3n de Inteligencia Artificial en la sede de Austin de Tesla<\/p>\n<p>Enriquecerse si Tesla aumenta su valor<\/p>\n<p>No todos los que figuran en la lista de las personas m\u00e1s ricas han llegado ah\u00ed gracias a sus crecientes paquetes de opciones sobre acciones.<\/p>\n<p>Por ejemplo, Bezos y Mark Zuckerberg, cofundador de Facebook, tomaron grandes participaciones en sus empresas como fundadores, pero ninguno ha recibido subvenciones de acciones u opciones desde que esas empresas tuvieron ofertas p\u00fablicas iniciales en 1997 y 2012, respectivamente.<\/p>\n<p>Las acciones de Tesla se han disparado un 42% en las cuatro semanas transcurridas desde el d\u00eda de las elecciones, ya que los inversores apuestan a que el presidente electo Trump seguir\u00e1 pol\u00edticas que ayudar\u00e1n a su &#171;primer colega&#187;. Solo esa subida de las acciones de Tesla ha elevado el valor de sus 411 millones de acciones en US$ 43.400 millones.<\/p>\n<p>Elon Musk asiste a la gala del America First Policy Institute en Mar-A-Lago en Palm Beach, Florida, el 14 de noviembre de 2024. Cr\u00e9dito: Carlos Barria\/Reuters<\/p>\n<p>Pero eso es apenas una peque\u00f1a fracci\u00f3n de las ganancias potenciales de las acciones de Tesla en los pr\u00f3ximos a\u00f1os.<\/p>\n<p>Si las acciones de la empresa van tan bien como Musk y sus seguidores predicen, sus participaciones actuales se revalorizar\u00edan tanto que el valor actual del paquete salarial que acaba de perder parecer\u00eda algo secundario.<\/p>\n<p>Ark Invest tiene un precio objetivo a cinco a\u00f1os para las acciones de Tesla de US$ 2.600 por acci\u00f3n. Eso supondr\u00eda una ganancia de m\u00e1s del 600% respecto a su valor actual, algo que elevar\u00eda su capitalizaci\u00f3n burs\u00e1til total a unos US$ 8 billones, o m\u00e1s que los valores actuales de Microsoft y Apple, juntos, en 2029.<\/p>\n<p>Musk dijo a los inversores en la reuni\u00f3n anual de la empresa que cree que las estimaciones de Ark son realistas, ya que, seg\u00fan \u00e9l, los planes de la empresa de poner en marcha autom\u00f3viles y taxis con conducci\u00f3n aut\u00f3noma real, as\u00ed como robots, en el pr\u00f3ximo a\u00f1o supondr\u00e1n un enorme aumento de los beneficios.<\/p>\n<p>Por otra parte, incluso Musk ha dicho que sus propias predicciones han sido demasiado optimistas, como cuando predijo por primera vez que sus autom\u00f3viles ser\u00edan capaces de conducirse solos por todo el pa\u00eds para finales de 2017.<\/p>\n<p>En el momento de escribir estas l\u00edneas, ning\u00fan Tesla disponible para los compradores de autom\u00f3viles es capaz de funcionar sin un conductor humano al volante.<\/p>\n<p>Aun as\u00ed, si la visi\u00f3n de Musk se hace realidad y las acciones de Tesla alcanzan ese precio objetivo de US$ 2.600, sus 411 millones de acciones actuales valdr\u00edan US$ 1 bill\u00f3n, lo que lo convertir\u00eda en el primer billonario del mundo, incluso sin m\u00e1s ganancias de SpaceX o xAI o de sus otras participaciones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva York (CNN) &#8212;\u00a0Elon Musk no va a recibir los US$ 101.000 millones que tanto deseaba. Pero sigue estando entre las personas m\u00e1s ricas del planeta y a punto de enriquecerse mucho m\u00e1s en los pr\u00f3ximos a\u00f1os. La jueza del Tribunal de Equidad de Delaware, Kathaleen McCormick, volvi\u00f3 a desestimar un paquete salarial de 2018 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456233","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nueva York (CNN) &#8212;\u00a0Elon Musk no va a recibir los US$ 101.000 millones que tanto deseaba. Pero sigue estando entre las personas m\u00e1s ricas del planeta y a punto de enriquecerse mucho m\u00e1s en los pr\u00f3ximos a\u00f1os. La jueza del Tribunal de Equidad de Delaware, Kathaleen McCormick, volvi\u00f3 a desestimar un paquete salarial de 2018 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-04T01:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco\",\"datePublished\":\"2024-12-04T01:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/\"},\"wordCount\":1808,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/\",\"name\":\"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-04T01:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco - Noticias","og_description":"Nueva York (CNN) &#8212;\u00a0Elon Musk no va a recibir los US$ 101.000 millones que tanto deseaba. Pero sigue estando entre las personas m\u00e1s ricas del planeta y a punto de enriquecerse mucho m\u00e1s en los pr\u00f3ximos a\u00f1os. La jueza del Tribunal de Equidad de Delaware, Kathaleen McCormick, volvi\u00f3 a desestimar un paquete salarial de 2018 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-04T01:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/"},"author":{"name":"","@id":""},"headline":"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco","datePublished":"2024-12-04T01:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/"},"wordCount":1808,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/","name":"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-04T01:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Elon Musk podr\u00eda embolsarse decenas de miles de millones de d\u00f3lares m\u00e1s. Pero quiz\u00e1 tenga que esperar un poco","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/03\/elon-musk-decenas-miles-millones-dolares-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-04T01:03:42Z","datePublished":"2024-12-04T01:03:42Z","dateModified":"2024-12-04T01:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Elon Musk podr\\u00eda embolsarse decenas de miles de millones de d\\u00f3lares m\\u00e1s. Pero quiz\\u00e1 tenga que esperar un poco\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/03\\\/elon-musk-decenas-miles-millones-dolares-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/03\\\/elon-musk-decenas-miles-millones-dolares-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-04T01:03:42Z\",\"datePublished\":\"2024-12-04T01:03:42Z\",\"dateModified\":\"2024-12-04T01:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465108,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/04\/elon-musk-paquete-salarial-ususd-29-000-millones-tesla-trax\/","url_meta":{"origin":1456233,"position":0},"title":"Elon Musk recibe paquete salarial de US$ 29.000 millones de Tesla","author":"","date":"agosto 4, 2025","format":false,"excerpt":"La junta directiva de Tesla le otorgar\u00e1 al CEO, Elon Musk, otro gigantesco paquete salarial.El nuevo paquete, valorado en unos US$ 29.000 millones, llega varios meses despu\u00e9s de que un tribunal de Delaware rechazara por segunda vez la compensaci\u00f3n por desempe\u00f1o otorgada a Musk en 2018, tras una demanda de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456211,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/02\/paquete-salarial-descomunal-elon-musk-bloqueado-jueza-trax\/","url_meta":{"origin":1456233,"position":1},"title":"El descomunal paquete salarial de Elon Musk en Tesla, valorado en miles de millones de d\u00f3lares, fue bloqueado de nuevo por una jueza","author":"","date":"diciembre 2, 2024","format":false,"excerpt":"(CNN) -- El paquete salarial r\u00e9cord de Elon Musk por servir como CEO de Tesla fue rechazado el lunes por un tribunal de Delaware, a pesar de haber sido aprobado por los accionistas de Tesla en una reuni\u00f3n celebrada en junio.El paquete salarial, valorado ahora en US$ 56.000 millones, se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469438,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/12\/19\/elon-musk-recupera-salario-millones-dolares-trax\/","url_meta":{"origin":1456233,"position":2},"title":"Elon Musk recupera su salario de US$ 139.000 millones de 2018 tras una batalla de un a\u00f1o con una jueza de Delaware","author":"","date":"diciembre 19, 2025","format":false,"excerpt":"La Corte Suprema de Delaware ha restaurado un enorme paquete salarial otorgado al CEO de Tesla, Elon Musk, en 2018, que hab\u00eda sido anulado dos veces por un juez de un tribunal inferior.El paquete otorg\u00f3 a Musk la opci\u00f3n de comprar 303 millones de acciones ajustadas por divisi\u00f3n, con un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466178,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/09\/05\/tesla-paquete-salarial-elon-musk-billonario-trax\/","url_meta":{"origin":1456233,"position":3},"title":"Tesla propone un incentivo para Elon Musk que podr\u00eda convertirlo en el primer billonario del mundo","author":"","date":"septiembre 5, 2025","format":false,"excerpt":"Elon Musk podr\u00eda convertirse en el primer billonario del mundo si los accionistas adoptan una nueva propuesta que le dar\u00eda sumas de dinero sin precedentes en caso de que la compa\u00f1\u00eda alcance ciertos hitos ambiciosos.El paquete salarial podr\u00eda otorgarle a Musk 423,7 millones de acciones adicionales de Tesla. Estas acciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467678,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/10\/23\/musk-control-tesla-billon-trax\/","url_meta":{"origin":1456233,"position":4},"title":"Elon Musk afirm\u00f3 que necesita US$ 1 bill\u00f3n para impedir que &#171;terroristas corporativos&#187; tomen el control de Tesla","author":"","date":"octubre 23, 2025","format":false,"excerpt":"Elon Musk afirma que necesita aumentar su participaci\u00f3n en Tesla lo suficiente como para convertirse en el primer billonario del mundo. Pero esta semana declar\u00f3 que su objetivo no era aumentar su riqueza, que ya es la mayor del planeta. En cambio, Musk afirm\u00f3 que el mayor paquete salarial de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468102,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/11\/06\/tesla-1-billon-musk-convertirlo-billonario-trax\/","url_meta":{"origin":1456233,"position":5},"title":"Accionistas de Tesla aprueban el paquete salarial de US$ 1 bill\u00f3n de Musk, lo que podr\u00eda convertirlo en el primer billonario","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"Los accionistas de Tesla aprobaron este jueves un paquete de compensaci\u00f3n que podr\u00eda convertir al CEO Elon Musk, ya el hombre m\u00e1s rico del mundo, en el primer billonario del mundo.Tesla anunci\u00f3 que m\u00e1s del 75 % de los due\u00f1os de las acciones votaron a favor del paquete salarial durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456233"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456233\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}