{"id":1456261,"date":"2024-12-04T15:03:38","date_gmt":"2024-12-04T23:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/"},"modified":"2024-12-04T15:03:38","modified_gmt":"2024-12-04T23:03:38","slug":"trump-nombra-atkins-sec-slater-antimonopolio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/","title":{"rendered":"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores"},"content":{"rendered":"<p>Las comunidades de criptomonedas y tecnolog\u00eda finalmente tienen algo de claridad sobre a qui\u00e9n responder\u00e1n potencialmente durante los pr\u00f3ximos cuatro a\u00f1os.<\/p>\n<p>En el \u00e1mbito de las criptomonedas, el presidente electo de EE.UU. Donald Trump planea designar a Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s). Se espera que regule las criptomonedas como el bitcoin con m\u00e1s sutileza que Gary Gensler, quien dirigi\u00f3 la comisi\u00f3n durante la administraci\u00f3n de Biden.<\/p>\n<p>Atkins se desempe\u00f1\u00f3 como copresidente del grupo de defensa de las criptomonedas Digital Chamber\u2019s Token Alliance desde 2017.<\/p>\n<p>\u201cPaul es un l\u00edder probado en materia de regulaciones con sentido com\u00fan\u201d, public\u00f3 Trump en Truth Social. \u201cCree en la promesa de unos mercados de capitales robustos e innovadores que respondan a las necesidades de los inversores y que proporcionen capital para hacer de nuestra econom\u00eda la mejor del mundo. Tambi\u00e9n reconoce que los activos digitales y otras innovaciones son cruciales para hacer de Estados Unidos un pa\u00eds mejor que nunca\u201d.<\/p>\n<p>En el frente tecnol\u00f3gico, Trump tiene la intenci\u00f3n de designar a Gail Slater, exejecutiva de Fox Corporation y asesora de pol\u00edtica econ\u00f3mica durante la primera administraci\u00f3n de Trump, para dirigir la divisi\u00f3n antimonopolio del Departamento de Justicia como secretaria de Justicia adjunta.<\/p>\n<p>Trump anunci\u00f3 su intenci\u00f3n de postular a Slater el mi\u00e9rcoles en una publicaci\u00f3n en Truth Social, en la que destac\u00f3 su expectativa de que el Departamento de Justicia contin\u00fae procesando a las grandes plataformas tecnol\u00f3gicas por presuntos abusos de la competencia.<\/p>\n<p>\u201cLas grandes tecnol\u00f3gicas se han descontrolado durante a\u00f1os\u201d, escribi\u00f3 Trump, \u201csofocando la competencia en nuestro sector m\u00e1s innovador y, como todos sabemos, utilizando su poder de mercado para acabar con los derechos de tantos estadounidenses, as\u00ed como los de las peque\u00f1as tecnol\u00f3gicas\u201d.<\/p>\n<p>Trump ha criticado durante mucho tiempo a la industria tecnol\u00f3gica. Durante su primer mandato, el Departamento de Justicia de Trump demand\u00f3 a Google por monopolizar el mercado de b\u00fasquedas en l\u00ednea, un caso que el Gobierno de Biden complet\u00f3 y que result\u00f3 este a\u00f1o en el fallo antimonopolio m\u00e1s importante contra un gigante tecnol\u00f3gico en una generaci\u00f3n.<\/p>\n<p>Ahora, quiere que una veterana miembro de Washington siga ejerciendo presi\u00f3n. Slater no respondi\u00f3 de inmediato a una solicitud de comentarios.<\/p>\n<p>Slater tiene una larga trayectoria en materia de pol\u00edticas tecnol\u00f3gicas. Ex asesora legal de la Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s), Slater ha manejado investigaciones antimonopolio que involucraban a las industrias tecnol\u00f3gica y farmac\u00e9utica. En ese momento, Slater trabajaba bajo la direcci\u00f3n de la comisionada dem\u00f3crata de la FTC, Julie Brill.<\/p>\n<p>En 2018, Slater visit\u00f3 la Casa Blanca de Trump para desarrollar las pol\u00edticas de la administraci\u00f3n sobre telecomunicaciones inal\u00e1mbricas 5G, privacidad y ciberseguridad.<\/p>\n<p>Slater tambi\u00e9n represent\u00f3 anteriormente a Fox como vicepresidenta senior de pol\u00edticas y estrategia y, m\u00e1s recientemente, se desempe\u00f1\u00f3 como vicepresidenta y asesora general adjunto en Roku.<\/p>\n<p>Pero tambi\u00e9n ha sido la voz de algunos de los actores m\u00e1s importantes de la industria tecnol\u00f3gica, y pas\u00f3 m\u00e1s de tres a\u00f1os como asesora general de la Asociaci\u00f3n de Internet. Aunque el grupo comercial cerr\u00f3 en 2021, se consideraba la asociaci\u00f3n de la industria tecnol\u00f3gica m\u00e1s poderosa de su tiempo y representaba a Amazon, Facebook, Google y Microsoft, entre otros.<\/p>\n<p>En el lapso de solo una hora desde que Trump public\u00f3 en Truth Social que hab\u00eda elegido a Atkins para dirigir la SEC, Bitcoin aument\u00f3 m\u00e1s de US$ 1,000 y sigui\u00f3 en alza, un testimonio de la aprobaci\u00f3n de la comunidad cripto a la medida de Trump.<\/p>\n<p>Atkins, excomisionado de la SEC durante seis a\u00f1os bajo el mandato del expresidente George W. Bush, es el fundador y CEO de Patomak Global Partners, un grupo de consultor\u00eda de servicios financieros.<\/p>\n<p>Adem\u00e1s de bancos y grupos de tecnolog\u00eda financiera, Patomak atiende a clientes relacionados con las criptomonedas, incluidos exchanges y empresas que buscan integrar monedas digitales en sus negocios.<\/p>\n<p>Al trabajar con la Token Alliance de la C\u00e1mara Digital, Atkins ha ayudado a desarrollar un conjunto de mejoras pr\u00e1cticas para regular las criptomonedas. En general, se lo considera una persona que adoptar\u00e1 una actitud mucho m\u00e1s pasiva si se lo confirma como presidente de la SEC en lo que respecta a los esfuerzos por frenar el uso de las criptomonedas.<\/p>\n<p>Durante la campa\u00f1a electoral, Trump trabaj\u00f3 duro para cortejar a la comunidad criptogr\u00e1fica, y prometi\u00f3 marcar el comienzo de una ola de pol\u00edticas procriptomonedas, incluida la creaci\u00f3n de una \u201creserva estrat\u00e9gica nacional de bitcoins\u201d y la retenci\u00f3n de los bitcoins que el gobierno confisca a los criminales en lugar de subastarlos, que es la pr\u00e1ctica actual.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las comunidades de criptomonedas y tecnolog\u00eda finalmente tienen algo de claridad sobre a qui\u00e9n responder\u00e1n potencialmente durante los pr\u00f3ximos cuatro a\u00f1os. En el \u00e1mbito de las criptomonedas, el presidente electo de EE.UU. Donald Trump planea designar a Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s). Se espera [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456261","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las comunidades de criptomonedas y tecnolog\u00eda finalmente tienen algo de claridad sobre a qui\u00e9n responder\u00e1n potencialmente durante los pr\u00f3ximos cuatro a\u00f1os. En el \u00e1mbito de las criptomonedas, el presidente electo de EE.UU. Donald Trump planea designar a Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s). Se espera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-04T23:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores\",\"datePublished\":\"2024-12-04T23:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/\"},\"wordCount\":869,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/\",\"name\":\"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-04T23:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores - Noticias","og_description":"Las comunidades de criptomonedas y tecnolog\u00eda finalmente tienen algo de claridad sobre a qui\u00e9n responder\u00e1n potencialmente durante los pr\u00f3ximos cuatro a\u00f1os. En el \u00e1mbito de las criptomonedas, el presidente electo de EE.UU. Donald Trump planea designar a Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s). Se espera [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-04T23:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/"},"author":{"name":"","@id":""},"headline":"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores","datePublished":"2024-12-04T23:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/"},"wordCount":869,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/","name":"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-04T23:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\u00f3n de Bolsa y Valores","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/04\/trump-nombra-atkins-sec-slater-antimonopolio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-04T23:03:38Z","datePublished":"2024-12-04T23:03:38Z","dateModified":"2024-12-04T23:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump nombra al entusiasta de las criptomonedas Paul Atkins para dirigir la Comisi\\u00f3n de Bolsa y Valores\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/04\\\/trump-nombra-atkins-sec-slater-antimonopolio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/04\\\/trump-nombra-atkins-sec-slater-antimonopolio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-04T23:03:38Z\",\"datePublished\":\"2024-12-04T23:03:38Z\",\"dateModified\":\"2024-12-04T23:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456272,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/04\/bitcoin-alcanza-100000-la-administracion-pro-cripto-trump-trax\/","url_meta":{"origin":1456261,"position":0},"title":"Bitcoin alcanza los US$ 100.000 mientras se forma la administraci\u00f3n pro-cripto de Trump","author":"","date":"diciembre 4, 2024","format":false,"excerpt":"Bitcoin alcanz\u00f3 los US$ 100.000 por primera vez este mi\u00e9rcoles, subiendo a un nuevo r\u00e9cord despu\u00e9s de que el presidente electo de Estados Unidos, Donald Trump, revelara selecciones para su administraci\u00f3n que se consideran claves para introducir pol\u00edticas favorables a las criptomonedas cuando asuma el cargo en enero.Entre las selecciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456579,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/","url_meta":{"origin":1456261,"position":1},"title":"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"Elon Musk aparentemente tiene una \u00faltima batalla que librar con el presidente saliente de la Comisi\u00f3n de Bolsa y Valores, Gary Gensler.Musk revel\u00f3 en su plataforma de redes sociales X que la agencia est\u00e1 exigiendo que acepte una multa de una cantidad no revelada para resolver los cargos por su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456310,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/analisis-trump-designados-criptomonedas-trax\/","url_meta":{"origin":1456261,"position":2},"title":"AN\u00c1LISIS | Las \u00faltimas designaciones de Trump son un regalo a sus aliados de las criptomonedas","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"Si no hab\u00eda quedado claro antes, ahora lo est\u00e1: el presidente electo de Estados Unidos, Donald Trump, planea impulsar la industria de las criptomonedas mientras contin\u00faa con una amplia ofensiva antimonopolio contra gigantes tecnol\u00f3gicos como Amazon, Meta y Google.Esa combinaci\u00f3n parece recompensar a los donantes m\u00e1s ricos e influyentes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456297,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/nayib-bukele-celebra-aumento-valor-bitcoin-orix\/","url_meta":{"origin":1456261,"position":3},"title":"Presidente de El Salvador, Nayib Bukele, celebra el aumento del valor del bitcoin","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"El presidente de El Salvador, Nayib Bukele, celebr\u00f3 este jueves el aumento de la cotizaci\u00f3n del bitcoin, que alcanz\u00f3 los US$ 100.000 este mi\u00e9rcoles.\u201cLas reservas de Bitcoin de nuestro pa\u00eds ahora valen un 127,30% m\u00e1s de lo que pagamos por ellas, lo que significa un incremento de m\u00e1s de US$\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468471,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","url_meta":{"origin":1456261,"position":4},"title":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"El bitcoin y las acciones est\u00e1n en ca\u00edda y los inversionistas dicen que podr\u00eda haber m\u00e1s turbulencia en el futuro.Las acciones en EE.UU. bajaron el martes, extendiendo una reciente racha de ca\u00eddas.El Dow cay\u00f3 413 puntos, o 0,89 %. El S&P 500 baj\u00f3 0,6 %. El Nasdaq Composite, de fuerte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457701,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/21\/analisis-moneda-meme-trump-tonto-criptomonedas-trax\/","url_meta":{"origin":1456261,"position":5},"title":"AN\u00c1LISIS | La moneda meme de Trump es un recordatorio del caso de uso m\u00e1s tonto de las criptomonedas","author":"","date":"enero 21, 2025","format":false,"excerpt":"El presidente Donald Trump prometi\u00f3 a los inversores en criptomonedas que marcar\u00eda el comienzo de una era de legitimidad para un sector que durante mucho tiempo ha estado relegado a la oscuridad financiera, desestimado por algunos inversores convencionales como una apuesta altamente especulativa, en el mejor de los casos, o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456261"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456261\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}