{"id":1456301,"date":"2024-12-05T13:03:51","date_gmt":"2024-12-05T21:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/"},"modified":"2024-12-05T13:03:51","modified_gmt":"2024-12-05T21:03:51","slug":"asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/","title":{"rendered":"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos"},"content":{"rendered":"<p>El CEO de UnitedHealthcare, Brian Thompson, ten\u00eda asignado un equipo de seguridad interno durante su viaje a la ciudad de Nueva York, de acuerdo con una fuente familiarizada con la seguridad de la compa\u00f1\u00eda, pero el equipo no estaba con \u00e9l cuando fue asesinado a tiros frente a un hotel la madrugada del mi\u00e9rcoles.<\/p>\n<p>Es habitual que los altos ejecutivos de las grandes empresas cuenten con seguridad personal proporcionada por sus compa\u00f1\u00edas. A menudo, estas medidas suponen un gasto importante que figura en los archivos corporativos, aunque UnitedHealth Group, la matriz corporativa de UnitedHealthcare, no desglosa el costo en sus propios archivos.<\/p>\n<p>La necesidad de proteger la seguridad de los altos cargos y el costo de hacerlo ha aumentado a lo largo de los a\u00f1os, sobre todo en el caso de los ejecutivos de alto perfil cuyos negocios suelen generar controversia o cr\u00edticas, como la atenci\u00f3n m\u00e9dica. La mayor\u00eda de las empresas enumeran el riesgo de p\u00e9rdida de su alto ejecutivo, por fallecimiento u otra salida menos dram\u00e1tica, como un factor de riesgo a tener en cuenta por los inversores.<\/p>\n<p>M\u00faltiples proveedores importantes de atenci\u00f3n m\u00e9dica empezaron a aumentar la protecci\u00f3n personal en torno a los altos ejecutivos el mi\u00e9rcoles tras el tiroteo, dijeron fuentes de la industria de seguridad al analista jefe de inteligencia y cumplimiento de la ley de CNN, John Miller.<\/p>\n<p>Aunque UnitedHealthcare, como una de las mayores aseguradoras sanitarias del pa\u00eds, es bien conocida, Thompson dif\u00edcilmente podr\u00eda haber sido considerado de alto perfil antes de su asesinato. Aun as\u00ed, una fuente con conocimiento de la investigaci\u00f3n dijo a CNN que hab\u00eda amenazas preocupantes contra UnitedHealth Group y que la empresa estaba al tanto de ellas.<\/p>\n<p>No se mencionaba espec\u00edficamente el nombre de Thompson, pero en las amenazas se hablaba de atacar a ejecutivos de alto nivel en la empresa.<\/p>\n<p>La esposa de la v\u00edctima <a href=\"https:\/\/www.nbcnews.com\/news\/us-news\/previous-threats-slain-unitedhealthcare-ceo-brian-thompson-didnt-trave-rcna182878\">dijo a la NBC<\/a> que \u201chab\u00eda habido algunas amenazas\u2026 no s\u00e9, \u00bffalta de cobertura? No conozco los detalles. Solo s\u00e9 que dijo que hab\u00eda algunas personas que lo hab\u00edan estado amenazando\u201d.<\/p>\n<p>Fuentes policiales dijeron a CNN que se encontraron dos palabras en casquillos de bala en el lugar de los hechos: \u201cretrasar\u201d y \u201cdeponer\u201d (\u201cdelay\u201d y \u201cdepose\u201d, en ingl\u00e9s). \u201cDeponer\u201d estaba escrito en un casquillo de una bala que se dispar\u00f3 contra la v\u00edctima. \u201cRetrasar\u201d estaba escrito en un cartucho vivo que no fue disparado sino expulsado, al parecer cuando el atacante estaba resolviendo un bloqueo al disparar. Hay una frase popular sobre la industria de los seguros \u201cretrasar, negar, defender\u201d y la polic\u00eda est\u00e1 explorando si estas dos palabras apuntan a un motivo.<\/p>\n<p>A trav\u00e9s de las redes sociales y en otras publicaciones en Internet el mi\u00e9rcoles muchas personas expresaron una falta de arrepentimiento por el asesinato de Thompson. Algunos sugirieron que UnitedHealthcare y todas las aseguradoras eran responsables de muchas muertes al negar la cobertura de tratamientos m\u00e9dicos vitales. Algunos publicaron emojis ri\u00e9ndose de la noticia.<\/p>\n<p>\u201cEste suceso subraya realmente la creciente amenaza a la que se enfrentan ahora mismo los directores ejecutivos de las organizaciones, los jefes de las empresas\u201d, dijo el exagente del Servicio Secreto y experto Jonathan Wackrow a Anderson Cooper en CNN el mi\u00e9rcoles por la noche. \u201cLas amenazas a las que se enfrentan los l\u00edderes corporativos hoy son significativas. Son la cara de la organizaci\u00f3n\u201d.<\/p>\n<p>\u201cEl espectro de amenazas es bastante amplio cuando se piensa en cuestiones internas como empleados descontentos, violencia en el lugar de trabajo\u201d, dijo Wackrow. \u201cY luego se enfrentan a las cr\u00edticas del exterior por los productos o servicios que fabrican\u201d.<\/p>\n<p>Un portavoz de UnitedHealth declin\u00f3 dar detalles sobre la seguridad relacionada con Thompson o por qu\u00e9 el equipo de seguridad no estaba con \u00e9l el mi\u00e9rcoles por la ma\u00f1ana. Sin embargo, un exdirector s\u00e9nior de seguridad de otra gran compa\u00f1\u00eda de seguros dijo a CNN que a menudo puede ser dif\u00edcil conseguir que los ejecutivos acepten la seguridad, incluso cuando hay amenazas.<\/p>\n<p>\u201cTen\u00edamos un s\u00f3lido equipo de protecci\u00f3n de ejecutivos\u201d, dijo. \u201cTen\u00edamos muchas amenazas de miembros descontentos con su cobertura, en particular de aquellos cuyas prescripciones\u2026 caducaban y no se repon\u00edan. Este tiroteo puede haber sido aleatorio, pero sin duda podr\u00eda haber habido alguien que tuviera una motivaci\u00f3n. A menudo es dif\u00edcil refrenar a los CEO que esperan tener libertad para actuar por su cuenta sin un destacamento de protecci\u00f3n que los siga a todas partes\u201d.<\/p>\n<p>Quiz\u00e1 el CEO de m\u00e1s alto perfil y m\u00e1s controvertido de Estados Unidos en la actualidad es Elon Musk, que dirige varias empresas. Tesla, su \u00fanica empresa que cotiza en bolsa y presenta informes financieros, inform\u00f3 que destin\u00f3 US$ 2,4 millones a su seguridad en 2023 y otros US$ 500.000 solo en los dos primeros meses de este a\u00f1o. El dinero se pag\u00f3 a una empresa de seguridad propiedad del propio Musk.<\/p>\n<p>Musk ha escrito sobre las amenazas a las que se enfrenta en su plataforma de redes sociales X. \u201cSe avecinan tiempos peligrosos. Dos personas (en ocasiones distintas) ya han intentado matarme en los \u00faltimos 8 meses. Fueron detenidos con armas a unos 20 minutos en auto de la sede central de Tesla en Texas\u201d, <a href=\"https:\/\/x.com\/elonmusk\/status\/1812281822887469104\">public\u00f3<\/a> en julio.<\/p>\n<p>Otras empresas tambi\u00e9n han revelado importantes gastos en la seguridad de sus altos ejecutivos. Muchas enumeran el costo de los viajes en jets privados o de los ch\u00f3feres como parte de ese costo, pero esas medidas pueden ser tanto por comodidad, gesti\u00f3n del tiempo y privacidad como por seguridad. Aunque todos los viajes a\u00e9reos en Estados Unidos se encuentran entre los m\u00e1s seguros, los jets comerciales tienen en realidad un mejor historial de seguridad que los jets corporativos.<\/p>\n<p>El fabricante de chips de inteligencia artificial Nvidia, una de las empresas m\u00e1s valiosas del planeta, gast\u00f3 US$ 2,2 millones en 2023 en seguridad residencial y honorarios de consulta, servicios de vigilancia de seguridad y servicios de autom\u00f3vil y conductor para su CEO, Jen-Hsun Huang. Apple gast\u00f3 US$ 820.000 en seguridad privada para su CEO, Tim Cook, y el doble de esa cantidad en sus viajes a\u00e9reos personales en el jet privado de la compa\u00f1\u00eda. Alphabet pag\u00f3 US$ 6,8 millones por la seguridad personal del CEO Sundar Pichai.<\/p>\n<p>Y Meta Platforms, propietaria de Facebook, destin\u00f3 US$ 9,4 millones en la seguridad personal del CEO y cofundador Mark Zuckerberg, que tambi\u00e9n recibe una asignaci\u00f3n anual antes de impuestos de US$ 14 millones para cubrir la seguridad de su familia.<\/p>\n<p>Muchas empresas, entre ellas UnitedHealth Group, tienen pol\u00edticas en las que se exige o anima a sus CEO a utilizar aviones corporativos para viajes personales, a expensas de la empresa, afirmando que se trata de una medida de seguridad.<\/p>\n<p>Aunque los costos de seis cifras son habituales, las grandes empresas suelen declarar una seguridad menos costosa que la que declaran las empresas tecnol\u00f3gicas, seg\u00fan los archivos.<\/p>\n<p>Por ejemplo, Warner Bros. Discovery, propietaria de CNN, gast\u00f3 US$ 705.000 en seguridad para el CEO David Zaslav en sus residencias y durante sus viajes personales. Eso incluye un gasto \u00fanico de unos US$ 389.000 para la instalaci\u00f3n de ciertos equipos de seguridad en sus residencias. Tambi\u00e9n gast\u00f3 US$ 768.000 por su uso del avi\u00f3n corporativo para viajes personales.<\/p>\n<p>JPMorgan Chase, el mayor banco de Estados Unidos, gast\u00f3 US$ 151.000 por el costo de los viajes residenciales, personales y de seguridad relacionados de Dimon, as\u00ed como US$ 362.000 adicionales por su uso de aviones corporativos para viajes personales.<\/p>\n<p><em>\u2013 Josh Campbell, Meg Tirrell, John Miller y Nathaniel Meyersohn, de CNN, contribuyeron a este reportaje.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El CEO de UnitedHealthcare, Brian Thompson, ten\u00eda asignado un equipo de seguridad interno durante su viaje a la ciudad de Nueva York, de acuerdo con una fuente familiarizada con la seguridad de la compa\u00f1\u00eda, pero el equipo no estaba con \u00e9l cuando fue asesinado a tiros frente a un hotel la madrugada del mi\u00e9rcoles. Es [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456301","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos - Noticias\" \/>\n<meta property=\"og:description\" content=\"El CEO de UnitedHealthcare, Brian Thompson, ten\u00eda asignado un equipo de seguridad interno durante su viaje a la ciudad de Nueva York, de acuerdo con una fuente familiarizada con la seguridad de la compa\u00f1\u00eda, pero el equipo no estaba con \u00e9l cuando fue asesinado a tiros frente a un hotel la madrugada del mi\u00e9rcoles. Es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T21:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos\",\"datePublished\":\"2024-12-05T21:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/\"},\"wordCount\":1330,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/\",\"name\":\"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-05T21:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos - Noticias","og_description":"El CEO de UnitedHealthcare, Brian Thompson, ten\u00eda asignado un equipo de seguridad interno durante su viaje a la ciudad de Nueva York, de acuerdo con una fuente familiarizada con la seguridad de la compa\u00f1\u00eda, pero el equipo no estaba con \u00e9l cuando fue asesinado a tiros frente a un hotel la madrugada del mi\u00e9rcoles. Es [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-05T21:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/"},"author":{"name":"","@id":""},"headline":"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos","datePublished":"2024-12-05T21:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/"},"wordCount":1330,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/","name":"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-05T21:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El asesinato del CEO de UnitedHealthcare muestra por qu\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-05T21:03:51Z","datePublished":"2024-12-05T21:03:51Z","dateModified":"2024-12-05T21:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El asesinato del CEO de UnitedHealthcare muestra por qu\\u00e9 las empresas gastan millones en proteger a sus altos ejecutivos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/05\\\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/05\\\/asesinato-ceo-unitedhealthcare-gasto-ejecutivos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-05T21:03:51Z\",\"datePublished\":\"2024-12-05T21:03:51Z\",\"dateModified\":\"2024-12-05T21:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456508,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/12\/ejecutivos-miedo-tras-asesinato-ceo-unitedhealthcare-trax\/","url_meta":{"origin":1456301,"position":0},"title":"Los altos ejecutivos tienen miedo tras el asesinato del CEO de UnitedHealthcare","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Las corporaciones se esfuerzan por proteger a sus altos ejecutivos mientras la Polic\u00eda advierte de una amenaza creciente a corto plazo contra los l\u00edderes empresariales. Los consejos directivos est\u00e1n reevaluando los presupuestos de seguridad y se les est\u00e1 pidiendo a los CEO que borren sus huellas digitales.El sorprendente asesinato del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456484,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/11\/directivos-empresas-temen-seguridad-asesinato-ceo-trax\/","url_meta":{"origin":1456301,"position":1},"title":"Altos ejecutivos de corporaciones aumentan su seguridad tras asesinato de CEO de UnitedHealthcare","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Las empresas luchan para garantizar la protecci\u00f3n de sus altos ejecutivos mientras la polic\u00eda advierte de una amenaza a corto plazo contra los l\u00edderes empresariales. Los consejos de administraci\u00f3n est\u00e1n reevaluando los presupuestos de seguridad. Y se est\u00e1 pidiendo a los CEO que borren sus huellas digitales.El sorprendente asesinato del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457032,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/27\/corporaciones-maxima-alerta-clientes-enojados-trax\/","url_meta":{"origin":1456301,"position":2},"title":"Las corporaciones estadounidenses nunca han sido populares, pero ahora est\u00e1n en alerta m\u00e1xima ante clientes enojados","author":"","date":"diciembre 27, 2024","format":false,"excerpt":"Tres semanas despu\u00e9s del asesinato del CEO de UnitedHealthcare, Brian Thompson, las empresas y los ejecutivos est\u00e1n monitoreando de cerca las amenazas de los clientes y reforzando sus vulnerabilidades de seguridad.Un hombre de Texas fue arrestado este viernes por presuntamente amenazar a ejecutivos de Capital One por correo electr\u00f3nico, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463221,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/06\/05\/estado-mental-luigi-mangione-homicidio-ceo-unitedhealthcare-trax\/","url_meta":{"origin":1456301,"position":3},"title":"Nuevos documentos dan idea del estado mental de Luigi Mangione en los meses previos al homicidio del CEO de UnitedHealthCare","author":"","date":"junio 5, 2025","format":false,"excerpt":"Las entradas del diario escritas por Luigi Mangione revelan el pensamiento detallado del joven de 27 a\u00f1os antes del presunto homicidio del CEO de UnitedHealthcare, Brian Thompson, el a\u00f1o pasado, seg\u00fan muestra una nueva presentaci\u00f3n judicial.La Polic\u00eda recuper\u00f3 un cuaderno rojo en el momento de su arresto el 9 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456260,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/04\/quien-era-brian-thompson-ceo-unitedhealthcare-tiros-trax\/","url_meta":{"origin":1456301,"position":4},"title":"\u00bfQui\u00e9n era Brian Thompson, el CEO de UnitedHealthcare que mataron a tiros en Manhattan?","author":"","date":"diciembre 4, 2024","format":false,"excerpt":"Brian Thompson, el CEO de UnitedHealthcare, quien recibi\u00f3 un disparo fatal en Midtown Manhattan este mi\u00e9rcoles en lo que la polic\u00eda de Nueva York llam\u00f3 un \u201cataque descarado y selectivo\u201d, era un l\u00edder de larga data en el mundo empresarial estadounidense, un estudiante modelo y un atleta estrella de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456287,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/asesinato-ceo-unitedhealthcare-nueva-york-lo-que-sabemos\/","url_meta":{"origin":1456301,"position":5},"title":"Esto es lo que pas\u00f3 en el asesinato del CEO de UnitedHealthcare en Nueva York y lo que sabemos del sospechoso","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"La Polic\u00eda est\u00e1 buscando a un atacante que dispar\u00f3 y mat\u00f3 al CEO de UnitedHealthcare, Brian Thompson, en lo que la Polic\u00eda describi\u00f3 como un ataque audaz y deliberado en el coraz\u00f3n de la ciudad de Nueva York.El atacante enmascarado estaba \u201cacechando\u201d afuera del Hilton Midtown poco antes de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456301"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456301\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}