{"id":1456308,"date":"2024-12-05T16:03:48","date_gmt":"2024-12-06T00:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/"},"modified":"2024-12-05T16:03:48","modified_gmt":"2024-12-06T00:03:48","slug":"notre-dame-reabrira-pronto-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/","title":{"rendered":"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber"},"content":{"rendered":"<p><a href=\"https:\/\/cnn.com\/2024\/11\/30\/style\/notre-dame-reopening-restoration-intl\/index.html\">Notre Dame<\/a>, la preciada joya g\u00f3tica de Par\u00eds que se incendi\u00f3 en 2019, reabrir\u00e1 oficialmente el s\u00e1bado.<\/p>\n<p>Inmediatamente despu\u00e9s del incendio, el presidente de Francia, Emmanuel Macron, hizo la ambiciosa promesa de restaurar la iglesia en cinco a\u00f1os.<\/p>\n<p>El viernes, elogi\u00f3 a cientos de artesanos, carpinteros y otros especialistas por ayudarlo a \u201ccumplir esta promesa\u201d durante su \u00faltima visita al sitio.<\/p>\n<p>\u201cLo han logrado. Y es un inmenso motivo de orgullo para toda la naci\u00f3n. Les estoy infinitamente agradecido, Francia les est\u00e1 infinitamente agradecida\u201d, dijo Macron.<\/p>\n<p>El 15 de abril de 2019, Notre Dame qued\u00f3 envuelta en llamas. La causa del incendio sigue siendo un misterio. Los investigadores dicen que probablemente se trat\u00f3 de un accidente, tal vez un cigarrillo encendido o un problema el\u00e9ctrico.<\/p>\n<p>Francia (y gran parte del mundo) se conmocion\u00f3 cuando el techo de la catedral de 860 a\u00f1os se derrumb\u00f3, cubriendo de holl\u00edn el piso de piedra. Macron lo calific\u00f3 de \u201cterrible tragedia\u201d y prometi\u00f3 reconstruir la hist\u00f3rica iglesia \u201cporque es lo que nuestra historia merece\u201d.<\/p>\n<p>Algunos de los empresarios m\u00e1s ricos del pa\u00eds prometieron cientos de millones de euros para la restauraci\u00f3n.<\/p>\n<p>Despu\u00e9s de m\u00e1s de 2.000 d\u00edas de trabajo, que involucraron a 2.000 personas, 2.000 robles y 2.000 elementos restaurados o reconstruidos, el mundo tuvo su primera visi\u00f3n de \u201cNuestra Se\u00f1ora de Par\u00eds\u201d la semana pasada, cuando el presidente de Francia recorri\u00f3 el monumento restaurado con su esposa Brigitte y un grupo de cl\u00e9rigos.<\/p>\n<p>La reapertura oficial comienza con una ceremonia el s\u00e1bado, seguida de ocho d\u00edas de misas y oraciones especiales.<\/p>\n<p>La lista de invitados ser\u00e1 larga e ilustre, pero el asistente m\u00e1s destacado ser\u00e1 Donald Trump. El presidente electo de Estados Unidos <a href=\"https:\/\/www.cnn.com\/2024\/12\/02\/politics\/trump-travel-paris-notre-dame-cathedral\/index.html\">anunci\u00f3 esta semana<\/a> que viajar\u00e1 a Par\u00eds (su primer viaje al exterior desde las elecciones del mes pasado) para lo que ser\u00e1 \u201cun d\u00eda muy especial para todos\u201d.<\/p>\n<p>Se espera que la ceremonia re\u00fana a unos 50 jefes de Estado y de Gobierno.<\/p>\n<p>Sin embargo, una ausencia notable ser\u00e1 la del papa Francisco. El pont\u00edfice viajar\u00e1 a la isla mediterr\u00e1nea francesa de C\u00f3rcega el 15 de diciembre, apenas unos d\u00edas despu\u00e9s de la reapertura, pero no visitar\u00e1 la capital. Un importante arzobispo franc\u00e9s dijo que la \u201cestrella\u201d de la ceremonia deber\u00eda ser la propia Notre Dame y que el papa no quer\u00eda distraer la atenci\u00f3n de la ocasi\u00f3n.<\/p>\n<p>En la ceremonia participar\u00e1n tambi\u00e9n unos 170 obispos de Francia y del mundo entero, junto con un sacerdote de cada una de las 106 parroquias de la di\u00f3cesis de Par\u00eds.<\/p>\n<p>Macron pronunciar\u00e1 un discurso frente a la catedral alrededor de las 18:00 (12:00 hora de Miami). A continuaci\u00f3n, el arzobispo de Par\u00eds, Laurent Ulrich, golpear\u00e1 las puertas cerradas de la catedral con su b\u00e1culo, un bast\u00f3n adornado.<\/p>\n<p>Una vez que las puertas se abran, la catedral \u201cresponde\u201d al llamado cantando el Salmo 121 (que comienza con \u201cAlzar\u00e9 mis ojos a los montes\u201d) tres veces. Despu\u00e9s de esto, las puertas se abrir\u00e1n.<\/p>\n<p>La ceremonia se desarrolla en tres partes. En primer lugar, el \u201cdespertar\u201d del gran \u00f3rgano, el m\u00e1s grande de Francia, con 8.000 tubos y 115 registros. En segundo lugar, el \u201ccanto del Oficio\u201d, una serie de salmos y oraciones, incluido el Padrenuestro. A continuaci\u00f3n, el arzobispo impartir\u00e1 la bendici\u00f3n final y el coro cantar\u00e1 el <em>Te Deum<\/em>, un himno latino.<\/p>\n<p>El servicio ser\u00e1 seguido por una transmisi\u00f3n de France TV, que narrar\u00e1 la reconstrucci\u00f3n de la catedral.<\/p>\n<p>La misa inaugural se celebrar\u00e1 el domingo por la ma\u00f1ana alrededor de las 10:30 (4:30 a.m., hora de Miami), con la presencia de Macron. Despu\u00e9s de bendecir el agua bendita, el arzobispo la rociar\u00e1 sobre la congregaci\u00f3n y luego sobre el altar.<\/p>\n<p>Las lecturas b\u00edblicas que se dar\u00e1n en la misa ser\u00e1n las mismas en todo el mundo, con motivo del segundo domingo de Adviento.<\/p>\n<p>El domingo por la noche se celebrar\u00e1 una segunda misa, abierta al p\u00fablico.<\/p>\n<p>Durante los ocho d\u00edas posteriores a la reapertura, se celebrar\u00e1n misas dos veces al d\u00eda, junto con ceremonias vespertinas especiales. Muchos de estos servicios estar\u00e1n abiertos al p\u00fablico.<\/p>\n<p>El 17 y 18 de diciembre la catedral acoger\u00e1 conciertos del \u201cMagnificat\u201d de Johann Sebastian Bach.<\/p>\n<p>Se espera que la catedral reciba hasta 15 millones de visitantes cada a\u00f1o. Por ahora, la visita es gratuita. Los visitantes podr\u00e1n reservar una entrada gratuita en l\u00ednea y acceder al edificio el mismo d\u00eda o uno o dos d\u00edas despu\u00e9s de realizar la reserva.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre Dame, la preciada joya g\u00f3tica de Par\u00eds que se incendi\u00f3 en 2019, reabrir\u00e1 oficialmente el s\u00e1bado. Inmediatamente despu\u00e9s del incendio, el presidente de Francia, Emmanuel Macron, hizo la ambiciosa promesa de restaurar la iglesia en cinco a\u00f1os. El viernes, elogi\u00f3 a cientos de artesanos, carpinteros y otros especialistas por ayudarlo a \u201ccumplir esta promesa\u201d [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456308","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber - Noticias\" \/>\n<meta property=\"og:description\" content=\"Notre Dame, la preciada joya g\u00f3tica de Par\u00eds que se incendi\u00f3 en 2019, reabrir\u00e1 oficialmente el s\u00e1bado. Inmediatamente despu\u00e9s del incendio, el presidente de Francia, Emmanuel Macron, hizo la ambiciosa promesa de restaurar la iglesia en cinco a\u00f1os. El viernes, elogi\u00f3 a cientos de artesanos, carpinteros y otros especialistas por ayudarlo a \u201ccumplir esta promesa\u201d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-06T00:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber\",\"datePublished\":\"2024-12-06T00:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/\"},\"wordCount\":807,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/\",\"name\":\"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-06T00:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber - Noticias","og_description":"Notre Dame, la preciada joya g\u00f3tica de Par\u00eds que se incendi\u00f3 en 2019, reabrir\u00e1 oficialmente el s\u00e1bado. Inmediatamente despu\u00e9s del incendio, el presidente de Francia, Emmanuel Macron, hizo la ambiciosa promesa de restaurar la iglesia en cinco a\u00f1os. El viernes, elogi\u00f3 a cientos de artesanos, carpinteros y otros especialistas por ayudarlo a \u201ccumplir esta promesa\u201d [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-06T00:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/"},"author":{"name":"","@id":""},"headline":"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber","datePublished":"2024-12-06T00:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/"},"wordCount":807,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/","name":"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-06T00:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-06T00:03:48Z","datePublished":"2024-12-06T00:03:48Z","dateModified":"2024-12-06T00:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Notre Dame reabrir\\u00e1 pronto. Esto es lo que debes saber\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/05\\\/notre-dame-reabrira-pronto-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/05\\\/notre-dame-reabrira-pronto-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-06T00:03:48Z\",\"datePublished\":\"2024-12-06T00:03:48Z\",\"dateModified\":\"2024-12-06T00:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456358,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/07\/fotos-impresionante-restauracion-notre-dame-trax\/","url_meta":{"origin":1456308,"position":0},"title":"En fotos: la impresionante restauraci\u00f3n de Notre Dame cinco a\u00f1os despu\u00e9s del incendio","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"(CNN) -- La resurrecci\u00f3n de Notre Dame \u2014la preciada joya g\u00f3tica en el coraz\u00f3n de Par\u00eds, afectada por un devastador incendio en 2019\u2014 ha sido un secreto muy bien guardado. Pocos hab\u00edan visto el meticuloso trabajo de arquitectos, artesanos y maestros artistas que lograron devolver la vida a la catedral.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456335,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/06\/gran-organo-notre-dame-distintivo-sonido-trax\/","url_meta":{"origin":1456308,"position":1},"title":"C\u00f3mo fue que el famoso gran \u00f3rgano de Notre Dame recuper\u00f3 su distintivo sonido","author":"","date":"diciembre 6, 2024","format":false,"excerpt":"El instrumento musical m\u00e1s grande de Francia est\u00e1 listo para sonar de nuevo.Ha tomado meses de limpieza meticulosa y descontaminaci\u00f3n de 8.000 tubos, 115 registros de \u00f3rgano y otros numerosos componentes musicales, pero el s\u00e1bado los majestuosos tonos del gran \u00f3rgano de Notre Dame volver\u00e1n a resonar.Ser\u00e1 la primera vez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442597,"url":"https:\/\/noticiasya.com\/palm-springs\/2023\/12\/24\/asi-ha-sido-la-restauracion-de-us-760-millones-de-la-catedral-de-notre-dame-en-paris\/","url_meta":{"origin":1456308,"position":2},"title":"As\u00ed ha sido la restauraci\u00f3n de US$ 760 millones de la catedral de Notre Dame en Par\u00eds","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"(CNN) -- La aguja de Notre Dame, coronada por un nuevo gallo dorado, recuper\u00f3 su lugar en el horizonte de Par\u00eds a mediados de diciembre de 2023.Mientras turistas y parisinos se reun\u00edan frente a la catedral, declarada Patrimonio de la Humanidad por la Unesco, para admirar el regreso de uno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456156,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/29\/notre-dame-reapertura-imagenes-iconicas-historia-trax\/","url_meta":{"origin":1456308,"position":3},"title":"Coronaciones, protestas y equilibristas: im\u00e1genes ic\u00f3nicas de la historia de Notre Dame antes de su reapertura","author":"","date":"noviembre 29, 2024","format":false,"excerpt":"(CNN) -- Durante cientos de a\u00f1os, Notre Dame fue el tel\u00f3n de fondo de algunos de los momentos m\u00e1s decisivos de la historia de Francia. Este viernes, la catedral ser\u00e1 la protagonista de la visita del presidente de Francia, Emmanuel Macron, antes de su reapertura oficial el fin de semana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456209,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/02\/trump-viajara-paris-reapertura-notre-dame-trax\/","url_meta":{"origin":1456308,"position":4},"title":"Trump viajar\u00e1 a Par\u00eds para la reapertura de la catedral de Notre Dame","author":"","date":"diciembre 2, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El presidente electo Donald Trump planea visitar Par\u00eds a finales de esta semana para asistir a la reapertura de la Catedral de Notre Dame el 7 de diciembre, en su primer viaje al exterior tras ser elegido en noviembre para encabezar un segundo mandato.El equipo de Trump ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456349,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/","url_meta":{"origin":1456308,"position":5},"title":"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"La catedral de Notre Dame ser\u00e1 el tel\u00f3n de fondo del regreso del presidente electo Donald Trump a la escena geopol\u00edtica este s\u00e1bado, cuando las autoridades francesas pongan punto final al proyecto de cinco a\u00f1os para restaurar este monumento emblem\u00e1tico con una ceremonia de reapertura en la que participar\u00e1n decenas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456308"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456308\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}