{"id":1456342,"date":"2024-12-06T19:03:46","date_gmt":"2024-12-07T03:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/"},"modified":"2024-12-06T19:03:46","modified_gmt":"2024-12-07T03:03:46","slug":"verificacion-fbi-selecciones-gabinete-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/","title":{"rendered":"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete"},"content":{"rendered":"<p>Mientras que el controvertido nombramiento del presidente electo de Estados Unidos, Donald Trump, para secretario de Defensa, <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/06\/estados-unidos\/hegseth-comprobacion-de-antecedentes-fbi-trax\">Pete Hegseth,<\/a> est\u00e1 comenzando el proceso para someterse a una verificaci\u00f3n de antecedentes del FBI, la revisi\u00f3n intensiva puede no proporcionar las respuestas que tanto los dem\u00f3cratas como los republicanos est\u00e1n buscando.<\/p>\n<p>Esto se debe a que el candidato no \u201cpasa\u201d una verificaci\u00f3n de antecedentes y el FBI no aprueba a los solicitantes. En cambio, los archivos de investigaci\u00f3n del FBI sobre los candidatos se env\u00edan a la Casa Blanca, que toma la decisi\u00f3n final sobre si pueden ocupar los puestos para los que los eligi\u00f3 el presidente.<\/p>\n<p>Las verificaciones de antecedentes del FBI han sido anteriormente un foco de atenci\u00f3n durante peleas de confirmaci\u00f3n contenciosas. Despu\u00e9s de que las acusaciones de conducta sexual inapropiada casi hundieran el nombramiento del juez de la Corte Suprema Brett Kavanaugh en 2018, por ejemplo, los dem\u00f3cratas dijeron que la investigaci\u00f3n de antecedentes del FBI estaba pol\u00edticamente restringida y no sigui\u00f3 los procedimientos adecuados.<\/p>\n<p>La confirmaci\u00f3n de Hegseth ha estado en peligro en medio de una serie de acusaciones relacionadas con el consumo de alcohol y conducta sexual inapropiada, que \u00e9l ha negado. A medida que han aumentado las llamadas para una evaluaci\u00f3n adicional, el abogado de Hegseth dijo a CNN esta semana que su nombre ha sido enviado al FBI para la verificaci\u00f3n de antecedentes.<\/p>\n<p>El FBI se est\u00e1 preparando para realizar verificaciones de antecedentes detalladas de miles de designados para la administraci\u00f3n entrante de Trump. Si bien el presidente electo se ha movido r\u00e1pidamente para <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/22\/personas-designadas-trump-cargos-gobierno-orix\">nombrar a su gabinete y selecciones administrativas clave<\/a>, su uso del sistema del FBI hab\u00eda estado en duda hasta que el equipo de transici\u00f3n de Trump firm\u00f3 un memorando de <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/04\/trump-transicion-departamento-de-justicia-fbi-trax\">entendimiento con el Departamento de Justicia<\/a> en los \u00faltimos d\u00edas.<\/p>\n<p>El acuerdo ahora permitir\u00e1 al FBI realizar al menos algunas investigaciones, pero sigue sin estar claro cu\u00e1ntas de las selecciones de Trump para liderar varias agencias y departamentos ser\u00e1n sometidos a esas verificaciones, ya que el equipo de transici\u00f3n tambi\u00e9n ha estado utilizando empresas privadas para realizar algunas evaluaciones.<\/p>\n<p>A pesar de las dudas de <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/23\/trump-aversion-directores-fbi-trax\">Trump sobre el FBI<\/a> y las quejas de sus aliados de que no se debe confiar en la oficina para examinar a sus designados, el sistema del FBI cuenta con el apoyo bipartidista de los miembros del Congreso. Senadores de ambos partidos han dicho que quieren que los designados pol\u00edticos se sometan a investigaciones de antecedentes del FBI como parte del proceso de confirmaci\u00f3n.<\/p>\n<p>Decenas de agentes del FBI y contratistas en la sede de la oficina en Washington y en oficinas de campo en todo el pa\u00eds est\u00e1n involucrados en investigaciones de antecedentes con el objetivo de ayudar a preparar a la nueva administraci\u00f3n para tomar las riendas del Gobierno y permitir que los designados tengan acceso a informaci\u00f3n clasificada y otra informaci\u00f3n sensible tan pronto como el nuevo presidente tome prosesi\u00f3n el 20 de enero.<\/p>\n<p>Las verificaciones de antecedentes no son investigaciones criminales, y el papel de los investigadores del FBI es realizar investigaciones para un cliente, en este caso la Casa Blanca o la agencia gubernamental que las solicita. En cada administraci\u00f3n, la Casa Blanca generalmente proporciona preguntas, adem\u00e1s del est\u00e1ndar enumeradas en los formularios de solicitud, que se les dice a los agentes que deben hacer.<\/p>\n<p>Si bien las investigaciones de antecedentes del FBI tienen acceso a bases de datos criminales del Gobierno, eso t\u00edpicamente no incluir\u00eda acusaciones de irregularidades que no resulten en un arresto o cargos.<\/p>\n<p>En el caso de Hegseth, eso significa que los investigadores no necesariamente ver\u00edan detalles de un incidente en California que incluy\u00f3 una investigaci\u00f3n de presunta agresi\u00f3n sexual, pero que no result\u00f3 en cargos. No est\u00e1 claro si los investigadores podr\u00edan buscar informaci\u00f3n de la parte acusadora, quien fue pagada en un acuerdo con Hegseth que inclu\u00eda una cl\u00e1usula de confidencialidad y tiene la opci\u00f3n de negarse a hablar con el FBI.<\/p>\n<p>El alcance de la investigaci\u00f3n del FBI sobre Kavanaugh todav\u00eda est\u00e1 bajo escrutinio. Al publicar<a href=\"https:\/\/www.whitehouse.senate.gov\/wp-content\/uploads\/2024\/10\/KavanaughReport_final.pdf\"> un informe<\/a> este oto\u00f1o boreal, el senador Sheldon Whitehouse, un dem\u00f3crata de Rhode Island en el Comit\u00e9 Judicial, calific\u00f3 la investigaci\u00f3n de antecedentes suplementaria del FBI sobre Kavanaugh como una \u201cfarsa\u201d.<\/p>\n<p>Las verificaciones de antecedentes incluyen formularios largos donde los candidatos deben detallar el empleo pasado, informaci\u00f3n biogr\u00e1fica, as\u00ed como registros criminales y financieros. Los investigadores examinan la historia personal de cada solicitante hasta su cumplea\u00f1os n\u00famero 18, con especialistas en seguridad del FBI examinando historiales de cr\u00e9dito y antecedentes criminales y realizando entrevistas con asociados que datan de a\u00f1os atr\u00e1s.<\/p>\n<p>Las investigaciones tambi\u00e9n incluyen una entrevista en persona con el FBI donde un agente revisa la informaci\u00f3n recopilada y a veces desaf\u00eda a los solicitantes a explicar discrepancias.<\/p>\n<p>\u201cLo comparo con un examen colorrectal mientras est\u00e1s despierto\u201d, dijo a CNN un exespecialista en seguridad del FBI que realiz\u00f3 investigaciones de antecedentes durante a\u00f1os.<\/p>\n<p>Las investigaciones para los miembros del gabinete pueden incluir hasta 60 entrevistas, dijo el exespecialista del FBI. Los agentes y contratistas pasan de 10 d\u00edas a dos semanas en las investigaciones de mayor perfil.<\/p>\n<p>Se les pide a los solicitantes que proporcionen contactos con empleadores que datan desde los 18 a\u00f1os. El FBI desarrolla su propia inteligencia para complementar la lista de personas que pueden conocer a un solicitante para asegurarse de que no se pierda informaci\u00f3n que un solicitante pueda omitir.<\/p>\n<p>En algunos casos, los agentes caminar\u00e1n por la calle donde vivieron para preguntar a los vecinos sobre ellos. Para los designados que anteriormente sirvieron en trabajos gubernamentales, las investigaciones tienden a ser m\u00e1s cortas ya que los agentes no necesitan repetir la investigaci\u00f3n de partes anteriores de los antecedentes.<\/p>\n<p>La administraci\u00f3n entrante de Trump tiene un pasado tortuoso con el sistema de autorizaciones de seguridad del Gobierno despu\u00e9s de que decenas de personas que eligi\u00f3 para servir en su primera administraci\u00f3n lucharon para completar el proceso de investigaciones de antecedentes.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2020\/04\/07\/el-nuevo-y-escalofriante-papel-de-jared-kushner\">Jared Kushner<\/a>, yerno de Trump, fue uno de varios designados cuyos contactos extranjeros y posibles conflictos plantearon problemas mientras buscaban recibir autorizaciones de seguridad. En el caso de Kushner, la informaci\u00f3n incompleta que proporcion\u00f3 al completar el formulario del Gobierno, conocido como SF-86, caus\u00f3 retrasos.<\/p>\n<p>Trump orden\u00f3 que se otorgaran autorizaciones de alto nivel a unas 25 personas, incluidas Kushner y su hija Ivanka, desestimando las preguntas planteadas durante las investigaciones de antecedentes, seg\u00fan el testimonio del Congreso.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras que el controvertido nombramiento del presidente electo de Estados Unidos, Donald Trump, para secretario de Defensa, Pete Hegseth, est\u00e1 comenzando el proceso para someterse a una verificaci\u00f3n de antecedentes del FBI, la revisi\u00f3n intensiva puede no proporcionar las respuestas que tanto los dem\u00f3cratas como los republicanos est\u00e1n buscando. Esto se debe a que el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456342","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete - Noticias\" \/>\n<meta property=\"og:description\" content=\"Mientras que el controvertido nombramiento del presidente electo de Estados Unidos, Donald Trump, para secretario de Defensa, Pete Hegseth, est\u00e1 comenzando el proceso para someterse a una verificaci\u00f3n de antecedentes del FBI, la revisi\u00f3n intensiva puede no proporcionar las respuestas que tanto los dem\u00f3cratas como los republicanos est\u00e1n buscando. Esto se debe a que el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-07T03:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete\",\"datePublished\":\"2024-12-07T03:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/\"},\"wordCount\":1171,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/\",\"name\":\"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-07T03:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete - Noticias","og_description":"Mientras que el controvertido nombramiento del presidente electo de Estados Unidos, Donald Trump, para secretario de Defensa, Pete Hegseth, est\u00e1 comenzando el proceso para someterse a una verificaci\u00f3n de antecedentes del FBI, la revisi\u00f3n intensiva puede no proporcionar las respuestas que tanto los dem\u00f3cratas como los republicanos est\u00e1n buscando. Esto se debe a que el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-07T03:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete","datePublished":"2024-12-07T03:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/"},"wordCount":1171,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/","name":"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-07T03:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Lo que podr\u00eda revelar una verificaci\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/06\/verificacion-fbi-selecciones-gabinete-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-07T03:03:46Z","datePublished":"2024-12-07T03:03:46Z","dateModified":"2024-12-07T03:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Lo que podr\\u00eda revelar una verificaci\\u00f3n de antecedentes del FBI para los elegidos por Trump para su gabinete\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/06\\\/verificacion-fbi-selecciones-gabinete-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/06\\\/verificacion-fbi-selecciones-gabinete-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-07T03:03:46Z\",\"datePublished\":\"2024-12-07T03:03:46Z\",\"dateModified\":\"2024-12-07T03:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456247,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/04\/trump-transicion-departamento-de-justicia-fbi-trax\/","url_meta":{"origin":1456342,"position":0},"title":"La transici\u00f3n de Trump firma un acuerdo con el Departamento de Justicia que allana el camino para que el FBI compruebe los antecedentes de los elegidos por Trump","author":"","date":"diciembre 4, 2024","format":false,"excerpt":"(CNN) -- El equipo de transici\u00f3n de Donald Trump firm\u00f3 un memorando de entendimiento con el Departamento de Justicia, allanando el camino para que el equipo solicite al FBI la comprobaci\u00f3n de los antecedentes de los seleccionados por el presidente electo.El acuerdo, anunciado por el equipo de Trump este martes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456319,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/06\/hegseth-comprobacion-de-antecedentes-fbi-trax\/","url_meta":{"origin":1456342,"position":1},"title":"El nombre de Hegseth fue sometido a una comprobaci\u00f3n de antecedentes por el FBI, seg\u00fan su abogado","author":"","date":"diciembre 6, 2024","format":false,"excerpt":"El nombre de Pete Hegseth fue enviado al FBI para una verificaci\u00f3n de antecedentes, dijo su abogado a CNN este jueves, mientras algunos legisladores piden una mayor investigaci\u00f3n de la elecci\u00f3n del presidente electo Donald Trump para dirigir el Pent\u00e1gono.\u201cRecibi\u00f3 los formularios ayer del FBI, y estamos trabajando en ellos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468808,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/11\/28\/verificacion-antecedentes-afganos-escrutinio-trax\/","url_meta":{"origin":1456342,"position":2},"title":"Proceso de verificaci\u00f3n de antecedentes de afganos est\u00e1 bajo nuevo escrutinio tras el tiroteo en Washington","author":"","date":"noviembre 28, 2025","format":false,"excerpt":"El presidente Donald Trump culpa al Gobierno de Joe Biden por el tiroteo de esta semana contra dos miembros de la Guardia Nacional en Washington e insiste en que el sospechoso, un afgano de 29 a\u00f1os, estaba entre los millones de extranjeros que el expresidente permiti\u00f3 ingresar a Estados Unidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465067,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/02\/antecedentes-atacante-manhattan-arresto-psiquiatrico-trax\/","url_meta":{"origin":1456342,"position":3},"title":"El atacante de Manhattan ten\u00eda un arresto previo y dos ingresos psiqui\u00e1tricos, seg\u00fan fuentes. \u00bfC\u00f3mo pudo obtener un arma?","author":"","date":"agosto 2, 2025","format":false,"excerpt":"El tiroteo m\u00e1s mortal en la ciudad de Nueva York en los \u00faltimos 25 a\u00f1os \u2014en un estado con algunas de las leyes de armas m\u00e1s estrictas del pa\u00eds\u2014 est\u00e1 generando preguntas sobre c\u00f3mo un atacante con antecedentes de problemas de salud mental pudo obtener varias armas de fuego y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470150,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/01\/16\/antecedentes-crediticios-contratacion-eeuu-trax\/","url_meta":{"origin":1456342,"position":4},"title":"Un informe crediticio podr\u00eda reducir tus chances de ser contratado\u2026 pero solo en algunos casos","author":"","date":"enero 16, 2026","format":false,"excerpt":"Una verificaci\u00f3n de antecedentes puede arruinar una oferta de trabajo si a los posibles empleadores no les gusta lo que ven. Si bien Pero aunque pueden solicitar que se incluya mucha informaci\u00f3n sobre el pasado de un candidato en dicho informe, cada vez m\u00e1s se les proh\u00edbe solicitar el historial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460459,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/26\/corte-suprema-reglas-verificacion-antecedentes-armas-fantasma-trax\/","url_meta":{"origin":1456342,"position":5},"title":"La Corte Suprema confirma las reglas que exigen verificaciones de antecedentes para las &#171;armas fantasma&#187;","author":"","date":"marzo 26, 2025","format":false,"excerpt":"La Corte Suprema confirm\u00f3 este mi\u00e9rcoles las regulaciones federales del Gobierno de Joe Biden sobre las \u201carmas fantasma\u201d, (kits de venta por correo que permiten a las personas construir de forma casera armas irrastreables), lo que le dio a los grupos de control de armas una rara victoria en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456342"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456342\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}