{"id":1456349,"date":"2024-12-07T05:03:39","date_gmt":"2024-12-07T13:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/"},"modified":"2024-12-07T05:03:39","modified_gmt":"2024-12-07T13:03:39","slug":"notre-dame-donald-trump-emmanuel-macron-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/","title":{"rendered":"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds"},"content":{"rendered":"<p>La<a href=\"https:\/\/cnnespanol.cnn.com\/mundo\/notre-dame-reabrira-pronto-trax\"> catedral de Notre Dame <\/a>ser\u00e1 el tel\u00f3n de fondo del regreso del presidente electo Donald Trump a la escena geopol\u00edtica este s\u00e1bado, cuando las autoridades francesas pongan punto final al proyecto de cinco a\u00f1os para restaurar este monumento emblem\u00e1tico con una ceremonia de reapertura en la que participar\u00e1n decenas de l\u00edderes mundiales.<\/p>\n<p>A punto de regresar a la Casa Blanca en poco m\u00e1s de seis semanas, la llegada de Trump a Par\u00eds se produce en un momento decisivo para los gobiernos de Europa Occidental, que \u2013como la propia Francia\u2013 se encuentra actualmente atrapada en un tira y afloja entre un orden democr\u00e1tico progresista vacilante y los crecientes movimientos de derechas decididos a ponerlo patas arriba.<\/p>\n<p>El presidente de Francia, Emmanuel Macron, que se encuentra en su segundo mandato de cinco a\u00f1os, invit\u00f3 a Trump a asistir a la reuni\u00f3n, ya que se esfuerza por estabilizar un Gobierno que se derrumba en su pa\u00eds y, al mismo tiempo, conservar su influencia en el extranjero, sobre todo en lo que respecta al futuro del apoyo occidental a Ucrania frente a Rusia.<\/p>\n<p>Trump ha insistido en que tiene un plan para lograr una paz inmediata en la regi\u00f3n, aunque a los aliados de Ucrania les preocupa que el presidente electo pueda impulsar un alto el fuego o un acuerdo de paz que se considere m\u00e1s favorable para el presidente de Rusia, Vladimir Putin, que ha mostrado poco inter\u00e9s en abandonar su guerra de conquista.<\/p>\n<p>El \u00e9xito de Macron al traer a Trump a Par\u00eds \u2013donde \u00e9l y otros l\u00edderes proucranianos pueden exponer sus argumentos en un escenario tan luminoso\u2013 le ha valido algunos elogios cada vez menos frecuentes de la prensa francesa, que lo ha descrito como un \u201cgolpe diplom\u00e1tico\u201d. (El presidente franc\u00e9s tambi\u00e9n hab\u00eda sido el primer l\u00edder extranjero en felicitar p\u00fablicamente a Trump por ganar un segundo mandato el mes pasado). La embajada francesa anunci\u00f3 este viernes que Macron mantendr\u00e1 sucesivas reuniones con Trump y el presidente de Ucrania, Volodymyr Zelensky, antes de las ceremonias, aunque sigue sin estar claro si Trump y Zelensky mantendr\u00e1n conversaciones directas.<\/p>\n<p>Los detalles de la visita de Trump se han ido perfilando a lo largo de varios d\u00edas, pero el presidente electo ha manifestado a su equipo su deseo de asistir. Hace tiempo que siente fascinaci\u00f3n por la catedral, e incluso tuite\u00f3 angustiado hace m\u00e1s de cinco a\u00f1os cuando un incendio arras\u00f3 su edificio g\u00f3tico, situado en la \u00cele de la Cit\u00e9, una isla dentro del r\u00edo Sena de Par\u00eds. Su emblem\u00e1tica aguja y su tejado quedaron destruidos ante el horror de los telespectadores de todo el mundo.<\/p>\n<p>Los investigadores creen que el incendio fue un accidente, pero a\u00fan no han identificado la causa directa.<\/p>\n<p>\u201cTan horrible ver el incendio masivo en la catedral de Notre Dame en Par\u00eds\u201d, <a href=\"https:\/\/archive.ph\/o\/0dGLh\/https:\/\/x.com\/realDonaldTrump\/status\/1117844987293487104\">public\u00f3<\/a> Trump el 15 de abril de 2019, durante su primer mandato en el sal\u00f3n oval. \u201cTal vez se podr\u00edan usar camiones cisterna de agua voladores para apagarlo. \u00a1Hay que actuar r\u00e1pido!\u201d<\/p>\n<p>Su sugerencia fue ignorada por los bomberos y la agencia francesa de seguridad civil, S\u00e9curit\u00e9 Civile, <a href=\"https:\/\/archive.ph\/o\/0dGLh\/https:\/\/x.com\/SecCivileFrance\/status\/1117874924268376064\">respondi\u00f3<\/a> en las redes sociales menos de dos horas despu\u00e9s, advirtiendo \u2013en ingl\u00e9s\u2013 que \u201clos aviones bombarderos de agua \u2026 podr\u00edan provocar el colapso de toda la estructura de la catedral\u201d.<\/p>\n<p>Trump ha buscado durante mucho tiempo el tipo de reconocimiento de la alta sociedad que ahora le ofrecen Macron y otros l\u00edderes europeos ansiosos por la direcci\u00f3n de la administraci\u00f3n entrante, pero algunos de sus cr\u00edticos \u2013encabezados por comediantes de programas televisivos nocturnos\u2013 de vuelta en Estados Unidos se apresuraron a burlarse de la vistosa visita.<\/p>\n<p>\u201cSi todo va seg\u00fan lo previsto, le gustar\u00eda comprarlo y convertirlo en un casino\u201d, brome\u00f3 Jimmy Kimmel a principios de esta semana. Jimmy Fallon brome\u00f3 diciendo que la catedral \u201cvolver\u00e1 a arder en llamas\u201d cuando Trump entre en ella.<\/p>\n<p>Para Macron, la ocasi\u00f3n no es para tom\u00e1rsela a broma.<\/p>\n<p>Inmediatamente despu\u00e9s del incendio, se comprometi\u00f3 a reconstruir y reabrir la destruida catedral en cinco a\u00f1os, un plazo que estuvo a punto de cumplir. Hay menos margen de error, y mucho m\u00e1s en juego, en sus esfuerzos por mantener la fr\u00e1gil coalici\u00f3n que respalda a Ucrania.<\/p>\n<p>Su felicitaci\u00f3n al presidente electo el mes pasado \u2013difundida antes de que la mayor\u00eda de los medios de comunicaci\u00f3n estadounidenses dieran por ganada la carrera\u2013 alud\u00eda a su relaci\u00f3n con Trump la primera vez que estuvo en la Casa Blanca, descrita en su d\u00eda como un <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/03\/invitacion-macron-paris-muestra-poder-fluye-rapidamente-de-biden-a-trump-trax\">romance<\/a>, aunque no dur\u00f3 mucho.<\/p>\n<p>\u201cFelicidades, presidente <a href=\"https:\/\/archive.ph\/o\/0dGLh\/https:\/\/x.com\/realDonaldTrump\">@realDonaldTrump<\/a>. Listo para trabajar juntos como lo hicimos durante cuatro a\u00f1os\u201d, escribi\u00f3 Macron en X el mes pasado. \u201cCon tus convicciones y las m\u00edas. Con respeto y ambici\u00f3n. Por m\u00e1s paz y prosperidad\u201d.<\/p>\n<p>M\u00e1s tarde, por la noche, \u00e9l y Trump hablaron por tel\u00e9fono, dijo la oficina de Macron.<\/p>\n<p>El presidente franc\u00e9s ha hecho un nuevo esfuerzo por ganarse el favor del presidente que regresa y de sus aliados. CNN ha informado de que Macron planea invitar a Trump y a Elon Musk, consejero delegado de Tesla y SpaceX, a quien el presidente electo <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/27\/elon-musk-revela-nombres-empleados-publicos-despedir-asusta-trabajadores-federales-trax\">ha propuesto para desempe\u00f1ar un papel en su administraci\u00f3n<\/a>, a Par\u00eds para una cumbre sobre inteligencia artificial a principios de febrero.<\/p>\n<p>Trump no ser\u00e1 el \u00fanico emisario estadounidense en Par\u00eds este s\u00e1bado. La primera dama, Jill Biden, tambi\u00e9n tiene previsto asistir a la ceremonia, en el que ser\u00e1 su \u00faltimo viaje oficial al extranjero. Sin embargo, no est\u00e1 previsto que visite el Palacio del El\u00edseo ni que asista a ninguna reuni\u00f3n de alto nivel.<\/p>\n<p>El viaje de este s\u00e1bado tendr\u00e1 lugar una semana despu\u00e9s de que Trump <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/30\/trump-elige-charles-kushner-embajador-eeuu-francia-trax\">anunciara su selecci\u00f3n<\/a> del padre de su yerno Jared Kushner, el promotor inmobiliario Charles Kushner, como pr\u00f3ximo embajador de Estados Unidos en Francia. Charles Kushner fue <a href=\"https:\/\/archive.ph\/o\/0dGLh\/https:\/\/www.cnn.com\/2020\/12\/23\/politics\/trump-pardons-stone-manafort-kushner\/index.html\">indultado por Trump<\/a> en 2020 tras declararse culpable en 2004 de 16 cargos de evasi\u00f3n fiscal, uno de represalias contra un testigo federal y otro de mentir a la Comisi\u00f3n Federal Electoral.<\/p>\n<p>Macron no ser\u00e1 el primer l\u00edder del G7 en reunirse con Trump en persona desde las elecciones. El primer ministro de Canad\u00e1, Justin Trudeau, vol\u00f3 a Florida y <a href=\"https:\/\/archive.ph\/o\/0dGLh\/https:\/\/www.cnn.com\/2024\/11\/29\/politics\/donald-trump-justin-trudeau-dinner\/index.html\">cen\u00f3 con \u00e9l<\/a> en Mar-a-Lago el 29 de noviembre.<\/p>\n<p>Durante la cena, Trump \u2013en medio de una discusi\u00f3n sobre sus aranceles propuestos\u2013 brome\u00f3 con que Canad\u00e1 evitar\u00eda cualquier dolor convirti\u00e9ndose en el 51\u00ba estado de EE.UU., dijeron a CNN dos fuentes informadas de la conversaci\u00f3n.<\/p>\n<p>\u201cEl presidente nos estaba tomando el pelo\u201d, dijo a la prensa en Ottawa el ministro canadiense de Seguridad P\u00fablica, Dominic LeBlanc, que estaba sentado en la misma mesa. \u201cEra, por supuesto, sobre esa cuesti\u00f3n, en ning\u00fan caso un comentario serio\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La catedral de Notre Dame ser\u00e1 el tel\u00f3n de fondo del regreso del presidente electo Donald Trump a la escena geopol\u00edtica este s\u00e1bado, cuando las autoridades francesas pongan punto final al proyecto de cinco a\u00f1os para restaurar este monumento emblem\u00e1tico con una ceremonia de reapertura en la que participar\u00e1n decenas de l\u00edderes mundiales. A punto [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456349","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds - Noticias\" \/>\n<meta property=\"og:description\" content=\"La catedral de Notre Dame ser\u00e1 el tel\u00f3n de fondo del regreso del presidente electo Donald Trump a la escena geopol\u00edtica este s\u00e1bado, cuando las autoridades francesas pongan punto final al proyecto de cinco a\u00f1os para restaurar este monumento emblem\u00e1tico con una ceremonia de reapertura en la que participar\u00e1n decenas de l\u00edderes mundiales. A punto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-07T13:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds\",\"datePublished\":\"2024-12-07T13:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/\"},\"wordCount\":1216,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/\",\"name\":\"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-07T13:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds - Noticias","og_description":"La catedral de Notre Dame ser\u00e1 el tel\u00f3n de fondo del regreso del presidente electo Donald Trump a la escena geopol\u00edtica este s\u00e1bado, cuando las autoridades francesas pongan punto final al proyecto de cinco a\u00f1os para restaurar este monumento emblem\u00e1tico con una ceremonia de reapertura en la que participar\u00e1n decenas de l\u00edderes mundiales. A punto [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-07T13:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/"},"author":{"name":"","@id":""},"headline":"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds","datePublished":"2024-12-07T13:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/"},"wordCount":1216,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/","name":"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-07T13:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump volver\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\u00eds","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/07\/notre-dame-donald-trump-emmanuel-macron-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-07T13:03:39Z","datePublished":"2024-12-07T13:03:39Z","dateModified":"2024-12-07T13:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump volver\\u00e1 al escenario mundial en la reapertura de la catedral de Notre Dame en Par\\u00eds\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/07\\\/notre-dame-donald-trump-emmanuel-macron-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/07\\\/notre-dame-donald-trump-emmanuel-macron-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-07T13:03:39Z\",\"datePublished\":\"2024-12-07T13:03:39Z\",\"dateModified\":\"2024-12-07T13:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456209,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/02\/trump-viajara-paris-reapertura-notre-dame-trax\/","url_meta":{"origin":1456349,"position":0},"title":"Trump viajar\u00e1 a Par\u00eds para la reapertura de la catedral de Notre Dame","author":"","date":"diciembre 2, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El presidente electo Donald Trump planea visitar Par\u00eds a finales de esta semana para asistir a la reapertura de la Catedral de Notre Dame el 7 de diciembre, en su primer viaje al exterior tras ser elegido en noviembre para encabezar un segundo mandato.El equipo de Trump ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456358,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/07\/fotos-impresionante-restauracion-notre-dame-trax\/","url_meta":{"origin":1456349,"position":1},"title":"En fotos: la impresionante restauraci\u00f3n de Notre Dame cinco a\u00f1os despu\u00e9s del incendio","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"(CNN) -- La resurrecci\u00f3n de Notre Dame \u2014la preciada joya g\u00f3tica en el coraz\u00f3n de Par\u00eds, afectada por un devastador incendio en 2019\u2014 ha sido un secreto muy bien guardado. Pocos hab\u00edan visto el meticuloso trabajo de arquitectos, artesanos y maestros artistas que lograron devolver la vida a la catedral.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456308,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/05\/notre-dame-reabrira-pronto-trax\/","url_meta":{"origin":1456349,"position":2},"title":"Notre Dame reabrir\u00e1 pronto. Esto es lo que debes saber","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"Notre Dame, la preciada joya g\u00f3tica de Par\u00eds que se incendi\u00f3 en 2019, reabrir\u00e1 oficialmente el s\u00e1bado.Inmediatamente despu\u00e9s del incendio, el presidente de Francia, Emmanuel Macron, hizo la ambiciosa promesa de restaurar la iglesia en cinco a\u00f1os.El viernes, elogi\u00f3 a cientos de artesanos, carpinteros y otros especialistas por ayudarlo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442597,"url":"https:\/\/noticiasya.com\/palm-springs\/2023\/12\/24\/asi-ha-sido-la-restauracion-de-us-760-millones-de-la-catedral-de-notre-dame-en-paris\/","url_meta":{"origin":1456349,"position":3},"title":"As\u00ed ha sido la restauraci\u00f3n de US$ 760 millones de la catedral de Notre Dame en Par\u00eds","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"(CNN) -- La aguja de Notre Dame, coronada por un nuevo gallo dorado, recuper\u00f3 su lugar en el horizonte de Par\u00eds a mediados de diciembre de 2023.Mientras turistas y parisinos se reun\u00edan frente a la catedral, declarada Patrimonio de la Humanidad por la Unesco, para admirar el regreso de uno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456156,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/29\/notre-dame-reapertura-imagenes-iconicas-historia-trax\/","url_meta":{"origin":1456349,"position":4},"title":"Coronaciones, protestas y equilibristas: im\u00e1genes ic\u00f3nicas de la historia de Notre Dame antes de su reapertura","author":"","date":"noviembre 29, 2024","format":false,"excerpt":"(CNN) -- Durante cientos de a\u00f1os, Notre Dame fue el tel\u00f3n de fondo de algunos de los momentos m\u00e1s decisivos de la historia de Francia. Este viernes, la catedral ser\u00e1 la protagonista de la visita del presidente de Francia, Emmanuel Macron, antes de su reapertura oficial el fin de semana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457234,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/05\/trump-se-reune-georgia-meloni-en-mar-a-lago-trax\/","url_meta":{"origin":1456349,"position":5},"title":"Trump se re\u00fane con la primera ministra de Italia, Georgia Meloni, en Mar-a-Lago","author":"","date":"enero 5, 2025","format":false,"excerpt":"El presidente electo Donald Trump se reuni\u00f3 con la primera ministra de Italia, Giorgia Meloni, en Mar-a-Lago en Palm Beach, Florida, este s\u00e1bado, y su campa\u00f1a public\u00f3 una foto de los dos en X.Meloni, miembro del partido de derecha Hermanos de Italia, asumi\u00f3 el cargo en octubre de 2022. Tambi\u00e9n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456349"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456349\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}