{"id":1456367,"date":"2024-12-08T00:03:37","date_gmt":"2024-12-08T08:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/"},"modified":"2024-12-08T00:03:37","modified_gmt":"2024-12-08T08:03:37","slug":"madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/","title":{"rendered":"&#8216;Miren a mi hijo a los ojos&#8217;: la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo"},"content":{"rendered":"<p>La madre de un reh\u00e9n que aparece en el \u00faltimo video de \u201cprueba de vida\u201d publicado por Hamas redobl\u00f3 las cr\u00edticas al primer ministro de Israel, Benjamin Netanyahu, e hizo un emotivo llamado para que llegue a un acuerdo para el regreso de los cautivos.<\/p>\n<p>En un video publicado por el grupo militante el s\u00e1bado, el reh\u00e9n Matan Zangauker \u2013que parece estar hablando bajo presi\u00f3n\u2013 describe las sombr\u00edas condiciones de los t\u00faneles de Gaza donde se encuentra detenido y critica el plan del l\u00edder israel\u00ed de ofrecer una recompensa de US$ 5 millones y un pasaje seguro a cualquiera que devuelva a uno de los cautivos.<\/p>\n<p>CNN no puede verificar cu\u00e1ndo se tom\u00f3 el video, aunque parece ser reciente ya que Zangauker dice que ha estado detenido durante m\u00e1s de 420 d\u00edas y el anuncio de Netanyahu sobre la recompensa de US$ 5 millones se hizo el 29 de noviembre.<\/p>\n<p>En el video, Zangauker describe c\u00f3mo es vivir con ara\u00f1as y ratas. Dice que no tiene jab\u00f3n y que sufre enfermedades de la piel. Dice que espera que el pueblo de Israel no lo olvide y que espera volver a ver a su familia pronto.<\/p>\n<p>La familia de Zangauker dice que quiere que el mundo vea el v\u00eddeo porque es una \u201cse\u00f1al de vida\u201d.<\/p>\n<p>La madre de Zanguaker, Einav, que anteriormente critic\u00f3 la oferta de Netanyahu de una recompensa de US$ 5 millones  como \u201csobornos\u201d para los captores, volvi\u00f3 a criticar el s\u00e1bado al primer ministro diciendo que \u201cla \u00fanica forma de traer (a Matan) y a todos de vuelta es a trav\u00e9s de un acuerdo\u201d.<\/p>\n<p>\u201cEl hecho de que Matan est\u00e9 vivo hoy no significa que sobrevivir\u00e1 al invierno o a la actual presi\u00f3n militar\u201d, dijo Einav Zangauker, visiblemente conmocionada, en la manifestaci\u00f3n semanal en Tel Aviv.<\/p>\n<p>\u201cNetanyahu, mira a mi hijo a los ojos, que lleva ya 14 meses muriendo en los t\u00faneles. \u00bfQu\u00e9 pasar\u00eda si fuera tu hijo?\u201d, dijo.<\/p>\n<p>En un mensaje a su hijo, exclam\u00f3: \u201c\u00a1Mi Matan! \u00a1Mi vida! Mam\u00e1 est\u00e1 aqu\u00ed y te espera y lucha por tu regreso y el de todos\u201d.<\/p>\n<p>\u201cSi me escuchas, \u00a1ag\u00e1rrate fuerte! Debes saber que no nos detendremos ni un momento\u2026 Mantente fuerte\u201d.<\/p>\n<p>El l\u00edder de la oposici\u00f3n israel\u00ed, Yair Lapid, tambi\u00e9n pidi\u00f3 al gobierno que busque un acuerdo, a trav\u00e9s de una publicaci\u00f3n en X en la que manifest\u00f3 que estaba \u201cpetrificado\u201d por el hecho de que Matan todav\u00eda estuviera all\u00ed y pidi\u00f3 al \u201cgobierno de destrucci\u00f3n\u201d de Netanyahu que \u201cdespierte\u201d.<\/p>\n<p>La oficina de Netanyahu dijo que hab\u00eda hablado con Einav Zangauker el s\u00e1bado por la noche despu\u00e9s de la difusi\u00f3n del video. Dijo que el primer ministro le hab\u00eda dicho que \u201centiende completamente el sufrimiento dif\u00edcil que est\u00e1 atravesando Matan\u201d y que est\u00e1 \u201cactuando con fiereza y con todos los medios para devolver a Matan y a todos los rehenes a casa, tanto los vivos como los muertos\u201d.<\/p>\n<p>Las autoridades israel\u00edes creen que todav\u00eda hay 100 rehenes retenidos en Gaza.<\/p>\n<p>Zangauker y su compa\u00f1era Illana Gritzewsky fueron secuestrados del kibutz Nir Oz, uno de los varios kibutzim, o peque\u00f1os enclaves agr\u00edcolas, que soportaron la peor parte del ataque terrestre de Hamas el 7 de octubre de 2023. Nir Oz perdi\u00f3 una cuarta parte de su peque\u00f1a comunidad a causa de las balas y los secuestradores de Hamas.<\/p>\n<p>Gritzewsky fue devuelta el 30 de noviembre de 2023, como parte de un breve acuerdo de alto el fuego. Estuvo junto a la madre y la hermana de Zangauker, Natalie, en la manifestaci\u00f3n del s\u00e1bado.<\/p>\n<p>En declaraciones al Canal 11 de Israel, Gritzewsky dijo que el video \u201cme hizo regresar a mi cautiverio. No me dio esperanzas porque s\u00e9 que cada momento puede importar all\u00ed, y el hecho de que est\u00e9 vivo ahora no significa que habr\u00e1 vida ma\u00f1ana o en cinco minutos. Vi sus ojos con dolor, con miedo e incertidumbre. Escuch\u00e9 su voz pidiendo ayuda\u201d.<\/p>\n<p>El \u00faltimo video aparece una semana despu\u00e9s de que Hamas publicara im\u00e1genes similares del <a href=\"https:\/\/www.cnn.com\/2024\/11\/30\/middleeast\/edan-alexander-hostage-video-hamas-intl-latam\/index.html\">reh\u00e9n israel\u00ed-estadounidense Edan Alexander<\/a> , quien tambi\u00e9n critic\u00f3 la recompensa de US$ 5 millones de Netanyahu y pidi\u00f3 al presidente electo de Estados Unidos, Donald Trump, que ayudara a liberar a los rehenes.<\/p>\n<p>La madre de Zangauker ha sido muy cr\u00edtica con la oferta de recompensa y dijo en el momento en que se hizo que el primer ministro estaba \u201cnegociando con las vidas de los rehenes\u201d.<\/p>\n<p>Critic\u00f3 a Netanyahu por \u201cofrecer dinero a Ham\u00e1s\u201d y dijo que su intento de \u201cdividir y gobernar en Gaza mediante sobornos a los captores\u201d pondr\u00eda a los rehenes en riesgo.<\/p>\n<p>Desde hace mucho tiempo ha pedido abiertamente un acuerdo para devolver a los rehenes, hablando semanalmente afuera de la sede de las Fuerzas de Defensa de Israel en Tel Aviv, as\u00ed como afuera de la residencia de Netanyahu en Jerusal\u00e9n, en el Knesset (el parlamento israel\u00ed) y otros lugares.<\/p>\n<p>En el video publicado el s\u00e1bado, Zangauker parece reconocer los esfuerzos de su madre.<\/p>\n<p>\u201cMam\u00e1, te estoy observando y estoy escuchando mucho sobre ti, estoy al tanto de las cosas que est\u00e1s haciendo. Estoy escuchando sobre tus actividades. Estoy muy feliz de saber que est\u00e1s bien. Espero volver a verte pronto, cuando nos encontremos. Espero sentarme contigo nuevamente en la misma mesa, comer contigo, hablar contigo, beber contigo\u201d, dice.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La madre de un reh\u00e9n que aparece en el \u00faltimo video de \u201cprueba de vida\u201d publicado por Hamas redobl\u00f3 las cr\u00edticas al primer ministro de Israel, Benjamin Netanyahu, e hizo un emotivo llamado para que llegue a un acuerdo para el regreso de los cautivos. En un video publicado por el grupo militante el s\u00e1bado, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456367","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&#039;Miren a mi hijo a los ojos&#039;: la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Miren a mi hijo a los ojos&#039;: la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo - Noticias\" \/>\n<meta property=\"og:description\" content=\"La madre de un reh\u00e9n que aparece en el \u00faltimo video de \u201cprueba de vida\u201d publicado por Hamas redobl\u00f3 las cr\u00edticas al primer ministro de Israel, Benjamin Netanyahu, e hizo un emotivo llamado para que llegue a un acuerdo para el regreso de los cautivos. En un video publicado por el grupo militante el s\u00e1bado, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-08T08:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#8216;Miren a mi hijo a los ojos&#8217;: la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo\",\"datePublished\":\"2024-12-08T08:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/\"},\"wordCount\":962,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/\",\"name\":\"'Miren a mi hijo a los ojos': la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-08T08:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Miren a mi hijo a los ojos&#8217;: la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"'Miren a mi hijo a los ojos': la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"'Miren a mi hijo a los ojos': la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo - Noticias","og_description":"La madre de un reh\u00e9n que aparece en el \u00faltimo video de \u201cprueba de vida\u201d publicado por Hamas redobl\u00f3 las cr\u00edticas al primer ministro de Israel, Benjamin Netanyahu, e hizo un emotivo llamado para que llegue a un acuerdo para el regreso de los cautivos. En un video publicado por el grupo militante el s\u00e1bado, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-08T08:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/"},"author":{"name":"","@id":""},"headline":"&#8216;Miren a mi hijo a los ojos&#8217;: la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo","datePublished":"2024-12-08T08:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/"},"wordCount":962,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/","name":"'Miren a mi hijo a los ojos': la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-08T08:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#8216;Miren a mi hijo a los ojos&#8217;: la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#8216;Miren a mi hijo a los ojos&#8217;: la madre del reh\u00e9n israel\u00ed en el \u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-08T08:03:37Z","datePublished":"2024-12-08T08:03:37Z","dateModified":"2024-12-08T08:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#8216;Miren a mi hijo a los ojos&#8217;: la madre del reh\\u00e9n israel\\u00ed en el \\u00faltimo video de Hamas llama a Netanyahu a llegar a un acuerdo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/08\\\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/08\\\/madre-rehen-israeli-ultimo-video-hamas-llama-a-netanyahu-acuedo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-08T08:03:37Z\",\"datePublished\":\"2024-12-08T08:03:37Z\",\"dateModified\":\"2024-12-08T08:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455955,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/20\/netanyahu-ofrece-us-5-millones-salvoconducto-salir-gaza-devuelva-rehen-trax\/","url_meta":{"origin":1456367,"position":0},"title":"Netanyahu ofrece US$ 5 millones y un salvoconducto para salir de Gaza a quien devuelva a un reh\u00e9n","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN) \u2014 El primer ministro de Israel, Benjamin Netanyahu, ofreci\u00f3 el martes US$ 5 millones y un salvoconducto para salir de Gaza a quien devuelva a un reh\u00e9n.\"A aquellos que quieran salir de este enredo les digo: quien nos traiga un reh\u00e9n encontrar\u00e1 una salida segura para \u00e9l y su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465582,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/17\/protesta-israel-acuerdo-rehenes-gaza-trax\/","url_meta":{"origin":1456367,"position":1},"title":"Manifestantes en Israel exigen acuerdo sobre rehenes en una de las mayores protestas desde que comenz\u00f3 el conflicto en Gaza","author":"","date":"agosto 17, 2025","format":false,"excerpt":"Cientos de miles de manifestantes se reunieron alrededor de la Plaza de los Rehenes en Tel Aviv la noche del domingo, y los organizadores afirman que la cantidad de personas en la multitud super\u00f3 las 300.000.En una de las mayores manifestaciones coordinadas desde el inicio de la guerra de Israel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457226,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/04\/familia-rehen-video-hamas-oportunidad-trax\/","url_meta":{"origin":1456367,"position":2},"title":"La familia de la reh\u00e9n del \u00faltimo video de Hamas insta a Netanyahu a aprovechar &#171;la oportunidad de traerlos de vuelta&#187;","author":"","date":"enero 4, 2025","format":false,"excerpt":"La familia de una reh\u00e9n que aparece en el \u00faltimo video difundido por Hamas ha pedido al primer ministro de Israel, Benjamin Netanyahu, que aproveche la oportunidad para llegar a un acuerdo de alto el fuego, describiendo las im\u00e1genes como algo que ha \u201cdestrozado nuestros corazones\u201d.La publicaci\u00f3n del video de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462228,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/05\/11\/hamas-liberacion-edan-alexander-rehen-estadounidense-gaza-trax\/","url_meta":{"origin":1456367,"position":3},"title":"Hamas anuncia la inminente liberaci\u00f3n de Edan Alexander, el \u00faltimo reh\u00e9n estadounidense que se conoce est\u00e1 con vida en Gaza","author":"","date":"mayo 11, 2025","format":false,"excerpt":"Hamas anunci\u00f3 la inminente liberaci\u00f3n de Edan Alexander, el \u00faltimo reh\u00e9n estadounidense que se conoce est\u00e1 con vida retenido en Gaza.El jefe del equipo negociador de Hamas dijo que hab\u00edan estado en contacto con el Gobierno de Estados Unidos \u201cdurante los \u00faltimos d\u00edas\u201d en conversaciones que \u201cmostraron positivismo\u201d.Tras las comunicaciones,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470487,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/01\/26\/recuperan-restos-ultimo-rehen-israel-gaza-trax\/","url_meta":{"origin":1456367,"position":4},"title":"Israel recupera los restos del \u00faltimo reh\u00e9n en Gaza","author":"","date":"enero 26, 2026","format":false,"excerpt":"Las fuerzas israel\u00edes anunciaron el lunes que hab\u00edan recuperado los restos del \u00faltimo reh\u00e9n fallecido en Gaza cuyo cuerpo segu\u00eda en el enclave, lo que marca la primera vez desde 2014 que no hay rehenes israel\u00edes en ese territorio.Ran Gvili, un agente de polic\u00eda israel\u00ed que muri\u00f3 el 7 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459011,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/02\/21\/rehenes-netanyahu-hamas-bibas-precio-trax\/","url_meta":{"origin":1456367,"position":5},"title":"Hamas pagar\u00e1 &#171;el precio completo&#187; por no devolver el cuerpo de la reh\u00e9n, dice Netanyahu","author":"","date":"febrero 21, 2025","format":false,"excerpt":"El primer ministro de Israel, Benjam\u00edn Netanyahu, prometi\u00f3 que Hamas pagar\u00e1 \u201cel precio completo\u201d por no haber entregado los restos de una reh\u00e9n fallecida, seg\u00fan los t\u00e9rminos del acuerdo de alto el fuego en Gaza.El cuerpo de Shiri Bibas no se encontraba entre los cuatro rehenes muertos devueltos por Hamas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456367"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456367\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}