{"id":1456373,"date":"2024-12-08T09:03:49","date_gmt":"2024-12-08T17:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/"},"modified":"2024-12-08T09:03:49","modified_gmt":"2024-12-08T17:03:49","slug":"talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/","title":{"rendered":"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria"},"content":{"rendered":"<p>El Ministerio de Asuntos Exteriores de los talibanes en Afganist\u00e1n felicit\u00f3 este domingo al pueblo sirio y a las fuerzas rebeldes, en particular a Hayat Tahrir Al-Sham (HTS), tras el derrocamiento del r\u00e9gimen de Bashar al-Assad, y pidi\u00f3 el establecimiento de un gobierno isl\u00e1mico.<\/p>\n<p>Afganist\u00e1n \u201cfelicita a los dirigentes del movimiento y al pueblo de Siria por los recientes acontecimientos, que han dado lugar a la eliminaci\u00f3n de factores clave que contribuyen al conflicto y la inestabilidad\u201d, declar\u00f3 el Ministerio de Asuntos Exteriores talib\u00e1n en un comunicado.<\/p>\n<p>\u201cExpresamos la esperanza de que el proceso de transici\u00f3n de poder se lleve a cabo de una manera alineada con las aspiraciones del pueblo sirio, allanando el camino para el establecimiento de un gobierno isl\u00e1mico independiente y orientado al servicio, que d\u00e9 prioridad a la reconciliaci\u00f3n nacional, evite las divisiones y las represalias, y adopte una pol\u00edtica de amnist\u00eda general para fomentar la unidad entre todos los sirios\u201d.<\/p>\n<p>Las fuerzas rebeldes entraron en la capital de Siria, Damasco, este domingo por la ma\u00f1ana (hora local) con <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/07\/ultima-hora-guerra-en-siria-noticia-orix\/#liveblog-856d906b-7dbd-47c9-810f-57d7e9879178\">poca resistencia<\/a> del r\u00e9gimen de Bashar al-Assad y tomaron la ciudad.<\/p>\n<p>Los rebeldes se hicieron con el control de la televisi\u00f3n estatal siria e interrumpieron la programaci\u00f3n habitual para emitir un mensaje en el que <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/07\/ultima-hora-guerra-en-siria-noticia-orix\/#liveblog-228e4678-8014-4014-a1b3-a6da3dc0e9fb\">anunciaban la ca\u00edda<\/a> del r\u00e9gimen de Assad y la <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/07\/ultima-hora-guerra-en-siria-noticia-orix\/#liveblog-a31d91e5-20b3-440d-93e0-130d6bc884e7\">liberaci\u00f3n de Damasco<\/a>.<\/p>\n<p>El mensaje, acompa\u00f1ado de m\u00fasica revolucionaria y patri\u00f3tica, declaraba la \u201cvictoria de la gran revoluci\u00f3n siria y el derrocamiento del r\u00e9gimen criminal de Assad\u201d.<\/p>\n<p>\u201cLlamamos al gran pueblo sirio a proteger las propiedades p\u00fablicas y privadas\u201d, dec\u00eda otro mensaje en la televisi\u00f3n estatal.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/07\/ultima-hora-guerra-en-siria-noticia-orix\/#liveblog-a8ae3fa3-6ab0-4986-94d2-a6a0800e8253\">Se vio a rebeldes y civiles sirios<\/a> recorriendo y saqueando residencias del ahora expresidente Assad en Damasco. Mientras ni\u00f1os corr\u00edan hacia la entrada del palacio presidencial Al Rawda de Assad, se observ\u00f3 a hombres que sal\u00edan con muebles, seg\u00fan un video publicado por Reuters. Adem\u00e1s, se vio a un hombre armado portando un rifle en el palacio.<\/p>\n<p>Otro video publicado en las redes sociales mostr\u00f3 los pasillos de lo que parec\u00eda ser otra residencia en la capital, con el sonido de hombres y mujeres celebrando. \u201cEste es el dinero del pueblo\u201d, se escuch\u00f3 decir a un hombre. CNN no pudo geolocalizar el video.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/07\/ultima-hora-guerra-en-siria-noticia-orix\/#liveblog-856d906b-7dbd-47c9-810f-57d7e9879178\">Sirios en Damasco<\/a> celebraron la ca\u00edda de Bashar al-Assad, despu\u00e9s de que las fuerzas rebeldes entraran en la ciudad.<\/p>\n<p>Miles de personas se reunieron en autos y a pie en la plaza principal de Damasco para celebrar.<\/p>\n<p>Omar Daher, un abogado de 29 a\u00f1os, dijo que sus sentimientos eran \u201cindescriptibles\u201d.<\/p>\n<p>\u201cDespu\u00e9s del miedo en el que \u00e9l [Assad] y su padre nos hicieron vivir durante muchos a\u00f1os, y el p\u00e1nico y el estado de terror en el que viv\u00eda, no lo puedo creer\u201d, dijo a Associated Press.<\/p>\n<p>Otro residente de Damasco, Mohammed Amer Al-Oulabi, de 44 a\u00f1os, dijo que no pudo dormir la noche anterior hasta que escuch\u00f3 la noticia de la ca\u00edda de Assad. \u201cDe Idlib a Damasco, solo les tom\u00f3 [a las fuerzas de la oposici\u00f3n] unos d\u00edas, gracias a Dios. Que Dios los bendiga, los leones heroicos que nos hicieron sentir orgullosos\u201d.<\/p>\n<p>Un lugare\u00f1o llamado Ghazal al-Sharif declar\u00f3 que \u201cDios hab\u00eda respondido\u201d la oraci\u00f3n de \u201ctoda persona oprimida\u201d.<\/p>\n<p>La destituci\u00f3n de Assad pone fin a m\u00e1s de 50 a\u00f1os de gobierno autocr\u00e1tico de su familia en una naci\u00f3n de unos 23 millones de habitantes, que ha sido golpeada y fracturada por m\u00e1s de una d\u00e9cada de guerra civil.<\/p>\n<p>Assad abandon\u00f3 Siria, dijo el Ministerio de Relaciones Exteriores de Rusia en un comunicado este domingo.<\/p>\n<p>Assad \u201cdecidi\u00f3 dejar el cargo presidencial y abandon\u00f3 el pa\u00eds, dando instrucciones para transferir el poder pac\u00edficamente\u201d, indic\u00f3 en el comunicado, y agreg\u00f3 que \u201cRusia no particip\u00f3 en estas negociaciones\u201d<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Asuntos Exteriores de los talibanes en Afganist\u00e1n felicit\u00f3 este domingo al pueblo sirio y a las fuerzas rebeldes, en particular a Hayat Tahrir Al-Sham (HTS), tras el derrocamiento del r\u00e9gimen de Bashar al-Assad, y pidi\u00f3 el establecimiento de un gobierno isl\u00e1mico. Afganist\u00e1n \u201cfelicita a los dirigentes del movimiento y al pueblo de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456373","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Ministerio de Asuntos Exteriores de los talibanes en Afganist\u00e1n felicit\u00f3 este domingo al pueblo sirio y a las fuerzas rebeldes, en particular a Hayat Tahrir Al-Sham (HTS), tras el derrocamiento del r\u00e9gimen de Bashar al-Assad, y pidi\u00f3 el establecimiento de un gobierno isl\u00e1mico. Afganist\u00e1n \u201cfelicita a los dirigentes del movimiento y al pueblo de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-08T17:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria\",\"datePublished\":\"2024-12-08T17:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/\"},\"wordCount\":698,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/\",\"name\":\"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-08T17:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria - Noticias","og_description":"El Ministerio de Asuntos Exteriores de los talibanes en Afganist\u00e1n felicit\u00f3 este domingo al pueblo sirio y a las fuerzas rebeldes, en particular a Hayat Tahrir Al-Sham (HTS), tras el derrocamiento del r\u00e9gimen de Bashar al-Assad, y pidi\u00f3 el establecimiento de un gobierno isl\u00e1mico. Afganist\u00e1n \u201cfelicita a los dirigentes del movimiento y al pueblo de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-08T17:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/"},"author":{"name":"","@id":""},"headline":"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria","datePublished":"2024-12-08T17:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/"},"wordCount":698,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/","name":"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-08T17:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-08T17:03:49Z","datePublished":"2024-12-08T17:03:49Z","dateModified":"2024-12-08T17:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\\u00e1mico en Siria\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/08\\\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/08\\\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-08T17:03:49Z\",\"datePublished\":\"2024-12-08T17:03:49Z\",\"dateModified\":\"2024-12-08T17:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464604,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/16\/ataques-aereos-israel-siria-trax\/","url_meta":{"origin":1456373,"position":0},"title":"Tras los potentes ataques israel\u00edes en Damasco, Siria retira tropas de la ciudad de Suwayda para evitar una &#171;guerra abierta&#187;","author":"","date":"julio 16, 2025","format":false,"excerpt":"Israel llev\u00f3 a cabo el mi\u00e9rcoles una serie de poderosos ataques sobre la capital siria, Damasco, intensificando una campa\u00f1a que, seg\u00fan dice, apoya a la poblaci\u00f3n drusa del pa\u00eds, un grupo minoritario \u00e1rabe involucrado en enfrentamientos mortales con las fuerzas del Gobierno sirio.Los ataques, que seg\u00fan Siria mataron al menos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456531,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/12\/rebeldes-siria-mapas-regimen-assad-trax\/","url_meta":{"origin":1456373,"position":1},"title":"C\u00f3mo los rebeldes de Siria derrocaron el r\u00e9gimen de Assad, en 7 mapas","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Durante m\u00e1s de una d\u00e9cada, la guerra civil siria ha hecho estragos en m\u00faltiples frentes, dejando al pa\u00eds dividido y lleno de cicatrices. Y durante la mayor parte de ese largo tiempo, los combates dieron pocas se\u00f1ales de menguar. Pero entonces, en cuesti\u00f3n de un par de semanas, el r\u00e9gimen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456765,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/19\/fuerzas-seguridad-assad-armas-gobierno-siria-trax\/","url_meta":{"origin":1456373,"position":2},"title":"Ex fuerzas de seguridad de Assad entregan sus armas al nuevo gobierno de Siria","author":"","date":"diciembre 19, 2024","format":false,"excerpt":"Las fuerzas de seguridad del antiguo r\u00e9gimen sirio entregaron sus armas al gobierno de transici\u00f3n vinculado a los grupos rebeldes en la ciudad de Latakia, en el sur de Siria, seg\u00fan un video grabado por la Agence France-Presse.Las im\u00e1genes, captadas a principios de esta semana, muestran largas filas de hombres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468783,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/11\/28\/israel-incursion-siria-crimen-guerra-trax\/","url_meta":{"origin":1456373,"position":3},"title":"La incursi\u00f3n de Israel en Siria que provoc\u00f3 13 muertos es un &#171;crimen de guerra&#187;, afirma el ministro de Exteriores sirio","author":"","date":"noviembre 28, 2025","format":false,"excerpt":"Una operaci\u00f3n militar de Isarel contra una aldea siria este viernes por la ma\u00f1ana se convirti\u00f3 en el ataque m\u00e1s mort\u00edfero de una naci\u00f3n extranjera contra Siria desde el derrocamiento del exdictador Bashar al-Assad el a\u00f1o pasado.Al menos 13 personas murieron y 24 resultaron heridas durante la infiltraci\u00f3n de fuerzas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462950,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/05\/29\/siria-bandera-eeuu-embajador-trax\/","url_meta":{"origin":1456373,"position":4},"title":"Izan la bandera de EE.UU. en la residencia del embajador en Siria por primera vez en m\u00e1s de una d\u00e9cada","author":"","date":"mayo 29, 2025","format":false,"excerpt":"La bandera estadounidense fue izada sobre la residencia del embajador de Estados Unidos en Damasco este jueves por primera vez desde el cierre de la embajada en 2012 durante el levantamiento de la Primavera \u00c1rabe en Siria.Estados Unidos no ha asignado un embajador a Siria y la embajada estadounidense a\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456375,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/rebeldes-sirios-liderar-amanecer-trax\/","url_meta":{"origin":1456373,"position":5},"title":"En un pa\u00eds desgarrado por la guerra civil, \u00bfpodr\u00e1n los rebeldes sirios liderar un nuevo amanecer?","author":"","date":"diciembre 8, 2024","format":false,"excerpt":"La bandera roja, blanca, verde y negra del Ej\u00e9rcito Libre Sirio onde\u00f3 el domingo sobre Damasco mientras miles de residentes se alineaban en la plaza principal en estallidos de j\u00fabilo desafiante, despu\u00e9s de que el presidente Bashar al-Assad renunciara a su control del poder.Durante los \u00faltimos 11 d\u00edas, una alianza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456373"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456373\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}