{"id":1456403,"date":"2024-12-09T14:03:40","date_gmt":"2024-12-09T22:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/"},"modified":"2024-12-09T14:03:40","modified_gmt":"2024-12-09T22:03:40","slug":"pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/","title":{"rendered":"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU."},"content":{"rendered":"<p>Varios pasajeros del vuelo 3041 de Volaris de este domingo dicen que se sintieron aterrorizados cuando un <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/09\/mexico\/detienen-hombre-desviar-vuelo-eeuu\">hombre intent\u00f3 desviar la aeronave desde M\u00e9xico hacia Estados Unidos<\/a>. El episodio llev\u00f3 a un aterrizaje de emergencia en el aeropuerto de Guadalajara, informaron la aerol\u00ednea Volaris y las autoridades mexicanas.<\/p>\n<p>\u201cMe sent\u00ed muy aterrorizado cuando eso estaba pasando. Muchas de las personas sintieron miedo y p\u00e1nico. Fue un terror muy malo\u201d, relat\u00f3 Gerardo Gonz\u00e1lez, quien tambi\u00e9n viajaba en ese avi\u00f3n.<\/p>\n<p>Tras la detenci\u00f3n en Guadalajara del pasajero que caus\u00f3 el incidente, el vuelo continu\u00f3 hacia Tijuana (el destino previsto).<\/p>\n<p>Sobre los motivos que dio el detenido para intentar redirigir la aeronave por la fuerza, Gonz\u00e1lez asegur\u00f3 al diario que les dijo \u201cque ven\u00eda huyendo de donde viv\u00eda porque ten\u00eda amenazas de muerte\u201d y que, para tranquilizarlo, la tripulaci\u00f3n de la aeronave anunci\u00f3 que aterrizar\u00edan en San Diego, California, pero que finalmente llegaron a Guadalajara, Jalisco.<\/p>\n<p>La Fiscal\u00eda de Jalisco le dijo a CNN que el detenido se encuentra hospitalizado y que su estado de salud es delicado. Agreg\u00f3 que el Ministerio P\u00fablico cuenta con un plazo de 48 horas para resolver su situaci\u00f3n jur\u00eddica.<\/p>\n<p>Jes\u00fas Torres, residente estadounidense que viajaba en el mismo avi\u00f3n y quien dice que ayud\u00f3 a tranquilizar al pasajero, expres\u00f3 preocupaci\u00f3n por la seguridad del hombre y de su familia, que viajaba con \u00e9l. Agreg\u00f3 que el pasajero que encabez\u00f3 el incidente amenaz\u00f3 con un l\u00e1piz a una de las asistentes de vuelo.<\/p>\n<p>\u201cYo creo que hice lo correcto, hice lo necesario por bien de todos, por la seguridad de \u00e9l, y la tripulaci\u00f3n, ya que tra\u00eda amagada a la aeromoza y todo se junt\u00f3, entonces, yo creo que hice la parte humana. Mi parte fue la parte humana de hacer las cosas lo mejor posible, lo que m\u00e1s se me vino a la mente, velar por la seguridad de la aeromoza y de \u00e9l mismo, por la confusi\u00f3n en la que se encontraba\u201d, narr\u00f3 Torres.<\/p>\n<p>Torres afirm\u00f3 que temi\u00f3 que estuviera armado y que no hubo apoyo por parte de las autoridades. Adem\u00e1s, dijo que al bajar del avi\u00f3n se encontr\u00f3 con la acompa\u00f1ante del pasajero detenido sin los menores. \u201cYo no vi mucha seguridad que se le debi\u00f3 haber dado a esta familia, protecci\u00f3n\u201d, cont\u00f3.<\/p>\n<p>CNN intenta comunicarse con Volaris, as\u00ed como con la FGR, para obtener comentarios sobre el apoyo que brindaron a los pasajeros del vuelo tras el incidente.<\/p>\n<p>Durante su rueda de prensa diaria, la presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este lunes que la Fiscal\u00eda General de la Rep\u00fablica (FGR) ser\u00e1 la que informe sobre el incidente, sobre qu\u00e9 delito ha cometido el detenido, y qu\u00e9 consecuencias habr\u00e1.<\/p>\n<p>La aerol\u00ednea inform\u00f3 en un comunicado que se ha constituido como parte acusadora para asegurar que esa persona enfrente todo el peso de la ley hasta sus \u00faltimas consecuencias.<\/p>\n<p><em>\u2013\u2013 Bel\u00e9n Zapata colabor\u00f3 con este reporte.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Varios pasajeros del vuelo 3041 de Volaris de este domingo dicen que se sintieron aterrorizados cuando un hombre intent\u00f3 desviar la aeronave desde M\u00e9xico hacia Estados Unidos. El episodio llev\u00f3 a un aterrizaje de emergencia en el aeropuerto de Guadalajara, informaron la aerol\u00ednea Volaris y las autoridades mexicanas. \u201cMe sent\u00ed muy aterrorizado cuando eso estaba [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456403","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"Varios pasajeros del vuelo 3041 de Volaris de este domingo dicen que se sintieron aterrorizados cuando un hombre intent\u00f3 desviar la aeronave desde M\u00e9xico hacia Estados Unidos. El episodio llev\u00f3 a un aterrizaje de emergencia en el aeropuerto de Guadalajara, informaron la aerol\u00ednea Volaris y las autoridades mexicanas. \u201cMe sent\u00ed muy aterrorizado cuando eso estaba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T22:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU.\",\"datePublished\":\"2024-12-09T22:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/\"},\"wordCount\":548,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/\",\"name\":\"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-09T22:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU. - Noticias","og_description":"Varios pasajeros del vuelo 3041 de Volaris de este domingo dicen que se sintieron aterrorizados cuando un hombre intent\u00f3 desviar la aeronave desde M\u00e9xico hacia Estados Unidos. El episodio llev\u00f3 a un aterrizaje de emergencia en el aeropuerto de Guadalajara, informaron la aerol\u00ednea Volaris y las autoridades mexicanas. \u201cMe sent\u00ed muy aterrorizado cuando eso estaba [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-09T22:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/"},"author":{"name":"","@id":""},"headline":"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU.","datePublished":"2024-12-09T22:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/"},"wordCount":548,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/","name":"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-09T22:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU.","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-09T22:03:40Z","datePublished":"2024-12-09T22:03:40Z","dateModified":"2024-12-09T22:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Pasajeros cuentan c\\u00f3mo tranquilizaron al hombre que trat\\u00f3 de desviar un vuelo de M\\u00e9xico a EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/09\\\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/09\\\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-09T22:03:40Z\",\"datePublished\":\"2024-12-09T22:03:40Z\",\"dateModified\":\"2024-12-09T22:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456391,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/detienen-hombre-desviar-vuelo-eeuu\/","url_meta":{"origin":1456403,"position":0},"title":"Detienen a un hombre por supuestamente intentar desviar un vuelo interno de M\u00e9xico a EE.UU.","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"Un pasajero fue detenido el domingo tras intentar presuntamente desviar un vuelo nacional de M\u00e9xico a Estados Unidos, seg\u00fan informaron la aerol\u00ednea Volaris y las autoridades mexicanas. Actualmente se est\u00e1 llevando a cabo una investigaci\u00f3n.Tras despegar de El Baj\u00edo con destino a Tijuana, el pasajero intent\u00f3 desviar la aeronave por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456376,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/","url_meta":{"origin":1456403,"position":1},"title":"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos","author":"","date":"diciembre 8, 2024","format":false,"excerpt":"La ma\u00f1ana de este domingo un pasajero intent\u00f3 apoderarse de un avi\u00f3n que cubr\u00eda la ruta de El Baj\u00edo, en el centro de M\u00e9xico, a la fronteriza Tijuana y desviarlo hacia Estados Unidos, pero fue detenido y puesto a disposici\u00f3n de las autoridades, inform\u00f3 la aerol\u00ednea mexicana Volaris.\u201cVolaris informa que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469458,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/12\/20\/agencia-aviacion-investiga-incidente-piloto-orix\/","url_meta":{"origin":1456403,"position":2},"title":"La Agencia de Aviaci\u00f3n de M\u00e9xico investiga incidente en el que un piloto retuvo un vuelo","author":"","date":"diciembre 20, 2025","format":false,"excerpt":"La Agencia Federal de Aviaci\u00f3n Civil del Gobierno de M\u00e9xico (AFAC) inici\u00f3 este viernes una investigaci\u00f3n a ra\u00edz de un incidente en el que un piloto inconforme con sus condiciones laborales retuvo moment\u00e1neamente un vuelo programado para viajar del Aeropuerto Internacional de la Ciudad de M\u00e9xico, la principal terminal a\u00e9rea\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469246,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/12\/13\/united-airlines-tokio-incendio-dulles-trax\/","url_meta":{"origin":1456403,"position":3},"title":"Vuelo de United a Tokio regresa a Dulles tras perder potencia en motor y generar incendio en vegetaci\u00f3n cercana a la pista","author":"","date":"diciembre 13, 2025","format":false,"excerpt":"El vuelo 803 de United Airlines perdi\u00f3 potencia en un motor y encendi\u00f3 algo de maleza alrededor de la pista mientras despegaba del Aeropuerto Dulles la tarde de este s\u00e1bado, seg\u00fan portavoces de United y de la Autoridad de Aeropuertos Metropolitanos de Washington.\u201cEl fuego fue extinguido y el vuelo regres\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446755,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/09\/batik-pilotos-dormidos-en-vuelo-trax\/","url_meta":{"origin":1456403,"position":4},"title":"Investigar\u00e1n a Batik Air de Indonesia despu\u00e9s de que dos pilotos se quedaran dormidos durante un vuelo","author":"","date":"marzo 9, 2024","format":false,"excerpt":"(CNN) -- El Ministerio de Transporte de Indonesia lanzar\u00e1 una investigaci\u00f3n sobre la aerol\u00ednea local Batik Air despu\u00e9s de que dos de sus pilotos se quedaran dormidos durante un vuelo reciente, inform\u00f3 la agencia de noticias estatal Antara citando a la directora general de aviaci\u00f3n civil del ministerio, M. Kristi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451449,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/07\/26\/gobierno-venezuela-retrasa-vuelo-mireya-moscoso-panama-orix\/","url_meta":{"origin":1456403,"position":5},"title":"Gobierno de Venezuela retrasa despegue de vuelo a Caracas con Mireya Moscoso a bordo, denuncia el presidente de Panam\u00e1","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Gobierno de Venezuela ha retrasado este viernes el despegue de un avi\u00f3n de la aerol\u00ednea Copa que cubre el tramo Ciudad de Panam\u00e1-Caracas y que lleva entre sus pasajeros a la expresidenta de Panam\u00e1 Mireya Moscoso y a otros exmandatarios, inform\u00f3 en X\u00a0el presidente del pa\u00eds centroamericano,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456403"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456403\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}