{"id":1456405,"date":"2024-12-09T15:03:42","date_gmt":"2024-12-09T23:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/"},"modified":"2024-12-09T15:03:42","modified_gmt":"2024-12-09T23:03:42","slug":"analisis-abu-mohammad-al-jolani-lider-siria-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/","title":{"rendered":"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios"},"content":{"rendered":"<p>El Departamento de Estado de Estados Unidos anunci\u00f3 una recompensa de hasta US$ 10 millones por informaci\u00f3n que conduzca a la captura de Abu Mohammad al-Jolani, a quien la agencia design\u00f3 por primera vez como terrorista hace m\u00e1s de una d\u00e9cada, diciendo que su grupo hab\u00eda llevado a cabo \u201cm\u00faltiples ataques terroristas en toda Siria\u201d. Sin embargo, Jolani es tambi\u00e9n el l\u00edder de las fuerzas rebeldes que acaban de derrocar al r\u00e9gimen tir\u00e1nico del dictador sirio Bashar al-Assad, en una ofensiva r\u00e1pida que sorprendi\u00f3 al mundo.<\/p>\n<p>Como resultado, Jolani es ahora el l\u00edder de facto de m\u00e1s de 23 millones de sirios y de los varios <a href=\"https:\/\/data.who.int\/countries\/760%20https:\/www.unrefugees.org\/news\/syria-refugee-crisis-explained\/\">millones de refugiados<\/a> sirios que se encuentran fuera de su pa\u00eds, muchos de los cuales seguramente querr\u00e1n volver a casa ahora que Assad se ha ido.<\/p>\n<p>Entonces, \u00bfqui\u00e9n es Jolani y qu\u00e9 es lo que busca? Como \u201ccombatiente extranjero\u201d sirio de unos 20 a\u00f1os, Jolani cruz\u00f3 a Iraq para luchar contra los estadounidenses cuando invadieron el pa\u00eds en la primavera de 2003. Esto lo llev\u00f3 a la tristemente c\u00e9lebre prisi\u00f3n iraqu\u00ed de Camp Bucca, dirigida por Estados Unidos, que se convirti\u00f3 en un campo de reclutamiento clave para los grupos terroristas, incluido el que se convertir\u00eda en ISIS.<\/p>\n<p>Una vez liberado, Jolani regres\u00f3 a Siria y comenz\u00f3 a luchar contra el r\u00e9gimen de Assad con el apoyo de Abu Bakr al-Baghdadi, que m\u00e1s tarde se convertir\u00eda en el fundador del ISIS.<\/p>\n<p>En Siria, Jolani fund\u00f3 un grupo combatiente conocido como Jabhat al-Nusra (\u201cel Frente de la Victoria\u201d, en espa\u00f1ol), que prometi\u00f3 lealtad a al-Qaeda, pero en 2016 Jolani se separ\u00f3 del grupo terrorista, seg\u00fan el Centro de An\u00e1lisis Navales de Estados Unidos.<\/p>\n<p>Desde entonces, a diferencia de al-Qaeda, que promov\u00eda una quijotesca guerra santa a nivel mundial, el grupo de Jolani, ahora conocido por las siglas HTS (Hayat Tahrir al-Sham), ha emprendido la labor m\u00e1s prosaica de intentar gobernar a millones de personas en la provincia noroccidental siria de Idlib, proporcionando servicios b\u00e1sicos, seg\u00fan el estudioso del terrorismo Aaron Zalin, que escribi\u00f3 un libro sobre el grupo HTS.<\/p>\n<p>Jolani rara vez concede entrevistas a organizaciones de noticias occidentales, pero el jueves habl\u00f3 con Jomana Karadsheh, de CNN. En esa entrevista, Jolani se esforz\u00f3 por distanciarse de grupos terroristas sun\u00edes como ISIS y Al Qaeda, diciendo: \u201cLa gente que teme la gobernanza isl\u00e1mica o bien ha visto implementaciones incorrectas de la misma o no la entiende correctamente\u201d.<\/p>\n<p>Tambi\u00e9n intent\u00f3 tranquilizar a la minor\u00eda alauita y cristiana de Siria afirmando: \u201cEstas sectas han coexistido en esta regi\u00f3n durante cientos de a\u00f1os, y nadie tiene derecho a eliminarlas\u201d.<\/p>\n<p>Jolani, que ahora tiene 42 a\u00f1os, tambi\u00e9n declar\u00f3 a CNN que ha madurado desde que luchaba contra los estadounidenses en Iraq, hace dos d\u00e9cadas. \u201cUna persona de veinte a\u00f1os tendr\u00e1 una personalidad diferente a la de alguien de treinta o cuarenta, y desde luego a la de alguien de cincuenta\u201d, se\u00f1al\u00f3.<\/p>\n<p>Es dif\u00edcil evaluar la veracidad de las recientes declaraciones apaciguadoras de Jolani y lo que podr\u00edan significar a largo plazo, aunque sus hombres no han llevado a cabo masacres sectarias al estilo de ISIS a la hora de tomar ciudades sirias.<\/p>\n<p>Desde la perspectiva estadounidense, un indicador positivo ser\u00eda tambi\u00e9n si Jolani ayuda a encontrar a Austin Tice, periodista estadounidense desaparecido en Siria hace una docena de a\u00f1os y de quien el presidente Joe Biden dijo el domingo que cre\u00eda que segu\u00eda vivo.<\/p>\n<p>Entonces, \u00bfes Jolani simplemente el mismo vino yihadista de siempre reenvasado en una nueva botella \u201cinclusiva\u201d? \u00bfO se parece m\u00e1s a un l\u00edder islamista como el presidente de Turqu\u00eda, Recep Tayyip Erdogan, que, aunque no es un dem\u00f3crata liberal, no desat\u00f3 una limpieza sectaria entre su poblaci\u00f3n?<\/p>\n<p>Vale la pena recordar que los talibanes se posicionaron a s\u00ed mismos como unos talibanes 2.0 m\u00e1s amables y gentiles antes de apoderarse de todo Afganist\u00e1n en el verano de 2021, y ahora gobiernan con pu\u00f1o de hierro mis\u00f3gino al igual que lo hicieron la \u00faltima vez que estuvieron en el poder, antes de los atentados del 11 de septiembre. Y cuando ISIS se apoder\u00f3 de gran parte de Iraq hace una d\u00e9cada, el ej\u00e9rcito terrorista suprimi\u00f3 sin piedad a casi todos los grupos \u00e9tnicos y religiosos que no fueran sun\u00edes. Por tanto, el trato que Jolani d\u00e9 a los alauitas y cristianos que ahora gobierna ser\u00e1 un indicador importante de su verdadera personalidad.<\/p>\n<p>Por su parte, el gobierno de Biden no quiere correr riesgos sobre si Jolani tiene la capacidad de gestionar la amenaza de ISIS. El Mando Central de Estados Unidos anunci\u00f3 el domingo que hab\u00eda llevado a cabo m\u00e1s de 75 ataques contra presuntos campamentos y operativos de ISIS en el centro de Siria.<\/p>\n<p>El s\u00e1bado, el presidente electo Donald Trump public\u00f3 sobre Siria en may\u00fasculas: \u201cESTA NO ES NUESTRA LUCHA. DEJEMOS QUE SE DESARROLLE. NO NOS INVOLUCREMOS\u201d. Pero Estados Unidos ya est\u00e1 involucrado en Siria, con casi 1.000 soldados estadounidenses desplegados all\u00ed en una misi\u00f3n contra ISIS.<\/p>\n<p>Las fuerzas estadounidenses han estado en Siria desde hace una d\u00e9cada y, durante su primer mandato, Trump fue y vino sobre la retirada de todas ellas. Qu\u00e9 hacer con esas fuerzas estadounidenses en Siria es una decisi\u00f3n a la que Trump probablemente se enfrentar\u00e1 al asumir el cargo.<\/p>\n<p>En 2003, los estadounidenses derrocaron a otro dictador baazista, el iraqu\u00ed Sadam Hussein, y despidieron a 30.000 miembros del partido Baaz que dirig\u00edan el pa\u00eds. Tambi\u00e9n disolvieron alrededor de medio mill\u00f3n de miembros de las fuerzas armadas iraqu\u00edes. Esto colaps\u00f3 simult\u00e1neamente el gobierno de Iraq al tiempo que creaba un gran cuadro de hombres furiosos, armados y entrenados, algunos de los cuales se unieron a la insurgencia que se enfrentaba a las fuerzas estadounidenses. Jolani luchaba entonces contra los estadounidenses en Iraq, por lo que es de suponer que conoce esta instructiva historia.<\/p>\n<p>En Libia, en 2011, una campa\u00f1a de bombardeos de la OTAN liderada por Estados Unidos contribuy\u00f3 a la ca\u00edda de otro brutal dictador laico, Moammar Gadhafi. Trece a\u00f1os despu\u00e9s, Libia sigue inmersa en una guerra civil en la que pa\u00edses como Emiratos \u00c1rabes Unidos, Qatar, Rusia, Turqu\u00eda y Estados Unidos apoyan o atacan a diversas facciones.<\/p>\n<p>Tal vez Jolani sea capaz de poner orden en Siria manteniendo a muchos de los bur\u00f3cratas de Assad en sus puestos, de modo que el pa\u00eds siga siendo gobernado al tiempo que se aplica una estrategia \u201cincluyente\u201d para proteger a todas las minor\u00edas religiosas de Siria.<\/p>\n<p>Jolani gan\u00f3 la guerra contra uno de los dictadores m\u00e1s repugnantes del siglo XXI. Ahora empieza lo dif\u00edcil.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Estado de Estados Unidos anunci\u00f3 una recompensa de hasta US$ 10 millones por informaci\u00f3n que conduzca a la captura de Abu Mohammad al-Jolani, a quien la agencia design\u00f3 por primera vez como terrorista hace m\u00e1s de una d\u00e9cada, diciendo que su grupo hab\u00eda llevado a cabo \u201cm\u00faltiples ataques terroristas en toda Siria\u201d. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456405","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Estado de Estados Unidos anunci\u00f3 una recompensa de hasta US$ 10 millones por informaci\u00f3n que conduzca a la captura de Abu Mohammad al-Jolani, a quien la agencia design\u00f3 por primera vez como terrorista hace m\u00e1s de una d\u00e9cada, diciendo que su grupo hab\u00eda llevado a cabo \u201cm\u00faltiples ataques terroristas en toda Siria\u201d. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T23:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios\",\"datePublished\":\"2024-12-09T23:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/\"},\"wordCount\":1187,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/\",\"name\":\"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-09T23:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios - Noticias","og_description":"El Departamento de Estado de Estados Unidos anunci\u00f3 una recompensa de hasta US$ 10 millones por informaci\u00f3n que conduzca a la captura de Abu Mohammad al-Jolani, a quien la agencia design\u00f3 por primera vez como terrorista hace m\u00e1s de una d\u00e9cada, diciendo que su grupo hab\u00eda llevado a cabo \u201cm\u00faltiples ataques terroristas en toda Siria\u201d. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-09T23:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios","datePublished":"2024-12-09T23:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/"},"wordCount":1187,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/","name":"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-09T23:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-09T23:03:42Z","datePublished":"2024-12-09T23:03:42Z","dateModified":"2024-12-09T23:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | Qui\\u00e9n es y qu\\u00e9 busca Abu Mohammad al-Jolani, l\\u00edder de los rebeldes sirios\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/09\\\/analisis-abu-mohammad-al-jolani-lider-siria-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/09\\\/analisis-abu-mohammad-al-jolani-lider-siria-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-09T23:03:42Z\",\"datePublished\":\"2024-12-09T23:03:42Z\",\"dateModified\":\"2024-12-09T23:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456375,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/rebeldes-sirios-liderar-amanecer-trax\/","url_meta":{"origin":1456405,"position":0},"title":"En un pa\u00eds desgarrado por la guerra civil, \u00bfpodr\u00e1n los rebeldes sirios liderar un nuevo amanecer?","author":"","date":"diciembre 8, 2024","format":false,"excerpt":"La bandera roja, blanca, verde y negra del Ej\u00e9rcito Libre Sirio onde\u00f3 el domingo sobre Damasco mientras miles de residentes se alineaban en la plaza principal en estallidos de j\u00fabilo desafiante, despu\u00e9s de que el presidente Bashar al-Assad renunciara a su control del poder.Durante los \u00faltimos 11 d\u00edas, una alianza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456371,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/jolani-celebra-derrocamiento-assad-siria-trax\/","url_meta":{"origin":1456405,"position":1},"title":"El l\u00edder rebelde sirio Jolani celebra la &#171;victoria&#187; en sus primeros comentarios desde el derrocamiento de Assad","author":"","date":"diciembre 8, 2024","format":false,"excerpt":"El l\u00edder del principal grupo que se encuentra detr\u00e1s de la oposici\u00f3n armada de Siria, Abu Mohammad al-Jolani, calific\u00f3 el derrocamiento del presidente Assad como una \u201cvictoria para toda la naci\u00f3n isl\u00e1mica\u201d en sus primeras declaraciones p\u00fablicas desde que los rebeldes capturaron Damasco.\u201cEsta victoria, mis hermanos, es una victoria para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456765,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/19\/fuerzas-seguridad-assad-armas-gobierno-siria-trax\/","url_meta":{"origin":1456405,"position":2},"title":"Ex fuerzas de seguridad de Assad entregan sus armas al nuevo gobierno de Siria","author":"","date":"diciembre 19, 2024","format":false,"excerpt":"Las fuerzas de seguridad del antiguo r\u00e9gimen sirio entregaron sus armas al gobierno de transici\u00f3n vinculado a los grupos rebeldes en la ciudad de Latakia, en el sur de Siria, seg\u00fan un video grabado por la Agence France-Presse.Las im\u00e1genes, captadas a principios de esta semana, muestran largas filas de hombres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456384,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/discurso-lider-rebelde-sirio-iran-trump-trax\/","url_meta":{"origin":1456405,"position":3},"title":"AN\u00c1LISIS | El discurso de victoria del l\u00edder rebelde sirio contiene un mensaje tanto para Ir\u00e1n como para Trump e Israel","author":"","date":"diciembre 8, 2024","format":false,"excerpt":"El camino que recorri\u00f3 Abu Mohammad al-Jolani hasta Damasco fue largo. Ha hablado abiertamente de su cambio a lo largo del recorrido: de joven combatiente de al Qaeda hace dos d\u00e9cadas a comandante de fuerzas rebeldes que defienden la tolerancia sectaria.Es un viaje en el que tuvo mucho tiempo para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456390,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/tras-decadas-brutal-regimen-el-regimen-bashar-al-assad-derrocado-trax\/","url_meta":{"origin":1456405,"position":4},"title":"Tras d\u00e9cadas de brutal r\u00e9gimen, el r\u00e9gimen de Bashar al-Assad fue derrocado.","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"Los sirios, que llevan mucho tiempo sufriendo, mostraron su j\u00fabilo en las calles despu\u00e9s de que una de las dictaduras m\u00e1s brutales del mundo se derrumb\u00f3 repentinamente en pocas semanas.Durante medio siglo, la familia Assad gobern\u00f3 Siria con pu\u00f1o de hierro, con informes largamente documentados de encarcelamientos masivos, torturas, ejecuciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456576,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/13\/rebeldes-islamistas-sirios-gobernar-trax\/","url_meta":{"origin":1456405,"position":5},"title":"\u00bfPueden los rebeldes islamistas sirios gobernar el pa\u00eds? Su dominio en Idlib ofrece pistas","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"Cuando el primer ministro nombrado por los rebeldes de Siria se sent\u00f3 el martes por primera vez con funcionarios del derrocado r\u00e9gimen de Assad, el tel\u00f3n de fondo inclu\u00eda la bandera de la revoluci\u00f3n siria junto a otra que llevaba la declaraci\u00f3n isl\u00e1mica de fe que a menudo es exhibida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456405"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456405\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}