{"id":1456410,"date":"2024-12-09T16:03:42","date_gmt":"2024-12-10T00:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/"},"modified":"2024-12-09T16:03:42","modified_gmt":"2024-12-10T00:03:42","slug":"masacre-pandillas-haiti-muertos-vudu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/","title":{"rendered":"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos"},"content":{"rendered":"<p>El Gobierno de Hait\u00ed afirm\u00f3 que las pandillas del pa\u00eds cruzaron una \u201cl\u00ednea roja\u201d despu\u00e9s de haber matado supuestamente a m\u00e1s de 180 personas durante el fin de semana, luego de que un l\u00edder de una pandilla culpara a los practicantes del vud\u00fa por la grave enfermedad de su hijo.<\/p>\n<p>Un comunicado de la oficina del primer ministro de Hait\u00ed acus\u00f3 al l\u00edder de la pandilla Micanor \u201cMikan\u00f2\u201d Alt\u00e8s y a sus asociados de ejecutar la masacre del 6 y 7 de diciembre en la empobrecida Cit\u00e9 Soleil, en la capital de Hait\u00ed, Puerto Pr\u00edncipe.<\/p>\n<p>Micanor orden\u00f3 la muerte de residentes ancianos en el \u00e1rea de Wharf J\u00e9r\u00e9mie por sospechas de que la brujer\u00eda hab\u00eda enfermado a su hijo, seg\u00fan la Red Nacional de Defensa de los Derechos Humanos de Hait\u00ed (RNDDH).<\/p>\n<p>\u201cLa masacre fue causada por la grave enfermedad de su hijo. Micanor busc\u00f3 el consejo de un sacerdote vud\u00fa (\u2018b\u00f3k\u00f2\u2019) que acus\u00f3 a los ancianos de la zona de practicar brujer\u00eda y afectar al ni\u00f1o\u201d, dijo RNDDH en un informe visto por CNN. El vud\u00fa se practica ampliamente en partes de la sociedad haitiana.<\/p>\n<p>\u201cEl viernes 6 de diciembre, Micanor dispar\u00f3 y mat\u00f3 a por lo menos sesenta personas mayores. El s\u00e1bado 7 de diciembre, \u00e9l y su grupo mataron a por lo menos cincuenta personas m\u00e1s usando machetes y cuchillos. A pesar de sus acciones, su hijo enfermo falleci\u00f3\u201d, indic\u00f3.<\/p>\n<p>Citando fuentes de la zona, el Comit\u00e9 para la Paz y el Desarrollo de Hait\u00ed (CPD) tambi\u00e9n dijo que el ataque ten\u00eda como objetivo \u201ctodas las personas mayores y los practicantes de vud\u00fa que, en la imaginaci\u00f3n (de Micanor), ser\u00edan capaces de lanzar un hechizo mal\u00e9fico sobre su hijo\u201d, y dej\u00f3 los cuerpos de las v\u00edctimas mutilados en las calles.<\/p>\n<p>Al menos 184 personas murieron en la masacre, incluidos unos 127 hombres y mujeres mayores, seg\u00fan Naciones Unidas.<\/p>\n<p>\u201cEstos \u00faltimos episodios elevan el n\u00famero de muertos solo este a\u00f1o en Hait\u00ed a una asombrosa cifra de 5.000 personas\u201d, dijo el Alto Comisionado para los Derechos Humanos, Volker T\u00fcrk, en una conferencia de prensa el lunes.<\/p>\n<p>Desde la masacre, Wharf J\u00e9r\u00e9mie permanece \u201cbajo un asedio informal\u201d con residentes ancianos y seguidores del vud\u00fa todav\u00eda en la mira de la alianza m\u00e1s amplia de pandillas haitianas Viv Ansamn, seg\u00fan RNDDH.<\/p>\n<p>El gobierno de transici\u00f3n de Hait\u00ed prometi\u00f3 encontrar a los culpables y llevarlos ante la justicia. \u201cSe cruz\u00f3 una l\u00ednea roja y el Estado movilizar\u00e1 todas sus fuerzas para localizar y aniquilar a estos criminales\u201d, afirma un comunicado de la oficina del primer ministro.<\/p>\n<p>Durante el \u00faltimo a\u00f1o, pandillas bajo el nombre de Viv Ansamn devastaron Puerto Pr\u00edncipe, atacaron instituciones estatales, incluidas prisiones, estaciones de polic\u00eda y el aeropuerto internacional de la ciudad, y obligaron a cientos de miles de civiles haitianos a huir de sus hogares.<\/p>\n<p>El creciente caos causado por las pandillas llev\u00f3 a la comunidad internacional a enviar una fuerza policial multinacional a la naci\u00f3n caribe\u00f1a durante el verano, pero hasta ahora el llamado MSS no ha logrado frenar la violencia extrema en Puerto Pr\u00edncipe.<\/p>\n<p>Este lunes, el secretario general de la ONU, Ant\u00f3nio Guterres, inst\u00f3 a los Estados miembros a brindar m\u00e1s apoyo a la misi\u00f3n multinacional y pidi\u00f3 una investigaci\u00f3n sobre la masacre.<\/p>\n<p>La Polic\u00eda Nacional de Hait\u00ed hab\u00eda insistido durante el fin de semana en que las operaciones conjuntas con el MSS respaldado por Estados Unidos se estaban desarrollando sin problemas, y neg\u00f3 lo que describi\u00f3 como rumores en l\u00ednea de que las dos fuerzas \u201cno estaban trabajando en perfecta armon\u00eda\u201d.<\/p>\n<p><em>\u2013\u2013 Sharon Braithwaite de CNN contribuy\u00f3 con este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Hait\u00ed afirm\u00f3 que las pandillas del pa\u00eds cruzaron una \u201cl\u00ednea roja\u201d despu\u00e9s de haber matado supuestamente a m\u00e1s de 180 personas durante el fin de semana, luego de que un l\u00edder de una pandilla culpara a los practicantes del vud\u00fa por la grave enfermedad de su hijo. Un comunicado de la oficina [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456410","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Hait\u00ed afirm\u00f3 que las pandillas del pa\u00eds cruzaron una \u201cl\u00ednea roja\u201d despu\u00e9s de haber matado supuestamente a m\u00e1s de 180 personas durante el fin de semana, luego de que un l\u00edder de una pandilla culpara a los practicantes del vud\u00fa por la grave enfermedad de su hijo. Un comunicado de la oficina [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T00:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos\",\"datePublished\":\"2024-12-10T00:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/\"},\"wordCount\":675,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/\",\"name\":\"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-10T00:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos - Noticias","og_description":"El Gobierno de Hait\u00ed afirm\u00f3 que las pandillas del pa\u00eds cruzaron una \u201cl\u00ednea roja\u201d despu\u00e9s de haber matado supuestamente a m\u00e1s de 180 personas durante el fin de semana, luego de que un l\u00edder de una pandilla culpara a los practicantes del vud\u00fa por la grave enfermedad de su hijo. Un comunicado de la oficina [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-10T00:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/"},"author":{"name":"","@id":""},"headline":"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos","datePublished":"2024-12-10T00:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/"},"wordCount":675,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/","name":"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-10T00:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-10T00:03:42Z","datePublished":"2024-12-10T00:03:42Z","dateModified":"2024-12-10T00:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Masacre en Hait\\u00ed deja m\\u00e1s de 180 muertos tras acusaciones de pr\\u00e1cticas de vud\\u00fa, dicen ONU y grupos de derechos humanos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/09\\\/masacre-pandillas-haiti-muertos-vudu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/09\\\/masacre-pandillas-haiti-muertos-vudu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-10T00:03:42Z\",\"datePublished\":\"2024-12-10T00:03:42Z\",\"dateModified\":\"2024-12-10T00:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472701,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/03\/30\/haiti-masacre-banda-criminal-muertos-orix\/","url_meta":{"origin":1456410,"position":0},"title":"Mueren al menos 16 personas en una masacre perpetrada por una banda criminal en Hait\u00ed, seg\u00fan la polic\u00eda","author":"","date":"marzo 30, 2026","format":false,"excerpt":"Al menos 16 personas murieron en una masacre ocurrida el domingo en Hait\u00ed, perpetrada por el grupo armado Gran Grif en Jean Denis, al norte de la capital Puerto Pr\u00edncipe, seg\u00fan inform\u00f3 este lunes la Polic\u00eda Nacional (PNH).Las autoridades dijeron que la banda criminal bloque\u00f3 caminos para impedir la llegada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449736,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/24\/pareja-misioneros-estadounidenses-pandilla-asesinados-haiti-trax\/","url_meta":{"origin":1456410,"position":1},"title":"Pandilla asesina a pareja de misioneros estadounidenses en Hait\u00ed, dice la familia","author":"","date":"mayo 24, 2024","format":false,"excerpt":"(CNN) -- Un matrimonio estadounidense que serv\u00eda como misionero en Hait\u00ed fue asesinado all\u00ed este jueves, dijeron familiares.Davy y Natalie \"fueron atacados por pandillas esta noche y ambos fueron asesinados\", dijo el padre de Natalie Lloyd, el representante del estado de Missouri Ben Baker, en una publicaci\u00f3n de Facebook. \"Fueron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447011,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/15\/operativo-captura-jimmy-barbecue-cherizier-haiti-pandillas-trax\/","url_meta":{"origin":1456410,"position":2},"title":"Intentan capturar al l\u00edder pandillero Jimmy &#171;Barbecue&#187; Cherizier en Hait\u00ed con un gran operativo, dicen fuentes","author":"","date":"marzo 15, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Un gran operativo se lleva a cabo en Puerto Pr\u00edncipe, capital de Hait\u00ed, para capturar al l\u00edder pandillero Jimmy Cherizier, alias \"Barbecue\", seg\u00fan dijeron dos fuentes policiales a CNN. De acuerdo a las fuentes, m\u00faltiples unidades de fuerzas especiales participan en el esfuerzo.El operativo se despliega espec\u00edficamente en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472762,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/04\/01\/bandas-criminales-haiti-ataques-region-artibonite-masacre-reux\/","url_meta":{"origin":1456410,"position":3},"title":"Bandas criminales de Hait\u00ed mantienen sus ataques en la regi\u00f3n de Artibonite, luego de la masacre que dej\u00f3 decenas de muertos","author":"","date":"abril 1, 2026","format":false,"excerpt":"Hombres armados perpetraron nuevos ataques el martes en la regi\u00f3n agr\u00edcola de Artibonite, en Hait\u00ed, pocos d\u00edas despu\u00e9s de que un asalto perpetrado por una banda el fin de semana en la zona de Jean-Denis dejara unas 70 v\u00edctimas mortales, seg\u00fan grupos de derechos humanos y residentes locales.La Polic\u00eda nacional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446258,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/03\/03\/fuga-presos-carcel-puerto-principe-haiti-pandillas-trax\/","url_meta":{"origin":1456410,"position":4},"title":"Se estima que m\u00e1s de 3.000 reclusos escaparon de la prisi\u00f3n de Hait\u00ed en medio de la violencia en Puerto Pr\u00edncipe","author":"","date":"marzo 3, 2024","format":false,"excerpt":"(CNN) --\u00a0Se cree que alrededor de 3.500 prisioneros escaparon de la Penitenciar\u00eda Nacional de Hait\u00ed durante un brote de violencia este fin de semana, seg\u00fan estimaciones de la ONU, aunque las condiciones no han permitido realizar un recuento completo, dijo el domingo una fuente de la ONU.Seg\u00fan la fuente, hab\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449864,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/05\/30\/ee-uu-negocia-pandilla-asegurar-cuerpos-misioneros-asesinados-haiti-trax\/","url_meta":{"origin":1456410,"position":5},"title":"Exclusiva: EE.UU. negocia con una pandilla para asegurar los cuerpos de los misioneros estadounidenses asesinados en Hait\u00ed","author":"","date":"mayo 30, 2024","format":false,"excerpt":"(CNN) -- El primer vuelo comercial de Estados Unidos a Hait\u00ed en meses realiz\u00f3 un sombr\u00edo viaje de ida y vuelta este jueves, regresando con los cuerpos de una joven pareja estadounidense asesinada por una pandilla en Puerto Pr\u00edncipe la semana pasada.Los restos de Davy y Natalie Lloyd fueron acompa\u00f1ados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456410"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456410\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}