{"id":1456411,"date":"2024-12-09T18:03:52","date_gmt":"2024-12-10T02:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/"},"modified":"2024-12-09T18:03:52","modified_gmt":"2024-12-10T02:03:52","slug":"microplasticos-por-que-son-malos-como-evitarlos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/","title":{"rendered":"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano"},"content":{"rendered":"<p>Vivimos en la <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC8016130\/\">era del pl\u00e1stico<\/a>.<\/p>\n<p>Ya sea en los alimentos y su envasado, en nuestras viviendas, muebles y ropa o incluso en nuestro entorno, casi no hay forma de evitar el pl\u00e1stico.<\/p>\n<p>Aunque el pl\u00e1stico nos facilita la vida de innumerables maneras, \u00bfse imaginan la vida sin zapatos, computadoras o autom\u00f3viles? Tampoco se puede negar que los pl\u00e1sticos est\u00e1n asfixiando nuestro medio ambiente. Y los dirigentes no se ponen de acuerdo sobre c\u00f3mo domar a este monstruo que hemos creado.<\/p>\n<p>Los pl\u00e1sticos tambi\u00e9n afectan a nuestra salud de formas que apenas estamos empezando a comprender.<\/p>\n<p>Los micropl\u00e1sticos y los nanopl\u00e1sticos (fragmentos de pl\u00e1stico incre\u00edblemente diminutos que se desprenden y desprenden de productos m\u00e1s grandes) se han abierto camino en muchos de los tejidos de nuestro cuerpo, incluidos el cerebro, los \u00f3rganos reproductores (tanto masculinos como <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S0160412020322297\">femeninos<\/a>) y el sistema cardiovascular.<\/p>\n<p>\u201cEs mucho m\u00e1s omnipresente de lo que parece\u201d, declar\u00f3 recientemente el Dr. Leonardo Trasande, director de Pediatr\u00eda Medioambiental y vicepresidente de Investigaci\u00f3n Pedi\u00e1trica de la Facultad de Medicina de la NYU, al Dr. Sanjay Gupta, corresponsal m\u00e9dico en jefe de CNN, en su podcast Chasing Life. Trasande ha pasado las dos \u00faltimas d\u00e9cadas estudiando c\u00f3mo la exposici\u00f3n ambiental, incluida la de los micropl\u00e1sticos, afecta a nuestra salud.<\/p>\n<p>\u201cComemos mucho pl\u00e1stico. Inhalamos mucho pl\u00e1stico\u201d en forma de polvo, dijo Trasande. \u201cUsamos literalmente cosm\u00e9ticos que se reabsorben en nuestro cuerpo\u2026 Hemos llegado a aceptar el pl\u00e1stico como algo normal. Y no es normal\u201d.<\/p>\n<p>No es solo el pl\u00e1stico en s\u00ed lo que causa estragos en el cuerpo humano, ya que, seg\u00fan Trasande, provoca irritaci\u00f3n e inflamaci\u00f3n. Tambi\u00e9n le preocupa lo que contiene el pl\u00e1stico.<\/p>\n<p>\u201cHay aditivos que se a\u00f1aden intencionadamente\u201d, explica Trasande. \u201cPensamos que el pl\u00e1stico crujiente de cloruro de polivinilo, al que estamos tan acostumbrados en los envases de alimentos, es as\u00ed por s\u00ed mismo, pero al cloruro de polivinilo se le a\u00f1aden ftalatos para hacerlo m\u00e1s blando\u201d.<\/p>\n<p>Entre los aditivos que preocupan a Trasande figuran los ftalatos (utilizados en productos de cuidado personal y envases alimentarios), los bisfenoles (empleados en el revestimiento de aluminio de latas y en recibos de papel t\u00e9rmico) y las sustancias perfluoroalquiladas y polifluoroalquiladas (PFAS), llamadas sustancias qu\u00edmicas para siempre porque no se descomponen f\u00e1cilmente en el medio ambiente.<\/p>\n<p>\u201cLuego est\u00e1n las sustancias a\u00f1adidas de forma no intencionada. Son impurezas u otros materiales que se mezclan\u201d, explica.<\/p>\n<p>Resulta que muchas de estas sustancias qu\u00edmicas a\u00f1adidas (por no hablar de las impurezas no intencionadas) no son buenas para nuestro organismo. La principal preocupaci\u00f3n: la disrupci\u00f3n del sistema endocrino.<\/p>\n<p>El <a href=\"https:\/\/www.epa.gov\/endocrine-disruption\/overview-endocrine-system\">sistema endocrino<\/a> es una compleja red de gl\u00e1ndulas y \u00f3rganos que producen y liberan hormonas que controlan muchas de las funciones b\u00e1sicas de nuestro cuerpo, como el metabolismo, el crecimiento y la reproducci\u00f3n.<\/p>\n<p>\u201cEl sistema endocrino no lo es todo, es lo \u00fanico\u201d, afirma Trasande. \u201cY es que endocrino es hormona. Las hormonas son nuestras mol\u00e9culas se\u00f1alizadoras, nuestras conductoras maestras de la comunicaci\u00f3n corporal\u2026 de las g\u00f3nadas al coraz\u00f3n y al cerebro\u201d.<\/p>\n<p>Las conexiones son \u201cdiversas y numerosas\u201d, dijo, y regulan \u201ctodo, desde la temperatura, el metabolismo, la sal, el az\u00facar e incluso el sexo\u201d.<\/p>\n<p>CNN se puso en contacto con el Consejo Estadounidense de Qu\u00edmica para pedirle un comentario y recibi\u00f3 una declaraci\u00f3n por correo electr\u00f3nico, que dec\u00eda en parte: \u201cLas empresas que fabrican productos qu\u00edmicos y pl\u00e1sticos se centran en producir sustancias qu\u00edmicas que ofrezcan importantes ventajas en materia de seguridad, rendimiento y durabilidad de los productos y que puedan utilizarse de forma segura. Nuestros miembros llevan a cabo exhaustivos an\u00e1lisis cient\u00edficos para evaluar el riesgo potencial de sus productos qu\u00edmicos, desde su desarrollo hasta su uso y eliminaci\u00f3n segura\u201d.<\/p>\n<p>La <a href=\"https:\/\/www.fda.gov\/food\/environmental-contaminants-food\/microplastics-and-nanoplastics-foods\">p\u00e1gina web<\/a> de la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s) sobre micropl\u00e1sticos y nanopl\u00e1sticos en los alimentos se\u00f1ala que hay algunas pruebas de que \u201clos micropl\u00e1sticos y los nanopl\u00e1sticos est\u00e1n entrando en el suministro de alimentos\u201d. Pero la agencia afirma que las pruebas cient\u00edficas actuales \u201cno demuestran que los niveles de micropl\u00e1sticos o nanopl\u00e1sticos detectados en los alimentos supongan un riesgo para la salud humana\u201d.<\/p>\n<p>\u00bfQu\u00e9 puedes hacer para reducir su exposici\u00f3n a los micropl\u00e1sticos y nanopl\u00e1sticos? Trasande ofrece estos cinco consejos.<\/p>\n<p>Aunque el <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC9671506\/\">bisfenol A (BPA)<\/a>, una sustancia qu\u00edmica que se utilizaba habitualmente en el revestimiento de muchas latas, tapas y tapones met\u00e1licos de alimentos y bebidas ya no est\u00e1 presente en los envases de la mayor\u00eda de los productos (por ejemplo, conservas de at\u00fan, refrescos y tomates), los datos de la industria muestran que se sigue utilizando en un <a href=\"https:\/\/www.cancentral.com\/wp-content\/uploads\/2023\/01\/CMI-Washington-State-Canned-Food-Market-Basket-Report-Raw-Data.pdf\">5%<\/a> de los casos, <a href=\"https:\/\/foodpackagingforum.org\/news\/report-finds-harmful-chemicals-widespread-in-packaged-and-processed-foods\">posiblemente m\u00e1s<\/a>.<\/p>\n<p>Adem\u00e1s, no est\u00e1 claro si lo que ha sustituido al <a href=\"https:\/\/ehp.niehs.nih.gov\/doi\/10.1289\/ehp.1408989\">BPA es m\u00e1s seguro<\/a>; seg\u00fan muchos informes, un sustituto com\u00fan, el bisfenol S, <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC7071457\/\">es tan t\u00f3xico<\/a> para la salud como el BPA, y tambi\u00e9n se ha filtrado en el <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0048969717325457\">medio ambiente<\/a>.<\/p>\n<p>\u201cHay latas que no contienen bisfenol, pero al consumidor le resulta muy dif\u00edcil averiguarlo\u201d, explica Trasande, y se\u00f1ala que algunas latas est\u00e1n ahora recubiertas de resinas naturales, como la oleorresina, una mezcla de aceite y resina extra\u00edda de plantas como el pino o el abeto bals\u00e1mico.<\/p>\n<p>\u201c\u00bfPuedo decir que son definitivamente seguras? No\u201d, afirma. \u201cPero si tuviera dos opciones, una con BPA y otra con oleorresina, elegir\u00eda la de oleorresina. Pero si pudiera evitar las latas en primer lugar, eso es lo que har\u00eda y me decantar\u00eda por el vidrio o el acero inoxidable o fresco\u201d.<\/p>\n<p>El calor y los limpiadores agresivos no son buenos para el pl\u00e1stico por un par de razones.<\/p>\n<p>\u201cNos han enga\u00f1ado con la idea del pl\u00e1stico apto para microondas (y lavavajillas)\u201d, dice Trasande. \u201cEl pl\u00e1stico apto para microondas (y lavavajillas) solo sirve para deformar el recipiente\u201d.<\/p>\n<p>Sin embargo, si se observa el recipiente de pl\u00e1stico a nivel microsc\u00f3pico, se puede ver el da\u00f1o, dijo.<\/p>\n<p>\u201cAqu\u00ed pasan dos cosas. Una es que hay aditivos que no est\u00e1n (fuertemente) unidos al pl\u00e1stico, por lo que se desprender\u00e1n en condiciones normales\u201d, explic\u00f3 Trasande.<\/p>\n<p>\u201cY luego est\u00e1n los pol\u00edmeros del pl\u00e1stico. Se descomponen\u2026 ya sea en micropl\u00e1sticos, nanopl\u00e1sticos o los propios productos qu\u00edmicos\u201d, explic\u00f3.<\/p>\n<p>Trasande se\u00f1al\u00f3 que esos trozos microsc\u00f3picos de aditivos qu\u00edmicos y\/o pl\u00e1stico se absorben en los alimentos, que luego se ingieren.<\/p>\n<p>Si el pl\u00e1stico est\u00e1 grabado, por ejemplo en una tabla de cortar de pl\u00e1stico muy usada o una tapa agrietada, des\u00e9chalo definitivamente porque las grietas aumentan las probabilidades de que las sustancias qu\u00edmicas se filtren tambi\u00e9n en los alimentos, a\u00f1adi\u00f3.<\/p>\n<p>Comprueba el peque\u00f1o n\u00famero de reciclaje de tu botella o recipiente para saber con qu\u00e9 tipo de pl\u00e1stico est\u00e1s tratando.<\/p>\n<p>\u201cEl 3 corresponde al cloruro de polivinilo; es el pl\u00e1stico al que se suele a\u00f1adir ftalato para ablandarlo\u201d, explica Trasande. Los ftalatos se han relacionado con una serie de problemas de salud, como los partos prematuros, la muerte prematura y muchas otras afecciones, como el c\u00e1ncer, los problemas cardiovasculares, el asma, los problemas reproductivos y la obesidad infantil.<\/p>\n<p>\u201cEl seis es por el poliestireno. No es el poliestireno en s\u00ed, es que\u2026 el <a href=\"https:\/\/www.niehs.nih.gov\/health\/topics\/agents\/styrene\">estireno<\/a> puede desprenderse del poliestireno y el estireno es un<a href=\"https:\/\/www.nationalacademies.org\/news\/2014\/07\/styrene-reasonably-anticipated-to-be-a-human-carcinogen-new-report-confirms\"> carcin\u00f3geno muy potente<\/a>\u201d, dijo.<\/p>\n<p>\u201cEl siete es una mezcla; el siete dice \u2018Otros\u2019\u201d, dijo, se\u00f1alando que un consumidor no puede saber lo que contiene. \u201cAh\u00ed es donde digo: \u2018Si no lo s\u00e9, no quiero molestarme y asumir ese riesgo\u2019\u201d.<\/p>\n<p>Una nota m\u00e1s sobre las botellas de pl\u00e1stico: si est\u00e1n pensadas para un solo uso, rec\u00edclalas despu\u00e9s de un solo uso, dijo Trasande. Los pl\u00e1sticos de un solo uso no s\u00f3lo no est\u00e1n dise\u00f1ados para el nivel de desgaste de los pl\u00e1sticos m\u00e1s resistentes, lo que puede aumentar el riesgo de contaminaci\u00f3n qu\u00edmica, sino que, adem\u00e1s, a menos que los laves cuidadosamente con agua tibia y jab\u00f3n, podr\u00edas estar introduciendo contaminaci\u00f3n bacteriana.<\/p>\n<p>Utiliza acero inoxidable o hierro fundido en lugar de ollas y sartenes antiadherentes, sugiere Trasande.<\/p>\n<p>\u201cEse revestimiento es de pl\u00e1stico\u201d, dijo, concretamente PFAS, o sustancias per- y polifluoroalquiladas. Trasande dijo que esas sustancias qu\u00edmicas llamadas \u201cpara siempre\u201d han acaparado mucha atenci\u00f3n \u00faltimamente porque tambi\u00e9n contaminan el suministro de agua.<\/p>\n<p>\u201cSi hay un tema\u2026 es \u2018lo que crees que no es pl\u00e1stico puede ser pl\u00e1stico\u2019\u201d, dijo.<\/p>\n<p>Pasa la aspiradora regularmente con un filtro HEPA y utiliza una mopa h\u00fameda para evitar que el polvo invada tu espacio vital. \u201cEl polvo es un vector de estas sustancias qu\u00edmicas\u201d, explica Trasande.<\/p>\n<p>Los micropl\u00e1sticos y nanopl\u00e1sticos diminutos, que se desprenden de muchas fuentes, como los tejidos utilizados en la ropa, los muebles y las alfombras, as\u00ed como los repelentes de agua, los antimanchas y los retardantes de llama que se les aplican, flotan y pueden acumularse en el polvo, explica Trasande. \u201cHay pl\u00e1stico en muchas partes de la sociedad humana, y arrastramos polvo de muchos sitios\u201d.<\/p>\n<p>La filtraci\u00f3n del aire tambi\u00e9n puede ayudar, dijo, y adem\u00e1s tiene la ventaja a\u00f1adida de reducir la cantidad de bacterias y virus (como los que causan los resfriados,la influenza y el covid), adem\u00e1s de estas sustancias qu\u00edmicas.<\/p>\n<p>Trasande admiti\u00f3 que, en lo que respecta a sus propios h\u00e1bitos, \u201cno es perfecto\u201d. Por ejemplo, a veces olvida su taza de acero inoxidable y est\u00e1 \u201cdesesperado por (su) dosis de cafe\u00edna\u201d, as\u00ed que tiene que comprar su caf\u00e9 en un vaso de papel, que est\u00e1 forrado de pl\u00e1stico.<\/p>\n<p>Trasande se esfuerza por utilizar menos pl\u00e1stico, pero es realista. \u201cNo hay que dejar que lo perfecto sea enemigo de lo bueno\u201d, dice.<\/p>\n<p>Tambi\u00e9n es optimista de cara al futuro. \u201cNo vas a cambiar el universo de la noche a la ma\u00f1ana. No se va a cambiar el comportamiento de las empresas de la noche a la ma\u00f1ana, pero se est\u00e1 creando esa demanda e impulso por parte de los consumidores\u201d, dijo, a\u00f1adiendo que, seg\u00fan su experiencia, la industria tambi\u00e9n quiere normas.<\/p>\n<p>\u201cSaben que los consumidores quieren materiales seguros, y ya est\u00e1n innovando para alejarse del pl\u00e1stico\u2026 Este sistema se ha ido construyendo a lo largo de 60 o 70 a\u00f1os. Llevar\u00e1 tiempo deshacerlo, pero merece la pena. Una pizca de sentido com\u00fan ayuda mucho\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vivimos en la era del pl\u00e1stico. Ya sea en los alimentos y su envasado, en nuestras viviendas, muebles y ropa o incluso en nuestro entorno, casi no hay forma de evitar el pl\u00e1stico. Aunque el pl\u00e1stico nos facilita la vida de innumerables maneras, \u00bfse imaginan la vida sin zapatos, computadoras o autom\u00f3viles? Tampoco se puede [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456411","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano - Noticias\" \/>\n<meta property=\"og:description\" content=\"Vivimos en la era del pl\u00e1stico. Ya sea en los alimentos y su envasado, en nuestras viviendas, muebles y ropa o incluso en nuestro entorno, casi no hay forma de evitar el pl\u00e1stico. Aunque el pl\u00e1stico nos facilita la vida de innumerables maneras, \u00bfse imaginan la vida sin zapatos, computadoras o autom\u00f3viles? Tampoco se puede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T02:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano\",\"datePublished\":\"2024-12-10T02:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/\"},\"wordCount\":1874,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/\",\"name\":\"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-10T02:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano - Noticias","og_description":"Vivimos en la era del pl\u00e1stico. Ya sea en los alimentos y su envasado, en nuestras viviendas, muebles y ropa o incluso en nuestro entorno, casi no hay forma de evitar el pl\u00e1stico. Aunque el pl\u00e1stico nos facilita la vida de innumerables maneras, \u00bfse imaginan la vida sin zapatos, computadoras o autom\u00f3viles? Tampoco se puede [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-10T02:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/"},"author":{"name":"","@id":""},"headline":"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano","datePublished":"2024-12-10T02:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/"},"wordCount":1874,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/","name":"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-10T02:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los micropl\u00e1sticos se encuentran en todo el cuerpo. Por qu\u00e9 son tan malos y qu\u00e9 puedes hacer para estar m\u00e1s sano","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/microplasticos-por-que-son-malos-como-evitarlos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-10T02:03:52Z","datePublished":"2024-12-10T02:03:52Z","dateModified":"2024-12-10T02:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los micropl\\u00e1sticos se encuentran en todo el cuerpo. Por qu\\u00e9 son tan malos y qu\\u00e9 puedes hacer para estar m\\u00e1s sano\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/09\\\/microplasticos-por-que-son-malos-como-evitarlos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/09\\\/microplasticos-por-que-son-malos-como-evitarlos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-10T02:03:52Z\",\"datePublished\":\"2024-12-10T02:03:52Z\",\"dateModified\":\"2024-12-10T02:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448375,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/22\/alimentos-plasticos-expertos-trax\/","url_meta":{"origin":1456411,"position":0},"title":"\u00bfCu\u00e1nto pl\u00e1stico hay en los alimentos que consumes? Mucho m\u00e1s de lo que crees, seg\u00fan los expertos","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN) -- \"\u00bfCu\u00e1nto pl\u00e1stico quiere cenar, se\u00f1or? \u00bfY usted, se\u00f1ora?\" Aunque pueda parecer una frase sacada de un sketch sat\u00edrico de Saturday Night Live, las investigaciones demuestran que dista poco de la realidad.Seg\u00fan un estudio de febrero de 2024, el 90% de las muestras de prote\u00ednas animales y vegetales dieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450549,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/06\/20\/microplasticos-penes-humanos-nanoplasticos-salud-contaminacion-trax\/","url_meta":{"origin":1456411,"position":1},"title":"Encuentran micropl\u00e1sticos en penes humanos por primera vez","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN) -- Cient\u00edficos hallaron por primera vez micropl\u00e1sticos en penes humanos, mientras aumenta la preocupaci\u00f3n por la proliferaci\u00f3n de estas diminutas part\u00edculas y sus posibles efectos sobre la salud.En un estudio publicado este mi\u00e9rcoles en IJIR: Your Sexual Medicine Journal, se encontraron siete tipos diferentes de micropl\u00e1sticos en cuatro de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464987,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/30\/aire-interior-microplasticos-pulmones-estudio-trax\/","url_meta":{"origin":1456411,"position":2},"title":"El aire interior contiene micropl\u00e1sticos diminutos que pueden llegar profundamente a los pulmones, seg\u00fan un estudio","author":"","date":"julio 30, 2025","format":false,"excerpt":"Miles de micropl\u00e1sticos tan peque\u00f1os que pueden penetrar profundamente en los pulmones est\u00e1n presentes en el aire que respiras en tu casa y en tu autom\u00f3vil, seg\u00fan un nuevo estudio.Las part\u00edculas probablemente son el resultado de la degradaci\u00f3n de objetos llenos de pl\u00e1stico, como alfombras, cortinas, muebles y textiles, as\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452736,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/09\/16\/encuentran-plastico-tejido-nasal-cerebro-trax\/","url_meta":{"origin":1456411,"position":3},"title":"Encuentran micropl\u00e1sticos en el tejido nasal de la base del cerebro, seg\u00fan un estudio","author":"","date":"septiembre 16, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Se encontraron peque\u00f1os fragmentos y fibras de pl\u00e1stico en el tejido nasal de cad\u00e1veres humanos, seg\u00fan un nuevo estudio.Los hilos y trozos de micropl\u00e1stico fueron descubiertos en el bulbo olfatorio, la parte de la nariz encargada de detectar los olores situada en la base del cerebro.\u201cUna vez presente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460422,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/25\/chicle-microplasticos-estudio-bienestar-trax\/","url_meta":{"origin":1456411,"position":4},"title":"El chicle puede liberar micropl\u00e1sticos en la saliva, seg\u00fan una investigaci\u00f3n","author":"","date":"marzo 25, 2025","format":false,"excerpt":"\u00bfLlevas una lista mental de todas las fuentes de micropl\u00e1sticos que se cuelan en tu vida cotidiana? Puede que tengas que tener en cuenta a otro culpable: seg\u00fan un nuevo estudio piloto, masticar un solo chicle puede liberar entre cientos y miles de micropl\u00e1sticos en la saliva.El estudio est\u00e1 siendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465552,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/16\/fracasan-negociaciones-tratado-plasticos-crisis-trax\/","url_meta":{"origin":1456411,"position":5},"title":"Fracasan las negociaciones para un Tratado Global de Pl\u00e1sticos y los pa\u00edses siguen divididos sobre c\u00f3mo abordar la crisis","author":"","date":"agosto 16, 2025","format":false,"excerpt":"Las conversaciones para finalizar el primer tratado global sobre la contaminaci\u00f3n por pl\u00e1sticos en Ginebra, Suiza, fracasaron este viernes debido a que los pa\u00edses permanecieron profundamente divididos sobre c\u00f3mo abordar la crisis.La cumbre, celebrada en la sede de las Naciones Unidas y con la participaci\u00f3n de delegados de m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456411"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456411\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}