{"id":1456428,"date":"2024-12-10T10:03:39","date_gmt":"2024-12-10T18:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/"},"modified":"2024-12-10T10:03:39","modified_gmt":"2024-12-10T18:03:39","slug":"bandera-rebeldes-siria-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/10\/bandera-rebeldes-siria-orix\/","title":{"rendered":"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado"},"content":{"rendered":"<p>Apenas un d\u00eda despu\u00e9s de la ca\u00edda del r\u00e9gimen sirio y<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/08\/mundo\/rusia-assad-abandono-siria\"> la huida a Rusia de su l\u00edder<\/a>, el presidente Bashar al-Assad, la bandera verde, blanca y negra que grupos rebeldes ondean desde el inicio de la guerra civil, en 2011, comenz\u00f3 a verse en las calles de Damasco.<\/p>\n<p>Esa misma bandera ya empez\u00f3 a ser ondeada en edificios p\u00fablicos en Siria y el lunes incluso fue<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/09\/ultima-hora-guerra-en-siria-noticia-orix-2\/\"> izada en la embajada de Siria en Mosc\u00fa,<\/a> ciudad donde se cree que Assad se refugi\u00f3.<\/p>\n<p>Mientras tanto, la vieja bandera roja, blanca y negra se ha convertido en un s\u00edmbolo <a href=\"https:\/\/www.cnn.com\/2024\/12\/09\/middleeast\/syria-assad-rebels-explainer-intl-hnk\/index.html\">del brutal r\u00e9gimen<\/a> que gobern\u00f3 Siria durante d\u00e9cadas, primero a trav\u00e9s de Hafez al-Assad y luego su hijo, Bashar, as\u00ed como del partido \u00e1rabe socialista Baaz.<\/p>\n<p>A la larga y sangrienta batalla por el pa\u00eds se suma ahora una batalla por los s\u00edmbolos, y la bandera puede ser central en los intentos de la variopinta y controversial coalici\u00f3n rebelde, liderada por el grupo extremista Hayat Tarim al Sham -ex filial de Al Qaeda en Siria- y el \u201cEj\u00e9rcito Nacional Sirio\u201d, para lograr una transici\u00f3n ordenada del poder y, sobre todo, restaurar la unidad de una Siria dividida desde hace<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/01\/siria-guerra-historia-rusia-assad-orix\/\"> 13 a\u00f1os por la guerra civil.<\/a><\/p>\n<p>\u00bfPero c\u00f3mo es la bandera de los rebeldes, qu\u00e9 significa y por qu\u00e9 es usada por la oposici\u00f3n a Assad?<\/p>\n<p>La ense\u00f1a rebelde tiene un cl\u00e1sico dise\u00f1o tricolor con bandas horizontales del mismo tama\u00f1o: verde arriba, blanco en el centro y negro en la base. Adem\u00e1s, cuenta con tres estrellas rojas centradas sobre la banda blanca.<\/p>\n<p>La mirada al pasado es clara, ya que esta bandera es muy similar a la utilizada por Siria por primera vez tras su independencia de Francia en 1941, seg\u00fan <a href=\"https:\/\/www.britannica.com\/topic\/flag-of-Syria\">se\u00f1ala Enciclopedia Britannica<\/a>.<\/p>\n<p>As\u00ed, los cuatro colores empleados en ese momento -negro, verde, blanco y rojo- representaban a las cuatro grandes dinast\u00edas de la historia \u00e1rabe: los abas\u00ed, los fatim\u00ed, los omeya y los hachemita.<\/p>\n<p>El domingo, poco despu\u00e9s de la ca\u00edda del r\u00e9gimen, la bandera rebelde se iz\u00f3 en la hist\u00f3rica Mezquita de los Omeyas en Damasco, y desde all\u00ed el l\u00edder de Hayat Tahrir al-Sham, <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/09\/mundo\/analisis-abu-mohammad-al-jolani-lider-siria-trax\">Abu Mohammad al-Jolani,<\/a> <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/09\/mundo\/cronologia-rebeldes-siria-trax\">proclam\u00f3 <\/a>una \u201cvictoria para toda la naci\u00f3n isl\u00e1mica\u201d.<\/p>\n<p>Estos colores son muy importantes para el mundo \u00e1rabe y est\u00e1n presentes en las banderas de Egipto, Iraq, Yemen, Kuwait y Jordania, entre otros.<\/p>\n<p>Las tres estrellas en la ense\u00f1a siria, en tanto, representan a las tres regiones de Damasco, Aleppo y Deir Ezzor, de acuerdo con <a href=\"https:\/\/dspace.mit.edu\/handle\/1721.1\/70372\">una investigaci\u00f3n <\/a>del Massachusetts Institute of Technology.<\/p>\n<p>La insignia de Siria sufri\u00f3 varios cambios durante su historia posterior a la independencia, y<a href=\"https:\/\/www.britannica.com\/topic\/flag-of-Syria\"> en 1980 el gobierno de Hafez al Assad adopt\u00f3 la bandera<\/a> de la fallida Rep\u00fablica \u00c1rabe Unida, un estado de breve existencia (1958-1961) surgido de la uni\u00f3n entre Egipto y Siria, como oficial.<\/p>\n<p>Se trata de la misma bandera que continu\u00f3 hasta la ca\u00edda del r\u00e9gimen el domingo: un dise\u00f1o de tres bandas horizontales de color rojo, blanco y negro, pero con solo dos estrellas verdes en el centro.<\/p>\n<p>De acuerdo con el <a href=\"https:\/\/www.cia.gov\/the-world-factbook\/countries\/syria\/flag\/\">CIA World Factbook<\/a>, el negro representa la opresi\u00f3n, el rojo la lucha para superarla, y el blanco el futuro brillante para el pa\u00eds. Y las dos estrellas, heredadas de la Rep\u00fablica \u00c1rabe Unida, representan a Egipto y Siria.<\/p>\n<p>La puja entre el proyecto socialista y pan\u00e1rabe del partido Baaz y los Assad, por un lado, y los diferentes movimientos islamistas, democr\u00e1ticos y autonomistas reunidos en la oposici\u00f3n, por el otro, tambi\u00e9n alcanza al simbolismo de la bandera.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apenas un d\u00eda despu\u00e9s de la ca\u00edda del r\u00e9gimen sirio y la huida a Rusia de su l\u00edder, el presidente Bashar al-Assad, la bandera verde, blanca y negra que grupos rebeldes ondean desde el inicio de la guerra civil, en 2011, comenz\u00f3 a verse en las calles de Damasco. Esa misma bandera ya empez\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456428","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado - Noticias\" \/>\n<meta property=\"og:description\" content=\"Apenas un d\u00eda despu\u00e9s de la ca\u00edda del r\u00e9gimen sirio y la huida a Rusia de su l\u00edder, el presidente Bashar al-Assad, la bandera verde, blanca y negra que grupos rebeldes ondean desde el inicio de la guerra civil, en 2011, comenz\u00f3 a verse en las calles de Damasco. Esa misma bandera ya empez\u00f3 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T18:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado\",\"datePublished\":\"2024-12-10T18:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/\"},\"wordCount\":663,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/\",\"name\":\"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-10T18:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado - Noticias","og_description":"Apenas un d\u00eda despu\u00e9s de la ca\u00edda del r\u00e9gimen sirio y la huida a Rusia de su l\u00edder, el presidente Bashar al-Assad, la bandera verde, blanca y negra que grupos rebeldes ondean desde el inicio de la guerra civil, en 2011, comenz\u00f3 a verse en las calles de Damasco. Esa misma bandera ya empez\u00f3 a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-10T18:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/"},"author":{"name":"","@id":""},"headline":"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado","datePublished":"2024-12-10T18:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/"},"wordCount":663,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/","name":"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-10T18:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/bandera-rebeldes-siria-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/10\/bandera-rebeldes-siria-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Rebeldes en Siria ya ondean su propia bandera: en qu\u00e9 se diferencia con la del r\u00e9gimen derrocado","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/10\/bandera-rebeldes-siria-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/10\/bandera-rebeldes-siria-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-10T18:03:39Z","datePublished":"2024-12-10T18:03:39Z","dateModified":"2024-12-10T18:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Rebeldes en Siria ya ondean su propia bandera: en qu\\u00e9 se diferencia con la del r\\u00e9gimen derrocado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/10\\\/bandera-rebeldes-siria-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/10\\\/bandera-rebeldes-siria-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-10T18:03:39Z\",\"datePublished\":\"2024-12-10T18:03:39Z\",\"dateModified\":\"2024-12-10T18:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456401,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/09\/cronologia-rebeldes-siria-trax\/","url_meta":{"origin":1456428,"position":0},"title":"Cronolog\u00eda de c\u00f3mo los rebeldes sirios acabaron con el r\u00e9gimen de Assad en menos de dos semanas","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"En la hist\u00f3rica Mezquita Omeya, en el coraz\u00f3n de Damasco, ondea una bandera roja, blanca, negra y verde.Al otro lado de la capital siria, arde el palacio del expresidente Bashar al-Assad.Un presentador lee las noticias del domingo: \u201cAnunciamos desde el canal de noticias sirio la victoria de la gran revoluci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456531,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/12\/rebeldes-siria-mapas-regimen-assad-trax\/","url_meta":{"origin":1456428,"position":1},"title":"C\u00f3mo los rebeldes de Siria derrocaron el r\u00e9gimen de Assad, en 7 mapas","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Durante m\u00e1s de una d\u00e9cada, la guerra civil siria ha hecho estragos en m\u00faltiples frentes, dejando al pa\u00eds dividido y lleno de cicatrices. Y durante la mayor parte de ese largo tiempo, los combates dieron pocas se\u00f1ales de menguar. Pero entonces, en cuesti\u00f3n de un par de semanas, el r\u00e9gimen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456373,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/talibanes-felicitan-rebeldes-sirios-gobierno-islamico-trax\/","url_meta":{"origin":1456428,"position":2},"title":"Talibanes felicitan a los rebeldes en Damasco y piden el establecimiento de un gobierno isl\u00e1mico en Siria","author":"","date":"diciembre 8, 2024","format":false,"excerpt":"El Ministerio de Asuntos Exteriores de los talibanes en Afganist\u00e1n felicit\u00f3 este domingo al pueblo sirio y a las fuerzas rebeldes, en particular a Hayat Tahrir Al-Sham (HTS), tras el derrocamiento del r\u00e9gimen de Bashar al-Assad, y pidi\u00f3 el establecimiento de un gobierno isl\u00e1mico.Afganist\u00e1n \u201cfelicita a los dirigentes del movimiento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456179,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/11\/30\/rebeldes-sirios-controlan-ciudad-aleppo-trax\/","url_meta":{"origin":1456428,"position":3},"title":"Los rebeldes sirios toman el control de la mayor parte de la ciudad de Aleppo","author":"","date":"noviembre 30, 2024","format":false,"excerpt":"(CNN) -- Las fuerzas de la oposici\u00f3n siria tomaron el control de gran parte de la segunda ciudad m\u00e1s grande del pa\u00eds, Aleppo, seg\u00fan un video verificado por CNN y residentes en la ciudad.Una alianza rebelde lanz\u00f3 un ataque sorpresa esta semana, desplaz\u00e1ndose hacia el este a trav\u00e9s de pueblos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456375,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/08\/rebeldes-sirios-liderar-amanecer-trax\/","url_meta":{"origin":1456428,"position":4},"title":"En un pa\u00eds desgarrado por la guerra civil, \u00bfpodr\u00e1n los rebeldes sirios liderar un nuevo amanecer?","author":"","date":"diciembre 8, 2024","format":false,"excerpt":"La bandera roja, blanca, verde y negra del Ej\u00e9rcito Libre Sirio onde\u00f3 el domingo sobre Damasco mientras miles de residentes se alineaban en la plaza principal en estallidos de j\u00fabilo desafiante, despu\u00e9s de que el presidente Bashar al-Assad renunciara a su control del poder.Durante los \u00faltimos 11 d\u00edas, una alianza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457150,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/02\/cambios-plan-estudios-siria-indignacion-redes-sociales-trax\/","url_meta":{"origin":1456428,"position":5},"title":"Cambios en el plan de estudios en Siria desatan indignaci\u00f3n en redes sociales","author":"","date":"enero 2, 2025","format":false,"excerpt":"El nuevo Gobierno de Siria enfrenta cr\u00edticas tras anunciar cambios en el plan de estudios escolar, incluyendo lo que algunos cr\u00edticos dicen es una inclinaci\u00f3n islamista en la ense\u00f1anza.Los cambios, publicados en una lista de enmiendas en la p\u00e1gina oficial de Facebook del Ministerio de Educaci\u00f3n, incluyen cambiar las frases\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456428"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456428\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}