{"id":1456713,"date":"2024-12-18T09:03:45","date_gmt":"2024-12-18T17:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/"},"modified":"2024-12-18T09:03:45","modified_gmt":"2024-12-18T17:03:45","slug":"charlie-engman-imagenes-inquietantes-ia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/","title":{"rendered":"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA"},"content":{"rendered":"<p>Demasiados dedos o demasiados dientes: el a\u00f1o pasado, cuando las im\u00e1genes generativas de inteligencia artificial irrumpieron en Internet, este tipo de variaciones corporales se convirti\u00f3 tanto en un chiste como en una se\u00f1al reveladora de que ciertas fotograf\u00edas no eran reales. En cambio, eran la forma de detectar la marca de una m\u00e1quina sobre el mundo a trav\u00e9s de indicaciones humanas. Las im\u00e1genes que se volvieron virales a menudo eran inquietantes: fotos nost\u00e1lgicas de fiestas con modelos sonrientes con molares adicionales, o retratos de un Steve Harvey llorando mientras agita licor en una habitaci\u00f3n completamente oscura.<\/p>\n<p>En los \u00faltimos dos a\u00f1os, el fot\u00f3grafo y director de Brooklyn, Charlie Engman, ha estado intencionalmente explorando la extra\u00f1eza de las fotograf\u00edas con IA para generar im\u00e1genes inquietantes \u2014con el programa Midjourney\u2014 que parecen situarse en el mundo real, pero juegan con la anatom\u00eda y los gestos de maneras perturbadorass. En su libro \u201cCursed\u201d, un hombre con traje se adentra hasta las rodillas en un charco poco profundo a la luz de la ma\u00f1ana, con alas de cisne extendi\u00e9ndose desde sus hombros. En otra imagen, una mujer mira un busto escult\u00f3rico rojizo con sus propios rasgos que parece estar mir\u00e1ndola. Las extremidades se transforman y desaparecen por completo, los rostros son lisos y enmascarados, y los objetos inanimados se asemejan a extremidades humanas. Las personas sostienen animales y se fusionan en ellos, mientras las nuevas formas parecen evolucionar o decaer.<\/p>\n<p>\u201c[La IA] hace las cosas muy mal\u201d, explic\u00f3 Engman a CNN en una videollamada. \u201cTiene esta relaci\u00f3n tercerizada con el mundo f\u00edsico, donde representa la representaci\u00f3n que tiene un humano de [ese mundo]. Y as\u00ed deconstruye gestos f\u00edsicos y cuerpos humanos\u2026 de una manera realmente cruda y visceral\u201d.<\/p>\n<p>Mirar las im\u00e1genes puede generar una sensaci\u00f3n de inquietud. Algunas se desv\u00edan sutilmente de lo cotidiano hacia lo antinatural, como una mujer sosteniendo una hoja filosa contra su mejilla, sonriendo, con los ojos fijos en el espectador. Otras son representaciones de pesadilla, como un feto al estilo de David Cronenberg tanto de insecto como humana.<\/p>\n<p>A trav\u00e9s de \u201cCursed\u201d, Engman buscaba lograr una especie de \u201cdisonancia equilibrada\u201d que se sienta como una elaboraci\u00f3n de su propio trabajo fotogr\u00e1fico, dijo.<\/p>\n<p>\u201cLo que es deseable, lo que es repugnante, lo que es hermoso, lo que es feo: te ves obligado a confrontar, a nivel de sentimientos, cu\u00e1les son esos criterios\u201d, agreg\u00f3.<\/p>\n<p>Engman ha jugado con esas tensiones a lo largo de su trabajo. Su intensa colaboraci\u00f3n de 15 a\u00f1os con su madre, \u201cMom\u201d, explora las din\u00e1micas tanto de una relaci\u00f3n madre-hijo como de la de fot\u00f3grafo-sujeto de maneras a veces inc\u00f3modas. Por otro lado, como  director art\u00edstico de la marca de moda de Brooklyn Collina Strada ha transformado modelos en animales en la pasarela o los ha hecho avanzar por ella con sonrisas desquiciadas.<\/p>\n<p>Como muchas personas, Engman dio sus primeros pasos con la IA a trav\u00e9s de la aplicaci\u00f3n Lensa, que permit\u00eda generar autorretratos estilizados con IA para compartir en redes sociales. Pero despu\u00e9s de que un colega en Collina Strada le mostrara sus experimentos en Midjourney, en 2022, Engman se enganch\u00f3 con sus posibilidades<\/p>\n<p>\u201cEs como una m\u00e1quina tragamonedas, \u00bfverdad? Pones una indicaci\u00f3n y luego obtienes algo. Y lo que obtienes no es realmente tan importante\u2026 Yo ten\u00eda una alegr\u00eda ingenua de principiante con eso\u201d, record\u00f3 Engman de las primeras veces que usaba Midjourney. \u201cCreo que tal vez era cl\u00ednicamente adicto a eso. Estaba despierto a las 2 a.m. [us\u00e1ndolo]\u201d.<\/p>\n<p>Debido a su trabajo continuo junto con su madre, Engman aprovech\u00f3 la tecnolog\u00eda como una nueva forma de colaboraci\u00f3n, entrenando a Midjourney con un conjunto de sus im\u00e1genes. Y aunque su madre aparece espor\u00e1dicamente en el libro, incluida como una figura sin extremidades y con alas de polilla, es m\u00e1s un huevo de Pascua para aquellos familiarizados con el trabajo de Engman, que un punto focal.<\/p>\n<p>Aunque \u201cCursed\u201d naturalmente se toca con el mundo del cine de terror, Engman evit\u00f3 las referencias visuales y en su lugar comenz\u00f3 a leer textos relacionados con la teor\u00eda cr\u00edtica de la discapacidad. Las preguntas que se plante\u00f3 sobre el cuerpo y la capacidad se reflejan en las im\u00e1genes.<\/p>\n<p>\u201c\u00bfCu\u00e1les son las limitaciones reales de un cuerpo? \u00bfQu\u00e9 es un cuerpo normativo? \u00bfCu\u00e1les son las limitaciones de un cuerpo normativo? \u00bfCu\u00e1ndo un cuerpo comienza a moverse fuera del marco normativo y cu\u00e1l es el umbral?\u201d, se plante\u00f3. \u201cEsas son las cosas de las que tambi\u00e9n habla el horror corporal, probablemente de una manera muy similar\u201d.<\/p>\n<p>Los animales \u2014cisnes, perros y caballos\u2014 aparecen como sugerencias de criaturas completamente formadas y tambi\u00e9n desensambladas. Engman los usa porque la forma en que se representaban le parec\u00eda hermosa, explic\u00f3, pero tambi\u00e9n tienen una larga historia de simbolismo impl\u00edcito.<\/p>\n<p>\u201cSon categ\u00f3ricamente animales aleg\u00f3ricos, por lo que pude hacer conexiones conceptuales po\u00e9ticas entre lo humano y lo no humano\u201d, dijo. Debido a su uso en el arte, la literatura y otros medios, \u201cya hay un lenguaje elaborado para eso con lo que la gente puede conectarse\u201d.<\/p>\n<p>Con la aceleraci\u00f3n de las im\u00e1genes generadas por IA, el libro ya es un hito de un tiempo que se desvanece de la vista. Los libros de fotograf\u00eda \u2014desde el concepto hasta la impresi\u00f3n\u2014 a menudo se arman durante a\u00f1os, no meses. Engman descubri\u00f3 que la tecnolog\u00eda avanzaba m\u00e1s r\u00e1pido que el proyecto, a medida que se lanzaban actualizaciones nuevas de Midjourney, y las caracter\u00edsticas desordenadas como las manos de seis dedos se estaban volviendo obsoletas.<\/p>\n<p>\u201cLas primeras im\u00e1genes que hice para el proyecto y la \u00faltima imagen que hice dif\u00edcilmente pod\u00edan coexistir\u2026 estaban casi en dos registros diferentes y eso tambi\u00e9n es muy interesante para m\u00ed\u201d, dijo.<\/p>\n<p>\u201cLo que fue tan fascinante, y en realidad fue muy motivador, es que estaba haciendo un libro desactualizado. Mientras hac\u00eda el libro, ya estaba fuera de sincron\u00eda con lo que estaba sucediendo\u201d, agreg\u00f3.<\/p>\n<p>Las nuevas habilidades de IA llegaron en r\u00e1fagas, y luego se detienen mientras el poder de procesamiento se pone al d\u00eda y se logran otros avances. Puede haber un \u201ctecho\u201d para esta nueva ola de im\u00e1genes generadas con IA en relaci\u00f3n a cu\u00e1n precisamente un programa de computadora puede entender y representar el mundo, reconoci\u00f3 Engman, y est\u00e1 curioso, no ansioso, sobre lo que suceder\u00e1 despu\u00e9s.<\/p>\n<p>En el futuro, el contexto puede perderse para \u201cCursed\u201d, con cuerpos an\u00f3malos solo como un destello en el esquema m\u00e1s amplio de representaciones fieles con IA. O tal vez la pr\u00f3xima generaci\u00f3n de la IA nos lleve a\u00fan m\u00e1s profundamente al valle inquietante de maneras a\u00fan desconocidas y aterradoras. De cualquier manera, Engman quiere que el libro se mantenga por s\u00ed solo.<\/p>\n<p>\u201cDebe haber algo interesante sobre el trabajo que est\u00e9 fuera de la tecnolog\u00eda\u201d, dijo. \u201cLa tecnolog\u00eda debe estar subordinada al contenido.\u201d<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Demasiados dedos o demasiados dientes: el a\u00f1o pasado, cuando las im\u00e1genes generativas de inteligencia artificial irrumpieron en Internet, este tipo de variaciones corporales se convirti\u00f3 tanto en un chiste como en una se\u00f1al reveladora de que ciertas fotograf\u00edas no eran reales. En cambio, eran la forma de detectar la marca de una m\u00e1quina sobre el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456713","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA - Noticias\" \/>\n<meta property=\"og:description\" content=\"Demasiados dedos o demasiados dientes: el a\u00f1o pasado, cuando las im\u00e1genes generativas de inteligencia artificial irrumpieron en Internet, este tipo de variaciones corporales se convirti\u00f3 tanto en un chiste como en una se\u00f1al reveladora de que ciertas fotograf\u00edas no eran reales. En cambio, eran la forma de detectar la marca de una m\u00e1quina sobre el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T17:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA\",\"datePublished\":\"2024-12-18T17:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/\"},\"wordCount\":1243,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/\",\"name\":\"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-18T17:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA - Noticias","og_description":"Demasiados dedos o demasiados dientes: el a\u00f1o pasado, cuando las im\u00e1genes generativas de inteligencia artificial irrumpieron en Internet, este tipo de variaciones corporales se convirti\u00f3 tanto en un chiste como en una se\u00f1al reveladora de que ciertas fotograf\u00edas no eran reales. En cambio, eran la forma de detectar la marca de una m\u00e1quina sobre el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-18T17:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/"},"author":{"name":"","@id":""},"headline":"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA","datePublished":"2024-12-18T17:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/"},"wordCount":1243,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/","name":"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-18T17:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El artista que crea im\u00e1genes inquietantes del cuerpo humano con IA","url":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2024\/12\/18\/charlie-engman-imagenes-inquietantes-ia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-18T17:03:45Z","datePublished":"2024-12-18T17:03:45Z","dateModified":"2024-12-18T17:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El artista que crea im\\u00e1genes inquietantes del cuerpo humano con IA\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/18\\\/charlie-engman-imagenes-inquietantes-ia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2024\\\/12\\\/18\\\/charlie-engman-imagenes-inquietantes-ia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-18T17:03:45Z\",\"datePublished\":\"2024-12-18T17:03:45Z\",\"dateModified\":\"2024-12-18T17:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465431,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/12\/fotografias-arte-cambio-climatico-trax\/","url_meta":{"origin":1456713,"position":0},"title":"Inquietantes fotos muestran los efectos del cambio clim\u00e1tico en nuestra vida cotidiana","author":"","date":"agosto 12, 2025","format":false,"excerpt":"Se necesita un momento para asimilar lo que se ve en las fotograf\u00edas de las Maldivas tomadas por Edoardo Delille y Giulia Piermartiri. En una imagen, una tortuga marina parece nadar junto a una pareja en motocicleta; en otra, una familia de cinco posa en el pasillo de su casa,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457252,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/01\/05\/meta-eliminar-cuentas-ia-reaccion-negativa-trax\/","url_meta":{"origin":1456713,"position":1},"title":"Meta elimin\u00f3 sus propias cuentas de IA despu\u00e9s de que se intensificara la reacci\u00f3n negativa","author":"","date":"enero 5, 2025","format":false,"excerpt":"Meta elimin\u00f3 r\u00e1pidamente varias de sus cuentas generadas por inteligencia artificial despu\u00e9s de que los usuarios humanos empezaran a interactuar con ellas y a publicar sobre las im\u00e1genes inquietantes de los bots y su tendencia a desviarse del camino e incluso a mentir en los chats con humanos.El asunto sali\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456587,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/12\/13\/jesus-ia-inteligencia-artificial-redes-sociales-trax\/","url_meta":{"origin":1456713,"position":2},"title":"Las im\u00e1genes de Jes\u00fas generadas por IA en las redes sociales lo muestran sospechosamente musculoso (y todos tenemos la culpa)","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"Las im\u00e1genes de inteligencia artificial (IA) se han convertido en una atracci\u00f3n inevitable en Facebook y otras redes sociales, donde representaciones dram\u00e1ticas y extravagantes de escenas emocionales atraen a los usuarios a dar me gusta, compartir y decir \u201cAm\u00e9n\u201d.Entre las im\u00e1genes distorsionadas de ni\u00f1os falsos llorando en la calle y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448166,"url":"https:\/\/noticiasya.com\/palm-springs\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/","url_meta":{"origin":1456713,"position":3},"title":"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n","author":"","date":"abril 16, 2024","format":false,"excerpt":"(CNN) -- La junta de supervisi\u00f3n de Meta evaluar\u00e1 el manejo de la pornograf\u00eda deepfake por parte de la compa\u00f1\u00eda en medio de crecientes preocupaciones de que la Inteligencia Artificial (IA) est\u00e9 impulsando un aumento en la creaci\u00f3n de im\u00e1genes falsas y gr\u00e1ficas como una forma de acoso.La junta de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469216,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/","url_meta":{"origin":1456713,"position":4},"title":"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes publicaron este viernes fotos del patrimonio de Jeffrey Epstein que muestran a numerosas figuras poderosas en la \u00f3rbita del difunto traficante sexual, incluyendo al presidente Donald Trump, al expresidente Bill Clinton, a Steve Bannon, Bill Gates, Richard Branson\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469890,"url":"https:\/\/noticiasya.com\/palm-springs\/2026\/01\/08\/xai-elon-musk-bajo-fuego-desnudez-digital-trax\/","url_meta":{"origin":1456713,"position":5},"title":"La xAI de Elon Musk est\u00e1 bajo fuego por no frenar la &#171;desnudez digital&#187;","author":"","date":"enero 8, 2026","format":false,"excerpt":"El chatbot de inteligencia artificial de Elon Musk, Grok, se ha visto inundado de im\u00e1genes sexuales, principalmente de mujeres, muchas de ellas reales.Los usuarios han instado al chatbot a \u201cdesvestir digitalmente\u201d a estas personas y, en ocasiones, a colocarlas en poses sugerentes.En varios casos la semana pasada, algunas parec\u00edan ser\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1456713"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1456713\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1456713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1456713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1456713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}