{"id":1465799,"date":"2025-08-23T20:03:38","date_gmt":"2025-08-24T03:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/"},"modified":"2025-08-23T20:03:38","modified_gmt":"2025-08-24T03:03:38","slug":"doj-subvenciones-universidades-estudiantes-hispanos-ap","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/","title":{"rendered":"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos"},"content":{"rendered":"<p>El Gobierno de Donald Trump dijo el viernes que no defender\u00e1 un programa de subvenciones de d\u00e9cadas de antig\u00fcedad para universidades con un gran n\u00famero de estudiantes hispanos que es impugnado en los tribunales, declarando que el Gobierno considera que el financiamiento es inconstitucional.<\/p>\n<p>En un memorando enviado al Congreso, el Departamento de Justicia (DOJ, por sus siglas en ingl\u00e9s) dijo que est\u00e1 de acuerdo con una demanda que busca eliminar las subvenciones reservadas para universidades donde al menos una cuarta parte de los estudiantes de pregrado son hispanos. El Congreso cre\u00f3 el programa en 1998 tras determinar que los estudiantes latinos asist\u00edan a la universidad y se graduaban a tasas mucho m\u00e1s bajas que los estudiantes blancos.<\/p>\n<p>Funcionarios del Departamento de Justicia argumentaron que el programa ofrece una ventaja inconstitucional basada en la raza o etnia.<\/p>\n<p>El estado de Tennessee y una organizaci\u00f3n contraria a la acci\u00f3n afirmativa demandaron al Departamento de Educaci\u00f3n de EE.UU. en junio, solicitando a un juez que detuviera el programa de Instituciones al Servicio de los Hispanos. Tennessee argument\u00f3 que todas sus universidades p\u00fablicas atienden a estudiantes hispanos, pero ninguna cumple con el \u201cumbral \u00e9tnico arbitrario\u201d para ser elegible para las subvenciones. Esas escuelas pierden decenas de millones de d\u00f3lares debido a requisitos discriminatorios, seg\u00fan la demanda.<\/p>\n<p>El viernes, el Departamento de Justicia public\u00f3 una carta en la que el procurador general John Sauer notific\u00f3 al presidente republicano de la C\u00e1mara de Representantes, Mike Johnson, que el departamento \u201cha decidido no defender\u201d el programa, argumentando que ciertos aspectos son inconstitucionales. La carta, con fecha del 25 de julio, cit\u00f3 una decisi\u00f3n de la Corte Suprema de 2023 que afirma que el \u201cequilibrio racial absoluto\u201d es \u201cmanifiestamente inconstitucional\u201d.<\/p>\n<p>El Departamento de Justicia declin\u00f3 hacer comentarios.<\/p>\n<p>Tennessee cuenta con el respaldo en la demanda de Students for Fair Admissions, un grupo legal conservador que desafi\u00f3 con \u00e9xito la acci\u00f3n afirmativa en las <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/05\/22\/eeuu\/trump-prohibe-harvard-matricular-estudiantes-internacionales-trax\">admisiones en Harvard<\/a> y la Universidad de Carolina del Norte. Dicha demanda condujo a un fallo de la Corte Suprema en 2023 que proh\u00edbe a las universidades considerar la raza de los estudiantes en las decisiones de admisi\u00f3n.<\/p>\n<p>Edward Blum, presidente de Students for Fair Admissions, dijo el viernes que el grupo no har\u00eda comentarios.<\/p>\n<p>M\u00e1s de 500 universidades est\u00e1n designadas como Instituciones al Servicio de los Hispanos, lo que las hace elegibles para el programa de subvenciones. El Congreso asign\u00f3 alrededor de US$ 350 millones para el programa en 2024. Las universidades compiten por las subvenciones, que pueden destinarse a diversos usos, incluyendo mejoras de infraestructura y programas cient\u00edficos.<\/p>\n<p>El expresidente Joe Biden prioriz\u00f3 las universidades al servicio de los hispanos al firmar un decreto el a\u00f1o pasado que promet\u00eda una nueva junta asesora presidencial y un aumento del financiamiento. El presidente Donald Trump revoc\u00f3 el decreto en su primer d\u00eda en el cargo.<\/p>\n<p>Trump est\u00e1 tomando medidas para desmantelar el Departamento de Educaci\u00f3n y ha pedido recortes masivos de fondos, pero su solicitud presupuestaria para 2026 mantuvo las subvenciones para universidades al servicio de los hispanos e incluso pidi\u00f3 al Congreso un ligero aumento. Aun as\u00ed, hay dudas sobre el compromiso de su Gobierno con el financiamiento.<\/p>\n<p>Una asociaci\u00f3n nacional de universidades al servicio de los hispanos present\u00f3 una moci\u00f3n el mes pasado para intervenir como demandada en la demanda de Tennessee, expresando preocupaci\u00f3n de que el Gobierno federal no representar\u00eda adecuadamente a los miembros del grupo.<\/p>\n<p>La Asociaci\u00f3n Hispana de Colegios y Universidades dijo que la agenda de Trump es \u201ctotalmente adversa\u201d a los intereses del grupo, citando el objetivo del presidente de cerrar por completo el Departamento de Educaci\u00f3n. El Gobierno \u201cha manifestado su rechazo a programas como las HSI, que toman en cuenta y buscan corregir la disparidad \u00e9tnica o racial\u201d, escribi\u00f3 el grupo.<\/p>\n<p>Tennessee y Students for Fair Admissions no se opusieron a la solicitud del grupo para liderar la defensa legal.<\/p>\n<p>A diferencia de las universidades hist\u00f3ricamente negras o tribales de ind\u00edgenas americanos, que reciben sus designaciones en funci\u00f3n de su misi\u00f3n, cualquier universidad puede recibir la etiqueta y las subvenciones HSI si la matr\u00edcula latina representa al menos el 25 % del alumnado de pregrado.<\/p>\n<p>La lista de HSI incluye campus emblem\u00e1ticos como la Universidad de Texas en Austin y la Universidad de Arizona, junto con muchos colegios comunitarios e instituciones m\u00e1s peque\u00f1as.<\/p>\n<p>En su presentaci\u00f3n ante el tribunal, la asociaci\u00f3n nacional argumenta que las subvenciones son constitucionales y contribuyen a la igualdad de oportunidades de sus miembros.<\/p>\n<p>Las universidades del grupo matriculan al 67 % de los estudiantes latinos del pa\u00eds. Sin embargo, estudios revelan que reciben mucho menos financiamiento estatal y federal que otras instituciones. Las universidades al servicio de los hispanos est\u00e1n abiertas a estudiantes de todas las razas; por ejemplo, la asociaci\u00f3n se\u00f1al\u00f3 a la Universidad Adventista del Sur, una escuela privada en Tennessee cuya poblaci\u00f3n estudiantil es 28 % hispana y 40 % blanca.<\/p>\n<p>El Departamento de Justicia generalmente tiene el deber de defender la Constituci\u00f3n y la legislaci\u00f3n federal, pero en raras ocasiones puede negarse a defender leyes que considera inconstitucionales. El Gobierno de Obama lo hizo en 2011 cuando se neg\u00f3 a aplicar la Ley de Defensa del Matrimonio. Durante su primer mandato, Trump hizo lo mismo con la Ley de Cuidado de Salud Asequible.<\/p>\n<p>El Gobierno de Trump ha luchado para eliminar las pol\u00edticas de diversidad, equidad e inclusi\u00f3n en el Gobierno, la educaci\u00f3n y las empresas, argumentando que discriminan a las personas blancas y asi\u00e1tico-estadounidenses.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Donald Trump dijo el viernes que no defender\u00e1 un programa de subvenciones de d\u00e9cadas de antig\u00fcedad para universidades con un gran n\u00famero de estudiantes hispanos que es impugnado en los tribunales, declarando que el Gobierno considera que el financiamiento es inconstitucional. En un memorando enviado al Congreso, el Departamento de Justicia (DOJ, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465799","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Donald Trump dijo el viernes que no defender\u00e1 un programa de subvenciones de d\u00e9cadas de antig\u00fcedad para universidades con un gran n\u00famero de estudiantes hispanos que es impugnado en los tribunales, declarando que el Gobierno considera que el financiamiento es inconstitucional. En un memorando enviado al Congreso, el Departamento de Justicia (DOJ, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-24T03:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos\",\"datePublished\":\"2025-08-24T03:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/\"},\"wordCount\":973,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/\",\"name\":\"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-24T03:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/","og_locale":"es_ES","og_type":"article","og_title":"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos - Noticias","og_description":"El Gobierno de Donald Trump dijo el viernes que no defender\u00e1 un programa de subvenciones de d\u00e9cadas de antig\u00fcedad para universidades con un gran n\u00famero de estudiantes hispanos que es impugnado en los tribunales, declarando que el Gobierno considera que el financiamiento es inconstitucional. En un memorando enviado al Congreso, el Departamento de Justicia (DOJ, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/","og_site_name":"Noticias","article_published_time":"2025-08-24T03:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/"},"author":{"name":"","@id":""},"headline":"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos","datePublished":"2025-08-24T03:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/"},"wordCount":973,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/","url":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/","name":"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-24T03:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/palm-springs\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Departamento de Justicia no defender\u00e1 las subvenciones para universidades con estudiantes hispanos","url":"http:\/\/noticiasya.com\/palm-springs\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/palm-springs\/2025\/08\/23\/doj-subvenciones-universidades-estudiantes-hispanos-ap\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-24T03:03:38Z","datePublished":"2025-08-24T03:03:38Z","dateModified":"2025-08-24T03:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Departamento de Justicia no defender\\u00e1 las subvenciones para universidades con estudiantes hispanos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2025\\\/08\\\/23\\\/doj-subvenciones-universidades-estudiantes-hispanos-ap\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/palm-springs\\\/2025\\\/08\\\/23\\\/doj-subvenciones-universidades-estudiantes-hispanos-ap\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-24T03:03:38Z\",\"datePublished\":\"2025-08-24T03:03:38Z\",\"dateModified\":\"2025-08-24T03:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1460215,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/03\/20\/claves-desmantelamiento-departamento-educacion-trax\/","url_meta":{"origin":1465799,"position":0},"title":"4 claves sobre el esfuerzo de Trump para desmantelar el Departamento de Educaci\u00f3n","author":"","date":"marzo 20, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, inici\u00f3 el proceso de desmantelamiento del Departamento de Educaci\u00f3n al firmar un decreto este jueves.El movimiento busca cumplir una promesa de campa\u00f1a de larga data y transferir m\u00e1s poder sobre la educaci\u00f3n a los estados. Aunque el presidente no puede cerrar completamente la agencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461572,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/04\/24\/trump-revoco-visas-estatutos-estudiantes-internacionales-trax\/","url_meta":{"origin":1465799,"position":1},"title":"El Gobierno de Trump revoc\u00f3 m\u00e1s de 1.500 visas y estatutos de estudiantes internacionales, seg\u00fan un informe de CNN","author":"","date":"abril 24, 2025","format":false,"excerpt":"Este a\u00f1o, m\u00e1s de 1.500 estudiantes internacionales, reci\u00e9n graduados y universidades han visto revocadas sus visas o estatus en el Sistema de Informaci\u00f3n de Estudiantes y Visitantes de Intercambio (SIIS) en m\u00e1s de 200 universidades estadounidenses, seg\u00fan datos de CNN.En Texas, 176 estudiantes se han visto afectados en varias universidades\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464806,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/23\/investigan-universidades-becas-indocumentados-trax\/","url_meta":{"origin":1465799,"position":2},"title":"La Oficina de Derechos Civiles del Departamento de Educaci\u00f3n investiga a 5 universidades por becas para indocumentados","author":"","date":"julio 23, 2025","format":false,"excerpt":"Cinco universidades est\u00e1n siendo investigadas por la Oficina de Derechos Civiles del Departamento de Educaci\u00f3n de Estados Unidos por otorgar becas a inmigrantes indocumentados inscritos en el programa DACA, implementado durante la administraci\u00f3n Obama, seg\u00fan un comunicado del Departamento de Educaci\u00f3n emitido este mi\u00e9rcoles.Acci\u00f3n diferida para los llegados en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468484,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/11\/18\/gobierno-trump-desmantelar-departamento-educacion-trax\/","url_meta":{"origin":1465799,"position":3},"title":"Gobierno de Trump avanza en el desmantelamiento del Departamento de Educaci\u00f3n y manda trabajo a otras agencias","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"El Departamento de Educaci\u00f3n anunci\u00f3 este martes un desmantelamiento adicional al transferir gran parte de su carga de trabajo restante a otras instancias federales, en un intento de convencer al Congreso de que ya no es necesario.Seg\u00fan un acuerdo interinstitucional, seis oficinas ser\u00e1n trasladadas para asociarse con otras cuatro agencias:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462984,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/05\/29\/cronologia-disputa-gobierno-trump-harvard-trax\/","url_meta":{"origin":1465799,"position":4},"title":"Cronolog\u00eda de la disputa entre el Gobierno de Trump y Harvard","author":"","date":"mayo 29, 2025","format":false,"excerpt":"Desde que regres\u00f3 al cargo en enero, el presidente Donald Trump ha intensificado los se\u00f1alamientos hacia las universidades de \u00e9lite de Estados Unidos por motivos ideol\u00f3gicos. Sin embargo, las bases para la postura m\u00e1s firme de la Casa Blanca se sentaron m\u00e1s de un a\u00f1o antes.Dos meses despu\u00e9s del ataque\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464787,"url":"https:\/\/noticiasya.com\/palm-springs\/2025\/07\/23\/investigacion-elegibilidad-programa-visas-harvard-trax\/","url_meta":{"origin":1465799,"position":5},"title":"El Gobierno de Trump abre una investigaci\u00f3n sobre la elegibilidad del programa de visas de Harvard","author":"","date":"julio 23, 2025","format":false,"excerpt":"El Gobierno de Trump abri\u00f3 una investigaci\u00f3n sobre la \u201celegibilidad continua como patrocinador del Programa de Visitantes de Intercambio\u201d de la Universidad de Harvard, anunci\u00f3 el Secretario de Estado Marco Rubio este mi\u00e9rcoles, lo que marca la \u00faltima escalada del Gobierno contra la instituci\u00f3n de la Ivy League.El anuncio se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/palm-springs\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1465799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/comments?post=1465799"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/posts\/1465799\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/media?parent=1465799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/categories?post=1465799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/palm-springs\/wp-json\/wp\/v2\/tags?post=1465799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}